{"id":12373,"date":"2021-03-04T11:21:28","date_gmt":"2021-03-04T10:21:28","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=12373"},"modified":"2021-03-04T11:21:28","modified_gmt":"2021-03-04T10:21:28","slug":"das-morgen-erforschen","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2021\/03\/das-morgen-erforschen\/","title":{"rendered":"Das Morgen erforschen"},"content":{"rendered":"<h1><strong>Wie unsere Welt in ein paar Jahrzehnten aussehen wird, ist und bleibt ungewiss. Oder doch nicht? Sozialwissenschaften gehen auf unterschiedliche Arten mit Zukunftsvorhersagen um.<\/strong><\/h1>\n<p class=\"dropcap dropcap-borders\">Setzt man sich mit Forschung auseinander, die sich mit der Zukunft besch\u00e4ftigt, steht man erst einmal vor einer Irritation: Wie ist es m\u00f6glich, dass empirische Wissenschaften sich mit einem Forschungsobjekt besch\u00e4ftigen, das es per Definition (noch) nicht gibt?<\/p>\n<h2><strong>Vorsicht bei fixen Vorhersagen<\/strong><\/h2>\n<p>Nat\u00fcrlich muss nuanciert werden. Naturwissenschaften entwerfen schliesslich dauernd auf Grundlage von Daten Szenarien, auf die wir uns mehr oder weniger verlassen k\u00f6nnen. Man denke nur einmal an die Klimaforschung, die uns derzeit keine rosige Zukunft prophezeit.<\/p>\n<p>Dar\u00fcber hat <em>Spectrum <\/em>mit der Sozialanthropologin Julia Eckert gesprochen. Ihre Einsch\u00e4tzung: \u00abWenn Ern\u00e4hrungswissenschaftler*innen aufgrund des zunehmenden Zuckerverzehrs Prognosen zu steigenden Diabetes-Raten machen, ist das sinnvoll.\u00bb In sozialwissenschaftlichen Disziplinen k\u00f6nne aber mit dem Blick in die Zukunft eine falsche Kausalit\u00e4t aufgemacht werden: \u00abWenn Islamwissenschaftler*innen wegen vermehrter hoher Bildungsabschl\u00fcsse unter Muslim*innen in Europa mehr Terror vorhersagen, weil viele der bisherigen T\u00e4ter*innen einen hohen Bildungsabschluss hatten, ist das problematisch.\u00bb<\/p>\n<p>Aber: \u00abSozialwissenschaftler*innen sollen durchaus ihre Einsichten in Zusammenh\u00e4nge und Dynamiken f\u00fcr politische Ma\u00dfnahmen n\u00fctzlich machen\u00bb, sagt Eckert. Im Stil von \u00abWenn wir dies tun, wird wahrscheinlich jenes passieren\u00bb. Seri\u00f6se Forschung weise aber immer auf die Vorl\u00e4ufigkeit solcher Vermutungen hin und zeige alternative Szenarien auf.<\/p>\n<h2><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-12374\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/\u00a9-Johanna-Schatton-475x600.jpg\" alt=\"\" width=\"348\" height=\"440\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/\u00a9-Johanna-Schatton-475x600.jpg 475w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/\u00a9-Johanna-Schatton-768x969.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/\u00a9-Johanna-Schatton-951x1200.jpg 951w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/\u00a9-Johanna-Schatton-530x669.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/\u00a9-Johanna-Schatton.jpg 1854w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/strong><\/h2>\n<h2><strong>Zwei Grundsatzfragen<\/strong><\/h2>\n<p>David Bozzini, Professor f\u00fcr Sozialanthropologie an der Universit\u00e4t Freiburg, vertritt eine \u00e4hnliche Auffassung, mahnt aber zur Vorsicht. M\u00f6chte man als Sozialwissenschaftler*in Aussagen \u00fcber die Zukunft einer untersuchten Bev\u00f6lkerungsgruppe treffen, w\u00fcrden sich zwei Fragen stellen: Erstens, ob das Fach \u00fcberhaupt in der Lage dazu ist, Daten zu liefern, aufgrund derer Vorhersagen getroffen werden k\u00f6nnen. Und zweitens, was f\u00fcr ethische Herausforderungen mit Aussagen \u00fcber die Zukunft einhergehen. \u00abWie die Menschen ihr Verhalten aufgrund einer Vorhersage anpassen, steht in den Sternen. Wenn ich sage, das politische Regime in Eritrea wird in den n\u00e4chsten f\u00fcnf Jahren fallen, kann ich Menschen damit in Gefahr bringen\u00bb, sagt Bozzini. Auch sei ungewiss, was politische Autorit\u00e4ten mit solchem Wissen anstellen w\u00fcrden. Man w\u00fcrde unter Umst\u00e4nden aktiv in politische Prozesse eingreifen.<\/p>\n<p>Auch der ersten Frage gegen\u00fcber ist Bozzini kritisch eingestellt. \u00abWir sind nicht in der Lage, Messinstrumente in der gesellschaftlichen Atmosph\u00e4re aufzustellen, um gesellschaftlichen Wandel wie das Wetter vorherzusagen.\u00bb Daf\u00fcr sei die soziale Realit\u00e4t schlicht zu komplex.<\/p>\n<p>Wie Bev\u00f6lkerungsgruppen in der Gegenwart mit der Zukunft umgehen, welche Sicherheitsvorkehrungen sie beispielsweise treffen, um sich vor politischer Repression zu sch\u00fctzen, sei allerdings fester Bestandteil der Forschung.<\/p>\n<h2><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-12376\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/Pixabay_Zukunftsforschung-800x600.jpg\" alt=\"\" width=\"800\" height=\"600\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/Pixabay_Zukunftsforschung-800x600.jpg 800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/Pixabay_Zukunftsforschung-768x576.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/Pixabay_Zukunftsforschung-530x398.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/03\/Pixabay_Zukunftsforschung.jpg 1280w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>Nachdenken, aber nicht Prophezeien <\/strong><\/h2>\n<p>In diesem Selbstverst\u00e4ndnis k\u00f6nnte man wohl auch das <em>Berliner Institut f\u00fcr Zukunftsstudien und Technologiebewertung (IZT)<\/em> verorten. Im Sammelband \u00abZukunftsforschung und Zukunftsgestaltung\u00bb distanzieren sich die Forschenden von einem \u00abprognostischen Umgang mit der Zukunft\u00bb wie er noch im positivistischen Verst\u00e4ndnis der 1960er Jahre gang und g\u00e4be war. Stattdessen streben sie unverbindliche Szenarien an. Gegenstand der Forschung k\u00f6nne nie die Zukunft selbst sein, sondern nur \u00abdie Bilder, die wir uns heute von ihr machen\u00bb, wie der Philosoph und Technikfolgenabsch\u00e4tzer Armin Grunwald in seinem Beitrag schreibt.<\/p>\n<p>Hypothesen zur Zukunft zu formulieren, scheint Denker*innen legitim und der Forschung von heute ein Bed\u00fcrfnis zu sein. Konkrete Vorhersagen \u00fcber gesellschaftliche Entwicklungen sind aber nicht nur heikel. Sie k\u00f6nnen sich auch selbst zum Stolperstein werden, wie der Historiker Yuval Noah Harari in seinem Buch \u00abHomo Deus\u00bb schreibt. Fangen wir an, \u00fcber die Zukunft unserer Gesellschaft zu sprechen, beeinflussen wir damit das Verhalten von uns Menschen. Harari nennt dieses Ph\u00e4nomen das \u00abParadox of Knowledge\u00bb: \u00abMarx vergass, dass Kapitalisten lesen k\u00f6nnen.\u00bb<\/p>\n<hr \/>\n<p>Prof. Dr. Julia Eckert hat den Lehrstuhl f\u00fcr Politische Anthropologie am Institut f\u00fcr Sozialanthropologie an der Universit\u00e4t Bern inne. Ihre Forschungsschwerpunkte liegen unter anderem in Fragen nach dem Wandel politischer Institutionen wie der Demokratie und des Rechts.<\/p>\n<p>Prof. Dr. David Manuel Bozzini lehrt an der Universit\u00e4t Freiburg am Departement f\u00fcr Sozialwissenschaften. In seiner Forschung hat er sich lange mit sozialen Ph\u00e4nomenen im Kontext der Militarisierung in Eritrea besch\u00e4ftigt, bevor er sich der Sicherheit und \u00dcberwachung im Internet widmete.<\/p>\n<h3 style=\"text-align: right;\">Text: Katharina Schatton<br \/>\nIllustration: Johanna Schatton<br \/>\nBild: Pixabay<\/h3>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQyNjcGAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c0ksVvDNL0pPzVNILUrLLypOzkjNAwA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcHBEcAgCATAivSM+aWbjGDwITqA\/WdXIrY\/gMch1shHR7fcBL65hZ0JYtRSL5Qb9Hqayz7WxNaXeRNW\/A==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"804syUgsysxLVAhOzkgsKcnPAwA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtQ1MNY1MFEwNLQyMLYysgAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"tVlNbxtHEr3nVzR4ShYUSUm2bGtlBRbkD8Vx1ogcG+vLoknWcDqc6Rl094gyf8sCe\/Fl4bsv8Un8Y\/te9wxJSXYQYO2DQHI+uqtevap61TrKd4+PfHCVnR2\/MaIa68WJeiNFUMYqwV+ttVM\/6dwtJbdBrNKN95Ljy8K4aV8ZH\/DaVI0LMWN+ncnCeD9Q\/5iKU9NqkitrJnn4UZ1XS6ML3hTrJ7nOuNosLqWbDG8GcbhuZFrgBVGPHB8oTVBvm3ljs+AvKpfjGT3D9aYcHA1b04+G8OO7o1pNCu39w97UVfVE16r93BlXDsb43vG5hGVQpbbKY4u49pOKm8JsOgaHtcWjfTUFGutn6ElrgxoLHl+9z4KZhb7yQfK0INYPBKzUhYKd\/Iq3zpwzQQdT2UNFgImWeFWuPs7oJPaBwUrK2jjj6fSb6\/CsTeBy5cZYX41\/l\/k1a8TG1bh8jZ1PJTPWcGf1vUUUfkhhUDNE6cejYQ288r118F9j4Xh7LEZl5hJbv96AvQ30HoE+\/kWH1SdXROvAB2UbbSdGXFALAdZ2oPBE424EW2zA7Yx+TfLCiPdxhaluxIFCZMFTBzIV2BQgWnWq+dr5Uqx2hg7yEYYG3CNZVSm5UxXjsxALDJy6EEcS4LX56qO1NOUFwgOb5gIzXRcjXsNCzwtT6qyDNcWdC2PJpQD3OYFXrvJYfM2BGrzKhfcHCcn6+FS71acx9s91UEdSHp\/XMgmuKdXREL86FqUc0DbkWKIqqhky7KemMFo9nswJ30w8VgcTYPdZjlx8bGwMcVjCvkN19eGNWKseO7t6nzsyYRvjQtzfDJ0mUDNCiV29wquSlwJmW\/jAjS7oXu68eumqma0I17Ihm8kjPnZq9FiC+J1fYwhKTZNStpNkHrtcVEUxuPpDnSGct1I7pjCX8UtTF8au46E0UUp4lOoEz81Zaoh7B2+EPNNFTIjnSEtdmAAEolNCUzqarfE484UuP4\/EQlgu4DC5EhihCrxWJ6aYEj49JhdXn\/BqKkHqRQNalu3bMO1xg1jpRLVX4hySe6sQ9bGBQcobKSSGeGw87hFH9QpGr+2QCAI3tzc2ZwKBNmEbYJAAFbVE6cATQLnj2SOgR69vF9ONxx6Bwce0cbjReGU6HjHDk09vAWoJRoBYKNixgJ++s7o0c9zPkNoK7DQh1aQXevUfq0kgZVefwjKlfWTE1R+ogXoWWvqCs6U6D8QD2dvGhrmK8HoVGqKFrqEW6Cdc2ti41u9iWbWQtighXHSgzgHh6iNisqnPwNm39DGw3a2LASpVsXrfZGY2Z8rC\/Qkj\/BohbwIbEmCHz3RySYIrXSAsFtheyKa4cLnBrcJ4ZMqZKio9NXb2sFfo5bseojyp0m\/t39lJr2s7oOnM2grkVYt6B3VlJju7e\/v37vSUd5OHvTyE2h8OUUwbcDcMGmsyN5jkQ9\/WiiFem1TssmHY1NzVD\/dGe7vD0f7w6r87P1W5tlbvnE\/Ilsru3Ll39\/JgNBr8Xs96dOphrwd8pyF\/2Nu\/c7+nAPAsx9U7d0bRBC\/h21qh8H3RV199i3sH9y8fHDyIW+D7t9jiwd3dy9291g38+BZ73N0fXR60buD7N9giLr17\/+6dBQJulkJWNqHqq+9LfbkTuXGowI368ge1OxpdwIT4q6eGxze7\/FYWvEXupdbsdVhm7vOi4FRfmKk6qZZLKI8+W0uGFo9yGQvK7dYnsQkjU3+zyEQIkFjknzgIycahF+NagHxqGwL6nW2FYZNlSLjYr0sNVZqKwhLNvdMxaPqrj6x2UZuhlagvFUys5pOiTP37ZiNyrTBtUu08kYvVxwK1juUbHbauRQUnWRY7AfycdqptScyeRKjYWFmSD9G38dX6vqrGscw\/QRVNG6NS11F0E5CfKYCmGi0Z\/aDfyiD8gmbKULn62+3didvWalAQCAvtaXvkRgf9xgIIq5IFC2wfAyMhT3X+mTi0iyyK5VQ22ab\/HB9sGyX8gNUet3j7RUSYjSaPVThnvd2SJAnWjc2gQR0lW6enIwrQfazSXDq2EWLKp5PK3WpPv8rMlBI7NdjiRKce0y4CnTTJCTqdtVkcZfhDMyB9Ndft0mujp5pe4+2nkuFZNXaGWKw7XcvvAYChRQhyN\/MkTLcse4TUc5HVLZapNZWtyoffLTE65iStmn60auS30mOBqMn0HB2Llm1tgSRDlqMvAtQZMgdxX2vSaCDpJJF1iYzgB7xJsaTYaN1Rc5eWjAtJtCukoDqqvWk7PmwRtA\/M0LHhA+oU6pN0N\/E63r6mAx+FsvI11AaUCHiwbFrH+5jjPvf8G45hBQIpMdpvJBCLJLvwMvlI6XmqI4MZhDiwxRwnIzrFGOcM2o3kmVdlXcjlGh7S9TPpbDs3nhKohYYovzkDNmXkPKUf46nOaTRMM3FEnUvepg\/kDAcqX0Mc+iRf1rUCfscywVlxE08H22tHWKukyCH9obhiasBJktZReiB1GSPIWHwAq0ANShPXculrSRl2kZ1SpgYGX1M1B19D1bw0l3qs3\/2rm\/DXk9jO\/dHoS9oGtzba5mD0tbTNX7JF4fv\/27e\/vBF1zt17B19L53x5IyqR\/Qf3v5YS+eJGSY\/s3R\/9mR4BpFt6JP6iHvkFvTGO7ex3LFepAr3shm8k2G0NchZHSY8aey7F2Afqilg\/rfGpE7aaYFHlBUpRPH7wcWI\/EVekQxuUNBOakNpj5xOB4Z7sYK9kktukYcaCNsspQ31\/9vbVD3Hap3KpeHqV5iFOWsUYWYpyeguhuF53lYUXXMdlFLepYWov40iUagVrXErwNKRzyEoHQ1cf6jTIpzJi0TZmGovfqFxYlSWVWPJgzpQoPZBd5sKsX3y9DRhf3X1wMJJ0BIjmoVuLZ6v3Y0G\/cxjVAqTnVGJHQziASKp8jQUMY7SOpNq2Bi3gEotrLF3Xy1Z3SmBbLdGVXB+jySLIUljxkM7G45yrD3yMA3V3bNedDeXShHSMRB2ymVdjU8GeL3NTVB5k2oTUzLOqgGFxLueZCx575EqKAZT0hS6irPAJ8xPUe3RU1mhK1s1Z0LN3dRVySYcqm66Bco6ol00RI9pXaQAO6pQc72b3AmImIC7NLWDoSHKJx7InMgU5MwaJbQKXBup5ZedOglyTg6nT32qx6rENCzOZF12n4vnbJsmILKybS4H4Aq9WQyYa6iR8YkCWDQf+qqijxjCd6Nyg\/AzUggiCh+qfzYUu1C+VztUz7cCFbTC55tWHZ1VZAZDGg6lrXKGSo5EMrMbSt4VoOrdmy964GXFBL00HV2PBPhmPWtqFksxj7m8UKiEmczotOOjshOsIVCwsHrxBelRllIoeNr\/EM9PqUlWZem6rRSHTmVz9wUOaF9pdshbMNMVhPOp9rmuDFDdRkBWyfU7ZHfKArMPIIw5QA3WKFLt2RMgTRmb\/zzzACw3KWKxTL7d05\/Uhq7xR0f7qJHbCHCMt26PIzekzPhDnurFzsA18jgfyUa7G43PE09hu9rE6qtCy03TbYqezC2onhiVR5lTKau50MKK6E8xfEcbg1xm2QSbNnFDNDZbutGzBk74\/HS4JyqnUEHdC6bqNy\/Uz60E83kwTyyYXGQJxKRsKkrNV91F+2g1DKCZL5mWQy1SIXxh4D0rxpIsrbU0t1\/+zMJb4X4R2k3h2vFaZEZbVv5EFC50MMoxxHJcCVVKJKtAJwH0U5XeFPOzRhp0o7A6Vo3j6e+\/4Fa4dgpQhh01Wq+4c4WgcSXhWIGOCa\/+B0R423HyItfdQtRIAjXj\/+Lv\/AQ==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Wie unsere Welt in ein paar Jahrzehnten aussehen wird, ist und bleibt ungewiss. Oder doch nicht? Sozialwissenschaften gehen auf unterschiedliche Arten mit Zukunftsvorhersagen um.&hellip;<\/div>\n","protected":false},"author":83,"featured_media":12379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[114,891,911],"tags":[2197,2196,1135,1152],"class_list":["post-12373","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossier","category-gesellschaft","category-wissenschaft","tag-entwicklung","tag-forschung","tag-gesellschaft","tag-zukunft"],"views":1965,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/12373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=12373"}],"version-history":[{"count":3,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/12373\/revisions"}],"predecessor-version":[{"id":12382,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/12373\/revisions\/12382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/12379"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=12373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=12373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=12373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}