{"id":13184,"date":"2021-10-29T20:22:58","date_gmt":"2021-10-29T18:22:58","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=13184"},"modified":"2021-10-29T20:22:58","modified_gmt":"2021-10-29T18:22:58","slug":"islam-ist-zu-einer-projektionsflaeche-geworden","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2021\/10\/islam-ist-zu-einer-projektionsflaeche-geworden\/","title":{"rendered":"\u00abIslam ist zu einer Projektionsfl\u00e4che geworden\u00bb"},"content":{"rendered":"<h2>Ein Gespr\u00e4ch mit Amir Dziri<\/h2>\n<p>&nbsp;<\/p>\n<h1>Die Abstimmungen im vergangenen Fr\u00fchjahr haben gezeigt: Themen rund um den Islam besch\u00e4ftigen und die Debatten dazu werden hitzig gef\u00fchrt. <em>Spectrum<\/em> hat mit Amir Dziri, dem Direktor des Schweizerischen Zentrum f\u00fcr Islam und Gesellschaft, \u00fcber aktuelle Kontroversen und \u00c4ngste gesprochen und gefragt, ob Religion einen solchen Wirbel wert sei.<\/h1>\n<p>&nbsp;<\/p>\n<h2><strong>Amir Dziri, verstehen Sie die Angst vor dem Islam?<\/strong><\/h2>\n<p class=\"dropcap dropcap-borders\">Ja, aber ich glaube, dazu geh\u00f6ren mehrere Aspekte. Das lateinische Christentum und der muslimische Orient haben sich \u00fcber Jahrhunderte hinweg oftmals in Abgrenzung zueinander definiert. Diese historische Erinnerung wirkt hier beidseitig nach. Ausserdem stelle ich in den Debatten fest, dass offensichtliche Missst\u00e4nde in muslimischen Gesellschaften direkt auf den Islam als Ursache zur\u00fcckgef\u00fchrt werden. Es gibt \u00fcber sechzig verschiedene muslimische L\u00e4nder, aber man orientiert sich in der \u00abIslamdebatte\u00bb weitgehend an den Negativbeispielen. Auf einer weiteren Ebene haben wir reale Konflikte des Zusammenlebens. Hier geht es um unterschiedliche kulturelle Wertvorstellungen, die religi\u00f6s, ethnisch oder kulturell begr\u00fcndet sind. Das sind oft intime und sensible Konflikte, welche etwa die Sexualmoral oder Rollenbilder betreffen. Solche Konflikte sollten aber nicht grunds\u00e4tzlich als etwas Negatives angesehen werden, sondern als ein Prozess, der sich l\u00f6sen und kl\u00e4ren l\u00e4sst. Man sollte es also nicht verteufeln, dass Menschen \u00c4ngste haben. Stattdessen sollten wir ins Gespr\u00e4ch kommen.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>K\u00f6nnte es auch sein, dass die nicht-muslimische Bev\u00f6lkerung der Schweiz, keine Ahnung\u00a0hat vom Islam?<\/strong><\/h2>\n<p>Ich glaube ein St\u00fcck weit, ja. Ich w\u00fcrde auch von einem starken Fehlen an Erfahrungen des Zusammenlebens mit Muslim*innen sprechen, wenn zum Beispiel angenommen wird, dass alle Muslim*innen gleich stark gl\u00e4ubig sind. Schwierig ist auch das Absprechen von Eigenkompetenz, wenn man etwa denkt, dass Muslim*innen keine eigene Entscheidungsverantwortung haben und blind das machen, was im Koran steht. Hin und wieder kommt es auch vor, dass es nicht an fehlender Sachkenntnis liegt, sondern an einer gewissen Haltung in der menschlichen Begegnung.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Wird mit dem Etikett \u00abIslam\u00bb viel zusammengefasst, was gar nicht zusammengeh\u00f6rt?<\/strong><\/h2>\n<p>Das ist ein grosses Problem in der Debatte. Islam ist zu einer Projektionsfl\u00e4che geworden, auf der man\u00a0 fassen kann, was man\u00a0will. Egal ob Migration, Kapitalismuskritik, Feminismus oder Fragen nach kulturellen Werten. Ausserdem ist der Islam auch ein politischer Treiber, der zur Profilierung genutzt wird. Bis in die 1900er Jahre war es die Migrationsthematik, damals sprach man vornehmlich von den \u00abJugos\u00bb. Jetzt haben wir mit dem Islam ein neues Etikett.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Sie haben von einer Projektionsfl\u00e4che f\u00fcr \u00c4ngste, Frust und gesellschaftliche Fragen gesprochen. In diesem Jahr wurde \u00fcber die Verh\u00fcllungs-Initiative abgestimmt. Auch das sorgte f\u00fcr emotionale Auseinandersetzungen. Wie k\u00f6nnte der Diskurs auf konstruktiver Ebene gef\u00fchrt werden?<\/strong><\/h2>\n<p>Ich war selbst stark in der medialen Debatte pr\u00e4sent. Auch bei mir machte sich eine Ern\u00fcchterung breit, weil die Diskussion kaum sachlich gef\u00fchrt wurde. Es gibt bei Streitfragen immer gute Argumente daf\u00fcr und dagegen, aber gewisse Sachst\u00e4nde wie dass es zum Beispiel bei der schweizer Burka-Initiative nicht darum gehen sollte zu beurteilen, was in Afghanistan oder Saudi-Arabien schief l\u00e4uft, sind nicht durchgedrungen. Der Konsens in unserer Gesellschaft ist ja, dass jede*r so leben kann, wie er oder sie will, solange man anderen damit nicht schadet. Was aber macht man jetzt mit jenen Frauen, die glaubhaft machen k\u00f6nnen, dass sie den Niqab freiwillig anziehen und kein Ehemann und keine Gruppe dahintersteht?<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Soll eine Organisation die muslimische Bev\u00f6lkerung in Zukunft medial vertreten?<\/strong><\/h2>\n<p>Die Beteiligung an der \u00f6ffentlichen Diskussion ist vielf\u00e4ltiger geworden und auch muslimische Stimmen werden st\u00e4rker wahrgenommen. Man sieht also, da passiert schon etwas. Viele Zeitungsredaktionen sind bem\u00fcht, muslimische Stimmen einzuholen, also bei muslimischen Gemeinden, Verb\u00e4nden und Organisationen, aber auch bei Einzelpersonen. Das ist gut, weil es gesellschaftliche Perspektiven auf Streitthemen breiter abbildet.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Wo sieht sich das Schweizerische Institut f\u00fcr Islam und Gesellschaft in dieser Debatte? Welche Rolle m\u00f6chte es einnehmen?<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>Das Institut ist eine Anlaufstelle f\u00fcr gesellschaftliche Fragen. Die Abstimmung zum Verh\u00fcllungs-Verbot war eine solche Frage, deswegen wurde unsere fachliche Expertise dazu auch angefragt. Es ist f\u00fcr die Aushandlung von Konflikten wichtig, dass auch solche Perspektiven, die noch nicht Eingang in den Diskurs gefunden haben, Raum erhalten. Viele muslimische Gemeinden haben keine professionelle Pressestelle. Wenn wir also die Sichtweise von Betroffenen erfahren und diese dann artikulieren k\u00f6nnen, sehe ich das als eine wichtige Aufgabe an. Uns erreichen aber auch Zuschriften aus der Schweizer Bev\u00f6lkerung, die sagen, der Islam generell mache ihnen Angst. Wir versuchen letztlich, unterschiedliche Stimmen zusammenzubringen und so eine Scharnierfunktion einzunehmen. Das Ph\u00e4nomen der \u00abEcho-Groups\u00bb, wo also jede Gruppe nur unter Gleichgesinnten argumentiert und sich best\u00e4rkt, m\u00f6chten wir aufbrechen.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_13187\" aria-describedby=\"caption-attachment-13187\" style=\"width: 464px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-13187\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/10\/Amir-Dziri.png\" alt=\"\" width=\"464\" height=\"381\" \/><figcaption id=\"caption-attachment-13187\" class=\"wp-caption-text\">Amir Dziri, Direktor des Schweizerischen Zentrum f\u00fcr Islam und Gesellschaft und Professor f\u00fcr Islamische Studien.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2><strong>Denken Sie, dass der \u00fcberwiegende Anteil der muslimischen Bev\u00f6lkerung in der Schweiz, welcher nicht Extrempositionen vertritt, sich vermehrt Geh\u00f6r verschaffen sollte?<\/strong><\/h2>\n<p>Das ist schwierig. 90% der muslimischen Bev\u00f6lkerung wollen eigentlich nur ihrer Arbeit nachgehen, ein Dach \u00fcber dem Kopf und eine Familie haben. Eben so leben, wie alle anderen auch. Diese Personen fragen sich also, warum sie sich abends nach sieben noch politisch engagieren m\u00fcssen, um zu verhindern, dass sie diskriminiert werden. Das soll nicht heissen, dass Engagement nicht wichtig sei. Aber es braucht auch den Einsatz der Privilegierten.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>W\u00fcrde also eine zentrale Organisation der muslimischen Bev\u00f6lkerung Druck von den Einzelnen nehmen?<\/strong><\/h2>\n<p>Das ist eine wichtige Frage. Das Problem ist nur: Die Organisation der muslimischen Religion ist historisch nicht von zentralen Strukturen gepr\u00e4gt, sondern funktioniert eher \u00fcber Diskurs und Kommunikation. Es gibt beispielsweise kein religi\u00f6ses Oberhaupt, das Dogmen festlegt. Ich denke es macht wenig Sinn, den Islam in einer einzigen Organisation b\u00fcndeln zu wollen &#8211; ich mag die Vielseitigkeit der Stimmen.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>Was genau verstehen Sie unter einem \u00abeurop\u00e4ischen Islam\u00bb?<\/strong><\/h2>\n<p>Man soll nicht mehr nur europ\u00e4isch oder muslimisch sein k\u00f6nnen. Solch unterschiedliche Identit\u00e4ten sollen sich nicht mehr ausschliessen. Allerdings wurde eine solche Opposition in den letzten Jahren stark medial konstruiert. Es geht darum, den Menschen die Perspektive zu bieten, dass sie unterschiedliche Merkmale ihrer Biografie zusammendenken k\u00f6nnen, ohne dabei auf etwas zu verzichten, das ihnen wichtig ist. Das ist die wichtigste Grundidee des europ\u00e4ischen Islams. Dazu geh\u00f6rt auch eine Gesamtgesellschaft, die das muslimisch sein nicht per se problematisiert, sondern zugesteht, dass es M\u00f6glichkeiten gibt, muslimisch und schweizerisch zu sein. Auf der anderen Seite soll man den muslimischen Gemeinden ein R\u00fcstzeug f\u00fcr die L\u00f6sung theologischer Grundfragen an die Hand geben, damit diese zu vereinbaren sind mit dem kulturellen Kontext, in dem sie leben.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Zu guter Letzt: Ist ihnen die Religion diesen ganzen Wirbel wert?<\/strong><\/h2>\n<p>Ein bisschen weniger Islam w\u00e4re manchmal vielleicht gut (lacht). Ich wollte mal einen Artikel dar\u00fcber schreiben, was passiert, wenn gerade mal keine Islamdebatte herrscht. Einerseits sind solche Kontroversen berechtigt. Manche Religionsforscherinnen sagen, dass sich seit Luther keine neue Religion mehr institutionalisiert hat in Europa. Das hat also durchaus historische Bedeutung. Andererseits w\u00fcnscht man sich, dass nicht alles so heiss gekocht wird und Religion im Allgemeinen auch einmal entspannter angegangen werden w\u00fcrde. Europa wandelt sich immer mehr zu einer areligi\u00f6sen Gesellschaft. Da ist es angemessen, die Frage zu stellen, welchen Platz Religion in einer s\u00e4kularen Gesellschaft in Zukunft haben kann \u2013 und die ist nicht einfach zu l\u00f6sen.<\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>Schweizerisches Institut f\u00fcr Islam und Gesellschaft (SZIG):<\/strong><\/p>\n<p>Das interfakult\u00e4re Institut, welches 2015 gegr\u00fcndet wurde, f\u00f6rdert die Auseinandersetzung mit dem Islam im Kontext der Schweiz. Es arbeitet an der Schnittstelle von Gesellschaft, Wissenschaft und Religion und erm\u00f6glicht eine akademische Auseinandersetzung mit gesellschaftlichen Fragen aus muslimischer Perspektive.<\/p>\n<p>Das Zentrum bietet Raum f\u00fcr den Dialog und leistet somit einen Beitrag zum Zusammenleben in einer pluralistischen Gesellschaft. Im Rahmen der Philosophischen Fakult\u00e4t bietet es das interdisziplin\u00e4re Masterprogramm \u00abIslam und Gesellschaft\u00bb an.<\/p>\n<h3><\/h3>\n<h3 style=\"text-align: right;\">Text: Matthias Venetz \/ Corina D\u00fcrr<br \/>\nFoto: Corina D\u00fcrr<\/h3>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQ2tDABAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"O7TaszgnMVchs7hEoapUITUzL7VIIaAoPys1uyQzP684LefwkuSMVIX01PL8opTUvEO7AQ==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DczbDYAwCAXQiZDqp9uYerVoXwEaE6fXM8BJ7t1WZvOxo\/o0qhw6xcTWEV1H4R28hGXmObBY3gqJOb2DIBVKXduF26VVO\/KGmEAnnqZ\/xh8=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"800sKcnITCxWCEvNSy2pAgA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtQ1NNA1slQwMrAyNLAytQAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"pVrNchvH1d3nKbqQSipJgaAo50scmmKKCilZkhWzTMeq0ibVABozLcwPvu4eQsYqi7xBXsAL7rzXxl4Rb5InyTm3uwcDkZJSlRWJwXT3\/T333Ns4KR+eXthGPTV+5bY3s1LVNqiz2jp1vrHOnhzihV+crE5\/3Uz96ouTwxU+lUen59aos6kPtq67pjCNsrW6Nq7Q\/ICPT9z25\/KNLp0q9RSfC7MxtgjH6tvS1PjsumauulrN8f8zX+laTY2fldubRbDcjl\/Pcca5meoQ8GCuN51aG8cFpQ0bW2DPBQ5xYaJOTH16tTKz4Lr65BAfcGp4T5MxzqrVuXVmGVqHD15dzcq1sRvjLI7Gvq9Nwx0UtnVJKsoB25iqwit6EcZq+\/PUOKWXocNDo160WNNCdZ+k3v6zKXwwkA4WbWVfPoawThdY307VN6ayhW0bZSxt5dtKXntl3dRUVDIob+wEtj+6a\/uHpyceJzbF6VA3ChAMd7mC1Wi5M4qhrkXVOmrz55PDtDS7Vc0q7f2j0dy1q5leqfT3YNrC0M6PTp\/rsdJU2CI0ikp3UzOOvihMuX3ncGBtSmccDvQrmNZM1Ln2qtIByold1V9KGBg+DF20J3ZWdecrW8fvv3YWX6ZA8Two2vg5wqfEAtjDwOfN2hSqXYRaV14hZM+mBY7fIPzUpsNhmm9i8wXONYwKxKjnQg9\/x5MunG0a47hkbd0SZ+JNRJ6dw94IPNXoWTlRZ533jLRaQWw6mTLhRMZeH5AL4wNN4T2EWpiGgofK8piX1nsftjcQiMsGujZ7wcSwlnhUulsMUoEK\/s15zb02HTJptsyxnlJgoi68Kuw0JFN5MyuZEgyDGZTCK2bPxl+JNC45s9aNasXqVoKt18+p2x9FhnlU8\/YnHGhDwciaKx1N8FdT6GCvYTa\/sqaiNGeQn8Hs5HXDsLiYUoboVBhbOaNjuiwqizCRBHzdeV0DDiqDt\/xEfUl34LCg8KVES8gKRcsuuyp0TnzyCpIjusVDAkFjCXsnubV958fKhFIiULVUrF8KfxewKcxBzZt5DFj+x+iCHQBqRgLV06vTodRj6Mdkxd5rLeddmbedrurW6Sqe800L6ZqpreYSWsEZRsdEXUmWDwyAtK8YAuKRhtGjCsKi396EDdWVOOBBPpscViHAekn0GAlj7EPPNvFtePHStRvj\/VjcKa6tYI4EQ8tqe0Pv4A9CdKJe6iYJQpNjizaJcs2s6xamalKQv4QxJIIzwIlroVdAoMCZ3jS9SvS3bfygqixb+nkSMeyDiPZi+65pkigdViEr8\/G0tUh2MAzrx+Z6+65axpSmvgnSx2rJcFRnZYNvbn9gObhuPwiDp896dBMTXgXmnMTyWL3RE8Xv16gKSGgR7DqBNxFCuyULnikrOhOB7xYArlgV7wa5VKWXosLvCEYw2soZGpax1TRI+BpqxdQSbzdiOtp0nmyhGf97exSVoaNFGHzY3nRToEGMbpoEeYXPQMIoPnZh9U4HizYXLLvw0srAgZskC3EiRjq+y2i3d3A0s+FiwGsT6BU7h\/IeAaSbsG5doG8iDjACpxUzjRLUOqmN\/0EfXiCHGiJuGYgE8e01scxJ+IQ+LJD2SRY8ieGqCcj0gAQBNoZPmoD0V5U1LLt9ljQJqAqzthK0X+pKREwAWEucC9w0cERhCobQpyIXtXsurmXVuAh2aULIWAoQvaYzNykQgOWQPUTFC52Tf\/c1C2u4J0qJU\/QhQ7RwLaT3zHYgVJ2lT+VpkioJ30atjhrj1TcoNiAeflExK0lS1m1EkViBpDTc\/qAoIL2rm+Qfeby2VYXKUxDqpqhyhdPcbaxe6JUNurIeubl0qKTLMRKiJgHAk4iLT0B\/sCUr7ADGG8HxWEJy0aXQXJGKIT1OjVdthZ0ZYE5964ydspzxPZRI6rawcLUAAc7pwiZIykzUYyt0gQBy9KcHDxKxMFDLMX74vFfFB9BTLfLPtRANJAklZiYg7BpT1gLNTBnWwtsfn3dF629\/mqjnhmfuCl6OhqgGNWhMhwNTdHwqosjj4mYZbO71oHDVBMkwuutgvMg3dzwj1s7kgB0vRZCIWTyEpEnUuiPARUZBs3xnXLn9WcqrP3jWwPpShFCxsAmpf6DbEp741hUhyWPqlkKy4MOtmZt5GEhgcQKqi1qewF7C1vpl57xE4ZJucN2SR7lEI96jPx9AcHoUWqMtSUjYp\/Tc6mpH3hSLEuI7iw8mo8ilCUgszDZGHPlig0KAZxJWUyf1AFWhir0JhfaeRH6pgdokbBIcO2lp0B1X4zlXgbssoi9gQiJRh0PPXNEh+WkPLTYUpoy3hNkIR0iIJfCW6eWabD8h4V7l4FlCAHKPox53bqmHboywM9dseYThZSYAxJiaDmlpqx6fwbcXRamR0YHkMcJsN7cHZ05PLdeSpi1ILDq2ScKn0gmdm5WFmbvk\/HOsBQ0iu1IC88h7PBoyY8GANzqh\/BvUgN9BlVZJDc2wBNWxrI00h6aoKuJ8xaIpCStRJ70jczEKw\/3B\/BCC0CqRYT7n+28kg\/num9TE6i7zSmEHIlosWzF8TaYnFEC4sf1\/PVUL+JjioObqZmNNbgJZLdUFIabZPTDqqetWK\/oRTU6IjRzh\/+PwAFfFIP2aXbf1gl8i6gcJEg5\/3S27hkpISgjLc6z491Uby+UMAltwtY7JtH1HPhtSgRzkAF3GOrfY3lRs4l1fXURVwfGhaFdEkJ7HKkY0mBRQCFCUWU8iqJYtAckpra1WMHjsW2ZlGwkKeofv2Iqghbcs5t6ZuRaglJaStMPUyEkE5n0iwI6brmwl2oUDCyLst201XpJKCVScSvJFvYbm71NVZ1i5wM6mWsGp\/Da2GjQUcj4hCRL3LlZfYgG7aaRpI6AYYSPE4YkAEU+ZSpvxyVLyqk0mFGQjWO9PPlAHAOehCx+bfKQa6nck48+o3dLTSMuj6u07gU8jbQgr5b1hNZQxUpr+9MRtOLtAti1S8y0yfaicSZc\/mEQJCO7VLbqrDbHac+84bYnLyR\/8mhCbal\/EItCfxADVxVv4DqzDxKGH+JX4IsMcQXYKLSLK0KXzwMg5T5ay3Xd7pASwji0yhZf2JooydHYEmwb1OeEVAohDtX78kAolJOgkBIUijNU3LEBQW1dCpmIyDEO9D+BEKiLygAksjKSvmPrSsY+LdgdCsgUgk5GUkGaXIiFwYA5qB3RwMvtgCknXs5vcicWwXsN6oHtWgLjHTHawKgdjalxNNhHNuCggJSw9UX9DlTDOmYg3u+xCWzUrnZUpigbJHHR\/LHYD3Is29TrOCHpiyZZF5gEC6MqWVEOmZuQnTmYpnRxasS4wHsZ3JxIZQjJ733RTZ5s8woTdRDMIph3HUvCawFKEnJgkERUuS4BKW5s8hrkAuB08dW23ArsEVrTRDayFuWA0nYsCqafS\/yFJLCkVrR7ZhMCkCGIFkCLIEgVjsib\/dotpbAXvRZIF8B9JYeePRkh7GIs7\/\/3os6PP\/zjCSVYfIItmDoR8Pv3+0WimV9TwYPfuQXrXh+8r82i0tvNQHqvf\/+H3q7ejPIFcrw7SQuhpi6ZBSI5OT2xdqKrVc5j00ajSm+9HMM+sjZ+1\/76Z9Tt4OP5g0cGh2MvWcHd\/rps9GpUhrPzxIfCom5P6dY1duMmsPPRpcHxIEVqaLxx2Kx7qDx8+eHh0ePTgkKPWAxm1TlZNAa2r8Gg0UqLJoxE0GSn0vUWJp599fjRSh6e0WlaIlvuwVe4Y4CCYt2G0N979X8fW8uAyJjt22b2Z6yCYnHh\/J\/WpfIDjP1ZZzk2zjDPnPKYhQ2ADAXZWsBtHRgUhzPtD3+YOM9mb3sQpW+6ML96i+tWr1ttU0YW2oByOY1zjI4fQASqzdU5TUE1kSpT2I820z+ORifrTg199Qs61DPfivEMQQXLQcgAOBo+CH6TBFTY9lp7vXPfzbDaDL9rVQpwhsPAEDqhsP0q7kAF4YrmR4MqoJ\/NY4l4ea18mSqFSK+HTwLAlX2c0kJHGh9hs7mPjjYc8Q+pL308rgxJTRIQGSWLnP+b0FfUOliytDE6GPNeyya\/jmL0fSMsQlaQ0+gzpEDeSZRc8gdwl0\/AE9XLPgfJtpBWfOmqYZ1ScIdsGxGojTrl09hr9COUMn54kvkrDuioj8IZJwoZ0ny5\/1Nvnrpst+1Y\/Ujma\/IPcZjCgGVQzoRoJ5PO0Bi8hco6FvXxcov6yiGt2lxl5TIsvsmqcW7Jv7py0+Wxyh5OvXHrEa6bMidpTCkbli5Ysyi5Flr3GVbpKH2u\/tDH9oB2O+3pK6tGt4ohQnbdFnW5I4LAQx6ccIQo5jP3W2jRw\/5VtpCbnmw+bJx0sj3IRuGecqYztK1bbnIq\/\/uXnD4+OvhAyAcyPcwuKKhc6S2PjLCmV6T5scpzc\/jDw4vsxxPGcaXT33u1aLLlx\/Hv7IxrldrW9Sd5KA797YiNP2pPjCFgCHoP1sZfdeV\/m35k0pRuEuwzkGcuZRWEPCe4yGgwOAkGSoaaM6ZFweMmxhvrEe4fM+OtVRtpMOoX\/4O\/zyPDibCV1kGlaE2\/cGC8mzxSiX\/trAzpmwHRlyGDZeg6Q5Y5uL41b1szaCLGPbVs4vbCmp1vzWIB6YtmCxWE\/tl5sm+LtSQSyjRXGE0M0sr2MQpacLyfv3Pa5y2uOp7yTsXMTb6zu8bbn0v5CNPQDS3JuCBmKvevjeRzY3PFydNZK7vJIywkTCHppdHc5vOk4eTNl2M2\/X27fFTQWQ515j3wdNrmR\/Q0ZA83BI+OtHSMu15crbhGDtE53ffc3wVLZvkGpCBvTFbv25yvAAYETfWpbtUUa1ooFU5nSMRC+1DKinEZ3yKRUqlr0FHafapc79zxHHQ6NeesOkjSOERqLnVTNT9WF152M25z6ijF9DA+GFAsUq8dakQbG1ID8vYv5exKbP5+YWh9NJLDWtxhrXrbRlmB8nLZYSh9v+tDu\/qYiEv423S7F0Rtfi78KOGPjhFORS+mOF+0Op95pIpenIOmqBofqeVwfW7vhNS6qsWNeMUUJrwTHdOXp+2vJ3c8YcJqR+I8XhNLiJ8v4RevEq+nuKjVVMYFjLAf1VRfo9ygHh947wwoa2dTwy4g4hrj8YIPDMeaXjsnIR7H15ACRPd7wLv8xGqGOsx7EscRv0mqNGuHzRM9L0ybipXsiOIA8JfITWG3ZRjri5pIpu2pbEyULifhEvegY8U8T\/Eo3UgU4C4g\/eslzrHhNOEmawFWsWPmOXea9YoP+VkbvCun+rwNohMgm4q1vbRKhsolSSCJLr95kxtyoy4qEaadGLqh+e4MEkqx6f6qTZ4JpMMCu\/d\/\/+Ff\/ExzhKmI87MTJCM+NV8r3Z5tD+zOssfv9iv\/vpk2\/uXr97Olvj9+rzoli0fQLTUCQBMsbZit49fDB0f\/Buf09v1S5MQ58x9+1hDyree9m4r0rG7mTFJwZNidS5bRwfRPyUBTfNehH0sSKpGz\/R0OvhAwPerHeQdILuDqBeKKOeolcTr3ZB8S8MxBr8gUPE2UA225YdSdDM+a+UcpwiCOkCOUyaNJAcBEPkOX5gm95cMyHx1Afx8m4be+Cexdxq6pzTO9wzy9fgHk1DizzuOOytFXr21WZ3n2SnBuycLyoy55H\/7Gxq8o24vyXGsI5VEwwg7rOd653Aur2J06TUoR+RvT+TP7LQwm6+UAmD8fKsZP\/YnT6LZ4d44AQSovDvzMNHKAO1V+AQY1W57CVO5lKuD9pQ3u8\/4Wc8B8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Ein Gespr\u00e4ch mit Amir Dziri &nbsp; Die Abstimmungen im vergangenen Fr\u00fchjahr haben gezeigt: Themen rund um den Islam besch\u00e4ftigen und die Debatten dazu werden&hellip;<\/div>\n","protected":false},"author":124,"featured_media":13190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[891,1230],"tags":[1365,2310,2311],"class_list":["post-13184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","category-interview-de","tag-islam","tag-religion-de","tag-schweiz-de"],"views":1098,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/13184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/124"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=13184"}],"version-history":[{"count":4,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/13184\/revisions"}],"predecessor-version":[{"id":13186,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/13184\/revisions\/13186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/13190"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=13184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=13184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=13184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}