{"id":13581,"date":"2022-03-03T16:01:02","date_gmt":"2022-03-03T15:01:02","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=13581"},"modified":"2022-03-06T20:58:06","modified_gmt":"2022-03-06T19:58:06","slug":"friede-freude-magische-kerze","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2022\/03\/friede-freude-magische-kerze\/","title":{"rendered":"Friede, Freude, magische Kerze"},"content":{"rendered":"<p class=\"dropcap dropcap-borders\"><em>Disneys<\/em> neuster Animationsfilm, <em>Encanto<\/em>, startete am 25. November 2021 in den Schweizer Kinos. Der bunte Streifen, dessen Titel \u00fcbrigens so etwas wie Charme oder Verzauberung bedeutet, erz\u00e4hlt die Geschichte von Mirabel und ihrer zauberhaften Familie Madrigal. Mirabel ist das einzige Mitglied der kolumbianischen Familie, welches als Kind keine \u00fcbernat\u00fcrlichen Kr\u00e4fte erhielt. Die Familie ist n\u00e4mlich im Besitz einer magischen Kerze, dem <em>Encanto<\/em>, welcher seit Generationen jedem Familienmitglied eine magische F\u00e4higkeit verleiht. Mirabel ist jedoch auch die Einzige, die bemerkt, dass sich dem Haus der fantastischen Familie ein Ungl\u00fcck n\u00e4hert. Sie versucht tatkr\u00e4ftig, das Mysterium herauszufinden und abzuwenden.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Encanto<\/em> pr\u00e4sentiert sich wie jeder klassischer <em>Disney<\/em> Film: Wir werden mit viel Farbe, Emotion und Musik in die Welt der Figuren eingef\u00fchrt. Passend zur kulturellen Darstellung einer kleinen kolumbianischen Stadt wird moderne Musik mit lateinamerikanischen Rhythmen kombiniert, die wie immer zum Mitsingen und Tanzen animiert. Die gro\u00dfe St\u00e4rke dieses Animationsfilms liegt im Versuch, lateinamerikanische Kultur, Geschichte und gleichzeitig erfrischend neue Figuren darzustellen: eine Familie voller starker, magischer Frauen. Die Geschichte stellt eine neue Art von Konflikt dar, bei dem kein b\u00f6ser, von aussen kommender Feind bek\u00e4mpft wird. Der Feind der Harmonie ist diesmal, auf realistische Weise, die Kommunikation und Erwartungshaltung innerhalb der Familie. Sie gef\u00e4hrdet diese den Zauber der gesamten Gemeinschaft.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Encantos<\/em> Konzept und Umsetzung machen Spa\u00df und unterhalten nicht nur Kinder, jedoch finden sich auch Aspekte, die meiner Verzauberung im Weg standen. Die Familie besteht aus unz\u00e4hligen Figuren mit verschiedenen Kr\u00e4ften, von denen einige kaum zur Geschichte und eher zu Verwirrung beitragen und einige Handlungsl\u00fccken und ein gehetztes Tempo offenlegen. Der H\u00f6hepunkt der Geschichte kommt fast am Ende des Films und ist ziemlich voraussehbar, weswegen er etwas weniger aufregend und \u00fcberzeugend wirkt. Vor allem wenn man an die allumfassenden und aufregenden Geschehnisse in anderen Filmen wie <em>Moana<\/em>, <em>Tangled<\/em> oder <em>Frozen<\/em> zur\u00fcckdenkt. Hier wird der realistische Konflikt der Spannung zum Verh\u00e4ngnis.<\/p>\n<p>&nbsp;<\/p>\n<p>Alles in allem ist <em>Encanto<\/em> ein Disneyfilm, der vor allem von der fantastischen Animation und der sympathischen Protagonistin lebt, den man sich jedoch seit dem 24. Dezember auch gerne auf Disney+ von zu Hause aus anschauen kann.<\/p>\n<h3 style=\"text-align: right;\">Text: Mara Wehofsky<\/h3>\n<hr \/>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13582 alignleft\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/03\/poster-large-405x600.jpg\" alt=\"\" width=\"245\" height=\"363\" \/>Titel:<\/strong> Encanto<\/p>\n<p><strong>Regisseur: <\/strong>Jared Bush und Byron Howard<\/p>\n<p><strong>Jahr:<\/strong> 2021<\/p>\n<p><strong>Cast:<\/strong> Stephanie Beatriz, Maria Cecilia Botero, John Leguizamo, Jessica Darrow, Diane Guerrero, Angie Cepeda, Wilmer Valderrama, Carolina Gaitan, Mauro Castillo, Adassa, Rhenzy Feliz, Ravi Cabot-Conyers<\/p>\n<p><strong>Dauer:<\/strong> 109 min<\/p>\n<p><strong>Streaming:<\/strong> Disney+<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQ2tTAEAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"cyvKTE1J1VFwK0otBdG5iemZxckZqQreqUVVqQA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcpBDoAgDATAF8ESvPkbUxYhBkLacvH1Oudp7stOwHwXTo979qpRGmxRXPdAIXLKGelA1c7CUJV\/DuO6u0ljeKgv8QE=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"800sSlQIT83ITyvOrgQA\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtI1MAYiBUMzKwNjKwMjAA==\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"hVfLctw2ELznK1B7yCUrrSzZrkSRVCXJklVWlEpZjl2VG7icJRDiwQJArZc\/44u+ISff9sfSA3BXDzuVi1ckB\/Po6emBjzoxNzLG40kdfDeXnRh\/dyofagpxcnJE9uSNjo5W8WiGv4WjPiYK4tRpK5P2Li60sVPBhhduLl3y2XAqYpIhUSIhrdh\/tSt+93dkKxzd39t\/IbQTNTlxO1dL0gPeXmvn4654gz+r3uHYbQqkF+SmMIwRth90IiPWX6ugG3JRRC8oLWUUS03iXMlgSXikLT5SGGSPUL1rREU19chjKvB2fa9MEjXs31KcKz1XCHTnnbjRQVbw3rtaaBXgpHhQcpEQ+lJabXDqRtYILs3u9oCO8IccSLsBaeF9amBZC06k9aa3lZZOI9iDm6lYksGLKKSJXHgtWpwnro2Ck2n9NRidT1yH9T0yQO5Kk0nAB1lssuHYbn1v2VZoK84o6jRwKohtZTNGvUbhxCja73SpZBJEJJ0ACk7mruLY38QnxljOburKiW6ci0sgqpuWD99RMKRVeooNvHhkJ3v8w7hfFJym+aEiS6FFa4Ag+sllcMwr2ceM3wKJypieoscZiD9dY9Zf5y3Xj\/QR9BZfkEJEoCSSTG1GTjfZubhZMWt1bwWs4X7oF4AdTrnhshr6JfHj7tGsO\/nhqDv50VWx+3Xz9Bw20cE5KJk0Qpe8mYOMGJrOI5VTDuJhfMq5S8zKofikA3APHN4ycOgsigsVULmwnuHPad30Ubd5UOD7EzFx4fJSN33ASaDQ0GL9VXHxf0iekFoMPeL3JsHCGBi9kQF1G8ODUGjRGv5131DzNsk6oYpQC8tDhCaX+JyhkQmnJJql2+2J92qVlM2u4MgxFKWrDIW2lmcIeGMgIqdaavog3YA\/4cTq3DbmcxP8+gsP\/Po+tMQ+ImbjqcJEgdY3iWn+sXR5+r20xHWufvp4vjlug7LnagBPNZAIi1CKqFnPaItpLcPQZ8DIHRamb0h35\/EyZFFrCf43E4CGgE9gTq7kUdTsJhUnOcgpqMJSc+3dwuiWZQN+KtKZ8ywAolr\/E9k5m4GksYBrmZqIQywUFbWY+G5RelX0snxhmyuIoHejNDCOVpopXC1EIGn0OEogk47jCF7Df++A35Z2F2EJ4QZjopKGf0FBx0poqkLAgkiZOKbgvQKVSzjKov5Xls5s3FCUlhX0LUZdO0SHoP7\/lI3LBlAN1KWc1p82Uho4HSsLYzu5\/pI\/8brg\/DiOY\/SF6\/NCqRnMUYHGec\/DmtXoNHbUphEGW6bjyeYA1T5Rwy3P0vBEeitCfxGIlap3ea\/wUtoyyRZBZDZAFNyDkrvS3fIOQXlntBJzwqP7jLSk8gxxVmj2uM10CnIzTeP5KyTIIx6zJD58A\/oKmCUM0weynRd+gX1qqMnVMF3W\/yjqetcWaXkUnmmXoL+gEdb3BQDgLZz1K5YliS+DprJ77nzIdFUVU3pJcckxMGebBU2cZ2AiBv5SZxd52w3U5xcosIUcfPSwwqRZPgMYJWtF7hDe9nZRdG6j2xt3mV\/MbAUVAAk1n0JFuSGGNYo1ifl146WT4+rjZ+gRpKEudMuXB357GTxUqrxEXxhVxOD8rqBaRSXZ9slQPcw1voCcznHDWALRP7W+dw2S+w\/qn6LkmNPOtTO43+wcbmjZJeXGxWHutnAVUj1fmVsNzXjx97iynUxq\/P5H8Ek2UAyccMJQxRJOBfc8KePw5NsBy9T+S2bOUC5yeYyavCtYYkpyP+VUwFre4pQHROa571nNgMoIgTrAZK0MHU8SfU47ALKB5uJ2pdKvk5MPeHeI61aQmEHlF7HFBlUHfC6IWZGLmIJ3zcmRto0wXtbYMscTI4fVBKnOfXmWceXmk809Vyy7HSDS0M6Lg1c\/74sc1dAiTUQM8+OJSqmLh7NZTD1gSLtQxkXYnasZtGKeQm9ncDD30BuXZn3HUeMM99n92d7BrPN8x9gxMsD\/y71Xn1\/v7e3+3TUThEnHEwTXdVLHk\/2Xrya4hnClx5OD1wcTFJTvtodHs7Emse1896TW99QwwftwKLa272TAteysjyo3+WyFt+LKQ8Tr58ffSRUeBeGL+HOTc5Dnkcltok5J3ihnJFPQw5SboqU4pzmEUIozj5r9VLzzyonfqOn1IC0\/486u55JvIMEvpyCHBE3e9hRCtj91Dd\/aqaNaTnEjMnxf+CgNOBqkxatzGbzBdhdvpYYCc9w+eMH5aWPYA18aYfgeRB5WWIKGs3sv7zSMKp92zr1bQYKfV\/gGTHyMwou9XyDX7rkZ\/\/cDYu+aR6Yjw7Ppvw==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Disneys neuster Animationsfilm, Encanto, startete am 25. November 2021 in den Schweizer Kinos. Der bunte Streifen, dessen Titel \u00fcbrigens so etwas wie Charme oder&hellip;<\/div>\n","protected":false},"author":160,"featured_media":13582,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[130],"tags":[2381,2380],"class_list":["post-13581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kritik","tag-film-de","tag-kritik"],"views":1151,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/13581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/160"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=13581"}],"version-history":[{"count":4,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/13581\/revisions"}],"predecessor-version":[{"id":13591,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/13581\/revisions\/13591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/13582"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=13581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=13581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=13581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}