{"id":14487,"date":"2022-12-07T13:16:55","date_gmt":"2022-12-07T12:16:55","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=14487"},"modified":"2022-12-07T13:16:55","modified_gmt":"2022-12-07T12:16:55","slug":"sci-fi-im-waschsalon","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2022\/12\/sci-fi-im-waschsalon\/","title":{"rendered":"Sci-Fi im Waschsalon"},"content":{"rendered":"<p class=\"dropcap dropcap-borders\" style=\"font-weight: 400;\">Bitte einen Bagel mit allem: Sesam, Mohn und eine grosse Portion Absurdit\u00e4t. Der US Indie-Film <em>Everything Everywhere All at Once<\/em> bietet wirklich (fast) alles. Was wie ein Familiendrama beginnt, verwandelt sich rasch in ein Science-Fiction Abenteuer. Oder doch in ein philosophisches Gedankenexperiment? Der Hauptdarstellerin Michelle Yeoh gelingt es spielerisch, das Skurrile und Fantastische mit dem Ernsten und Tragischen zu verbinden. Sie spielt Evelyn Wang, deren Waschsalon die Zwangsversteigerung droht. W\u00e4hrend sie bei der Steuerbeh\u00f6rde ihre Steuerabz\u00fcge rechtfertigen muss, versucht ihr Mann Waymond, ihr von den Scheidungspapieren zu erz\u00e4hlen.<\/p>\n<p style=\"font-weight: 400;\">In diesem angespannten Moment taucht Waymonds Doppelg\u00e4nger aus einer anderen Dimension auf. Er erkl\u00e4rt Evelyn, dass eine b\u00f6se Macht namens Jobu Tupaki alle Paralleluniversen bedroht. Evelyn sei die Einzige, die es mit Jobu Tupaki aufnehmen k\u00f6nne. Daf\u00fcr muss sie aber m\u00f6glichst schnell lernen, wie sie zwischen den Universen hin und her springen kann. Da es eine unendliche Anzahl Universen gibt, gibt es auch eine unendliche Vielfalt an Evelyns. Deren Eigenschaften muss sie sich nun zunutze machen, wenn sie nicht nur das \u00dcberleben ihres Waschsalons und ihrer Familie sichern will, sondern das des gesamten Multiversums.<\/p>\n<p style=\"font-weight: 400;\">In Evelyns Kampf gegen Jobu Tupakis Zerst\u00f6rungswut muss Evelyn ihre Entscheidungen konfrontieren. Wenn sie nicht mit Waymond in die USA ausgewandert w\u00e4re, w\u00e4re sie eine ber\u00fchmte Kung-Fu Meisterin geworden, in einem anderen Leben eine S\u00e4ngerin, eine K\u00f6chin oder eine Putzfrau. In diesem Prozess lernt sie nicht nur sich selbst, sondern auch ihre Tochter und Waymond neu kennen. Ist er vielleicht gar nicht so albern, wie sie immer gedacht hat? Vor allem stellt sich die Frage: Wenn alles auch anders h\u00e4tte kommen k\u00f6nnen, wieso kam es dann so?<\/p>\n<p><span style=\"font-weight: 400;\">Dieser Film \u00fcberzeugt mit seinem Dialog, den Special-Effects und Kost\u00fcmen. Immer wieder schwankt er zwischen ernst und komisch hin und her. Obwohl die Handlung manchmal v\u00f6llig absurd wirkt (z.B. als Evelyn versehentlich in einem Universum landet, in dem Menschen Hot-Dogs statt Finger haben), bleibt sie doch in sich geschlossen. Wer die erste Viertelstunde des Films aush\u00e4lt, in der scheinbar nichts Sinn ergibt, wird mit ganz grossem Kino belohnt, das noch lange nach dem Abspann nachklingt.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: right;\">Text: Alyna Reading<\/h3>\n<hr \/>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14488 alignleft\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/12\/Everything_Everywhere-424x600.jpg\" alt=\"\" width=\"322\" height=\"456\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/12\/Everything_Everywhere-424x600.jpg 424w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/12\/Everything_Everywhere-848x1200.jpg 848w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/12\/Everything_Everywhere-768x1086.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/12\/Everything_Everywhere-1086x1536.jpg 1086w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/12\/Everything_Everywhere-530x750.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/12\/Everything_Everywhere.jpg 1131w\" sizes=\"auto, (max-width: 322px) 100vw, 322px\" \/>Everything Everywhere all at once<\/h2>\n<p><strong>Regie<\/strong>: Dan Kwan &amp; Daniel Scheinert<\/p>\n<p><strong>Darsteller<\/strong>: Michelle Yeoh, Ke Huy Quan, Stephanie Hsu, Jaime Lee Curties, James Hong<\/p>\n<p><strong>Jahr<\/strong>: 2022<\/p>\n<p><strong>Dauer<\/strong>: 139 min<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2>Trailer<\/h2>\n<div class=\"embed embed-responsive embed-responsive-16by9\"><iframe loading=\"lazy\" title=\"Everything Everywhere All At Once | Official Trailer HD | A24\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/wxN1T1uxQ2g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQxsTAHAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"C07O1HXLVMjMVQhPLE7OKE7Myc8DAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcHRDcAgCAXAifS1fHYbgxpJKhqBdP3eDfdtD2AetannUOkn84Dtxn5iojbQRYSbYCypS5KZvmI8rLxL8QM=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c8ypzEtUCEpNTMnMSwcA\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtI1NNI1MFcwNLYyNLIyNQUA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"tVfJctw4Er33V2TUocOOqF2L1doc8kga2RqN3S25O7ovHSgSRWKKBBgAqFpiPmWO\/gaddKsfm5dJlha7xzEXXapIEMjl5csFhxUlhQrhqJN6VyWqova\/N3E+1T50KMRloY86U2djb65Nlsd92h4ODzrH70yMmrSx2tI7lemCShNJFYUu9+laB1V26crllmqbyjbKvAtB0yfno3GWTiah9qmJ6y+xT6fa0+drem9To3vnpijpUJfHZ7faL2NubEbyOM+113RSFKQifbSJPhxgF02MjjrS3PhZYZKcXk1ViK\/FltCn31TAJzGVzlVpCqNt6lWpaKIzY23sEmTPlU11ESmwAK8CfrGfz1wnOJCwVUlrt7ZR19r36SNAotQ97q1yU7jg8AcBOtDfdarsTFu9qLQ3JQ6+FVcvVF3FVPkQNYz0OHkFvfxMv2uXE+CE05EgIlRG8xYI7FIKX65ntfcGOxnYc2UjnBV1EoBUl3TmLQQ3yN94lclXS6uaHZ0YOGr7dA1IRHZkbIulBVA2gwpAzM84E1QBfxER+gPwZAGnIddk2teICLiSI3K\/rb\/kOJECOQ1EDQugawFoovP1HYhEBjvaNTVZre8zTV4neZxqUCGDurIOQcIQaizzfrpSls1Yls6mXVm5ZWM0ByTXJoUJoVJwwDeuab+CJQVcOxxUxz8cVt\/h7nvxKgAquKUhBiyAlCvHEaKoxIhWd6BTV1W6yNZfsNeTqoPQGU+2weqUAxuYGqqe9oE+bJkV6y9+g6zErTlFk\/UdcuBKsQar+CB9cJOabupKzYxwlj4pz\/9FbQ1DAhUT3aLdhiowzsD7zNgVAOzKC8jCDHgmrp5anUMLzdZ31mokmpqu770ALhFTE3hSru8yzpwA\/ie5BQ8JlENmdyVzeN9q3rKII\/D5wTDkptAMiQk2gcgczRnwZE1skThdQ1TKCpC8dqXy4omEzEyQgfzL2xn6b878CpZOFYiqbAtAkIqB02dMHximprGlkVgrWWxrJoat4wqpodh4uKPBKt5hjUSg9pJT6\/8AhkIjs4Wr4Qn\/g\/jHq35TPkQ88AE4RdGl4JgIVgSlOJtx8RM+1UUUN+sy\/H+sbL2jS1VWUwhiNJ\/EM9AfnIJIKmb\/vI6Nxy0pJMvObAyb\/OBQODv1UCVpgmR97j7TpaU5VzAm0efrE6Z4pqUggsJzEBkEkz852tBY+\/V9Di\/pEop65zVdaYPiwKUMZ7l9AO2mKkqaNanyD4FYJFw3+WSwTd4v13cJs8lx\/ZCVT4jc1Ku6T4\/5+sm7lYbLTM\/4VSAl6EEXkxAfgyKEEmRuUKdhoIRz47TVNaE8W8bmPdiPz7eGy7AIzZRvxQeHzITPTxLClCV2ZyjwvCFXqOy\/Ot80QJK63jYTRvUcVVjvN\/BLW2rsElgC5WiBQHLmysdMbTRB70yVnBgpl8Pg3rY0Oj7kqvUdMp0yXmAst9L1PUxf6TprIh6amJwa0FsKPkpqpRO89s6mU53EhvKXDky7LwUa8RX2cGxAL3BjJmA9VAXNLUeOwQtee1oZ0Cgnc4esZygu4HTB\/aNUNslLVdDt+q4oTIZSxAOBtPFIr1b9d31g9cBuKRdQFaXFPzCrLSR1SQWjGYV03ASvpC7AtAsXe6cuQ2GIKkYgImU8R+Gzr7s0QawnDZM2jVyihiRO8oIHFkkb31RY7n9cjjziGyLc05LxjDKHNCCSxcYEQQpGTjYsQuvGuAEhTcmDn6nEI1N21Q5HJV0a65BdBSan2PR7y2YV3KjQMJhP2IXZiZuWLMxkVEB94aXjDT9+tNhy0LzlWxuiRL2IPQWw7T55pguYcoO1fQxVS6voF61SSDsc5Ft8ztOA\/8bHh6bMqHDy8ahTqNWyAzsS17yrsLRJZzNL0rzqmRJ87422t\/f2SNQVehoxTfrkqJPHWIX9wQD4gXqxjy439f0kh\/3gnq\/LAQQkjjtyHNQVaw2D8XA8HozGg8eJ8M\/HibC3Pd5e7A6H\/X9VWQf64lEHVpg05kedrfG4Aw6yr0ed7Z1dMSLo+NJ2EJ7nXXoBJXvbe4vRuNWCl5fR8mYXWoZ7u6IFLy+jhTUsRjtbjRp+exk9O1vDxZudBjI8v4iSxoXR1mgOjhl0KSRGHV2XXpVq0RM67hPoWC1ew9PhLYyQtw6S7K8vOqq56Di56CALm7of0c+z419wd8Fq+7aPacvSJeoy\/YjR4YBf0ceaURmzanxsG82B04e7xxMZz+4gXbpEsa6X9HOt0IwwvVc5C6WLUHfpg8LQi3au6W81ZngdeKlEKbxwXD6eK\/ug8qdqGMVv7amfmTLa+gm10f5VNfveG0DChceIWwJYam43dUmXmKJJfnsY8SqMdmgd3yz0RruT5U8dlDzMHvDxq6oXTeRC+r9vpifNzZT+TR+nU8NdlVqT6OIUqyfj7YfiNBq9GT5Wp92dva9K5Hw+7y9dHeuJ7ieuHIitg\/nin6ObUb34eZy9nWoVa6+PnHzqkNjc3N6POkMuhoWbg4hJwpdI3G8wAR0Q87Iq1PIA2Jhq4pRPe3Nvoj4gXHX9soqApNSpUQeULdGZElfhW4UbMJT1jO21j62CaV0UIfFac\/9pcMMDsD\/+4b8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Bitte einen Bagel mit allem: Sesam, Mohn und eine grosse Portion Absurdit\u00e4t. Der US Indie-Film Everything Everywhere All at Once bietet wirklich (fast) alles.&hellip;<\/div>\n","protected":false},"author":119,"featured_media":14488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[130,1153],"tags":[2381,2380,2618],"class_list":["post-14487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kritik","category-kultur","tag-film-de","tag-kritik","tag-sci-fi"],"views":934,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/14487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/119"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=14487"}],"version-history":[{"count":5,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/14487\/revisions"}],"predecessor-version":[{"id":14501,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/14487\/revisions\/14501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/14488"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=14487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=14487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=14487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}