{"id":15626,"date":"2024-04-09T17:19:16","date_gmt":"2024-04-09T15:19:16","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=15626"},"modified":"2024-04-09T17:19:16","modified_gmt":"2024-04-09T15:19:16","slug":"sustainability-week-unifr","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2024\/04\/sustainability-week-unifr\/","title":{"rendered":"Sustainability Week @UNIFR"},"content":{"rendered":"<h1 style=\"font-weight: 400;\"><strong>Veganer Kochkurs, Kleiderb\u00f6rse, Diskussionsrunden und vieles mehr: Im Rahmen der Sustainability Week wird an der Universit\u00e4t Freiburg auch in diesem Jahr ein vielseitiges Programm angeboten. \u00a0<\/strong><\/h1>\n<p style=\"font-weight: 400;\">\n<p class=\"dropcap dropcap-borders\" style=\"font-weight: 400;\">Unter dem Netzwerk \u00abSustainability Week Switzerland\u00bb veranstalten Studierendenorganisationen in der ganzen Schweiz j\u00e4hrlich eine Nachhaltigkeitswoche. In diesem Jahr beteiligen sich etwa 100 Freiwillige von 23 Hochschulen in 15 St\u00e4dten an dem Projekt. Mit \u00fcber 250 Veranstaltungen und Tausenden von Besuchern sind die Nachhaltigkeitswochen zur gr\u00f6\u00dften von Studierenden organisierten Nachhaltigkeitsbewegung in der Schweiz geworden.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Die Universit\u00e4t Freiburg f\u00fchrt die Nachhaltigkeitswoche schon das sechste Jahr in Folge durch, dieses Jahr vom 8. bis 12. April. Organisiert wird diese von <em>Myosotis<\/em>, der Umweltvereinigung der Universit\u00e4t Freiburg. Ziel der Veranstaltungen ist es, Studierende, Akademiker:innen und die breite \u00d6ffentlichkeit \u00fcber Nachhaltigkeit aufzukl\u00e4ren und zum Handeln zu ermutigen. Damit wird die Studierendenorganisation zu einem Nachhaltigkeitsvorbild f\u00fcr die gesamte Gesellschaft. <em>Spectrum<\/em> war im Gespr\u00e4ch mit Noemi Messerli, Verantwortliche f\u00fcr Kommunikation und Medien bei <em>Myosotis,<\/em> und befragte sie zur Organisation und dem Programm der diesj\u00e4hrigen Sustainability Week.<\/p>\n<p style=\"font-weight: 400;\">\n<h2 style=\"font-weight: 400;\"><strong>Neue Organisator:innen und neue Ausrichtung<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Nachdem sich das Organisationskomitee im letzten Jahr aufgel\u00f6st hatte, hat sich in diesem Jahr unter der Schirmherrschaft von <em>Myosotis<\/em> ein komplett neues Team zusammengefunden, um die Sustainability Week zu planen. Das diesj\u00e4hrige Organisationskomitee besteht aus 16 Mitgliedern mit unterschiedlichen Hintergr\u00fcnden. \u00ab<em>Wir haben Leute verschiedenster Herkunft, unterschiedlichen Alters, mit verschiedenen Erfahrungen, die verschiedene Sprachen sprechen und aus diversen Studienrichtungen stammen<\/em>\u00bb, so Noemi.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Dem vielf\u00e4ltigen Team fehle es noch an Erfahrung mit der Organisation von grossen Events, jedoch nicht an Einf\u00e4llen, wie mit der Herausforderung umgegangen werden k\u00f6nne. \u00ab<em>Wir hatten die Idee, dass sich jeder f\u00fcr sich selbst \u00fcberlegen soll, worin er\/sie gut ist und was er\/sie gerne als Beitrag leisten m\u00f6chte. So kam ein v\u00f6llig diverses Programm zusammen, was uns auch gut als Gruppe beschreibt<\/em>\u00bb, erkl\u00e4rt Noemi. Aber die Vielfalt im Team stelle auch eine Herausforderung dar: \u00ab<em>Wir mussten uns nicht nur der Aufgabe, sondern auch einander ann\u00e4hern, uns kennen und verstehen lernen &#8211; allein schon sprachtechnisch<\/em>\u00bb, meint Noemi mit einem L\u00e4cheln. Sie f\u00fcgt hinzu: \u00ab<em>Es ist extrem sch\u00f6n, dass wir mittlerweile als Team so gut funktionieren und viel zusammen unternehmen, das m\u00f6chten wir weitergeben.<\/em>\u00bb Diese Erlebnisse im Team h\u00e4tten die Organisatoren zum Motto f\u00fcr die diesj\u00e4hrige Sustainability Week inspiriert:\u00a0 \u00abNatur und Zusammensein\u00bb.<\/p>\n<p style=\"font-weight: 400;\">\n<h2 style=\"font-weight: 400;\"><strong>Ein breites Programm f\u00fcr ein breites Publikum<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Die Diversit\u00e4t im Team spiegle sich auch im Programm wider und solle ein breites Publikum ansprechen. \u00ab<em>Mit praktischen Aktionen wollen wir kleine Ver\u00e4nderungen bewirken, die unserer Natur helfen k\u00f6nnen. In diesem Sinne werden wir einen veganen Kochkurs, eine Kleiderb\u00f6rse und eine Abfallsammlung anbieten. Auch planen wir Vortr\u00e4ge, Dokumentarfilmabende und Diskussionsrunden, mit welchen wir f\u00fcr das Thema Nachhaltigkeit sensibilisieren m\u00f6chten. Ich pers\u00f6nlich freue mich auf die Joggingrunde am Donnerstagmorgen, bei der wir mit Stirnlampe Freiburgs Natur im Morgenrot entdecken werden<\/em>\u00bb, schw\u00e4rmt Noemi. Detaillierte Informationen zum Programm werden in der Agenda der Universit\u00e4t Freiburg und auf dem Instagram-Account @Myosotis.unifr ver\u00f6ffentlicht.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"font-weight: 400; text-align: right;\"><strong>Text<\/strong> Christina Schuhmacher<\/h3>\n<h3 style=\"font-weight: 400; text-align: right;\"><strong>Flyer <\/strong>\u00a9 Myosotis <strong>\u00a0<\/strong><\/h3>\n<hr \/>\n<h2>Myosotis<\/h2>\n<p style=\"font-weight: 400;\"><em>Myosotis ist die Studentenvereinigung der Universit\u00e4t Freiburg, die sich f\u00fcr den Umweltschutz einsetzt. Ihr Ziel ist es, ein Bewusstsein f\u00fcr Nachhaltigkeit auf allen Stufen der akademischen Gemeinschaft zu f\u00f6rdern und nachhaltige Praktiken an der Universit\u00e4t zu etablieren. Wer sich f\u00fcr Nachhaltigkeit interessiert und sich f\u00fcr ein besseres Umweltbewusstsein an der Universit\u00e4t Freiburg engagieren m\u00f6chte ist bei Myosotis herzlich willkommen. Gesucht werden unter andrem neue Mitglieder f\u00fcr das Komitee, insbesondere ein:e Pr\u00e4sident:in, Sekret\u00e4r:in und Kassierer:in. Auch braucht es immer Helfer:innen f\u00fcr Gartenarbeiten. Myosotis ist ausserdem offen f\u00fcr neue Ideen zur Umsetzung von Nachhaltigkeit an der Universit\u00e4t. Wer sich engagieren m\u00f6chte, kann sich per E-Mail an myosotis@unifr.ch oder via Instagram @Myosotis.unifr melden<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2024\/04\/SW-2024-Programme-final.pdf\">SW 2024 Programme final<\/a><\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQ1MzIDAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"Cy4tLknMzEtMyszJLKlUCE9NzVZwCPXzdAsCAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"HcvRCoAgDAXQL9Ir4lN\/Y7pwVEPcRvT3Qef9DLOpG6DmncSiCx8rtgGd1Gz5jU7IKRekAnW1ylJ3vtje8BCd4Q\/4AA==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c84oyiwuycxLVAhOzijNyE1MzkgtAgA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtE1ACJLBUNzKwMTK0MzAA==\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"rVhNbxtHEr3vr2hogZwoUpKdRSDLQpSVLDuKnGDlDyC3HrJmpj09PUR3j7jmD9nr5qBLkLsu9kn8Y\/uqeoYayrRjIHuxTPZMdX2896qKR+W+CvG9pac7eePi7oJMUcZD9Xhv78nO8VGIvnHF8RsqtCOvLpppWbU+jNSFJTMjn61ufaCROjWhakMwjQu+dTNyCv+qa0OWgqqp9IfqRa3+pcsaR3hPXbUhauN0ZqyJ79VbokotjJ8pnc5fO3NNPpi4uonqmSeTtb5Qup2WyuAJQ4Fq9aMuvSJ85osCmWgKXPeLbwqv6xqmCsqaSG6s7n47mnSxHE3K\/eO\/Hc2\/EDafTq0O4enOzDfzqZ6r7u9u1ni4F3a+8PZrFxHADP69pLhckK\/U3R\/b4r1amLgkb7Wb3X1QCFc7PGThsLqKLWL0xKlsPJJvgo7ILo5MShC+W\/KD0xK3L9W71U3prUF6kA9SL\/W0LGHKFBXSEhaoG43Vi83MZRQJ7hQwE+TNuNBqf29P8r0wlo\/UdePUwSP1HBbCtGxt8mD\/W7i4upmxr1KxmtP+jqo4VpcmqtXHDD4efLun3qzDal3R4eKVboOEJtZ\/oICykmcvcAgPt7rv1LJF2H51u\/pv7F4dpkl1ecJnPn5gIqMFFfCgT1+ft4IWXFE3PprMvwIVnz89hdvbQZuvPpY+fjYuhbQilJkOKhCSHClVB44+aywqMGv9tBylyoV0dt3U6ruxykxQ+wdjdTL3xo7Vz\/cJSFySVyRRR1QfX75vQhNNOJrgwyixrF6QjfAZoDGSns9yb6x+Bcnk\/GFJTYiKoAmDaozUSaWBClORPzTOdYXnHGQwiBhX\/8lzcpEhy7noELOZIPA9X7aVXd34zsCyrdVz8IUsw0GRr1smPRh+qmtzH\/ZnCSRvgSH1w1pcNx7cnHG1vFiAlOgajp4jh9aiSDoHuDmRV3OaRt\/Wkki10KhVzY\/N\/eoGNGI\/XjaIXV1SCOC3GaWURUBNAqZ0y0VT160zVXKMw7sk3OxATLNRsVG6iZ\/IKPe6gFsosxDi52FwkuPExSSBXC5GgciDMH2LEH0V9suDr+gTL6mle4+aYekdH520wSN+xs1Qjw\/+5HYuFYclKsVEGQYdqgYZJ+IiWAguk19IAvAUZFe3QGepYwQm8SfZeNBC2k6xRRaMryFGPhV8O3mk5+DaOe6LEllQr0jXKAgwgxZXUC5dcKSAV4HjFvkHEufQ\/gTesFGm7QFmBHEomRWg\/T9YZwtraMbKyZiTKOA2vhKQOfXc8FeQzI\/sDLrgHxzKW+ORiQznP1ELJF33bxFIjRw8R8dqXR5HWyyeWP5mJPcN3sPJmc+RShEE0aqNY3U191oMgCQk\/2FMcCAz0Zp1y3M9PvjZKMmUlN99GKnQJF79da1G4XlkyFc3VuQjVS+n0hKUTDnoMre1dUwSL+Njg22MjcI3gb0\/u4aYITHvaMYvO45CTBjHt1jOygJZ6Q0hyYg+l2mCL2jrgmcs9gUTA7ezanUL8mwWLTK4ObkvZgQ8gwohAfodwyCpinyGZGWhE1VLkszGWrjQeECX\/ITlo2ijaDeXYgEE9l8DUKS0DejMJkJtQCs8Bhv16hZhwaerRlVImIxeq1seFPo6DsavngwjMd66kMY3vpWNn\/t2PhdQT0vuMXFdZ+CPJb9TUbS3LKmYesM1g2Qz1aVi8AqpTXZl7nmY1pnG5HmfwRozahTwha5Erk3EP4FYgBMMMieM6m1ys4GWOAdq4vuRvFvRWtc4arASnyznzalv\/v7dwf7+E8RoOT+puwfBfwT0gZ5puQ61xiN9t2BopNb0E\/cRtDgk2kivKCBhxi3bPpazkJruv6NnWZyWwEoHhwWHaWKENwC9TYVMyWok91CmiuEr3XE9pq+rlUjvqJTKsdh2VXdiesHN22OulpFJosDwz2PGGYCWIbpA6\/KUGCB6xA66goxytbpsYmzu++2G\/m3TS+PC3Hiebg7vfkMiXurYegng1853rADu7sP\/r52BvN24MoC1OEzDkzazpuJx4Os7Gk+Lp4Mpaw3ouaHCUiJx2nYG3XzBK5dEzGymrV4Aqr3G9trBAznwh6qHJOJVt0os2Eqqa2WFP5hTVjcukUcGEZxVvaID+cAMD2mceAA0X8uUGy4XV9z1exlj42waSiFLpBsskXLlxiYpwcnXJxmYbrmulomsXWZIVrkTzkpqnGL8DYYqOF3wFtogAdBh7XNja25xs2Txk\/U0dTAMv5IQNpNwCLi\/KqnWDwdRSHwwDMaQaNNzAmGzN6gj0iDrV+550KlT\/XLJ249NURhXyM0KRT5tkB+ohi5qjKbsDA98XNqOvOiFxjura+hjP3+HLu2GicNv+QYC4OKMptW6ady3Sqw3kNB6raGnBD5BqHk5QqmgkHW\/UDIX7yGWqtZtSSe4Z6a\/sJCnLp7L0PmCdwK2snsynTaQEfV9PzWNMebmnrVydbse+2NP1ONvXBbmT9Kn8tFnaaMiBG9Xo9u4Q+X5+wFXX+FszUD1T8hIiBAQnujasubhw4OXj\/7CDc\/se+Rhfcfd76oPT\/WPbP7MIJd5NRG5GUyQf6oOw4FThL7faJA5cl+1riXGiowkZKOoadvjLT4umWSBp2UgGD7KbtfvcSwrP9CCeyUrajLw6WYmHU7mtrz7UUennS+pzDlxc+vGaMy6OQgunVW2gbU1AvZYmqr+l4QHAfG+FnVmhXdjdAI\/iOqBUzLuYueSDVhkcv2kSKWsY9DKlIhsEOIXf3XCPK+LDd5Lqpi06yoBXkvhP\/9ugoG9ZmfP5ZeN2JMqrRkYKLhpyz50P8Lf689FmvZH3O\/gsYwjIvWHnKrVTTAMA2xWWLip8gRfec+SeC+0BC87d6eUmdfiA8I28IonT+h2v5nJreeafzHRPuNOgvc2oIdxKrD7tWqYuekNcZ5n0PSjzOuaocR45JH4IVI+Te2gjJ\/mdoTR0nW\/SEFY1dnuJZSLzdSdX9+Lmoxx3rDla6PvtecTzanJ9sK4TW7mx0daYf7Mn+6UMc7D4QQEFqKN+1smodv3J4v57rRhCsZJO7eNnoXJwd7B48ne48nV213+724vpLSbQ33seD7Ld46v3io+XKssZjo+PJro5NP\/AA==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Veganer Kochkurs, Kleiderb\u00f6rse, Diskussionsrunden und vieles mehr: Im Rahmen der Sustainability Week wird an der Universit\u00e4t Freiburg auch in diesem Jahr ein vielseitiges Programm&hellip;<\/div>\n","protected":false},"author":188,"featured_media":15629,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[1223],"tags":[2802,2200,2427],"class_list":["post-15626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universitaet","tag-myosotis","tag-nachhaltigkeit","tag-universitaet"],"views":870,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/15626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/188"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=15626"}],"version-history":[{"count":2,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/15626\/revisions"}],"predecessor-version":[{"id":15632,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/15626\/revisions\/15632"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/15629"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=15626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=15626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=15626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}