{"id":16066,"date":"2025-10-15T13:38:48","date_gmt":"2025-10-15T11:38:48","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=16066"},"modified":"2025-12-03T13:53:16","modified_gmt":"2025-12-03T12:53:16","slug":"y2k-als-die-computer-zittern-sollten","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2025\/10\/y2k-als-die-computer-zittern-sollten\/","title":{"rendered":"Y2K \u2013 als die Computer zittern sollten"},"content":{"rendered":"<h1 style=\"font-weight: 400;\"><strong>Zwischen Panik und Party \u2013 zum Millennium trafen \u00c4ngste vor Computerchaos und Weltuntergangsprophezeiungen auf die Euphorie des neuen Jahrtausends.<\/strong><\/h1>\n<p class=\"dropcap dropcap-borders\" style=\"font-weight: 400;\">Zum Jahresende 1999 lag eine sp\u00fcrbare Spannung in der Luft. Die Jahrtausendwende nahte und wurde ebenso ersehnt wie gef\u00fcrchtet. W\u00e4hrend manche den Weltuntergang durch einen Absturz von s\u00e4mtlichen Computersystemen voraussahen, mahnten andere zum Optimismus und feierten zuversichtlich ins Jahr 2000.<\/p>\n<h2 style=\"font-weight: 400;\"><strong>Der Y2K-Bug \u2013 Technik am Limit<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Den \u00c4ngsten einer Apokalypse lag das sogenannte Y2K-Problem zugrunde. Die damaligen Computersysteme rechneten mit zweistelligen Jahreszahlen. Das bedeutet, dass Daten im Format TTMMJJ verarbeitet wurden. F\u00fcr die Jahrtausendwende wechselten die Computer also von 99 auf 00. Es wurde bef\u00fcrchtet, dass die Systeme f\u00e4lschlicherweise ins Jahr 1900 springen k\u00f6nnten. Letztere w\u00fcrden in einem solchen Fall streiken. Da bereits Ende der 1990er-Jahre Computer in vielen Bereichen des Lebens nicht mehr wegzudenken waren, h\u00e4tte ein Zusammenbruch weitreichende Folgen gehabt. Das Schlimmste wurde angenommen: Stromausf\u00e4lle, Flugzeugabst\u00fcrze, B\u00f6rsencrashs, Chaos in Spit\u00e4lern und Explosionen in Atomkraftwerken. Um einem solchen Kollaps essenzieller Infrastrukturen vorzubeugen, investierten Unternehmen sowie Verwaltungen weltweit gesch\u00e4tzte 600 Milliarden Dollar in die \u00dcberpr\u00fcfung und Anpassung ihrer IT-Systeme.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<h2 style=\"font-weight: 400;\"><strong>Apokalypse im Angebot<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Sekten sahen in der Verunsicherung rund um die Jahrtausendwende auch die M\u00f6glichkeit, sich mit Prophezeiungen zum unmittelbar bevorstehenden Weltuntergang zu profilieren. Sektenf\u00fchrer:innen, die sich bereits im Datum geirrt hatten, wagten erneut eine Prognose und datierten den Untergang auf Ende des Jahres 1999. Sektenanh\u00e4nger:innen glaubten an die verschiedensten Szenarien: an eine Sonnenfinsternis, D\u00fcrren und Br\u00e4nde oder eine Verlagerung der Erdachse mit heftigen Verschiebungen der Kontinentalplatten. Manche Sektenanh\u00e4nger:innen sehnten dem Ende entgegen und scheuten sich nicht davor, notfalls selbst nachzuhelfen, sollte das Szenario doch nicht eintreten. Andere Sekten wussten, wie die Apokalypse fernzuhalten war, und verkauften als L\u00f6sung metergrosse beleuchtete Kreuze, die mit ihrem Licht die Leute vor dem grossen Unheil bewahren w\u00fcrden. Das Weltuntergangsfieber bei diversen Sekten hatte vor allem eine hohe Alarmbereitschaft bei der Polizei zur Folge, die geplante Anschl\u00e4ge und Massensuizide verhindern wollte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-16067 aligncenter\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-896x600.jpg\" alt=\"\" width=\"546\" height=\"365\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-896x600.jpg 896w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-1793x1200.jpg 1793w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-768x514.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-1536x1028.jpg 1536w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-2048x1371.jpg 2048w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-1920x1285.jpg 1920w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/10\/jack-guo-G6YltyA2Mvg-unsplash-530x355.jpg 530w\" sizes=\"auto, (max-width: 546px) 100vw, 546px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"font-weight: 400;\"><strong>Countdown ins Nichts<\/strong><\/h2>\n<p style=\"font-weight: 400;\">Das Ergebnis: Hier und da fielen Bankautomaten aus oder Rechnungssysteme hatten Probleme, die aber allesamt schnell korrigiert werden konnten. Eine Katastrophe, wie sie vielfach angek\u00fcndigt worden war, trat jedoch nicht ein. Trotzdem soll beispielsweise der damals amtierende B\u00fcrgermeister von New York, Rudy Giuliani, die ber\u00fcchtigte Nacht unter Sicherheitsvorkehrungen in einem Bunker verbracht haben.<\/p>\n<p style=\"font-weight: 400;\">Nicht zuletzt spielten auch die Medien eine wichtige Rolle bei der Verbreitung einer gewissen Unruhe. Doch diese sei gem\u00e4ss Expert:innen zugleich ausschlaggebend daf\u00fcr gewesen, dass viele Unternehmen ihre IT-Systeme rechtzeitig modernisierten.<\/p>\n<p style=\"font-weight: 400;\">Auch in der Schweiz war man zum Jahrtausendwechsel in Alarmbereitschaft: Der Bund beauftragte eigens einen Jahr-2000-Delegierten, \u00fcber m\u00f6gliche Probleme zu informieren. An Silvester war aussergew\u00f6hnlich viel Personal auf Pikett \u2013 doch auch hierzulande funktionierte alles zuverl\u00e4ssig. Nur der Orkan \u00abLothar\u00bb, der wenige Tage zuvor in der Schweiz gew\u00fctet hatte, hatte f\u00fcr grosse Sch\u00e4den und Stromausf\u00e4lle gesorgt.<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><\/p>\n<h2 style=\"font-weight: 400;\"><strong>Millennium und das, was blieb<\/strong><\/h2>\n<p style=\"font-weight: 400;\">R\u00fcckblickend zeigt das Y2K-Ph\u00e4nomen, dass die Angst vor dem Unbekannten manchmal gr\u00f6sser ist als die Gefahr selbst \u2013 und doch f\u00fchrte ebendiese Verunsicherung dazu, dass Milliarden in die Sicherheit von IT-Systemen investiert wurden. Nichtsdestoweniger ebnete die strikte Vorbereitung den reibungslosen Weg ins n\u00e4chste Jahr. Die Jahrtausendwende wurde damit zu einem Lehrst\u00fcck \u00fcber Technik, Medien und die anhaltende Faszination f\u00fcr Katastrophenszenarien. Auch heute sind Erz\u00e4hlungen vom drohenden Ende keine Seltenheit. Sie reichen von realen Herausforderungen wie dem Klimawandel oder Cyberattacken bis hin zu dystopischen Fantasien \u00fcber eine KI-Rebellion. Eines zeigt sich dabei immer wieder: Panik ist selten ein guter Ratgeber \u2013 doch sie reicht oft aus, um Gesellschaften in Bewegung zu setzen.<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"font-weight: 400; text-align: right;\"><strong>Text<\/strong> Gianluca D\u2019Andrea<\/h3>\n<h3 style=\"font-weight: 400; text-align: right;\"><strong>Bild<\/strong> Unsplash<\/h3>\n<p style=\"font-weight: 400;\">\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQzMDMDAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"izTyVnjUMFkhMadYISUzVcE5P7egtCS1SKEqswRI5SkU5+fklKTmAQA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcVBDoAgDATAF5UiiRd\/Y6AGIhRCl4O+XucyGRh2MBtWEoVbWq7pYmYbEjFX4yQcfNh58\/yEm85qlIpQ7G0syKS34E\/Jeq0Q5Q8=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c89MzMspTU5UcFF3zEspSk0EAA==\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtU1NNA1NFUwNLYyNLAysQAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"vVjNUhtJEr7PU2TosLEbIYEEBhsGHAEGPGPAQwD2hH0rqUvdZXVXdVRVI9BpDvsGe9qIPeyB2959WU7Wm8yT7JdZLX4841k7NtiDsdTqysqfL7\/82SoGFOJVqbc7Y2djb6pNXsRNetLvf995vhWidzZ\/\/n5qwqjQlk6UNRNqbIZPPl7Rr7\/8jWZNRcemLLW1Bh+jV2O8Of+rzUPUdOE8vXBV3UTtR4VyQU7\/rMvYWDzKFV6rvasLPdOmsTmOqmZMmdG039SF8\/iQ6UBWN\/jplSp8VE3QNgtLW8utelvLxeD5d1s1jUoVwnYng7yRqqn9vzd0PtM+dP7A0vfQnIVrFq1psLGxQaXKSRurKdTzGz9UXtNZrayFlmQstPJ01IzjEu1Bx3uaTUWEVQXMZ2OnDa4nPdQ2OIIeurCRpjiT6zEEj\/AehPw8v8b1eL1SFr6GePvQTZQ1eFc0srQzDLHxM7jXUphfV7E0EqCFq8MVnF\/hAfwPrYLCj12IxtXsYSgIazhyP9XRVCZUTQrMWBvt+ZVZcwEpECqSYW8QE2ml3+\/D8zX8Xax8BXT24KV3K4e93SYXtJzrUcEYUhUd4eJ4P4grEsQvy9y7w5UVP3jaqd1ElVd10BKuTAUKDiBCmOB9vvjEu2GpKxiUe1ioU7gyVanS5L\/1GHlWUPMN0I5m0ADPy\/RuQshMFQA75OCyoc40TscuXx3wiA+aig6cr1Sk8\/Pj41evCK5UfqgNXkxowOkDhF5g\/hvkTKFBQOQhiX9fKEiqBH444MAm5wgCQfuhhdfwDkutLnz2rDVqPL8ukcECEs8m6buIDjb6fUDcG0m+yfwjuw4KHuk4iwyTKQQzGk1yegUPlwK2A1WWCJfXZpL8AS3wJQbaZzs4QZBIfe174rg7SyDpwmg4kXb5gAjjJD+SJCHLsKNKQ7mpzmcNLscFNEUGAsTF\/DoitlCF3jdBVUD50DfAKOyKrTTcfuBKtifXhRrGFKwz9kBVMS0lpyk22bGETToDDCuEgV1V6i4dlE0+002ukGlwwAyPducfkb125FUoQpdeCJ1BjbPaRJzS3koO7V\/WpQvG2eSzneiqCUgxTrUXP72pPvPjoStLVQfSAdJncAxE0Y92jHuibyZI9JTIs2YIhdgHxl7oENtUfcMMYXXB6R4cE8tbBFkxdbAHpoASuwauAATgPESV1hFzJm2jJLR7rIHEhVEz\/wfiWPv5zZipjk3asTUgJcSHQEK5814LrZYL6q+ggk\/\/vJfsX00g9zIcebUDk4bum1jjTE\/YS0KBC96GgxobJBvYKCYGAhn+bjoqxhb\/cjz\/mHMGTeDMLvFpoYiTh9WLSbWx+AGsgZqBlEDk4CpB5eeUPmsIxW9sSoSSoZF0RSazlzeNtRxsvltuW2QX\/ACiwT25Nt5HKhQuw4tTlQszAgxNTKULyuXWhVSIMrWATLaAjWjBZNJmbGg5TirgQh9lARsY12pEeamaYaojohxXilFhQIVWqPlshjMo3MgqlTiDzhyfHBt+wVuD7NlDUjGuWbFdD\/m433Fs5H0ECHyeosMP932mmBXF44UeR+Hjt+3Fw+R6fvEQAOAKGVVZl+KXJTpOFfX3jZFyLIer5ASczXXeasZtTyPw4QAkYsoUItol6+IYBIiCg0CHiII\/KmZNocsxxwK5DQaXgtS6w1HmbmXASHCVaLeTinEL0ymKdQomVyn8u4f\/MVyHG5SUBrBhV1SE9yeIoMQD2hzNP0qiVprD6x04BcApdSO1QdOh1w2TGctmZ3JCcy0Wy\/DsiO2Vto09kgQwWAptSgiaMjzsoiYkXn3YzY0RD824N5DH0GBEJOMEqCIbjtOJBqlwiM0O6Kdq8Y02cRzTecg5caVBciFVfOL0pHquEV6u8TuWC9v8Ok8YP1asb2jMzGSCzMKwf6GxBGRBV8+3TJVT6VSGsrfdKdXsqoPrRi59V+HKjjqLfnJa90wFNPYG6\/31p8SNgx1pNhgtpR9td4oY67C5DFLiWhWXGmvGfmlULIdaj0Dh1TJEjBzjLC43NV8bllf6K2vLg\/7yBzWa9PLG9V6uvyvj1c7K8UXeAzvBvlD0nm2sX4Kslz7UeQc3x+1OB9DIYrHdWXuy3kEuMNdtd1bX10SZoOP\/Sx\/C5ynq8eNdNni6sXo5WGmv42+Pe9\/T9WeXa4Mnchs+P7Jxa6vrl4P+yrNkHL497n0r\/SfPLgerTwdyH397ZPs2VvoI3rO1ZB++Pe59a6v9y9W1dBs+T5EOIA6kr2qi69KfK3XZk8zZJGROffkXGvT7F9BJvnVo+fmCG\/5kh6H+\/ht6lBcO9Je5qZWu+jVzafimwQYkuu\/R2aAybtIPKNJtvaZx2yYrO2EzKpkv0J2kUnnKswrIPiyGl9QJUDvztFSphjoRLprlyBXNosOkifPe5NwPoEOUJnDi2s5\/n2n5UEVuP7m3ScUocKWHOmPUOemcJ\/Mbm5kc552cl4qE8T\/SB\/2w1C3RuXdxlqWel8uICTVEhTSKsCkykAWMhVFaIXD3LkoMynQlA5iXwee1ntI75yddOm2yK3ppGjSw1iQzYeX8BhdCI02vFV8tRYnOpM8ruLSg9EwwVqR24Xae2W0wX3guFkMv5zAywA\/\/vbOVSKMylTwqkZiU4rPoGDX+th3Q1Ihumk7hAX1b3t7ypVCNS3YaaXM9NW3N9WgnUGJdEgdPBZzKdTW\/xnyHMQPBa7sYTLcljz6MDa6HKs95lmIM8VzIQnm10Y6GMnw9mBu4C7jX1csUHFF2oTFVjDUgM\/WOX+GWnUY2BmIfZi78OGNw8GZD2uMHLbbMujInfd4CbBIvD3Y5E4aaOxzP\/S28lPOQmPYgLKrHO4neHkzKk4pdmt8w5qu2Yde3CcENt7FjDOdtw72D3sSUPEzhfdaR\/YdGRk\/nHwsrqw92Fp2gj3FWldIrn2DejVHWGYJziTfaUAxoJa9WCHPTJGIAFHVS6qWFSsmRM\/kSvW68uOcn9G6WPv3ryMVC+U\/\/7spTDB6MlHP0HHzO+c+9yfrd8DZBEr7bNlYp0qnlO+NRL2u72IezLQ+Czufx0Ue3e1vBRGeBZ5RAQ4w7w2\/hx1Mk9gSnRhOGNGCZR+msZb\/D7byrbrEtPTPviG572Dd2qCeyELJpuQamgZvQJwfeReBNZh4+91KPeSPSNvQcX9GbYywzWUxrvJSLn82QmZo1rQr3But2or6jIOGxu0Sz90b529VQKiAYxqJLSMBQNOSdVBoFozfopumt8ylb0oxkkbOGB6FQuiCDZi7VyM6vkWIxDbZf2FWmbQgomDdeTcuKRyBKXn2MJm06tau77oLWxDdcX2waSXjposLMWMXYT2i8V0VsWIyFSDvJGJk0guGViZ\/Nr4sy8fKFq3h12w7MMpNN0hAp9MpexGRqmKTS6ohd6rXiQvmD5nXnWBa+7fpDFsgVHZbo4aecnmUqni+uYBTyRjGqaGgCUpj5iTKExtXtxvsAQ4YKbG5ygihy+GPvFEBAlF1bLkOLShkTM8XsbqqKU5nHYr\/Zbs4ZbO1qj\/dXuWzDTlXMZWS6JZSwMC6SwygEi7q8nngJ2JVlIseErV3Qet6kRQI6\/9kdPT9sYla\/mFwU9WXsyUizSZ6f30vgc\/x2m6cot8qWzUjR3q+\/\/B1TK1yO3F39H+TvmjK7k\/+m7eRaoX9ECN\/9Bw==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Zwischen Panik und Party \u2013 zum Millennium trafen \u00c4ngste vor Computerchaos und Weltuntergangsprophezeiungen auf die Euphorie des neuen Jahrtausends. Zum Jahresende 1999 lag eine&hellip;<\/div>\n","protected":false},"author":195,"featured_media":16067,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2878],"tags":[2880,2879,2881],"class_list":["post-16066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-back-to-the-90s","tag-computer","tag-dossier-back-to-the-90s","tag-jahrhundertwechsel"],"views":623,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/16066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/195"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=16066"}],"version-history":[{"count":3,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/16066\/revisions"}],"predecessor-version":[{"id":16227,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/16066\/revisions\/16227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/16067"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=16066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=16066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=16066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}