{"id":3331,"date":"2016-05-23T10:11:43","date_gmt":"2016-05-23T08:11:43","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=3331"},"modified":"2017-10-03T11:16:30","modified_gmt":"2017-10-03T09:16:30","slug":"das-us-amerikanische-bildungssystem-unser-vor-oder-feindbild","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2016\/05\/das-us-amerikanische-bildungssystem-unser-vor-oder-feindbild\/","title":{"rendered":"Das US-amerikanische Bildungssystem \u2013 unser Vor- oder Feindbild?"},"content":{"rendered":"<h1>Immer wieder h\u00f6ren wir vom schlechten Bildungssystem der Amerikaner \u2013 aber sp\u00e4testens seit der Bolognareform passen wir uns ihm immer mehr an. Doch welche unserer plakativen Vorstellungen des amerikanischen Modells stimmen eigentlich und welche sind pure Vorurteile?<\/h1>\n<p>Grunds\u00e4tzliches zuallererst: Wie sind das Schweizer und das Amerikanische Bildungssystem eigentlich aufgebaut? Bis die Sch\u00fcler dreizehn Jahre alt sind, sieht das ganze mal sehr \u00e4hnlich aus: Mit vier Jahren kommt man in den Kindergarten (Preschool), dann folgt die Unterstufe (Elementary School) und die Mittelstufe (Middle School). W\u00e4hrend Schweizer Kinder dann nach ihren Schulleistungen in drei verschiedene Sekundarstufen oder aber das Gymnasium eingeteilt werden, gehen alle amerikanischen Kinder getreu nach dem bisherigen Muster weiterhin in dieselbe Highschool. Deshalb kann deren Niveau nat\u00fcrlich nicht mit unserem Gymnasium verglichen werden, schliesslich landen in unseren Gymnasien nur die schultauglichsten zwanzig Prozent der Jugendlichen. So wie unsere Sekundarsch\u00fcler sp\u00e4ter eine Lehre (mit oder ohne Berufsmaturit\u00e4t) antreten und sich danach entweder an Fachschulen, Fachhochschulen, Hochschulen oder Universit\u00e4ten weiterbilden k\u00f6nnen, ist das in den USA nicht m\u00f6glich. Es gibt nat\u00fcrlich auch dort praktisches Training (Vocational Education), aber dieses gliedert sich sowohl begrifflich als auch systematisch nahtlos in den Ablauf von Highschool und dann vier Jahre College ein. W\u00e4hrend sich unsere Automechaniker ihr Wissen also mit 16 Jahren in einer Lehre aneignen, w\u00fcrden ihre amerikanischen Pendants bis 18 in die Highschool gehen und dann einige Zeit in einem technischen College zubringen. So weit, so \u00e4hnlich.<\/p>\n<figure id=\"attachment_3332\" aria-describedby=\"caption-attachment-3332\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/student.unifr.ch\/spectrum\/2016\/05\/das-us-amerikanische-bildungssystem-unser-vor-oder-feindbild\/4_dossier_gioja_illustration_clarisseaeschlimann\/\" rel=\"attachment wp-att-3332\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3332 size-medium\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/05\/4_dossier_gioja_illustration_clarisseaeschlimann-300x159.jpg\" alt=\"\" width=\"300\" height=\"159\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/05\/4_dossier_gioja_illustration_clarisseaeschlimann-300x159.jpg 300w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/05\/4_dossier_gioja_illustration_clarisseaeschlimann-1024x544.jpg 1024w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/05\/4_dossier_gioja_illustration_clarisseaeschlimann-335x178.jpg 335w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/05\/4_dossier_gioja_illustration_clarisseaeschlimann-1050x558.jpg 1050w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/05\/4_dossier_gioja_illustration_clarisseaeschlimann.jpg 1793w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-3332\" class=\"wp-caption-text\">Illustration: Clarisse Aeschlimann<\/figcaption><\/figure>\n<h2><strong>Bildung als ausgleichender Faktor?<\/strong><\/h2>\n<p>Der gr\u00f6sste Unterschied besteht hingegen in der Finanzierung: In Amerika macht jeder, der es sich leisten kann, einen weiten Bogen um die \u00f6ffentlichen Schulen. Sp\u00e4testens die hohen Studiengeb\u00fchren im College schlagen eine weitere Kerbe zwischen die Bildungsm\u00f6glichkeiten von Arm und Reich. Abgesehen davon variiert die Qualit\u00e4t der \u00f6ffentlichen Schulen bereits massiv zwischen reichen und armen Vierteln \u2013 ein Grossteil der Schulfinanzierung wird durch lokale Verm\u00f6genssteuern gedeckt, mit sehr geringer geographischer Querfinanzierung. Wohnst du also in einer armen Nachbarschaft, wird dein Kind in eine Schule gehen, welche sich m\u00f6glicherweise kaum Schulmaterialien leisten kann und ganz sicher keine Sonderprogramme wie das International Baccalaureate-Diplom (IB) anbietet. Dieses kann in besseren Highschools als Zusatzdiplom erworben werden und berechtigt zum Beispiel auch zum Studium an Schweizer Universit\u00e4ten. Es ist vom Niveau her also vergleichbar mit der eidgen\u00f6ssischen Matura. Dazu kommt, dass die terti\u00e4re Bildung an Colleges und Universities eigentlich nicht bezahlbar ist. Durchschnittlich waren College-Absolventen letztes Jahr mit 35&#8217;000 Dollar verschuldet. Will man auf dem Arbeitsmarkt aber ernst genommen werden, muss man gar nicht erst mit einem der billigeren Abschl\u00fcsse einer staatlichen Universit\u00e4t antraben. Bildung als ausgleichender Faktor ist in Amerika also eine Utopie.<\/p>\n<h2><strong>Aktuelle Entwicklung<\/strong><\/h2>\n<p>Wir m\u00fcssen uns dar\u00fcber im Klaren sein, dass wir uns auch in der Schweiz in diese Richtung bewegen. Immer mehr Jugendliche wollen das Gymnasium abschliessen und viele, die eine Lehre absolviert haben, h\u00e4ngen eine Berufsmaturit\u00e4t dran, weil sie ohne Fachhochschulabschluss finanziell nie gut situiert dast\u00fcnden. Ob und wie wir das Problem dieser eventuellen \u00dcberakademisierung l\u00f6sen k\u00f6nnen, werden wir in den n\u00e4chsten Jahren sehen. Amerika will auf jeden Fall unsere gute alte Lehre einf\u00fchren.<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzY2NgQA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c0ksVggN1k3MTS3KzE7MyyxOzkhVcMrMSSnNSy8uriwuSc1VeNQwWaE0rzi1SCEsv0hXIT8FyHJLzcxLSQKqswcA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"FcpBDsJACAXQE1GqiS68zThQh+jQhg8m3l7dvcUbmQduzMgS9VzKbYulD8ahPaMmi\/J5PV15vbA0UIHa1LBnc0MfSnd7SfkD+CB1Ujk06L0H7fLDpubyL\/wF\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c8\/Mz0pUCE\/NTErNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNM1MNU1MlYwNLAyMLUyMQYA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"xVjLchu5Fd3nK1CcqpRcJT4kmWOPInGKGns8Go8nzji2q2ajQneD3TDRAAtAixJX+Ydss9Q3aKUd\/yRfknMvusmWJ6kkG89GYjeBi4NzX+fyrDqaXda18mKtVYF\/1fbeK4snL65dLUJeGZVXEa8utCkaW4ZwG6KqBS2eY6NeSouP\/\/zb34XM8CGstndRYYkNIigdeeGFM6600quF87VYyRDaMxqs0lUtNGOoVeWFtCPxwuWVWCuTV4qWKI8vV0YuZdTX2PnBeRxgDODgqVBByBaJBmC8euMKfA0AkQxboTQWRqNhtbFFZzlofF41XpHBxkeljfr2bAxK\/nC2mr3yWBpwmQ3twxmbRhpDUEI8FR91u7+QQbzLq7XSG+XZOr2Z9\/F8Tl0PjWwWpcpkE7\/FoiAKWIWx7QPOEYUnm5UVP8oKGKWJfOIh\/qoq8jGltBslamlANajb3lW2NRtOxRuQf61hiPdbsXR1HbHYCk2kWfEa1pQvpSf3Hrz1CmCdM08OYdtasXCmjAzpvY1062ahxMFLo8BolP6WkNLydGksw4HwSrvujS4Ko7o1I\/ER4ICi6JGVzk+HWQnYmnFiQQOiNQyxfwktqBDXwJBXFKYWdtUSx8qEygpHhjj+iJZXt7WVQTdENUyQYyOc7rHzUJSKIoRc+XnUtHiwwasmISrgrkyHCusIypsGDkSuIK6Vr3TCplVQJlPiB11WiUEEsAqVNJlY0t1gFHt\/RuhKMhu3D569ZPEHDoGbUozXPeC4bMlxZ3fAKRdxVuC9RtoicZP22m4vPtnGsz8CERllw4YoI8VmjYDRpXjr3QZO5Nz8scHNinTWSLxzVAlao3uWu5hM2e2JVyV+UhSXB3QB5t9VeHmhfLMItYyN1xGLnyChwSedTnESCDw8TuQCwZqLDkLye7xgvHRTeqhc78UP+4d01HurKRz4BKaIHJIhzSjOt\/fW0i5EEIdDG+7v3807yrf3zMlIvEQO6Sz2vSIbQuh8FCsvl5FjI4i\/eqktgkkcfHA5ypCzSLqXRZM+I2VS8FEswKThYhrTbYNbu8qITJVeLxbpDNQmPidVBMmnAEQVjdvhnWcG5QFl2PZCq60wiKp9aovvHKK5VOSVXqKFVO7YkfMmuhqFHLG+xDYkGioYV2FAcRyDR193hUJb9q9vHYz6rksmdA2OOOr49ePkeYsj4elA6SKOnreZ0UeeEm+HH0cgp8Sv1CPaE2sRgbGz2N1q02Se0riNTqxHLrhdsRudjVco2AtdUiXXxflAxogAoip1dXJycjwQ0ms5RJvIvc5Ukd2eD3K5Ir8N90uHaWmIt0adD9a6iNWpOJlMVjcDkRt0LLxcDdt9YA2U5Irq4mB2JgUIWZwPqhhX4XQ8RlECTXHUWL3wo7wah5XKo2\/q8fHk6OvxZDpGWA6bMHzE4TB71CaG7LrhtfNDCvnhAgwVtGT89KpwAZnur0rtPskrjU4YoudIvAJWT56ViusFyr0dD4RXps+LwFXwlO48O9N1KYyTBVg+Hxi5uR0gAHOXnmW4tXmfA9gsFW9FiG3UsFYFKhao8\/n\/QgGx6ECcjeNmRaeGHSv\/78WG8M\/N0fSb0adVOaAGeT4YCHbd+QBfDUSFyK3wFmsYX1Dxd4RI4bQ+FF\/2\/KPJ8dOb6dOnDIAevjiCk5PpzdGz54mBk+nvwMB0cjOdPm8ZmH5xH6SDn31zsh5wxiCNoPjcIVqnvBn2S80T4JtcA19beMazs7GcUW3rCg\/Vt\/9YvH5Tp4ZR3cTB7LIH8FR81yIU8z3Es\/H+jBk\/oJiiqlbHszPsdLactSK27V2hhEKjMk3d+Hv0Sechndul0NDHrKFfkJzy2\/uAgtaqSFZwaIZ4g05cUWHvRB5Z0pYUCjSELU\/Fpe2ENGQrNe5P1FYPeSXaLDc4ForU9XGLQ+4irRzAxOLIMsQUNaLt\/WLRqu5OY3JH6Y0rtKxy\/DXCAkoK0nz7kFpivWtHxJksVepYrfJQ4jXkB1rVuu1dZKpT\/Z3aWCZU1M\/nmIKoEf6iWIXMsxK6gfdJ+voaDtKkH8jMXzB2sM7ha\/\/ba4BOCGT03hr+19d7GD75iM+SniahD2RXGcsDG24gXnlH3tGGzbPBRc8JNKWhYTeeqHZLCdX8QXm6EhjDvkZ5i86OdrFEWyYdwZNIqbhl0wdXermqGJDHZZTvm4dcgWokndYkJbLTHgnuz3B7xvpTLmA\/gSHYpNW7xS0NSWAc7qc7QO64Vx6OQsgvJcKBl0N0ASOoxSn9GGKuaK5iAwCyTEc4ivSVp9tgpGSRTNrykoLadoLwQua5hGrzCtaHLzQKRy0OLi9IBGcaIjhiNEgakc\/S5LqQ9PteKQXOsV+bIOOmSDaA3yHAumGAQZLTkRQaQ9oGt7rAJVZamSQs6Q1HMf5L2xu6HitnVsCkk2nYbycUujT7gmcQiiB4gF3LeacLuJ5Supu1SepL3EtumjRj0vwYUjqBnKi3d36XDQSmzaTAt9jhAS39yTgp9UxtZGXofIDEGRSHgSRiTKvW0u+V4nCeBWeuSZWRT+MGic2alsGfTP\/41fPjo2d\/mkwm4gV2wGgaKRuMDTD+EXWcx2NS3TT4zcE4sqqWfhmTvoerwRUwOv5ZoZvM6iYE3olZugVO8zIfm3QtMQftBtXIvgZQVJHtA1XhFO4hStlldd9FPD3hbHjqvxZgdqTe10x2Ikfv++gQGq1S7tX0+TI2iibhlxjFdL6kX1R+W8U\/ajDIYHnahHf99oHoQFV8bdgDAce0bu9+1uEwbMt6G367cVn8QiTRZTK1ViztL\/e\/APUmUrEm19rPpnqZdbNwmwqYhYw65IjrTaaSw4ELaUUUou1v7+yudH8+qYrCSy4fqIXo7mmcfTSKpnPJ2V0NQ8RYLC0bmvVik4q2DBgmaTwfiT9n6QcnrZgXugZm78yoOhGBkKJ4ZSdYsf0HWJVLieDToa2\/BqnWH2rbAkDW2jnRbu\/a8b6d37iVjHZhsKa4ppim7kmTtjHdWAjc\/MNSxxh4WaSOl2LlXw==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Immer wieder h\u00f6ren wir vom schlechten Bildungssystem der Amerikaner \u2013 aber sp\u00e4testens seit der Bolognareform passen wir uns ihm immer mehr an. Doch welche&hellip;<\/div>\n","protected":false},"author":38,"featured_media":3332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[891,120],"tags":[1101,1099,964,1102,1100],"class_list":["post-3331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gesellschaft","category-unileben","tag-bildung","tag-bologna","tag-gioja-weibel","tag-schweiz","tag-usa"],"views":4864,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/3331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=3331"}],"version-history":[{"count":4,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/3331\/revisions"}],"predecessor-version":[{"id":7218,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/3331\/revisions\/7218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/3332"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=3331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=3331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=3331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}