{"id":7265,"date":"2017-10-21T17:27:34","date_gmt":"2017-10-21T15:27:34","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=7265"},"modified":"2017-10-21T17:26:49","modified_gmt":"2017-10-21T15:26:49","slug":"kooperation-statt-zentralismus-in-bildungsfragen","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2017\/10\/kooperation-statt-zentralismus-in-bildungsfragen\/","title":{"rendered":"Kooperation statt Zentralismus in Bildungsfragen"},"content":{"rendered":"<p class=\"dropcap dropcap-borders\">Vor Kurzem wurde der Vorwurf laut, in der Westschweiz w\u00fcrden viel mehr Sch\u00fcler das Gymnasium besuchen und die Aufnahme ans Gymnasium sei viel einfacher als in der Deutschschweiz, insbesondere als in den Ostschweizer Kantonen. Dies wirft Fragen auf: Ist demzufolge das Niveau in der Westschweiz tiefer und eine Westschweizer Matura weniger wert als eine aus der Ostschweiz? Bleibt durch die stark unterschiedlichen Aufnahmeverfahren die Chancengleichheit auf der Strecke? Wenn ja, kann und sollte dieser Ungerechtigkeit mit mehr Zentralismus entgegengewirkt werden?<\/p>\n<p>Nein, mehr Zentralismus ist nicht die Antwort. Eine einheitliche zentralistische L\u00f6sung bez\u00fcglich Aufnahmeverfahren ans Gymnasium w\u00e4re zwar ohnehin keine \u00abschweizerische L\u00f6sung\u00bb, wie es Franz Eberle, Professor f\u00fcr Gymnasial- und Wirtschaftsp\u00e4dagogik an der Universit\u00e4t Z\u00fcrich, im Interview mit der NZZ ausdr\u00fcckt. Doch auch ganz abgesehen davon: Zu viel Zentralismus schadet, weil er zur Standardisierung f\u00fchrt, Sch\u00fclerinnen und Sch\u00fcler in ihrer Wahl zwischen wirklich verschiedenen Angeboten der einzelnen Gymnasien einschr\u00e4nkt und Lehrpersonen ihrer Freiheit und Eigenverantwortung in der Unterrichtsplanung beraubt. Eberle sieht die Ursache f\u00fcr das Problem im mangelnden Austausch unter den Kantonen. Ob ein blosser Austausch zu interkantonaler Angleichung und mehr Chancengerechtigkeit f\u00fchren wird, ist jedoch fraglich, da alle Kantone an ihren seit Jahrzehnten \u00abbew\u00e4hrten\u00bb Systemen festhalten. Quoten sind ebenfalls keine L\u00f6sung, da in einem teils zweij\u00e4hrigen personalisierten Vorbereitungs- und Aufnahmeverfahren, wie es zum Beispiel der Kanton Schwyz kennt, kaum mit Quoten gearbeitet werden kann. Damit angesichts dieses Problems nicht der Zentralismus als L\u00f6sung avisiert wird, m\u00fcssen Bund und Kantone daran arbeiten, dass der Bildungsf\u00f6deralismus beziehungsweise -individualismus, eine grosse St\u00e4rke der Schweizer Bildungslandschaft, immer viel mehr Vorteile als Nachteile mit sich bringt. Es muss ein System erarbeitet werden, das den Kantonen weiterhin Gestaltungsfreiheit in ihren individuellen Verfahren zugesteht, gleichzeitig aber sicherstellt, dass der Weg zur Matura als Zugangsberechtigung f\u00fcr ein anschliessendes Universit\u00e4tsstudium auf nationaler Ebene vergleichbar und im kantonalen Vergleich gleich viel wert ist. Dies erfordert nicht nur einen st\u00e4rkeren Austausch unter den Kantonen, sondern setzt ihren Willen zur Zusammenarbeit voraus.<\/p>\n<p style=\"text-align: right;\"><strong>Fotocredits: Landestopographie Schweiz<\/strong><\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzcyMwUA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"887PL0gtSizJzM9TKC5JLClRiErNKylKzMkszi0tVsjMU3DKzEkpzUsvTitKTE\/NAwA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DctBEkAwDAXQE1WwMeM2paEZpJ3kZ+P0vP2rQPeVyBGFFUOoHDbslbzzDouHCtM8TgtNI12tdbYMaZocGUjvfyzf4k94Ek2b3CX09MPyyUof\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"880sykrMVQhOzsjNLKkCAA==\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNc1NNA1MlQwNLcyNLAyNgEA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"hVbNUuQ2EL7nKbo4D+ydsFAQYGuzhE2KIlTNTbbbthhZntLPTPDzcNv7XpYTfrF8LdkDbKjKgYLRtKTu708crak0yvuPe5Xr16Va0\/R7v+hdxc7vHf\/dO\/oS3cAdbSPWCMuERXyoyagYFqRtWrxjH3zZblkPtB2fUGtpo9lQx62jm7IdnwzKKuXp00Nnldexo4J9LFtURltRpZlOY21V2zEp+7rOs86Hsba1wg5Hyvj56nOOcvV0u3TkcXBv8R2\/1Fn6uusQm74oG3rL9oDONXvaalcHunSqQaGK9SF99gG7uiHWvWk4NX6tN6ziexMHzTWWZAy0yK+\/w\/IfKkSnaMtWN\/i4ZRdSX6lURZ+Oe+nuhM4M6wLXR1e2CRcflFvh+ABWylZzZXTCbcZrw65WrcOKVP\/WKluybXBK2basg0yULrkJjssVn6BBa+leLWilbIbf98YElv0ehbcWnXLZBt2s5IBOfoTJJdvglNG+Q9\/4u2Eg1jDwWwWZDECfHH1YH\/9ytD6+xoCLd7ZpQGvRWsic27DtXTigC4EDW6TjNB8N866gvXy+Gr\/7aBvoZhifGql5B4G30tmOj1DBsFWO+tZyC\/JWCffnbzuC3hz+\/GMBNaARL3KwA10U7Awv6E\/X1+w9HFFD3\/MVyuwn+O60E\/5UHfx6fKxU0zd6hV4S7LcWynFeh\/Ex0BK70Tl02tFnYRTK3iaApfR6uRRJVG58KlcA5bzHkAouoUaaUUUDfoT6Sm16e0jLmJ3xBmBppGKYE\/PBNI6GKNwrWylXaa\/ZCYoYo3Uoms2prZ2suLMr0NIAFWJXrQGKCSkrblkl9DezHlm2nkIIRR84Dw2UBzayPkGFv7CGejc+WqhFbrqCONY4RKw4XXXpWCfRyvcXcIzFLSqLRNrWM6aAToAE4EbZLAunYiFKSpQRrpw0duu8xEZmTqwMMguDVAMHnULbxlbJTjBaRIfZaik1XoLiayH9U2F6LxZ5KR4kE1C\/SqVKgDud3CdtyRzJBLMv3zgrsZAxrRbJGvdcCek1wsgkoVQKcYF5plZEVTrt8XLA75D9wK0V3J+\/FQzFg1a2zz\/o5sEH7rAO4YZWwd8Y46+YKPJawqpgBKpBFmVTTB5IV+pEFzAKEJEH+azv5WhhhDJnojeISY7DowDQ0Q+2+2yJ\/1hzZ6wBxjxj7dei3GqXxqK77cOAXqwNEk0oE19MHTescIcOPAdNCi9YREmRsOiTHHKG7Tj2c9bwTzEkETwnitrkSSYauvEJHFs6kznkZ4YeBgL6Ux9WcPI5vs+0qWT0evyOj\/MVCCpoUNaBnmfaB+h6o6s4FSzyG9A4kRQcirBa5Uf2Zvd6zCdD5FVOGImODt+8vK9AX1jKz901pJ4\/CS6CCRUwdyPG8IRb08sziQPp8BOqaag30pcYgbwlOz9BSNBRmnT2qZ7lOA\/HECsUsUvkIYKaAC8uKLtiwDYN0KGY1B\/EFLApvMLzjpuUWtPbKXMtIyKw8cVsnynDUtJI6petAfGgrQL5ryPX+xAreQzkGbQq6MmkiAmAj7LcVaHyC45M2Dk5jZG\/nnrPqKc3HGad\/n3AqOlfpvldszF1JTbLnLr\/SZcF5X9YxNNhCBOgdzohKTgso1cg3WayaNMj6vzB9NLilgfDH\/cC\/xP2Ia0GDwN82oZf946PfHC9bY4v+9CXjisd\/CFdKQEp9Ou+cWqNAJ\/1dvRhKk8n\/ws=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Vor Kurzem wurde der Vorwurf laut, in der Westschweiz w\u00fcrden viel mehr Sch\u00fcler das Gymnasium besuchen und die Aufnahme ans Gymnasium sei viel einfacher&hellip;<\/div>\n","protected":false},"author":54,"featured_media":7266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[170],"tags":[1327,1325,1328,1329,1324,1326,1323],"class_list":["post-7265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kommentar","tag-chancengerechtigkeit","tag-gymnasium","tag-kantone","tag-kantoenligeist","tag-matura","tag-roestigraben","tag-ungerechtigkeit"],"views":1510,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/7265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=7265"}],"version-history":[{"count":4,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/7265\/revisions"}],"predecessor-version":[{"id":7281,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/7265\/revisions\/7281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/7266"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=7265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=7265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=7265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}