{"id":8733,"date":"2018-04-27T12:46:01","date_gmt":"2018-04-27T10:46:01","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=8733"},"modified":"2018-04-27T12:46:01","modified_gmt":"2018-04-27T10:46:01","slug":"worte-gegen-die-leere","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2018\/04\/worte-gegen-die-leere\/","title":{"rendered":"Worte gegen die Leere"},"content":{"rendered":"<h1><strong>Der Besuch des Bundespr\u00e4sidenten Frank-Walter Steinmeier an der Uni Freiburg zeigt: Viel Wirbel schafft noch keine Bedeutung.<\/strong><\/h1>\n<p>Noch bevor man den Ort des Geschehens vollends erreicht, passiert man schon die ersten Polizisten. Schilder lotsen einen zu den zwei einzigen Eing\u00e4ngen, den zwei schmalen Br\u00fcckeng\u00e4ngen zur Aula Magna; die sind so schmal, dass ein W\u00e4chter allein jeden Eintretenden auf unlautere Absichten scannen k\u00f6nnte, trotzdem wachen gleich ein Dutzend, man l\u00e4sst sich nicht lumpen. Nicht nur Rucksack und Jacke muss man abgeben, auch Stift und Papier f\u00fcrchtet man \u2013 zu Recht, schliesslich wusste schon Napoleon: \u201eLetztendlich unterliegt das Schwert immer der Feder.\u201c, und man schreibt ja ausserdem f\u00fcr Spectrum, und Spectrum schreibt bekanntlich scharf.<\/p>\n<p>Kurz bevor die mehr als eine Dreiviertelstunde Wartenden von ihrer gespannten Erwartung erl\u00f6st werden, verh\u00e4ngt man noch die Fenster \u2013 wegen potenzieller Scharfsch\u00fctzen? Die Aula Magna ist nun komplett abgeschottet, Freiburgs Ground Zero. Und dann, endlich, wie von Geisterhand, tun sich die W\u00e4nde auf, und in gleissendem Licht \u2013 so m\u00fcssen die Paradiespforten aussehen \u2013 zeichnet sich die Silhouette des Mannes ab, welcher Urheber all dieser Aufregung ist: Sein schlohweisser Haarschopf, in welchem alles bis auf die letzte Str\u00e4hne perfekt parallel liegt; sein markantes Profil mit der Schnabelnase und den umgekehrt U-f\u00f6rmigen Mundwinkeln \u2013 eine ehrw\u00fcrdige, eine weise Gestalt, eine Miene st\u00e4ndig mahnender Strenge, eine nicht zu leugnende \u00c4hnlichkeit mit einem Uhu.<\/p>\n<p>Der Mann, um dessen physische Unversehrtheit der Staat Freiburg so vorbildlich bem\u00fcht ist, gilt als langweiligster Politiker Deutschlands. Die Aufgabe des Bundespr\u00e4sidenten, moralische Integrit\u00e4t zu verk\u00f6rpern, ist ihm auf den Leib geschneidert. Frank-Walter Steinmeier eckt nirgendwo an, er hat es zur Perfektion gebracht in der Kunst, banale Phrasen sehr tiefgreifend vorzutragen wie zum Beispiel: \u201eWir m\u00fcssen \u00fcber Demokratie nicht mehr nur reden, wir m\u00fcssen wieder lernen, f\u00fcr sie zu streiten.\u201c Sobald eine Formulierung in den Verdacht ger\u00e4t, auch nur ein bisschen w\u00fcrzig zu sein, nimmt er sich sofort den Wind aus den Segeln. Wer k\u00f6nnte etwas auszusetzen haben an einem, der es allen recht macht?<\/p>\n<p>An diesem Morgen (Donnerstag, 26. April) kommt er in die Uni Freiburg, um mit seinem Schweizer Amtskollegen Alain Berset, einer Politikwissenschaftlerin, einer Jus-Professorin und der Co-Chefin der <em>Operation Libero<\/em>, Flavia Kleiner, \u00fcber die Frage zu diskutieren: Kann die Demokratie im 21. Jahrhundert bestehen?<\/p>\n<p>Steinmeier, der die Diskussion er\u00f6ffnen darf, nennt \u201edrei Stichpunkte\u201c zum Thema, die jeweils mehrere Schachtels\u00e4tze umfassen. Spiegelstriche bilden die Favoriten in seinem rhetorischen Stilmittel-Inventar. Anschliessend soll eine Diskussion die Antwort auf die Leitfrage suchen. Aber zuerst erkl\u00e4rt Steinmeier noch, wie grossartig die Schweizer direkte Demokratie ist und weshalb er sie trotzdem nicht in Deutschland will.<\/p>\n<p>Es geht um China, autorit\u00e4re Staaten, antidemokratische, populistische Bewegungen, Digitalisierung, \u00dcberwachung, dann wieder direkte Demokratie. Steinmeier m\u00f6chte klarstellen: Das deutsche parlamentarische Demokratiesystem m\u00f6chte seinen B\u00fcrgerinnen und B\u00fcrgern nicht m\u00f6glichst Verantwortung vorenthalten; im Gegenteil, viele kommunale Verwaltungen suchten h\u00e4nderingend neue K\u00f6pfe, die sich in politische Entscheidungsprozesse einbringen wollen.<\/p>\n<p>Eine politische Erm\u00fcdung bei Vielen \u2013 dieses Motiv kehrt immer wieder. Welche Ursachen dahinterstecken k\u00f6nnten, das kommt in der Gespr\u00e4chsrunde leider zu kurz. Zweimal erw\u00e4hnt Steinmeier die immens steigenden Mieten in Grossst\u00e4dten, einmal die Tatsache, dass Millionen deutscher Arbeitnehmerinnen und -nehmer nichts vom pausenlosen Wirtschaftswachstum haben, und die fehlende Infrastruktur in l\u00e4ndlichen Regionen. Diese Entwicklungen fanden und finden unter Regierungen statt, an welchen seine Partei fast durchgehend beteiligt war. Vielleicht scheuen immer mehr nicht aus purer Unlust mehr politische Verantwortung, vielleicht haben sie auch den Eindruck, dass Politik nur noch wenig ausrichten kann. Der Umgang der deutschen Politik mit dem Diesel-Skandal zeigt: Die Arena, in der die Entscheidungen gef\u00e4llt werden, liegt viel zu oft nicht mehr im Parlament, sondern in CEO-B\u00fcros. Auch was soziale Gerechtigkeit anbelangt, hat die Politik, hat die deutsche sozialdemokratische Partei an Glaubw\u00fcrdigkeit stark verloren. Zu verdanken hat sie das ihrem Ex-Kanzler Gerhard Schr\u00f6der, unter dem Steinmeier Chef des Bundeskanzleramtes war und einer der Hauptarchitekten der Hartz-Reformen. Viele der von Hartz-IV-Betroffenen f\u00fchlen sich von der SPD verraten \u2013 zu Recht. Kanzlerkandidat Martin Schulz erlebte einen Hype, als er den Anschein erweckte, das Hartz-System ernsthaft reformieren und endlich wieder echte sozialdemokratische Politik machen zu wollen. Und er erlebte den Absturz, als klarwurde, so ernst meint er es doch nicht.<\/p>\n<p>Wie soll die Politik reagieren, wenn sich immer mehr B\u00fcrgerinnen und B\u00fcrger nicht mehr durch sie vertreten f\u00fchlen und sich Populisten zuwenden? Moderator Nicola Forster, Begr\u00fcnder des Jungakademiker-Think-Tanks <em>Foraus<\/em>, der mit Fliege, Siebzigerjahre-Lockenkopf und roten Socken einen Schuss flippige Energie in die Runde brachte, zitierte nach Emmanuel Macron die drei m\u00f6glichen Strategien: Die Merkel-Strategie (Ignorieren), die Kurz-Strategie (Eingliedern) und die Strategie des Bek\u00e4mpfens. Mit letzterer meint Macron nat\u00fcrlich die richtige und sich selbst.<\/p>\n<p>Wie w\u00e4re es mit einer vierten Strategie: Zuh\u00f6ren? Flavia Kleiner, die Co-Chefin von <em>Operation Libero, <\/em>betonte, wie wichtig es sei, immer wieder aus seiner Meinungsblase herauszutreten und gegens\u00e4tzliche Meinungen zu h\u00f6ren. <em>Operation Libero<\/em> schickt ,,Online-Warriors\u2018\u2018 ins Netz, die systematisch populistische Kommentare aufsp\u00fcren und die Fakten richtigstellen. Zweifellos eine sinnvolle Arbeit, doch die Frage bleibt, ob man die Leute auf diese Weise wirklich zum Umdenken bewegen kann oder ob ein solcher Umgang mit Populismus nicht oberfl\u00e4chlich bleibt. Der Frust und der Hass mancher dieser Leute richtet sich vielleicht nur auf den ersten Blick gegen Ausl\u00e4nder, Muslime und die anderen typischen Feindbilder; eventuell speist er sich eigentlich aus den Folgen einer entfesselten, liberalisierten Wirtschaft. Wenn das stimmt, dann hilft es auch nicht viel, wenn man klarstellt, dass der Ausl\u00e4nderanteil in der Schweiz nicht bei f\u00fcnfzig Prozent liegt, dann ist die Neutralisierung populistischer Facebook-Kommentare so, als ob man alle paar Meter den platten Autoreifen repariert, anstatt die kaputte Strasse zu sanieren.<\/p>\n<p>Der Informationsgehalt der Diskussion blieb bescheiden. Es fielen S\u00e4tze wie: \u201eWir befinden uns heute in einer schwierigen Lage.\u201c(Steinmeier). Ich frage mich: Gab es je schon mal einen Politiker, der sagte: \u201eIch finde meinen Job sehr einfach, aber danke trotzdem, dass ihr mir ein Schloss zur Verf\u00fcgung stellt.\u2018\u2018?<\/p>\n<p>Alain Berset kam schliesslich die Aufgabe zu, ein Schlussfazit zu f\u00e4llen. Da ich mir ohne Papier und Stift nichts notieren konnte, ist mir von diesem Fazit nichts h\u00e4ngengeblieben, und Bersets franz\u00f6sischer Akzent kann da nur begrenzt etwas daf\u00fcr.<\/p>\n<p>Der aus den Garderoben str\u00f6mende potenzielle politische Nachwuchs wurde noch eine Weile zur\u00fcckgehalten, bis der Konvoi aus mindestens zehn schwarzen Autos und Transportern \u2013 ohne Zweifel bis obenhin voll mit Spezialeinsatzkommandos \u2013 den Gefahrenherd verlassen hatte. Zur\u00fcck blieb die Frage, was von einem Besuch eines Bundespr\u00e4sidenten (in diesem Fall sogar zwei) \u00fcbrigbleibt. Es war k\u00fchl, keine warme Luft mehr.<\/p>\n<div class=\"gallery gallery-slider owl-container owl-simple\"><div class=\"owl-carousel\"><div class='owl-slide'><figure><a href='https:\/\/student.unifr.ch\/spectrum\/de\/2018\/04\/worte-gegen-die-leere\/frank-walter-steinmeier-3\/'><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4251-1024x683-900x600.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4251-1024x683-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4251-1024x683-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4251-1024x683-530x354.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4251-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/div><div class='owl-slide'><figure><a href='https:\/\/student.unifr.ch\/spectrum\/de\/2018\/04\/worte-gegen-die-leere\/frank-walter-steinmeier-4\/'><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4320-1024x683-900x600.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4320-1024x683-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4320-1024x683-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4320-1024x683-530x354.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4320-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/div><div class='owl-slide'><figure><a href='https:\/\/student.unifr.ch\/spectrum\/de\/2018\/04\/worte-gegen-die-leere\/frank-walter-steinmeier-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4167-1024x683-900x600.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4167-1024x683-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4167-1024x683-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4167-1024x683-530x354.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4167-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/div><div class='owl-slide'><figure><a href='https:\/\/student.unifr.ch\/spectrum\/de\/2018\/04\/worte-gegen-die-leere\/frank-walter-steinmeier\/'><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4473-1024x683-900x600.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4473-1024x683-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4473-1024x683-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4473-1024x683-530x354.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/04\/frank_walter_steinmeier_26042018_PYM4473-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/figure><\/div><\/div><div class=\"owl-dots\"><\/div><\/div>\n<h4 style=\"text-align: right;\">Fotocredits: Pierre-Yves Massot<\/h4>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"szA3NgYA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"C88vKklVSE9NT81TSMlMVfBJTS1KBQA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcFBDoAgDATAF5VF48H4HViBBJGUNn7fmWo21wUs88xhwUe7NaSKNZlM\/UEm9ridiAe+V41SWDgkN0onlfgB\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNA1MNE1MlcwNLIyMLEyMAQA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"3VpNcxTHlt37V2RoY4joloTA2COEHGCQHgZhBcIQ720c2V3ZVUlnZXVkZqmhV17MP5jNLF7Mit\/Ail3\/E\/+SOedm9pfHxGwmYHgRttXVXZV5895zzz33lk+aW6cnMYXO16ePTFAPTezHjapMVA97jz+zsHwfbWV8Ml6dBe2nw9faJdx6lYz1rbH4qD2eCOpXb3GLsaM+1GphbJ2O1StrnHptwwh\/4rjRk0lSvsMWUzxtsF9l+tT7ev\/koJhxcgCbvjmZnT7nbSNz3QXVyg5e\/RKS2HZusJZpjI\/qunPO+CoqE7D1uEkDNdMxwqwkj+HGDg9bgxsiD3HZObuw\/LivrsaNdTTddSniN9rk1aKXzRZzY\/nNwta4emx9vXzv8XGw+RWLtxrbq4dh+XE8NatbsERQD3qn1YWuvb4n+0frKxW78hBWgZlcX71evofd9COOgus3psobpmBgJi90P1G9d7rHbUY9GEWe1PB02tPk6fKDR4gGCj5Mi8q0aq7hIa9qR6fINo\/6tMBqA3GLQ1hjUlxHeS6mXN\/O6JPncuVxgBf9eBr1eIqdK\/UzPhjV9rCZz+tRbUb0hSZerpJFXHnbpZ4REZPlx0ALcwz++P0\/6NQXRsKD8ztrYnTce44FkylReq5nnTOdP8YT\/\/XMpAVPL7f1OFzAU3Wi2xi3OQNs2xabMYBn8FnY\/+P3fw7EjBJ5gjGpNxpWxmgC\/ULL1NXMjFPo23zz6mrzxMhM4dckWxO1YQJ8zgSVT\/uwKKhkUFvTMG4SSKMe4fFrQs+4mJg\/6rUOJYTXOKDF+kHVSCsuzyCHOW4A\/oFOt\/yAiMxpJvx6bUJDMGUPSspwvzNgnlChS+eGUJt1WGiBNHNMSjEWJi8\/Mtg\/qkd4ZgNEBdwjtMBL186cSUniSOcnxGqwzl5kWOjomn+Y0O0jsSu43cOqEo+BmmNdnujcMJVCowksHCQjipYC1XQAkJu9bDMYEQfPODwTmPEYSIl2+ZHfy3OXOmj8jbNJR9fl0BHKgiKi2Zu02ebKuqbrcRQjzHDBfIg4Fkw0DikAWgoNoCrZxSeAA3hkEkxNt8P6Y3XF9CAsO8CKFgb1N60D\/TKD9fgxr9VKhkY1slEykvs7gSkyAEQJy9TMhImZJpBQ4M1OCWrvqcg9Wh0ArIQlLkM3sU61Ngl8ETevwZFeRyPeImL6tjZT4CupX4eT5YfQChFd4Oe59VPcLC4R4OGuOYBd4Y5B\/oYHMSTKBLou311Yg\/\/GxMjYGtbAYC\/bg2n8+tHMB0hYZ\/pa7lDLf288Aw\/WTmI0b2zVr02\/TgyWjwsBCTIJoWA8Z827aEnVgBAAHXmYxqzOnLROm4IBGCCpRuBjSbuRAShgBgI0ULV1SbLMaV\/jZM7WkgXk8mSn+PQIZYQRBA7jfkH9pIZLP1HLwIIdApSNe4Jv6mDhFzk2LAWfBkQStzFjbNPmeONIz2CukpzxBmuFtP\/JsmjGwIG3AVGr5h2qJPwbVINDwyRWiMuMFYs8ApsGTbfbXEuf9p4HH2mP+qIum6DpTzpQJWsmNbw2wbJ02aJPQRMZzMkFnP8QoQcLO6FR1N51ei0\/jsRVbTcNGsuUSAuHkfCDEeqZbz2CNaU+whf8Sdgzyj7AEYxgGQXrqqtupF2V8XPWhbYH7IMkWK7cr0Brcr7aIAqp1A1uyrxAQkUpVwQx6q0sjx8GsLBtE90mCR87koIs+JrVFNwgF1dgQofa9Ro3llKoTJprpmlc9NGQDOH5Efkkl\/l2IH4mV1BA4OziCtr44wrSD3wmjFZddIyiuvGoA71AR+h6oI7u7qsHs2DdTdJpttJmDttWQpIPTJmYc0Zql12QhdoUp5QvXPqB03j4IZOkpOsa3nMhTVFPCYGgW\/LvP\/dxSCJBsnX4uhBHUD91w58aMylQOjHt6S8AsxagPbPAQHdygC\/B905fW62eOllvUAAidYaQEiVk47QHVkAQx+op8lt+3sKQbdXRrX3ogyY0TLPA8onsRDjXjtwkRfa6LMGFIdRgEyDxYTKhjqlQvRB0gwgSvBV8SHExbma9nyZDpBHhL8HFeiDLvDHkgyggpjZiBaTycBEwW4BM24mm+yD2kBM1C3OwTHoyTSk5ZxppRCgzfiVMKBoJX2ZYwgSHEGLV4RMQmU86IPZ+pWSMCDuUlywCNgfj4g98mhO0q4IBAkkT8S6lNg17QKcveuIKrphCmuH2LR5h8c8Vtw5djBAMyBCpfWsoVTaASHbjErMim5vYaDfKOWQ2AjHnPnXhhjqxiXNrRn8cka24Bw7\/qbFeM2npE\/AkHU36FgXoE4iw7Et\/QYF3MxBAzJcA9VyKLW9+ZGubyLuZHgC5f+L0FKtyRZWx4pz\/eab9ba+0yw+Ms5o6TWHPJD5WjzQJQc5jWIKdbiVa2ZDNSvEdHmnXa8Qs\/B+CfWomGC\/ou\/KFXxHl8kPN4gTPgs90DixJDvDBNg0rgL\/HjDhnTsNWyHzoQTA4GaIXLn\/F47ok\/hAIEHeNiCXszFoB\/PdGPV1+mE3MoLQOID9LrUdCkLM89nJIW2EhVLZuQRwSgKO8ippLY7QJJqG5\/XwAxfNhZKuVNq1ILGE8CKku2WuV5UeW2TksJFknFT3E3GJUGuBI0l2xBVoRsJcOp1BjoaLzXIThwSDq2EkJJc1MIav31T8AZ\/RGwOqcamonCyrhmpY9H3aiFGL6QtKUvD1nblDbVLI3n9Mi+NRLncTU0nJdAONITlpekAIqRoNqkzdNux3+Yf4iR5+tZgtMoZp410UpQSFlVo4EMBR\/m2tMFrzcemIaJwLqiUfOg3r6aeqlTDhGnGDCQi9MLQaJcIkS27kdT13GyETLSbkkKD1\/pNLgU5JExFHSiUV1pVQLjVFMw1dYApCterRkNXm5QsyTqCj0G6SyV9I+CMbpj54elZhnaSA\/sNbO+iB9vutjkQ1biNpJiYz7smYuvGQfnacL0t1WAf1liUmpdCIIpNeZGw+Sw56hdLpsyOAfbt\/WUIG5jpQA+vUCWVC32ZFueIXHKsCgTCNEFyJV9WCFSAZpO5XYMpvJ8r1zm1Ys9508D5HacYKx0U1I9ssVz6C37ZjGgsefHv8yJH900KMPeGzKkdgtLEng3IjesLUIau0h\/XEmLEB1KF1QPs\/mizWr5SV2CHcVZoT\/3Ol+VFoBWRvICFNKWkeOQoqJvgXPTkURJQkLE5W9aasevx2iyC+cJCvaulCxyqA+V6zdGXj071ZiUmpsqexpfly3bHOALgFu1iuVNFb9DCaNG9TbaTK+fBnSYvjCQN21NFLoSH5hj5l\/ffJq+NCgek2ge5kV6A6cKf0m75KW4vIRTxdYmHamDvuqnIp4sBWOfcEy6nm43i3YfZtRMmUA9Ld3M5CFdPVB0CqlnkIVxERVn6mkGHaVawnCHhPJAFKS5xDJlA9fhhilrplccv4qjCsQZ2KF8YXEpQPno8VMsWkEwgmLbCeL4LwHXAnBbArgCVpWWeNW3WrOsy4Ir1lXutwTr3cORtdiONtnX7y7RQWfqpDbGSE8I7BCKPIIax0tPiJrXhaFIMecC5f\/iJpTUaZ2gUOozml2EuzzBpAQdVh+9DnnI4Svr\/VUw3ts\/oYvUYCmw5fAdBS1i8fAHEXj8hmywhnTGP65smbEkV54A8Vqhs86Fq0pGn0xLnCagm5GKllGAyECipo4O5vhOdCFCTWLUdZ3L6SS5e4Nyy9skgGQ8vhCPW5b7XsQx4UehyIIRdSupISIS+IVK\/pMUBdAKalr9bW68aT2kF0My82sBziE2r6Bw0kn6PI317Vn87skp5ku37dQFB58dAF\/5MFFkMgSKMVCrxNC6lbjFaFfnnodOdAqkLcDo7kIQmyymgwEladgW4c7BvM06KoZ5z+3Hdxo07Mwmf+qZxkoiShKVyejTgrieTaPe6PgDXaUilSsmM25wB8KpZHjgAUVX\/rCAk4eraZgk5ZBorJ6IGdhtnv\/050Uq6Zltz8Y\/OIddhy+1iFYoPeP3\/8T\/wArUT2Hw4ucE8bIWf8nrfy0a7NilclZnCEWxcLcqAhllqAU1Ztl0wSfuzKGjMhPmYsXXTPI+b\/p60aOY86B6kZ5tC5tSZ\/MqkmBj17L\/Ghu0Y8w6uy6fm2RpcyLkcmjR9ZkxZzlQjJD68rILZdowqEkeotYZI7o4LWJowjMcx4xJVf2s9CXpiUXhTxrlhXL4C5bmTVBGQJu6Qyqh9Wcpkz7H2KTaY4uqnB0WWcP1AU+29asPUuNRU+nd7PS853hQJU0ieGeMmz6kMdOxRknnuuJhAjRPCheDSPOOlcX8gD3+sT23LiUlQQOX7qftKMgKavZW1MjJM48Si\/UWDeReVGel8gxeeLCz4zeugFKRUxVMuFcnVVLH7LSO6VlLCtR+oOa\/YQzl0s2ESACkTtlex6V7nluOGRat227oEXg9NiMum463IJv7HJpKhjjlAXqWTMXUymrMwfVKoEB58tACwUIXRu9QzErqlb2n+pZn\/KYld28zIe0F0rcGUBCZqP0Sn5GSF30WXLqrZZ8hOONOKEQxcfsQZs7ye3PVR4ZzMlWZXQ2MmvNHcEbRJ9dxRZL4NYgU9lnSCsOwm5shNHNffUEMcu9fgt\/H6tzPWIs36xeeEivI0VmPcnMBSvqOmUjZAmaIDSNO3+GQ2UOiMuJ5mRAy9CGim7d3RckQNNh5zxju+J8O+bBI6Q6wi4D8Iyc\/cxTm8nX1jQKzm93X9pUW+PVRT9YLw8XTzQKIMMjGlpaGq34DM3oGmlJ5A2RvHiR10alu\/JdnjKhY8yvsog9PnXdrcdwZ7J6eaDJ79pqIyFddV3Z5ki3+8XyQywIfTAVbAtjVVqYYgRNYfwilUlhpTnc3EHTKqPPIYNB9dLEJGjhVlq6rRcv223Qc8RkjmSF+KUgy+2M0DIo1dFh8q4wo5NW822CjHw7kLaVTVsGnPyFcJlG3k1ASS9KqkQ56EscMM74jiRkrSveLaVAFqXBjRRUl980XM2MtB+oRjot2JmD9rCctP08p5lQE3k4rJKWQSZn7BKSYecghpcMWheTgTQ2DFIenJVXyLz4y5fIN+xWOEmoXQ1S4OvUm5w\/Ip1WJeFx7h+m1I6D8sIYX4C1n\/WTLDZLuCp7rca09v5eTaIJ71T5OwRipUDN3XAM3aAlc3kVLV+B7Z1uPyx36dChx3c7v3wrT3Cpb09PJrZGH3x6ohWcNbn\/bZPSLB4fHECP84z7vbeTsD9uDmJ5sXhQmYOjw1s\/HBzeOWB\/bIZSkIZww9AZgP5gIq8Q5vIKYRjXFDK8fYD9bFsr1+kKIu\/+ntOLd3uI1rjL1zq+8+M9cFaVmvt7\/3Z4uAeasnWT7u\/d5UUM4\/t7\/7uF85m4Bz8e9DNuFtcWi22\/Zdt+29j229Hdwzu857fLv1\/cOfru1vDW4dGdt3d\/uD2EFW+x+f6bWb23ci0whMRgcRi2prJ822oXpnzeQ3mAwWItsvdLGqzweY62+\/Ma8P3dH95+d+tIDMDnz2\/Ad7cP397+7o4YgM+f3QDZmBfzPQEGEQOqG6gbrX47FHQfMzSztzdx2+E1DJSrPXVwenKg8e8qKw+Qtf8fUvfO15K6t48Ov67U\/ZTBny11dwz4Eqm7Y8CXSN1tA\/71Uvfoa0ndW3e\/\/7pS91MGf7bU3THgS6TujgFfInW3DfiXS92vJXHvfH\/760rcTxn82RJ3x4Avkbg7BnyJxN024P86cf+cvtIJV12Kezt3fHPS3FExvXPm\/l4yb9NQO1v7YxWYQff2Ts+61I0DMJrisbq0\/F+yh3+\/lv8tM8YunRw0d06\/+W8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Der Besuch des Bundespr\u00e4sidenten Frank-Walter Steinmeier an der Uni Freiburg zeigt: Viel Wirbel schafft noch keine Bedeutung. Noch bevor man den Ort des Geschehens&hellip;<\/div>\n","protected":false},"author":13,"featured_media":8741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[170],"tags":[1425,188,1552,1549,1313,1551,1553,1550],"class_list":["post-8733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kommentar","tag-1425","tag-alain-berset","tag-berset","tag-bundespraesident","tag-bundesrat","tag-frank-walter-steinmeier","tag-staatsbesuch","tag-steinmeier"],"views":1403,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=8733"}],"version-history":[{"count":3,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8733\/revisions"}],"predecessor-version":[{"id":8742,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8733\/revisions\/8742"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/8741"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=8733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=8733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=8733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}