{"id":8867,"date":"2018-05-09T16:31:28","date_gmt":"2018-05-09T14:31:28","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=8867"},"modified":"2018-05-09T16:31:28","modified_gmt":"2018-05-09T14:31:28","slug":"die-grossstadtambitionen-der-kleinen-stadt-freiburg","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2018\/05\/die-grossstadtambitionen-der-kleinen-stadt-freiburg\/","title":{"rendered":"Die Grossstadtambitionen der kleinen Stadt Freiburg"},"content":{"rendered":"<h1><strong>Die Stadt Freiburg m\u00f6chte im Jahr 2020 fast doppelt so viele Einwohner haben wie heute. Durch die geplante Fusion mit acht umliegenden Gemeinden soll die Universit\u00e4tsstadt aber nicht nur gr\u00f6sser, sondern auch bedeutender werden.<\/strong><\/h1>\n<p class=\"dropcap dropcap-borders\">Freiburg ist heute f\u00fcr viele nur ein kleiner Bahnhof an der Zugstrecke zwischen Bern und Lausanne. Die Stadt hat lediglich vier Mal so viele Einwohner wie die Uni Freiburg Studierende hat. Aber ab dem Jahr 2020 k\u00f6nnte sich das \u00e4ndern. Die Idee: Ein Freiburg mit 75&#8217;000 Einwohnern, statt der heute 40&#8217;000. Ein Freiburg als drittgr\u00f6sste Stadt der Westschweiz nach Genf und Lausanne und ein Freiburg, dass es sogar in die Top Ten der gr\u00f6ssten St\u00e4dte der Schweiz schafft. All dies m\u00f6chte die Stadt durch eine gross angelegte Fusion mit den umliegenden Gemeinden Corminboeuf, Avry, Matran, Marly, Villars-sur-Gl\u00e2ne, Belfaux, Givisiez und Granges-Paccot erm\u00f6glichen. Dieser Zusammenschluss ist schon seit l\u00e4ngerem ein Thema, vor allem da der Siedlungsraum der meisten Gemeinden sowieso nahtlos in den der Stadt \u00fcbergeht \u2013 mit Ausnahme von Avry, Matran und Belfaux. Erst im letzten Sommer wurde aber ein provisorischer Perimeter festgelegt. Es ist ein ehrgeiziges Ziel, in nur knapp zwei Jahren eine Fusion von neun Gemeinden zu verwirklichen. Doch der Oberamtmann des Saanebezirks, Carl-Alex Ridor\u00e9, zeigte sich anl\u00e4sslich der ersten Sitzung der Fusionsversammlung zuversichtlich: \u201eWenn wir hart arbeiten, die Sache geeint und koh\u00e4rent angehen, dann wird uns auch ein koh\u00e4rentes Projekt gelingen\u201c, erkl\u00e4rte er vor den 36 Abgeordneten laut den Lokalzeitungen. Im M\u00e4rz stellte der Lenkungsausschuss schliesslich sieben Arbeitsgruppen auf, die sich mit den Themen Verwaltung, Technik, Unterhalt, Schule, Gesellschaft, Finanzen, Entwicklung und Politik besch\u00e4ftigen sollen. Jede Gemeinde ist in allen Gruppen vertreten. Bis zum Jahr 2020 sollen sie eine Fusionsvereinbarung entwerfen, \u00fcber die dann die Bev\u00f6lkerung der betroffenen Gemeinden das letzte Wort haben wird.<\/p>\n<h2><strong>Chancen und Risiken<\/strong><\/h2>\n<p>\u201eMomentan spielt Freiburg nur in der zweiten Liga der Schweizer St\u00e4dte\u201c, erkl\u00e4rt Thierry Steiert, Syndic der Stadt Freiburg. Mit der Fusion k\u00f6nne die Stadt wichtiger werden. \u201eDadurch k\u00f6nnten wir st\u00e4rkere Verbindungen auf nationaler Ebene kn\u00fcpfen. Die Stadt Freiburg h\u00e4tte ein gr\u00f6sseres Gewicht, wenn sie mit Partnern wie zum Beispiel der <em>SBB<\/em> oder der <em>Schweizer Post<\/em> Projekte realisiert\u201c, erz\u00e4hlt er weiter. Aber auch Mobilit\u00e4tsprojekte innerhalb der Stadt w\u00e4ren einfacher zu verwirklichen, wenn die Agglomeration und die Stadt zu einer Gemeinde w\u00fcrden: \u201eProjekte f\u00fcr die \u00f6ffentlichen Verkehrsmittel, zum Beispiel mehr Busse, mehr Velowege oder sogar eine Tramlinie bis nach Marly k\u00f6nnten nach der Fusion leichter geplant und durchgesetzt werden\u201c, sagt Steiert: \u201eDavon w\u00fcrden sicher auch die Studierenden an der Universit\u00e4t sehr profitieren.\u201c Gegen die Fusion sprechen in den Gemeinden vor allem die Steuern. Momentan zahlen vor allem die Einwohner von Villars-sur-Gl\u00e2ne deutlich tiefere Steuern als die der Stadt Freiburg. Auch in Matran sind die Steuern momentan eher tief im Vergleich zu den anderen Gemeinden. \u201eEs bleibt abzuwarten, wie die Vereinbarung aussieht, die die Fusionsversammlung ausarbeiten soll\u201c, erkl\u00e4rt Olivier Pillonel, Kassierer und Gemeindeschreiber von Matran. Schlussendlich h\u00e4nge aber alles von den Stimmb\u00fcrgerinnen und Stimmb\u00fcrgern ab. Den anderen sieben Agglomerations-Gemeinden geht es \u00e4hnlich. Viele wollen erst mal abwarten, was diese Fusion f\u00fcr sie zu bieten hat. Falls sich die Steuern erh\u00f6hen sollten, muss es also genug andere Vorteile geben, die dies ausgleichen.<\/p>\n<h2><strong>Fusion in zwei Etappen<\/strong><\/h2>\n<p>Um zu verhindern, dass kurz vor der Abstimmung noch Gemeinden vom Fusionsprojekt abspringen k\u00f6nnen, geht die Fusionsversammlung in zwei Etappen vor. Der Syndic erkl\u00e4rt: \u201eBis Anfang 2019 wollen wir die grossen Prinzipien definieren, also zum Beispiel die Steuern, den Namen der neuen Gemeinde und ihr Wappen.\u201c Danach w\u00fcrden alle Gemeinden konsultiert und k\u00f6nnen sich entscheiden, aus dem Projekt auszutreten. \u201eDie, die noch \u00fcbrigbleiben, k\u00f6nnen genauer ins Detail gehen. Die Abstimmung erfolgt dann fr\u00fchestens im Jahr 2020\u201c, so Steiert. Erst danach d\u00fcrfen die Gemeinden fusionieren. Und auch wenn Freiburg wohl immer klein und famili\u00e4r bleiben wird, k\u00f6nnten wir dann sagen, dass wir in einer Schweizer \u201eGrossstadt\u201c studieren.<\/p>\n<h4 style=\"text-align: right;\">Fotocredit: zVg<\/h4>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"s7AwMwcA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c8lMVXAvyi8uLi5JTClJzE3KLMnMz0vNU0hJLVLIzknNBLGDQXIKbkWpmUmlRekA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"HclRCoAwCADQE5krCKLbrLRNahbq7h\/19+DViMdXRI9OrDF0lcOGvaI\/vIf1hsQ4pXHBNCMJQ7Hb3SNT5LZJyK2sQGxwXiyf\/4PDWLZuBV8=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c04sysxLVfBNzUwtAgA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNA1MNU1sFQwNLMyMLUysgAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"dVhNcxy3Eb37V6CUqpyWFMUodiLTrCL1wbIjxixLpqp8w+z0zCCLAbYADFfak\/9Dri4fUrzkD\/Ck2\/4T\/5K8bmBmZyXlQu6CA6D79Xuve3jWPTk\/iyl4156\/MKTeJF0n9SqQqYbQqn73sOwSKdOrH3QX1OnJ6YlqdEyq9us12aSiV3eGLKmXxm185yioTlfk1AandTQkOlYvhrDsVI2FltZWOxz4aojGO9WbpDRuUENvDbXkauy8op6MfIreWtn3szN3FKJJu\/sUo8SIS4Jyhje7Iag27B5ipLDAJuwNTukBl1ZUcwy8ojYUcOjx2eOS79ljJP\/V2VotrY7xu0d18OulXqvy+6jyeD7ER+cTHAaJS06q2X0MJXG+HfGqlcVPXHOpO9f5Rmmn+NZfhhb30XJFarsxcdkhr0uOb3C1eq2HqJ1jjCbwO52Updq0FsnxHUFda\/sloBnigs6+ZG\/SgLXAKfNRx+qCgdIVgpkXcbV7cFyIyJfUOqrdvcCWI\/m+JnrGN82ogFJ989c\/\/+lvp0+++fbk5GQfhwPmSack6WZ4np7sHzw+PEfbCIRNSrliaUybN7+jmIDQhsxWOfACVHDNAVDyhWbnLTj4qCgCoFYHhT8xJG\/9Wr2lXIHxIoebdvc1buTVN+Ue3KebhnHKXIsT6eupJLUQmMuLwzyu065FKdpDIjNjv8zj5z70xlWehmahLu7ChwVKmoJ2\/DtYfL011uoQj+IQjq7s7j+OFmCJbfTwfqGuzJ2JhraS\/FXgy+PRjV4ufVIUEK5QhXLtonAu6r4nh9zsgHCZt\/iMOCMhUItat6BIL0i+7ajXC3XnwRJrsVjrDJCh2g6ujUEPvawgHYFxLlBwEMx0ukvWR0G\/oJ6R230E+1qCSP\/49d+C0sUQ8XRPuNAdYCHZlZzBmYCYYTuW0lZK55EQKD9Ak1n7HPs6eEDjg+gqqBsKpqeETw2YlEuEozIA\/Dx1CMZsDQBUv0BNC46YBbxyer2GQMmIRnChVLtUl0N1NMwz3w4KjrQxYTVh71lJuPtHRKf71IOv+B7VG60dVbTFs3GhnqPgRxeW3qufTO3D7r8LtSXTjlLUDtWJUbTPh8GAJH2TtqiFLOWgIhsiqswlQjRij6Atb3wGsH9\/R45NmO04wC1DhcoTCCeshrbYjJFLEthXvtvdI+skzO7kOZ3313ggZjMVlxufRGI3wf+LVgkHWYNt7o9ff1sg4BUyCMgHoTKpGK2\/fA0bagmG6ojTsXrIenntV9oi\/zTwAcfq+15dYzdkmcjaItXX5FZMRHgA6syEZmKDeBkmSIMbzoWkGNswoDOx\/Tc5WYF11CeTHb9uUTpt+dIFbGLZObNawEbBnA7LCzaHwUKCV5CTtWIRWH1lnHZbBuelSxuzXAn2jN+NtyaZFdoNnt3dNwkMy+2Lk\/oBTWiijnARQLLWQKgSLcqHJpH46UsTUc+5V+dzOM85K5kA+FrpwFGgIuhvDQcnmpPUpYb84ZLudg92RWHkUEXogQ0eP5Az94EsOPXOhzR18lCja67RK7vTaVp43mm3pKzan2BPK3LzznrKnfUcPLz2ADxB3nFteGCYGgHLzmSvYN0xLV6bVs\/NWWxELPuAWqgiOlz4gD8SPnC9PrjaLGe+M95yrK5Nmqkm9725t29YNSjXNB+weF7obPmlS2YhRYQSgCExfSogJpxlosH\/Eg7XFqe8BGQEP9l9XDfFkj+dqsCQlKSW09gCNV2RhLJAHC4Xm0l7A\/Vyj5Vmz7S4hAkzkpLUGfXnby4vzx7jt\/K8Mq1OCN74mPIDRa+kAmnLHSWkgut2d99ZbiZKKhHGqYFVf+0rY\/PktR4PMMCQpVLNIN+IL3BWjRY3\/tQiS2YM\/UXbWvAiCGxCoX1BsC0PUpNiNhi2UBmxtSkHmcB41+6BeZzyHVyaFVw+ArvE\/n4AWY+\/qEsYCKQtn2\/J+g36dcYuTxAisbdwcJgajq8gR5lFpFPvGSFrM2Jh+uOpIYwzbs6KWYRmw5oq\/BLEo27TyN5nmXDcY0qiYlkj\/BmYaaZz41w5H4nR1pEMqtPAhfi5Y9wC\/JievL+EiPqRgFTa9F74s+Yv19Ego+Ck3a3u7GeP7QdRjv3zCUbx6C0OjaAa1k05OM+Ahr6o1wtOGgGWoSCaiRx5bz\/GRAwRn8xjAsreSgWYPhmlmoHY5yi6xihQ4bGKXx+2wwbaElqWOfp2bqjcbAyxHuvy5y\/0XZ5KS2cVlz60qR+tkfH9BtB4x2z8h+ZDA9ZklCuxoWdw+gXInPgxeyAPbyi6YNjJ0JZHH65BlIdrmWpN31egDkyMhZkFNV8FHBWcaAbL2DPnOoxHe0LIyEb8VtA5vv4Y9eWXj01uRTyVqB5vJbqaQNRS0zixTQQaxbUgImn78j7yCtHH8t4xqyv8ZPfQFRzlxH7Igz3Y4hGQG9oSvrpFcyJjeYSpxplGRnfUI9NA3vM+6VglLnBL5ryXSXPr\/bxp\/dwX6+qMvBKVV4zVgLEkDzQB9hgZX+aA8\/KispdSPzKl2CVAwkeZkEr7wZEC8P9h1ScR8qVcvTC2uZFg4hw8LlzAcrHv9OTJ38cKccOSN25+X8H3GwSwNXBB5kzDzhY4DMH2sK3sa7IQev1T92Wkxwg8U5SwzMB33kmUYjkvtNji6GPM0xk0K+Q5WHaoMnVmMDIXIGoe4k0tYQ1R3lfHCRPft8M4ILFdGspVF\/Ax8ATTirB583gs8NZIA3BGoJe0sUpm29yTZxXE3OQtDFnGpSbsPnbEQ3c8+LdH9m0\/unZ5Q6lzwjUSborZ7vNtpLTZkOHXdTZ0aYLTLAAHtbiH323kHwgCTKN7tFyUWJWkZAZbHI4jEi0aCY0E5UXjSvPc93\/AdcUkkH+bcJHi2E1GiTzF0gdL3z1K9D4dYTRo0WuBaJe+fXT+yie\/DFQb0G1720IlT8+\/+h8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Die Stadt Freiburg m\u00f6chte im Jahr 2020 fast doppelt so viele Einwohner haben wie heute. Durch die geplante Fusion mit acht umliegenden Gemeinden soll&hellip;<\/div>\n","protected":false},"author":40,"featured_media":8870,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[1231],"tags":[1425,392,1202,1559,1558],"class_list":["post-8867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-freiburg","tag-1425","tag-freiburg","tag-fribourg","tag-grossstadt","tag-zusammenschluss"],"views":1173,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=8867"}],"version-history":[{"count":3,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8867\/revisions"}],"predecessor-version":[{"id":8871,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8867\/revisions\/8871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/8870"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=8867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=8867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=8867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}