{"id":8896,"date":"2018-05-29T07:30:06","date_gmt":"2018-05-29T05:30:06","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=8896"},"modified":"2018-09-20T15:40:07","modified_gmt":"2018-09-20T13:40:07","slug":"nachtschwaermerei","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2018\/05\/nachtschwaermerei\/","title":{"rendered":"Nachtschw\u00e4rmerei"},"content":{"rendered":"<p class=\"dropcap dropcap-borders\">Die Nacht ist die sch\u00f6nste Zeit des Tages. Gut, die Verbindungen des \u00f6ffentlichen Verkehrs sind nachts schlechter, besonders zwischen Bern und Freiburg. Doch ansonsten gibt es dutzende Gr\u00fcnde f\u00fcr meine Behauptung. Ganz grunds\u00e4tzlich liegt der Nacht ein besonderer Zauber inne. Unser Vorstellungsverm\u00f6gen steigt, wir handeln wagemutiger und denken kreativer. Eines der h\u00f6chsten Gef\u00fchle ist es etwa, in der D\u00e4mmerung loszuziehen und dabei nicht zu wissen, was in den n\u00e4chsten Stunden geschehen wird. Vieles, woran man tags\u00fcber kaum zu denken vermag, scheint in der Nacht m\u00f6glich. Und genau diese Tatsache macht f\u00fcr mich die Zeit, in welcher der Mond vom Himmel leuchtet, so faszinierend.<\/p>\n<p>Die Nacht bietet vor allem auch Raum f\u00fcr Experimente. Gerade dann probieren viele Menschen neue Identit\u00e4ten aus, kleiden sich in expressiver Mode, brechen mit gesellschaftlichen Konventionen \u2013 es herrscht ein gr\u00f6sseres Gef\u00fchl von Freiheit als in den hellen Stunden des Tages. Ein zentrales Element ist dabei sicherlich die Clubkultur. Clubs aller Art sind Zufluchtsorte, um dem zunehmend beschleunigten Alltag zu entkommen und sich hedonistisch in der Nacht zu verlieren. Gerade hier steckt man sich mit dem \u201eNight Fever\u201c an, wie es die Bee Gees einst besangen. Ist im Tageslicht die Hemmschwelle bei vielen noch relativ hoch, so verliert man sich in Clubs in der Musik und tanzt genau so, wie es sich im Moment gerade richtig anf\u00fchlt. Im Taumel der Schattenwelt herrscht eine sp\u00fcrbar intensive Ausgelassenheit und das nicht nur aufgrund von Genussmitteln. Zudem schliesst man Bekanntschaft mit den unterschiedlichsten Menschen \u2013 nicht selten mit solchen, mit denen man im Alltag wom\u00f6glich kein Wort gewechselt h\u00e4tte. Doch genau die haben oftmals die spannendsten Geschichten zu erz\u00e4hlen.<\/p>\n<p>Was f\u00fcr die Clubkultur gilt, mag sich nat\u00fcrlich auch auf Konzerte, die nahenden Festivals im Sommer oder aufs n\u00e4chtliche Um-die-H\u00e4user-ziehen \u00fcbertragen. Und gewiss geschieht sowas nicht alle Tage. Doch das ist auch gut so, denn schliesslich soll die Euphorie rund um die Nacht nicht an eine Gewohnheit verloren gehen.<\/p>\n<h4 style=\"text-align: right;\">Fotocredit: Pixabay<\/h4>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"s7CwNAMA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"80tMzigpTs4oP7ykKDe1KDUTAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcFBCoAwDATAH3WrIIi\/KWkkPTSUZIvfd8bIlQ+Q3F2dZft4o4ghlwpjT3TFWY8b9YI3MabY1zSmhg78\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C0pNSs3OTnTOKMosLknNAwA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNA1MNU1slQwMLcyMLUyMAMA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"VVW7btxIEMz9FQ3F2nXiyCcLkE\/SyjjIOJzOMqBsuOwlBxzOEPPYlTfyP1x6uEjfoEgZ\/8RfctVN7kIKhCVH3T3d1VXFs4HWzqT06aSOYVibgebfRRVizTGdnF9apq9m3WayKVONt7Rux2efMtMDWxxxor9Nw2lJq5JPNeSeY2V9XXzDXgPG582GfXZ23eIE\/+64jYkSgshL9SRlHeOJ4ylVnIKX+2m\/s0lzPnP0VBB+HdlWJTZLugzrloxHKJrx1NgqE+6qS94zsmkVxxf53YwvkXq2nlGlNWXIaAzdGr+nJqJmGp\/yXnojZ7mRkeI8M5KOzeDwwZQKP9Z7XtI3n\/B8HyJudw4l05ZjPz7LzDiyDcDY2UitQbbztANIfcm2QZYMUrPvENpFNtkidUlXaDHp7UB43epUK0b7QEbhx38578wpOtCwy\/Gp7xkjNORC2pe9ZcFKq5uKLXkrU+wLGkmJPRoyaUr25Men+Y47ACInWCKwlgrou17SvWXHCUkhGk89\/rJp0vgiGHSm9FJ4nkJGN82pbBGY5UODE4oCisArmNW4xZsiNEkM4uSEEEZxCZw2JYsQFgm9dNQdO8RErXiLXdA29HRjMbojx0VIg8AUaGPS3nqLXfl6efZ+OH93NrxicGUZkciOZJzjngxy6S+ZRG++ehw42h5ExXpXHA3IUxvvaYih0qq0FUjolv3ESs+F6QswyDaDRDgxBYB1jq0AmmQUDMCPQ+SUZMsYoGYwPLIW6KEgwA4CoaDZHBTyR\/BbKRo8Xn79\/Ec2DwRiOpCyieMzNoqqB4ZgLK\/iaEWVxh333KL4qyW\/0iv4RpBKjgZrpisgwn7WubJH2ufoDvv43ZWqKy4XUFWek6IY6SLmSckPZeNkGynEjBkBa81CEs8tKteiJBF58dAGOrlwDnwSEuHaLmCdE3UVtZbr4NGKyP8tmxC\/la5kH8c1tXgV1a27rETVGr3aUw8A\/\/tqG6ReMzJ\/\/fwXriHaZLULK7YAt2BRl4WXSJ9GrGtJX\/Bm+wkvp1qS8Bvue7S1E2BJgFJWgA1iSJGd6JlavCgp52Zf9YVxJvzmuW5Lsp2OnuFJeVZICscep6we3NENNdPMURqyDYZRAmS0K60WkYWUvQOjMoBGn\/kNe+DhA\/heGbEyBAgx6aKkhuVjwF4ZNJlImi3EF2imbNQulWkr9iUlIAzzA1APRYCW9ULXaZr1M3cQT56IPS9DNgyLx5nlWhBVAzrqSag+XQhJ5FkfKYj8sbG5BE9eBDxmBu3CwWGoE3F8B\/8A0g4SSzo7pCmS1g\/G0X5gzBVKhU3uRS36aRvQMJg6O690KebilaNxPz6Bvf5oLN+BjvrGW3HgQ+RgR7DDaW\/eZARpd+o3gFH0vWcVieR607Jq85pB+K1qt6c7UUSkIKtETpoMe3II+tYvkLm4GZ8KXGAxG79aM+Ss3J28Vox\/MnaECJa7405FvUrtGRnZtohfu2xKVgaiLX\/cqw6BdTht+6oMbYh4UFKI2o9OO1\/gJ7ateBfaiVUihhD1W9MeoWw\/QLo\/HH86yfyYF8bZxn8EvSHZ307Or0MO68i1zR\/pT\/toKvPj7H374fzd\/w==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Die Nacht ist die sch\u00f6nste Zeit des Tages. Gut, die Verbindungen des \u00f6ffentlichen Verkehrs sind nachts schlechter, besonders zwischen Bern und Freiburg. Doch ansonsten&hellip;<\/div>\n","protected":false},"author":48,"featured_media":8897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[170],"tags":[1425,1568],"class_list":["post-8896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kommentar","tag-1425","tag-nacht"],"views":1012,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=8896"}],"version-history":[{"count":5,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8896\/revisions"}],"predecessor-version":[{"id":9141,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/8896\/revisions\/9141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/8897"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=8896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=8896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=8896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}