{"id":9839,"date":"2019-03-23T14:05:15","date_gmt":"2019-03-23T13:05:15","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=9839"},"modified":"2019-03-23T14:06:52","modified_gmt":"2019-03-23T13:06:52","slug":"spectrum-feiert-60-jahre","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/de\/2019\/03\/spectrum-feiert-60-jahre\/","title":{"rendered":"Spectrum feiert 60 Jahre"},"content":{"rendered":"<h2 class=\"Normal\"><span class=\"Subtle_0020Emphasis__Char\">Ein Professor der Volkswirtschaftslehre, ein ETH-Professor, ein Fotojournalist, ein Mitarbeiter beim Bundesamt f\u00fcr Umwelt und ein Klimatologe versammeln sich im Auditorium B der Mis\u00e9ricorde<\/span><span class=\"annotation_0020reference__Char\">\u00a0<\/span><span class=\"Subtle_0020Emphasis__Char\">. Das Ergebnis? Eine Podiumsdiskussion \u00fcber den Klimawandel. Der Anlass? Das sechzigj\u00e4hrige Jubil\u00e4um von Spectrum. Wir schauen zur\u00fcck.<\/span><\/h2>\n<p class=\"Normal dropcap dropcap-borders\"><span class=\"Subtle_0020Emphasis__Char\">Zum Thema\u00a0<\/span>\u201e<span class=\"Subtle_0020Emphasis__Char\">Werden wir \u00fcberleben?<\/span>\u201c fand am 19. M\u00e4rz die Diskussion rund um den Klimawandel statt, moderiert von Cerise Drompt, Co-Chefredakteurin und Selina Grossrieder, Verantwortliche Web f\u00fcr die deutsche Redaktion von Spectrum. Innerhalb von zwei Stunden wurde eine Vielzahl an Themen angesprochen: von China und ihrem Technologienmonopol, den Auswirkungen Klimawandels, \u00fcber L\u00f6sungen f\u00fcr vom Klimawandel verursachte Probleme bis zum Einfluss der Klimademonstrationen und -streiks. Samuel Turpin, Fotojournalist und Mitgr\u00fcnder des multimedialen Projekts\u00a0<span class=\"Normal__Char\">Humans &amp; Climate Change Stories,\u00a0<\/span>erz\u00e4hlte von Familien in Mali, Gr\u00f6nland und der Schweiz, die im Rahmen des Projekts von 2017 bis 2026 begleitet werden. Als er schilderte, dass er in Gr\u00f6nland Erdbeeren probieren durfte, ging ein leises Kichern durch den Saal. Eigentlich grotesk, gr\u00f6nl\u00e4ndische Erdbeeren.<\/p>\n<h2 class=\"Normal\"><span class=\"Normal__Char\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9830\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/Confe\u0301rence_Spectrum_1-900x600.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/Confe\u0301rence_Spectrum_1-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/Confe\u0301rence_Spectrum_1-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/Confe\u0301rence_Spectrum_1-1800x1200.jpg 1800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/Confe\u0301rence_Spectrum_1-1920x1280.jpg 1920w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/Confe\u0301rence_Spectrum_1-530x353.jpg 530w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/>Ist schneller agieren m\u00f6glich?<\/span><\/h2>\n<p class=\"Normal\">Angesprochen wurde auch, ob autokratische L\u00e4nder wie China nicht im Vorteil seien, da sie potenziell schneller Restriktionen und Gesetze durchsetzen k\u00f6nnten, um der Umwelt zu helfen. \u00dcberraschend meinte ETH-Professor und Forscher Anthony Platt daraufhin, dass wir gar nicht schneller vorgehen k\u00f6nnten. Unsere CO<span class=\"Normal__Char\">2<\/span>-Emissionen seien in den letzten Jahren konstant geblieben und die Frage, ob es \u00fcberhaupt n\u00f6tig sei, schneller zu handeln, sei berechtigt. Die Schweiz habe vor, bis 2020 ihre CO<span class=\"Normal__Char\">2<\/span>-Emissionen im Vergleich zu ihren Emissionen im Jahr 1990 um zwanzig Prozent zu senken, f\u00fcgt Alexandre Berset hinzu. Zudem sei das Ziel \u2013 seit der Annahme des Energiegesetzes von 2017 \u2013, nicht mehr auf atomare Energie zur\u00fcckzugreifen und k\u00fcnftig mittels erneuerbarer Energie Schweizer Haushalte zu versorgen. Trotzdem l\u00e4sst die Schweiz 75 Prozent ihrer Energie importieren, sagt Anthony Platt. Dies f\u00fchre zu einer Kodependenz zwischen den Energieverbrauchenden und den Produzierenden.<\/p>\n<h2 class=\"Normal\"><span class=\"Normal__Char\">Die Revolution steht an<\/span><\/h2>\n<p class=\"Normal\">Ob die Demonstrationen und Streiks der Sch\u00fclerinnen und Sch\u00fcler etwas bewirken, wollte man von den Experten wissen. Diese waren sich einig: Um etwas \u201eoben\u201c zu bewirken, brauche es Bewegung von \u201eunten\u201c. Seit den Demonstrationen werden erstmals Steuern auf Flugzeuge und Kerosin im Parlament diskutiert, sagt Alexandre Berset. Anthony Platt f\u00fcgte an, seiner Meinung nach gehe es hier um eine Revolution. Die Vorbereitungsphase habe man abgeschlossen und nun werde es bald ans Eingemachte gehen. Doch diese Revolution wird auch negative Konsequenzen haben, mit denen wir uns zuk\u00fcnftig befassen werden m\u00fcssen.<\/p>\n<p class=\"Normal\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9833 alignright\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2025-900x600.jpg\" alt=\"\" width=\"522\" height=\"348\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2025-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2025-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2025-1800x1200.jpg 1800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2025-1920x1280.jpg 1920w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2025-530x353.jpg 530w\" sizes=\"auto, (max-width: 522px) 100vw, 522px\" \/>Etwas entt\u00e4uscht zeigten sich mehrere Zuh\u00f6rende: Jonas, der in Fribourg studiert, h\u00e4tte gerne das Thema erneuerbare Energien genauer besprochen. \u201eIch denke, wir werden uns radikal ver\u00e4ndern m\u00fcssen. In Zukunft wird nichts mehr unserem jetzigen Lebensstil \u00e4hneln\u201c, erkl\u00e4rt er. Der \u00e4ltere Zuh\u00f6rer Jacques zeigte sich auch eher kritisch: \u201eMeiner Meinung nach sollte man nicht in ein universit\u00e4res Umfeld kommen, um wirklich seri\u00f6se Fragen zu stellen. Ich bin entt\u00e4uscht, dass das Dogma des Wachstums immer noch pr\u00e4sent ist. Dass man dieses nicht in Frage stellt.\u201c Lo\u00efc, der aus Lausanne angereist ist, war \u00fcberrascht, dass nicht mehr Zuh\u00f6rende anwesend waren. \u201eIch frage mich, ob die Leute wirklich sensibilisiert sind gegen\u00fcber dem Thema des Klimawandels oder ob es mehr ein Hype ist.\u201c Insgesamt habe er die Diskussion aber \u00e4usserst spannend gefunden, besonders die Eindr\u00fccke von Samuel Turpin seien interessant gewesen.<\/p>\n<h2 class=\"Normal\">F\u00fcrs Erste \u00fcberlebt<\/h2>\n<p class=\"Normal\">Im Anschluss an die Konferenz versammelten sich die Anwesenden in der Tour Vagabonde, um mit einem Bier oder einem Glas Wein auf die sechzig Jahre Spectrum anzustossen. Zudem bot sich f\u00fcr die Zuh\u00f6renden die Gelegenheit, mit den Experten in einem etwas intimerem Rahmen zu sprechen. Den Ausklang fand der Abend mit einem Konzert der Band<span class=\"Normal__Char\">Street Corner Talking<\/span>, die bis zum Schluss f\u00fcr gute Stimmung sorgte. Auch ein Geburtstagskuchen f\u00fcr unser Magazin durfte nat\u00fcrlich nicht fehlen. An dieser Stelle m\u00f6chten wir von Spectrum uns bei allen Mitwirkenden f\u00fcr einen gelungenen Abend bedanken und hoffen, die Diskussion um den Klimawandel h\u00f6rt nicht hier auf.<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9836\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2154-900x600.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2154-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2154-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2154-1800x1200.jpg 1800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2154-1920x1280.jpg 1920w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/03\/5H9A2154-530x353.jpg 530w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<h3 style=\"text-align: right;\"><span class=\"Subtle_0020Emphasis__Char\">Text: Elisa Jeanneret-Grosjea<\/span><span class=\"Subtle_0020Emphasis__Char\">n<\/span><\/h3>\n<h3 style=\"text-align: right;\">Fotos:: Linda M\u00fcrset und Valentina Scheiwiller<\/h3>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1U9J1QcA\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"s7QwtgQA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"Cy5ITS4pKs1VSEvNTC0qUTAzUPBKzChKBQA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"PchbCoAgEAXQFY13KhBqN6EjGiQyj\/331\/k83X3ZBZhHlekp5miaSoctKa7xogp23k7w8R81GaJOmem5uwo+\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNQ1MNY1MlYwNLEyMLYyNAUA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"xVlLcxvHEb7nV0zhkEqqQBAkTVmk9SiKpp5krBJpqUoX1Sy2sTvC7OxmZpagcHJ+Q66uVA685JSbTjoF1\/wK\/5J83bN4UJZlKyErB4nAPnr6+fXXjTvlthpZHcLd3p9qX2nbu3cnNNotLp62WbT0ZjjcHh5VTamDCW\/eHJba9+4dGaee+3pMIdRe5eTVy9pOwtT4GEalHsdgqfTUV4QHj84ebywfTpce1rF+W7feaWtCTNdOTNQ+IxMhDX8q9aB1OQVdRTWef\/Dq+2pKNipclMefWVPpWNu6IHVOHs9VZJ0KZlQqvHzQ5ibW3rSQIwqemDD\/hzej2ud0Z5PtvGqtdq6OOpraicWexuTJjWhh8r\/+\/qm3PuOjgfpWB3XkC8qcCfcVfEbqeZ1DpZCbMGlDwGFq\/iEjdmFn0VTDaIt3cfHA8SH3RU6gUTkzxdv5ZekNTH7aZsbOL2HeOYScNjSKvq0G6pXxikPQQuCs9fMPo8lgofhmuX3vd3eaq0FXua+bkW4Wfzcy9pAPvz0ZXkOJs5IqvXTRTz\/87be+\/Io8247MSZ6wlJG7v5TzoxrDIUpXamtvoE7ml36mckPq25UDPWcEVPjIhSogmkitqoY1hnwURx3ic8Drvq4a3DysNw5LGnvK9SRS65FXLO2UrHFaPfJ1CHgXAvrqJXnt4rT20SLFSL2iLOUlq5NTy4lP6oVIYrWuhuWJc+RLbTO5PpuSUaeR8xumt\/AApzSpl4bsTJdWwXXsUdzVrqDQ+BrC3X4yoWTdWE2DEoPrkRmO68CQq2pXN7XtizMOWi7ISQsJVzwT+l3SHc\/fh3RXDDmvqysORFW1qKtRGYmLPbNQSGUmIK8qzuaxRQSktuStnHB6iF5qiJIjN\/CdzCQM1KmuWsg8a31jXP8jAJBnUf8F8tXlUg5BVa2NpqLcaEuCNm9pEgNybD2zUg4vkulxW2kX1O911XyjDgUgCP5iH8LdQAMK\/WWSkp+hmCyeYK8+1JWx8KBiJIJSfUR\/\/h4FyMmFf6zV6ahE4GZ9CTkw5oUuOUSs7EI9kbU93PpaHLU93L4FLCsso1pUU8n1gTqwQZGUqbGQG4GTOazhazh9de6RzzNiFFJIgMzIp7z1Y36hMK4QHITsAAWecVJ6uQ8A5PCfag0cOQJYOElZVfg6UpjgXTlhfukAQ5y0y3OAFA0Q4lf6wlWf3zFVoWytcyh0t2f17F0Px4\/q9F2Hd27UW2KsNQVgFpkezIw2OLhIpWmzgUgVtLF3e2fYU8GP7vbKGJuwv7kZYgtb4qB1ZuwHoxKhSyW1ibdGtYu4udk2fH7YhN\/3Noc7m4e1G9O\/\/5Lge1GDb7Y29obDi1vD4eBtU\/SUtvFurwfgyWN5t4dbPVWSKUpcvTVMagSKN6+JwudpX93IMV\/fun2xu7Utx+DzTR2zdRvmbG139vC3Gztpb5tPut2dhG83ddLuzvBiZ3dHzsHnaU9SlnO4jXVf\/aHSFxuSO\/scwObij2prODyHNvKtpzbvPQGuobwcWYvC1kWq32r+vuBqvP\/Zpty7d7CG+12L0O2o7Ks6U6zChHFWqveYCxknTA11vcFBfmSAeoluRQatkIBsDDIwglQDGHAztBq7pt8LAlSbyRp2PyLk\/4wSoshHpyYADvZjPzXcJSmbtSgeO2Zwm\/+I1uI1qwYhFSAKCHuFAor0h7XnR5jkxLJ279Rzi3YNFb1ux6VxHSQyLyi070xaqXteg1eVaxoN1PcuwMPq8LvPgNV25\/WNo8oIe4AEcQ4DL4OmhZ2Qpp7qkqM14Y6Gtq9A4tAdss41jP8PPSBLwgH0lX4K0tVE5ebvoylYan9NX3aQdFUYhltoCh5tGw9GUD1I61oLHsq4H4FvdP1jKF3+y63i6JPnzgPkx+lG7Ln6ABuJItobcjRn6PogmNzJEGkJaSA34ViDHRQRXYsuYAKUeQB6iHaGKM3agXqNqqvEKERMvUZeqZ9++CtfiJIiB85xn5Q2eQQWhEIoUmqtdUu80e+CXGFyQIqPFdh9pXFc99KCzs7aApxi3IViAsYwZodXJkaSxuqoJZ\/hTb98tXMvrjzWbQAPiyxO5gZOJGTPGZrjjA1BXwyo3HwtKF\/vLr3CblyJNVWDCpPCRlg1O2k9myW0gd3HIcR5TPLAlsBIG2LuN4PXpYhT8nVioVXmudjlmY59CAPK25kclv93rZoT7QWd17YVhhoiwd3a\/QoSfZclxv0Jenea2N2CHM0\/INWNW97triiKU2RGRsxG2VPT2nIAwNUkAcT0i4aJEA8CIXA82HOkppqzVmY6+M4U+wCcThxmjBr1yCMCPLsS3rmOq\/IBTakAwZVT8HzLQIEXwEZTcrqfWZUoGpIoRBgfYCEnk5N8fGjbYkYtuCRb94wwHRipo+faW11xeshcxwkRF\/nwUdEMPsI7KS1Ae4IFzo4T\/GGdnWbKRsmSEiK5SGVKWIUwYQdQnuHEYJ4oAk9XlGCE\/asz1NqotDV7VfSG8GQly820xXAFygw6X2CCE64vwArRNRNJCcNa0sDNuXQi5aiA184J+Qzk\/TMGTu4QfDKMqZJ\/u8mudTw0LEs1o7EWfTpvV\/MPEvSU0j9LwC9hmOtcckcJ3\/RM6q6DVu4+3jsAIu9+jkfubm+veOTOV7eviUd+6ujrII5LudfMFJdyr58arkRfOxdciv4C8oeAr5E\/+cbk70gwCofE+WUbuK3NkBRxAWbc45isvG7L+XsB9H31tHY69AVLeUPmTYb5GEQCliRAKeeXUcoTHU56rSxd1hveooM4POR0K4u0BYkcMAI+SbPhBMSF67KrPy5Pj\/KaaBn6E59claV64qDopEXxpvKXPh1So26FdVXqLRo6j5rqmFkSOihoJ8Zr0B9G3D60nKCz+ogPabk1v0QPWLnAg42MACKhc1TykwANMU2ceCN8d5\/NOPkEVIZVU+n4r5P5GBnAbd4gEB7Sv6\/GBMyb1FXV0VhuHDIfwxAzfx86aueEAUWmb+wC3M9Y4iqiHUPlQHxbFwgEE5xXUAURqwL6QgUVHYNoA5cGYQ8hylYwiJqCrWGlrRybjowD7mvH9fyfo5QRYC3qGP9pdFfZCQHvgwjsc5NMBFRY90KvNTK1yjK8OsWhaAPSWZc5MZajK9MNGNzvj6mFO9ec44LJjDVBdmnofDmSDG5a7C+7HaB4YX3ZpHj\/1tFk0YaD8vhdQ+INNvOJC0Xa80rbIv\/xhk9nki\/4xn1ZMVtxJOePZYXW5zSvOWmDvIpmlgtVTKudK6unJd3n5AshcXvxyS8yqofzD54XuYjMckcZf4ktPanQ4bnj8m4sBZkbpCyTZ6tF9RIJ+P5BF5TFGOLVGUpfvdSFztgsSVPuqJz2lXrAZEC8mr4\/ggbqFbuVWQoL7JbFaYpZbiGhzqwNsU5FnWh7Vsekx3KVuUqWpPwjshxm9LS4bOsrupaKjBakDG41leBBtxvjGmp41BFGkZaSE4sETntdmQ8yGRSX5sFbM04xvvcAD32G0DL\/xCByWHuGgzNtJ6AEHZ1NW7rFuvK0i4iYWXBmn0LTitGDJ4BIIGZtYpmwOGt9xNxXIAOFnMtbgnTqBEGZmcUeDtATcU8qJBXcmEoBjIOuvj1TSGAID\/7MrhIhWl8OC\/xmGJ80Qw2vQROVzRcHs1sY0a3satmH4rGMcs3zmbC6sh6PZcS\/WjmfWItzdGOnrNBKJM3gepd4t66NbW3tfvV\/2Np96uhrY1ss9ybYFsu9IbYlom+GbbHo\/33V1iH3DprnO0t3e5Eu4obk6b4S+v\/Nb\/816wzv7qsjNDqtnhJ3Gk9xg38Kekv6C38CXButd35VQf5JJOzvq2N0L61OuOlQ+mXkJf8CEnmzBxgjMzW8Ukoy\/wM=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/de\/\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Ein Professor der Volkswirtschaftslehre, ein ETH-Professor, ein Fotojournalist, ein Mitarbeiter beim Bundesamt f\u00fcr Umwelt und ein Klimatologe versammeln sich im Auditorium B der Mis\u00e9ricorde\u00a0.&hellip;<\/div>\n","protected":false},"author":13,"featured_media":9829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[120],"tags":[1618,1653,129,1654],"class_list":["post-9839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unileben","tag-jubilaeum","tag-klimawandel","tag-spectrum","tag-tour-vagabonde"],"views":71571,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/9839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/comments?post=9839"}],"version-history":[{"count":2,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/9839\/revisions"}],"predecessor-version":[{"id":9841,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/posts\/9839\/revisions\/9841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media\/9829"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/media?parent=9839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/categories?post=9839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/de\/wp-json\/wp\/v2\/tags?post=9839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}