{"id":1058,"date":"2013-07-10T00:09:12","date_gmt":"2013-07-09T22:09:12","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=671"},"modified":"2021-05-09T14:12:54","modified_gmt":"2021-05-09T12:12:54","slug":"the-philosophers-2013","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2013\/07\/the-philosophers-2013\/","title":{"rendered":"The Philosophers (2013)"},"content":{"rendered":"<p>Cinq ans apr\u00e8s le succ\u00e8s bien m\u00e9rit\u00e9 de \u00ab\u00a0La Vague\u00a0\u00bb, qui d\u00e9crivait de fa\u00e7on poignante comment un professeur peut transformer une classe ordinaire en micro \u00c9tat fasciste, \u00ab\u00a0The Philosophers\u00a0\u00bb nous plonge dans une apocalypse philosophique sans pr\u00e9c\u00e9dent.<\/p>\n<p>Dans un coll\u00e8ge international de Jakarta, le professeur Zimit propose une \u00ab\u00a0modeste\u00a0\u00bb exp\u00e9rience de pens\u00e9e \u00e0 ses \u00e9l\u00e8ves: comment s&rsquo;organiser lors d&rsquo;une apocalypse nucl\u00e9aire, sachant que l&rsquo;on ne dispose que d&rsquo;un bunker de dix places et qu&rsquo;il y a vingt personnes \u00e0 abriter?<\/p>\n<p>Plongeant ses \u00e9l\u00e8ves dans une le\u00e7on d\u2019\u00e9thique extr\u00eame et un utilitarisme sans concessions, le professeur de philosophie se retrouvera \u00e9galement confront\u00e9 aux limites de son propre syst\u00e8me de pens\u00e9e et de valeurs.<\/p>\n<p>Avec un synopsis aussi prenant, il est difficile de ne pas se sentir imm\u00e9diatement emport\u00e9 dans l&rsquo;intrigue philosophique de ce film. Si une partie des sc\u00e8nes se d\u00e9roule dans une classe de Jakarta, le spectateur est rapidement projet\u00e9 dans un monde post-apocalyptique dans lequel le professeur et sa classe vont pousser leur \u00e9thique jusque dans ses derniers retranchements. La photographie de qualit\u00e9 rend parfaitement hommage au sc\u00e9nario et les sc\u00e8nes de d\u00e9bat utilitariste sous les champignons nucl\u00e9aires n&rsquo;en sont que plus dantesques.<\/p>\n<p>Un certain malaise se fait toutefois ressentir. En effet, l\u2019opposition classique rationalit\u00e9\/humanit\u00e9 est abondamment utilis\u00e9e et la pseudo conclusion -\u00ab\u00a0la rationalit\u00e9 est d\u00e9pass\u00e9e, il faut \u00eatre humain\u00a0\u00bb- f\u00e2che et ennuie tant elle est banale.<\/p>\n<p>Pourtant, si le d\u00e9bat \u00e9thique s&rsquo;av\u00e8re un peu d\u00e9cevant, le sc\u00e9nario d\u00e9voile tr\u00e8s vite dans une intrigue beaucoup plus subtile. Naturellement, le spectateur se met \u00e0 la place des \u00e9l\u00e8ves et cherche les limites du monde cr\u00e9\u00e9 par le professeur. Ce dernier intervient tout au long du film en se donnant le r\u00f4le de \u00ab\u00a0ma\u00eetre de jeu\u00a0\u00bb, de joker. Petit \u00e0 petit, on se rend compte que ce brave philosophe n&rsquo;est pas aussi rationnel que veulent bien le faire croire ses tirades utilitaristes. Le R\u00e9el contamine graduellement le monde apocalyptique propos\u00e9 par le professeur \u00e0 ses \u00e9l\u00e8ves et les relations complexes qu&rsquo;il entretient avec certains de ses \u00e9l\u00e8ves s&rsquo;insinuent dans l&rsquo;exp\u00e9rience, rajoutant des variables humaines savoureuses au milieu de concepts froids.<\/p>\n<p>\u00ab\u00a0The Philosophers\u00a0\u00bb r\u00e9ussit l&rsquo;exploit de rendre la philosophie et l&rsquo;\u00e9thique attrayantes malgr\u00e9 une certaine faiblesse conceptuelle. Des passages plus l\u00e9gers \u00e9vitent au film de s&rsquo;enfoncer dans la lourdeur et la pr\u00e9tention tandis que les relations du professeur avec sa classe donnent un niveau de lecture suppl\u00e9mentaire plus que bienvenu \u00e0 l&rsquo;intrigue.<\/p>\n<p>Un film \u00e0 ne rater sous aucun pr\u00e9texte, aussi bien pour les amoureux de la philosophie que pour ses d\u00e9tracteurs!<\/p>\n<div>\n<p style=\"text-align: right;\">\n<p style=\"text-align: right;\"><strong><strong style=\"text-align: right;\">Florian Mottier<\/strong><\/strong><\/p>\n<p style=\"text-align: right;\"><strong><strong style=\"text-align: right;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-673\" title=\"The Philosophers\" src=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2013\/07\/the-philosophers1-300x123.jpg\" alt=\"The Philosophers\" width=\"300\" height=\"123\" \/><br \/>\n<\/strong><\/strong><\/p>\n<\/div>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQwtQAA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"C8lIVQjIyMzJL84vyEgtKlbQMDIwNNYEAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"HclBDoAgDATAF8GiHkz8DtaUBKGh2\/+bONdR0vwCnHHLYI7RnpWrwk0qV7zYy3agnKBKMm19+jSV5emPDw==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNY1MNc1NFAwMLAyMLcyNAIA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"rVc9kxw1EM39K8QGRLe7Z18VrrLvjqJsCCigXHwFZNqZnh2dNZJOH+M9IlJ+AtkVCbemioiM7Oaf8Et4Le3Ozm3ZkJD4ZmekVvfr917L5+7yhTLXQpogpPPDXRCaREhVxY8rRUZ0w9arOGxFTeL+9\/vbL6T4Xq4T3d\/e\/3UirpMS9bCtvOqlirymkcNv1ghn1dpIE0lUtuvIRJHw0tuGQqDkhaMURfQ4uLG+I4\/PWKolvgrra2Wk8iT4fFV5K4afo4yIHSoVIp3kTL5tSbxqlbbBupZ84IyEsSkIp61Zk6i5LI4rna2kvnGI7fYb1HVCpbwCdW+rYVsjycX50l0+OneXL8tWJK\/1cIdYCqV4I6OyRmqu83P5WvooTxiwSV0\/qA444IWzOI0P51Q7WxPyzhnSxjGkZCriOI5MGLYkhlsRKIhhi\/N6Cs9G3MKHPlwn+9z6tTQqACptfRD17vVRfSZVetgyeCeormrRAsGV6n0UI7ChViHnx18OgcQqmdeIX\/OCDVCUFTIiDrBbo7S4EVL0yqxRJDC3xnDSt0KuwBLyH+8BfJVbwKdPqzq0RFOmSf33T78M21i6QZvoh7cd8ZHIJkWlVZRehW7XqcoCtBDQg3CMez1tLZaT8BS9TT15iePXUlNGEyEabw0TWqaN0NwuzgtbbCaoA+3CTYjDXfegP5TZ3SNO8mHkySc9VZxruDHWBQUVJeSHOMTkPxEADI0HnE2jKqVzRFTvZOAUAzJSXqgOIquVjCVF6pz1WXFc875xIKBX0N0RgxEPPGqU7hbiG5WhdeCl4i84AzrmBuEsqBRw6Ikqdmo74nJwVEFrjCln7qVTdckL4FzRmBeK7qxhgGyI8z0DY0kqJ0541EdtAopB7k\/uLUeFYDOp+fNIhasUxkAh98cbBb7lrkpTtTmlsBCwI9faaNdItM1Vg61SZ8dCE2pGo4E1lRJaaEpCzTIxNFsDclnOSU+wqjNWK9jNgYCR6ZFCXgdNdQ7mBhJO1IbnXaPgWcHuVOd0ypwHxfDzQJvv4CwExBVAlFqqzAXBeYpoU6TGKi41FIIsxKdGUNMQCKUhGOuAuWIrKkhmxPzOm7jyZZs6eAVjwD2UKzRK7lyYa9oTWgM8tKW2WVnIlUPO2bDwZRqwkHjYgre8N\/O6kXDw4W2EXvg4Zdjd5qIZfkV3ODoZk9CRyCZAGjzgICuJkDQC8comH7NSoBo9Ij\/yYG9+sh\/uPOUZQilPHOrzNmbs2Em87y2rLOZR1qPtB7qPAlqRTJVNrnQnpBUgoYX4SsbkOU\/G6VgK6E6HkmB0jBkbY9bX6Gv4hqo9V84cGW0l7URSYcYARpDxoSAW4gXtyV1mTK+4TcwCZim7KEdhgfM0ZL3CcxlSxPHDn8VS8oyRwx\/cDPy8olTGMz9bWPpCvKKocv6OH06ENcUjoRAMGhfLLEBZKy\/7icnQgdfoHvtWcbjCDgOB876e4CzIKd8YdGay56It\/2H9gsWSAZtKitVL4mvwSTP\/ouwU2gQh12nfBo5VAHxoMGW+vgvQ4zm6Vzc6mzMOuVxNG7ybjjUcBmvJ2Ev29J08y2SYxgujHwdlEq9\/YNOT6X4CkK7QR24W196jbLniZIpeOJjsIQBKfAK63QEcpjeVSediEBhWqj4Yx3vvPeAX9yVOE9G2XMm4y+gDM3cyIumwdpSbjHDXm+xXbExrRC2joqCRG8sVhDHD3KqFeIkNbA4w11B0BV9cs2FDkpCCyWzOLK4PqibTcBS\/g1CC7snXuznB6eJ83su2BBhxayl3mQf9hDom7c\/NO4wYFsvu8mlUD+Hz8RqyTkzM5BzSZKJlvua8+QCmcU8mZb0fzd+ph+d6sMZk+0UdeUjAXfJdl3Pf8GW1KCZrA9PO5\/xllxu\/yfk8bEwmuM2mE9jS0JKKTSh8UI6uVc8JiBBvNF3M+JA5bHptnglk2Mbns\/\/6fB5wNTLr\/d9\/W\/oZLptKGvGljVCHP1\/utx4e3P943Lnq1mCBxH8A1hczLX+8mQGhypbfEtesalZ6i1+8NW\/E8PiR5h3VKnXijZsrHvLzj56ezWA8kc861sxMBF9dzNoY3bMlSkn59p+MavyiapfZ+X3qlgjG1oSPy+Q4r7B8cvr4bHn6dBlbmrtJyMfzs9PTzeMnZ4srt54JqeO7jn2j6thezLB0Jlri5C9m2DMTy8vzlce\/j94H8TL3\/R8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Cinq ans apr\u00e8s le succ\u00e8s bien m\u00e9rit\u00e9 de \u00ab\u00a0La Vague\u00a0\u00bb, qui d\u00e9crivait de fa\u00e7on poignante comment un professeur peut transformer une classe ordinaire en micro \u00c9tat fasciste, \u00ab\u00a0The Philosophers\u00a0\u00bb nous plonge dans une apocalypse philosophique sans pr\u00e9c\u00e9dent.\n<\/div>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2272,160,29],"tags":[377,107,692],"class_list":["post-1058","post","type-post","status-publish","format-standard","hentry","category-archives","category-culture","category-news","tag-film-philosophique","tag-niff","tag-the-philosophers"],"views":1314,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=1058"}],"version-history":[{"count":1,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/1058\/revisions"}],"predecessor-version":[{"id":12902,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/1058\/revisions\/12902"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=1058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}