{"id":11196,"date":"2020-04-22T17:30:28","date_gmt":"2020-04-22T15:30:28","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=11196"},"modified":"2020-04-22T19:01:11","modified_gmt":"2020-04-22T17:01:11","slug":"covid-19-consequence-de-la-crise-ecologique","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2020\/04\/covid-19-consequence-de-la-crise-ecologique\/","title":{"rendered":"Covid-19, cons\u00e9quence de la crise \u00e9cologique ?"},"content":{"rendered":"<h1><strong>Depuis le d\u00e9but de la pand\u00e9mie du Covid-19, l\u2019inqui\u00e9tude sanitaire ne cesse d\u2019augmenter. Dans le m\u00eame temps, des mains pointent du doigt la faune et la flore qu\u2019on voit ici et l\u00e0, enfin, \u00ab\u00a0respirer\u00a0\u00bb\u00a0! Mise au point avec Philippe Roch et Dominique Bourg, tous deux sp\u00e9cialistes de l\u2019\u00e9cologie.<\/strong><\/h1>\n<p><strong>Un lien de causalit\u00e9\u00a0?<\/strong><\/p>\n<p class=\"dropcap dropcap-borders\" style=\"text-align: left;\">Le virus a voyag\u00e9 de Chine vers le monde entier. Un peu comme le gobelet en plastique qui a d\u00fb faire Hong Kong-Zurich, pourrait-on dire\u00a0? Avec la mondialisation, toutes les conditions sont r\u00e9unies pour causer et augmenter le d\u00e9s\u00e9quilibre des \u00e9cosyst\u00e8mes. \u00ab\u00a0Une situation id\u00e9ale pour qu\u2019un microbe parte \u00e0 la conqu\u00eate du monde sans \u00eatre frein\u00e9\u00a0\u00bb, nous apprend Ph. Roch, Dr en biochimie, \u00e9cologiste et ancien directeur du WWF Suisse et de l\u2019Office f\u00e9d\u00e9ral de l\u2019environnement. De son c\u00f4t\u00e9, D. Bourg, philosophe \u00e9cologiste, professeur honoraire \u00e0 l\u2019Universit\u00e9 de Lausanne et directeur de La pens\u00e9e \u00e9cologique, rappelle qu\u2019avec le Covid-19 \u00ab\u00a0nous avons \u00e0 faire \u00e0 une zoonose, une infection d\u2019origine animale\u00bb, pr\u00e9cisant que \u00ab\u00a0le coronavirus a pour esp\u00e8ce h\u00f4te un type de chauve-souris dont on a d\u00e9truit l\u2019habitat et qui pour cette raison se serait rapproch\u00e9 des habitats humains.\u00a0\u00bb Il poursuit\u00a0: \u00ab\u00a0quoi qu\u2019il en soit, la destruction des \u00e9cosyst\u00e8mes et des populations ruine les \u00e9quilibres entre populations et suscite des pullulements de pathog\u00e8nes.\u00a0\u00bb On peut donc clairement confirmer que c\u2019est la crise \u00e9cologique qui cr\u00e9e la crise sanitaire\u00a0!<\/p>\n<figure id=\"attachment_11201\" aria-describedby=\"caption-attachment-11201\" style=\"width: 200px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-11201\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2020\/04\/Philippe-Roch-399x600.jpg\" alt=\"\" width=\"200\" height=\"301\" \/><figcaption id=\"caption-attachment-11201\" class=\"wp-caption-text\">Philippe Roch, Dr en biochimie, \u00e9cologiste, ancien directeur du WWF Suisse ainsi que de l\u2019Office f\u00e9d\u00e9ral de l\u2019environnement. &#8211; Cr\u00e9dit Thibaut Kaeser<\/figcaption><\/figure>\n<p><strong>Pas assez alarmante, la sonnette d\u2019alarme\u00a0?<\/strong><\/p>\n<p>Depuis de nombreuses ann\u00e9es d\u00e9j\u00e0, des sp\u00e9cialistes ou de modestes citoyen\u2219ne\u2219s crient leur d\u00e9sarroi face aux violences faites \u00e0 l\u2019encontre de l\u2019environnement. Et le risque de catastrophe humaine ou environnementale n\u2019a jamais \u00e9t\u00e9 aussi explicite et \u00e9vident que depuis ces derni\u00e8res ann\u00e9es. Des visionnaires, tels que Jacques Attali en 2009 par exemple, ont m\u00eame lanc\u00e9 des avertissements sur une \u00e9ventuelle crise sanitaire plan\u00e9taire et ont \u00e9voqu\u00e9 la fort probable r\u00e9apparition du coronavirus vers \u2026 2020\u00a0! Les autorit\u00e9s n\u2019ont-elles pas \u00e9t\u00e9 assez attentives\u00a0? D. Bourg remet sur le tapis l\u2019attaque du Covid-2 qui a surgi en 2002 avec le SRAS en Chine.<\/p>\n<p>&nbsp;<\/p>\n<p>Il souligne que \u00ab\u00a0Ta\u00efwan ou la Cor\u00e9e du Sud ne l\u2019ont pas oubli\u00e9 et ont remarquablement lutt\u00e9 contre la pand\u00e9mie.\u00a0Du c\u00f4t\u00e9 europ\u00e9en, \u00e0 l\u2019oubli se sont ajout\u00e9es les politiques n\u00e9olib\u00e9rales de saccage de la sant\u00e9 publique. En France par exemple, on poss\u00e9dait jusqu\u2019en 2013 un stock d\u2019un milliard quatre cents millions de masques\u00a0!\u00a0\u00bb Aujourd\u2019hui, suite \u00e0 des politiques ayant imagin\u00e9 un futur sanitaire sans vuln\u00e9rabilit\u00e9 particuli\u00e8re, les stocks n\u2019ont pas \u00e9t\u00e9 renouvel\u00e9s et il y a p\u00e9nurie de masques. Ph. Roch n\u2019h\u00e9site pas \u00e0 relever que \u00ab\u00a0nous assistons \u00e0 une incroyable mobilisation collective plan\u00e9taire contre le virus\u00a0\u00bb. Selon lui, la situation actuelle devrait permettre une mobilisation pour stopper l\u2019\u00e9rosion de la biodiversit\u00e9 et lutter contre les causes des changements climatiques, ajoutant que la situation devrait \u00e9galement \u00ab\u00a0mettre fin aux graves injustices qui frappent tant de populations, de groupes humains et d\u2019individus sur l\u2019ensemble de la Plan\u00e8te\u00a0\u00bb.<\/p>\n<p><strong>Quelle le\u00e7on apr\u00e8s le chaos du Covid-19\u00a0?<\/strong><\/p>\n<p>La liste des catastrophes environnementales est longue. Tr\u00e8s longue. Mais quelle grosse catastrophe faudrait-il pour admettre des limites\u00a0\u00e0 la course de la croissance ? Quels moyens employer en plus des manifestations et de la d\u00e9sob\u00e9issance civile pour d\u00e9fendre les id\u00e9es \u00e9cologiques\u00a0? L\u2019ancien directeur de l\u2019OFEV souligne que \u00ab\u00a0la d\u00e9nonciation d\u2019une situation intol\u00e9rable par des manifestations est utile, mais il est encore plus important d\u2019annoncer un monde meilleur et de travailler ensemble \u00e0 son av\u00e8nement dans la joie et l\u2019esp\u00e9rance.\u00a0\u00bb Selon lui, il faut donc garder espoir. D. Bourg interroge les d\u00e9cisions gouvernementales\u00a0: \u00ab\u00a0Si pour \u00e9viter des centaines de milliers de morts, qui est le bilan probable sans confinement dans les pays europ\u00e9ens,\u00a0les gouvernements n\u2019ont pas h\u00e9sit\u00e9 \u00e0 stopper l\u2019\u00e9conomie, pourquoi ne le feraient-ils pas devant un danger annon\u00e7ant des centaines de millions de morts \u00e0 l\u2019\u00e9chelle plan\u00e9taire\u00a0?\u00a0\u00bb Il rappelle que d\u00e8s la prochaine d\u00e9cennie, nous pourrions conna\u00eetre des effondrements r\u00e9gionaux de la production alimentaire, comme en Australie cette ann\u00e9e. Autrement dit, si ce n\u2019est pas le Covid-19, t\u00f4t ou tard d\u2019autres catastrophes nous contraindront \u00e0 baisser la cadence.<\/p>\n<figure id=\"attachment_11197\" aria-describedby=\"caption-attachment-11197\" style=\"width: 227px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-11197\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2020\/04\/Dominique-Bourg-480x600.jpg\" alt=\"\" width=\"227\" height=\"284\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2020\/04\/Dominique-Bourg-480x600.jpg 480w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2020\/04\/Dominique-Bourg-768x960.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2020\/04\/Dominique-Bourg-960x1200.jpg 960w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2020\/04\/Dominique-Bourg-530x663.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2020\/04\/Dominique-Bourg.jpg 1024w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><figcaption id=\"caption-attachment-11197\" class=\"wp-caption-text\">Dominique Bourg, philosophe \u00e9cologiste, professeur honoraire \u00e0 l\u2019Universit\u00e9 de Lausanne et directeur de La pens\u00e9e \u00e9cologique. &#8211; Cr\u00e9dit Roberto Ackermann<\/figcaption><\/figure>\n<p style=\"text-align: left;\"><strong>Un apr\u00e8s Covid-19\u00a0?<\/strong><\/p>\n<p>\u00ab\u00a0Je crains qu\u2019\u00e0 la fin de la pand\u00e9mie, nous assistions \u00e0 l\u2019explosion des forces \u00e9conomiques et politiques du pass\u00e9 pour r\u00e9tablir la situation d\u2019avant sans rien y changer\u00a0\u00bb, nous confie Ph. Roch. D. Bourg est du m\u00eame avis : \u00ab L\u2019\u00e9conomie doit \u00eatre un moyen et non une fin\u00a0!\u00a0\u00bb Les deux sp\u00e9cialistes s\u2019accordent sur l\u2019importance des diff\u00e9rentes questions \u00e9cologiques\u00a0: la biodiversit\u00e9 et le climat qu\u2019on ne saurait s\u00e9parer, les modes de consommation et le mod\u00e8le \u00e9conomique.<\/p>\n<p>Ph. Roch conclut par une invitation \u00e0 agir\u00a0: \u00ab\u00a0Puisque nous votons souvent en Suisse, nous pouvons nous engager politiquement en faveur d\u2019une civilisation plus douce, plus solidaire et plus \u00e9cologique. Profitons-en\u00a0!\u00a0\u00bb<\/p>\n<p>&nbsp;<\/p>\n<div class=\"content-block block-border-all\" style=\"text-align: center;\">\n<p><strong>Pour prolonger la r\u00e9flexion\u00a0:<\/strong><\/p>\n<p><em>Croissance, d\u00e9croissance, pour une transition \u00e9cologique<\/em>, Ph. Roch, Jouvence, 2018<\/p>\n<p><em>Le March\u00e9 contre l\u2019Humanit\u00e9<\/em>, D. Bourg, Puf, 2019<\/p>\n<\/div>\n<p><strong>Illustration :\u00a0Antoine Bouraly<\/strong><\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQ0tDQDAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c84vy0zRNbTUUUjOzys+vLKwNDUvOVUhJVUhJ1EhuSizOFXh8Mrk\/Jz89EyglII9AA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DclBEoAgCADAFyHmdKnfNEjJjKEJ9v7a6xb3bjui+cysHqbKOQIVtM7kY96YYooYV6T2SoZlA2pq\/ExWYsgM9QAaYgxMrbZL\/sEP\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"800tykzNVfAvKUktAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtA1MNE1MlIwNLcyMLEysgAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"vVnLchzHEbz7K1rrCIUVsYsXaZKgAChoUgo9qBAtSlaEL47emd7dpma7B\/0AAZ509C\/ohpMFyBH2xTfdsH+iL3Fm9cw+AJCWbdoHgruzM9XVWVVZWT0Hs92jg5iCd9OjJ6bNNqrGqHpxOc5J1UY1WrXa4fvc4nJWj\/2JrUe7+0PV\/Pzd99YdZ7u4TBl3Ru1s0jYY5YyqTIy4H7foPJ0bl0zYUk+0E+vzxY9zo5KZt3GINaKaa4tfWm9xn0tcpvZ2mrj4RGeYM+Vz42H9OMOqd+rE26RsZeXHxflQGTexbqiu\/np1Hkxs4Um4Or\/66er8HfW5hTc6lyWUPjGVejazjW1bo7701Yw2nvi5dfY4G\/U7n8N0qJLPEe7lUxXbxWVldWNjMlFQgQu45Bs\/tWbrYLsD8GAbaP7qoF0i+rVTjTWOj1Q6R1hIi8ur8w\/Wnmj5gKoaHePhoA6+rXSruv9HYx9qE+JAxXTWmMNBMqdpBCtT9xBATtL7g6OnRp3YAE81EDnT08UlV3s8s4DtBM8K4N7hGqC1DAOcak1WlZ8jCvh16semAQDws4UbSTBAXGGxXvyECDCmH8Nb9Rn+jP6Yg61mQ2CZQ9A2jRCLGrdgW+oRkUWkuKDgpZP1TqAkcg3+VfyJV6OKHsEIi8vsrIliT1AygeFY5k2Xj3FxCZ8aO4YzzBnCH89iWlzMTdySqH+NLUebsiyqLB7SeFbsStJkp+a2CtgucjokoxbndBYeHefFj0nyu0AVmam4hLUmwVjHoF39NFSOKaHbNhhXI4O2JHmG6kkgeGOLLxZ1MlR9biBfZC+ukiwASlUycAcLffPNR+o5yi3KHV1OfTGZ2AprLi7hfNBNf904xNg7ZwgJCskQO1Ut\/oF0wvJbfcq2SGoffTsz6y7gevATViSWnnnng4SUu4ftr51lnjAzudxT5qkrNbfmMH9A2jiEYWUbiTJUAXiYpukKU2oLX3qekMAU2E4Ycyw66VdnZb\/y8CfCDL9YN8F6DB6Zwwc7ZRaDV+YIJPFvAwsR\/iXFJKVtrFV5YKP7KpB4o\/4XF0ByBogMbKt01hopw5nOJ2YUcROormYGYjlm+mUKGYxCSGZ6DCpLhIB1UDLTJFgCckQeQUOaIvll9wFxF\/Ci6p7EhyyktsW8UZ80YiPC\/tX5Q3H7OHtbELMNkyeCzYbMRliBIx0K1\/O8pAprpc2NLlUEr52R0lpVSGSxB7NxHx6NOVY2lfrBD01uJKGE0lqdZn66uHCmc\/oLoYlEjCryE4LGm1kuExvmJkgIKmZnFHquAll2LTcEvCowY5Y\/L7sEaLmQ38ROM1y19eFAp6SrGVf50+7u3s7uQOlg9Qju4uGxqcdnhwPQIvczWt076u7tOPKlrdPsodrb2WlPBz2xvmxH3YNK6JPkOTg6sPOparyurZseDhr96mwAKCpfvut45qqlBQUTyMOpWS4XqsPBLKU2PtwGnaMFojRBZZOwVc22Y4tMDnm+zZW99LXt3HKtuL23s7ezvXN3u29BI7LI6M7+\/um9nZ2tF+0U+27S4QBrci+HA+xloGbGTme4eoeLbx8Rt35LxO71uNyAYMQ2Mjja6IBvJrHhv6Iw5rqVhPj3mOzdXz\/Y2919Xz1GlqAtqK9mdqyRdJ9pgwI72F5t8ki+IFM2GuwzjZKHA6+AmA5zEIORKopcggUrEoQ\/mVvabq944Jvzc9QNmg\/sOfA9+\/zi8gV1BatlUwH4zEfmnrXKlmaTPzPu5z9\/7wz+RKY6K6URnNC6dAio9omuKEJO0a99YxwkEqmQBjomxjUvZXs7Vh\/SokIVdTBXOmnuh2xf6MbQs42n2AAdIVAvNO4gR5DnwfEIlzltGyuEAG5YXIKwTUesdcGlErUTnF1chBUw7D8Rm4iIimMpQ8Ul00R58lNd4b+oHiENG8uMQvLus99iOSi+BvEh6RYN2CCtOuZE4wiJuVQYKQI6tgS4he9ZGsw1BqFagUPls0liFrd7NPNLkYs+JHa+sR4TN6iBFm7Ywqx5o2uIUPr5u78oliYF41N6lBNaEOCKAiHMj+gGqFMvcSypl1je6KKRGqjvxop8mWQjWD7pltKaoQAygnEvpvc6sYU7pz1ie6pvpM+\/fPScF0XRbfWJ+64bx\/b9\/hv6Cxoaec0s++JXevH3l9oxI4DFYy80jDWf55oCvSk7kr34PG6g4nsM4bcOx5moCeE3OXGvXW6uDwRoFE9yJ0MUkt2jSgzkXpfPYld6Jc3qFxCBUliCoYcWtpIqiCG+jIUmiryOuqrAtN38wXYP+y2t4QEUglMfBWSOuZ5WsBohUGo25hc5SnsVPHfvUAPE5KtvhRFECTaN1aEGYJr7qiTt5Cq7Jetbs9IQ03ekHz7K2EDg07Nsh4rNXFRMvbkbfUZ1wk5B2chlJzkhB1ZpK+LyJDeOOx5bmQlEkNoKMWSpDQUicXeZe2tZB\/XpIWIaZiZiBgFxRt2zuHQQNWbN9a2lRhUrECmRToulc5hpzEnXxlcqDcSAhYtSK5oMivlMSmju6W3R9EgH1ELFrN+owz5LuqmEyG2p56bBEw1hYzyXEl1XXWXX5kTUVGtA1IkGuPTGeiLC4BkaVujmr+BjUUm0isZVr4SsKWmLW5cOxTJcRAkYZKCbdlRTNYhWid6wZGmvLzec7X1cXE51VxlErfMXo6dw+zSgcCNQQ\/4hoCZKcU9EJOMJMV1vCDM2GDzmc2uWslF0nszX2JOtc+HD0hPAkOOmr41nhP4iGcG5p4O+Of6+gNuYxQ8EG+L5QsZBbN7H9WH+ttYIuS\/drsC1ajXxRoPBFQpAPMzi\/Kqs0n37nD3nuPiBPVIqrLctTPe1zJC2KGSl6w5Proq4sD1enfdzGiR0v3EkJZqFkMAHihtF7bIJwxmwAT6FMs\/m2J0wQJjBzZUWLmbYnT2op7dVAe5+ZsRvE8x5XfJwnOzkeCdvhe2fktFvaKNOA3304R9uEnNZ1UFVW72cdfLm6OqSb4QdmsJxt20BmOdkSXzS2DlGRA7xlZfWiI3beYsWKBknXnJNw7baTblzA7ajvwWOhNTVvELouiwD8px39AkHA8n5Wg5xoCe8LecyMgC09BbWy+iwVu9wa6L7KWKqeZzB4cxbngf1nZLnPpBI04J0LTOebHJKngurTOunp+fdUEbRwiKXHOU96JGFu8njbOqi00JClbEOJVENuAJls5IGQsgy1mzsUTr9WVw1tjjkuLnp1SY\/F4YF\/xC3Da6CeS+qmn7L8CdDm5pwjKRYt00RFqAZRgxBqklRQUncFj8U4rhtm3274jb71osFZ1J0a9yMdO2n0bWZnYcrFxJRmWNFRTICxjm6K01BjnpknYqSb\/G3vkLNZOJZIQUJSIwp7iINdieHwdfdKAsxKEG07G7l6Akl8wgkia5vTTdeF4W5heupmzZrjsXQqlXRsQwgUVo7YYD4hAChzkls5+XMMYXrrCUbkWaALdZBxOK5GmtKziCMomuK8q03T6W7+\/d\/8VQq916bSvfuv2EqDZzw\/vOxtKz3X4+ly4PQkVTn6O6DndcOpnv3V4Pp3oO7snw06X\/ngcLnl0P1Vs3fv\/fgdP9eMY\/Pb9s8TJ9iEi\/28eVt2\/\/tHaBz746Yx+e3bF7M7u7s3X2J4NpXBjnHwWiofjPXp6P1tH4Pt+2cYPkuyX\/hGYVk7evOKG4cyv\/\/TzhvHlJ86ceYVb16VH1reObgXntO8YZz+7VXBJ0ye5MaY9P7lBOwqEMZbIooou689pqmP6YWJW87KS9tGvN+L5kjx+OqEzRsTTK8AJG1UQYKEVwbOZ2w2Qb2Ecxg4ZoullNftifpozz6wDxSBHZYOzaXBmuWE8la+yep8+hdjgQwkUfFLi\/Satk4+UYodUfyImCg9egueqPMCsChH9Semltf20T6WVV8o+LSUk\/3GqkqDa22kwmkDF88iG7tAdxQfQ9vnzdMN0ks31BR0+ksQwNAhI4zoUx2cnIkRzgwjl5YgCw28NviojHrcVkK++U0h58qzDeiDcuQdmKLMGSsMXqGXik9y+W8SEJw4lN575J5qMIGXI7vVm1ezujli3FTTfmxzId598gEAw7rpVOtopiXQ5robZ8rViQ\/Rzxd9wc0cmWjsp6hai19Gpk+fLedcADoniE61hqNG87y8rd7S4b6am59UVbJaySU3MbBITMapMFBpfR\/pPekMafYBrC7UYAHZn70eDlzDEUirX2VAiEckBculjOmtZ0ebOPx4dobo08lBHxyb2f3wfoiTw2GpiAvFPrRFUh\/nCn\/kWmdpdUrn2d5Ikb2i5FtYLWx0U+aRkSWuPTw6vwRZgtqPD6um7PNjf4T\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Depuis le d\u00e9but de la pand\u00e9mie du Covid-19, l\u2019inqui\u00e9tude sanitaire ne cesse d\u2019augmenter. Dans le m\u00eame temps, des mains pointent du doigt la faune&hellip;<\/div>\n","protected":false},"author":91,"featured_media":11199,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[1840],"tags":[1826,1943,1944,1946,327,1202,1945,1947,1912,129,714,161],"class_list":["post-11196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coronavirus","tag-coronavirus","tag-covid-19","tag-crise","tag-dominique-bourg","tag-ecologie","tag-fribourg","tag-pandemie","tag-philippe-roch","tag-sante","tag-spectrum","tag-unifr","tag-universite-de-fribourg"],"views":3785,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/11196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=11196"}],"version-history":[{"count":5,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/11196\/revisions"}],"predecessor-version":[{"id":11205,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/11196\/revisions\/11205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/11199"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=11196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=11196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=11196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}