{"id":12258,"date":"2021-02-07T12:39:44","date_gmt":"2021-02-07T11:39:44","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=12258"},"modified":"2021-02-22T15:19:15","modified_gmt":"2021-02-22T14:19:15","slug":"apres-covid-films-en-streaming","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2021\/02\/apres-covid-films-en-streaming\/","title":{"rendered":"Apr\u00e8s Covid, films en streaming ?"},"content":{"rendered":"<h1><strong>La pand\u00e9mie a mis en perspective notre mani\u00e8re de consommer et d\u2019aborder la culture. Mise sous projecteur d\u2019une situation plus complexe qu\u2019il n\u2019y para\u00eet.<\/strong><\/h1>\n<p>Le confinement a du bon pour les plateformes de streaming. Disney+ a gagn\u00e9 plus de 86,8 millions d&rsquo;abonn\u00e9\u00b7e\u00b7s en un an. Netflix peut se vanter de 15,8 millions au lieu des 8,2 millions attendus rien qu\u2019au premier trimestre : 2 millions d\u2019abonn\u00e9\u00b7e\u00b7s juste pour la Suisse. Xavier Pattaroni, programmateur des salles Rex Cinemotion \u00e0 Fribourg, ne sent cependant pas le cin\u00e9ma menac\u00e9 par le streaming. Il rel\u00e8ve que, malgr\u00e9 cette augmentation de visionnage en ligne, le cin\u00e9ma a avant tout un int\u00e9r\u00eat social\u00a0: \u00ab\u00a0Malgr\u00e9 toutes les installations maison, je suis confiant dans le fait que les gens auront envie de sortir.\u00a0\u00bb<\/p>\n<p>Le principe des fen\u00eatres consiste \u00e0 donner la priorit\u00e9 d\u2019un film aux cin\u00e9mas. C\u2019est apr\u00e8s qu\u2019il y a un passage \u00e0 la t\u00e9l\u00e9vision, puis en VOD et enfin des sorties DVDs (si une demande existe pour ce type de m\u00e9dia). \u00ab\u00a0Les r\u00e9alisateurs sont conscients des recettes non-n\u00e9gligeables\u00a0\u00bb, affirme Xavier Pattaroni. Universal a fait du bruit derni\u00e8rement puisque le studio a sign\u00e9 un contrat avec des exploitant\u00b7e\u00b7s qui permet \u00e0 ces dernier\u00b7\u00e8re\u00b7s de diffuser apr\u00e8s trois semaines seulement les films \u00e0 la demande (VOD).\u00a0 \u00ab\u00a0Un film qui a march\u00e9 en salle, marchera en VOD et un film qui n\u2019aura pas march\u00e9 en salle, ne marchera pas en VOD\u00a0\u00bb, explique notre interview\u00e9. Exception faite s\u2019il y a eu un buzz ou une pol\u00e9mique sur ledit film.<\/p>\n<p>Les cin\u00e9mas sont donc sous pression pour ne pas voir se r\u00e9duire ces dites fen\u00eatres\u00a0: \u00ab\u00a0Je suis convaincu que cela d\u00e9nature le cin\u00e9ma, si les studios de cin\u00e9ma vont dans cette direction, nous n\u00e9gocierons les prix car il n\u2019y a aucune raison pour nous de payer le m\u00eame prix si nous n\u2019avons pas l\u2019exclusivit\u00e9. \u00bb Le programmateur du Rex ne voit pas d\u2019avenir dans ce concept\u00a0: \u00ab\u00a0Les salles de cin\u00e9ma sont une vitrine publicitaire importante. Les studios le savent, et si en situation de crise, cette strat\u00e9gie peut \u00eatre un mod\u00e8le n\u00e9cessaire, ce n\u2019est pas cette derni\u00e8re qui va nous tuer.\u00a0\u00bb<\/p>\n<p><strong>Le monde culturel n\u2019a pas attendu la pand\u00e9mie pour conna\u00eetre la pr\u00e9carit\u00e9.<\/strong><\/p>\n<p>Cinemotion, sur ses trois sites, compte une cinquantaine d\u2019employ\u00e9\u00b7e\u00b7s. Pour la majorit\u00e9, il s\u2019agit toutefois d\u2019une activit\u00e9 auxiliaire, seul\u00b7e\u00b7s 14 d\u2019entre eux\u00b7elles en font une activit\u00e9 principale. Le cin\u00e9ma Rex a pu toucher les RHT et les assurances perte de gain. Ainsi, depuis le 18 d\u00e9cembre les auxiliaires qui ont un revenu inf\u00e9rieur a\u0300 3&rsquo;470 francs touchent une indemnit\u00e9 de 100% en cas de RHT et un maximum de 3&rsquo;470 francs en cas de perte de gain compl\u00e8te pour ceux dont le revenu se situe entre 3&rsquo;470 et 4&rsquo;340 francs. C\u2019est plus compliqu\u00e9 en ce qui concerne les APG.<\/p>\n<p>Un v\u00e9ritable d\u00e9fi pour toutes les personnes travaillant dans le milieu artistique comme les technicien\u00b7e\u00b7s lumi\u00e8re, son, les acteur\u00b7rice\u00b7s, com\u00e9dien\u00b7ne\u00b7s et tant d\u2019autres. Il faut se souvenir qu\u2019il s\u2019agit l\u00e0 d\u2019un milieu qui travaille essentiellement sur mandat. Lors de la premi\u00e8re vague, les th\u00e9\u00e2tres et salles ont pu \u00eatre indemnis\u00e9s pour les repr\u00e9sentations annul\u00e9es. Les artistes ont donc pu toucher leur cachet. Une chose que la Conf\u00e9d\u00e9ration a toutefois omis de prendre en compte, c\u2019est qu\u2019aujourd\u2019hui, plus aucun mandat n\u2019est propos\u00e9 aux acteur\u00b7rice\u00b7s culturel\u00b7le\u00b7s. La situation est bien trop incertaine pour cela. En somme, cela signifie qu\u2019aucun revenu n\u2019entre pour ces personnes\u00a0: \u00ab\u00a0Ceux engag\u00e9s \u00e0 l\u2019ann\u00e9e par une infrastructure (comme l\u2019Equilibre) ont un salaire fixe, pour le reste, \u00e7a fragilise beaucoup de gens\u00a0\u00bb, confirme Xavier Pattaroni.<\/p>\n<p><strong>De l\u2019optimisme vers l\u2019au-del\u00e0<\/strong><\/p>\n<p>Le grand public a su montrer son soutien \u00e0 Cinemotion\u00a0: notre intervenant a re\u00e7u des dizaines de mails et a \u00e9chang\u00e9 dans la rue avec nombre de passant\u00b7e\u00b7s. Xavier Pattaroni propose aux int\u00e9ress\u00e9\u00b7e\u00b7s d\u2019offrir des bons, qui ont une dur\u00e9e de validit\u00e9 de 2 ans. Un bon moyen de partager sa passion pour le cin\u00e9ma en attendant la r\u00e9ouverture des salles. Notre intervenant conclut avec ces mots\u00a0: \u00ab\u00a0Lorsque j\u2019avais des baisses de motivation, j\u2019aimais aller dans le corridor de la s\u00e9ance et observer les gens regarder l\u2019\u00e9cran. Le fait d\u2019aller en salle est \u00e0 la fois un effort, un acte politique, culturel et un partage d\u2019\u00e9motion.\u00a0Car au final, m\u00eame si vous vous rendez \u00e0 deux ou en groupe, m\u00eame en \u00e9tant tous ensemble, vous \u00eates seul face au film. Cette double dimension me motive.\u00a0\u00bb<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQyMrUAAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"cywoOryiWME5vywzRUchLTMnt1ghNU+huKQoNTE3My9dwR4A\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcHRDYAgDAXAicpDPt2GQNEmUklbnN+7O2L5CXjszhppqwxL7YYvbmF7ouRyIBfUZezU3k86DXmmEyt5GNcpeuEH\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c8zJzEtVcCtKTM\/Lz8kEAA==\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtQ1MNI1MFcwNLIyMLIyMQEA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"bVjLjhzHEbz7K+pig4RHQ1KibUJeEBCW8gsriZAtwdea7uzZWnRXDau6xrM86Td8I3wRVwZ85UG37au\/wl\/iiKzq6aYoECCHs\/XIioyMjNyL6yfPL9IYg98\/v7LmYH073Q1OjDWDS0a8OUhMB2lGdxTjwxjFDNa76S0+tGKa4FMYBolGRtP+77t\/2l2ILf7bW9PkfsxRtuYLl8SkkJM5xHCDsyRHXZw9vndjtqMLuKnHiiYMh15OYl5lLHC98fjnFoFFO\/1n3F48qsFePELkv7g4PL\/SIDrnZRA\/Iu42mx1PC7ikF9zZ21G6EAd8RsTYL3Zwfr81L1zycvtr7NnbvZ\/uSgRY8+y3m2d4f98jLHzxq5he5fB7PM1j1f07uX+n0GRvrN+aL2XsencCUnk0eOnR+hEI4Jwnv1mfY7PpnWT8IJlnm49XPxhH8S2ujg6n6sOx9hAFiYhmjA6hE\/hPzWpTBXsV0U1Oo9R3W\/PX7FIC+H+3R57yEpdYIOc2TMI+2mGwJQ+IJtmeSH0tJ3NJIIPmY3pj\/hDdDuftN4aZIr6NHBArXoiUJOBrGocIBtBFvG2IoSXsa5j\/3Jso\/fT2yKTKBvzp9xErG8G7gcqeiSsUAGZHl\/DJ270Q4t7tPbas7sEfAmzGALSRAefH6S5OPwD60Djb37\/51Nz\/+\/7NF\/UWrpOkTHA+jXipXpUQhkvBb8wNggVWhUU8Ga\/Tl3XWjYxY9+5FMwgER8QFSJVLIY4ubu\/f3P948egw0\/EQnW\/cQRTaTjxii6LnJ8cMAdcWLyxFgsUhOjyhFoTpXD\/gotP84LQ1l\/gJGGDsIU5v07kyboEFNiAPiWjhWJyHk\/rproCIVOdSxN9+9YIFKqyTknFGjn9ffPsimQfJGZZiKyhtPEtO7sykRsx4q28xw3TXOvtwq\/BeYTPgtb1LyiMeSXrgkQ1YPCa9JoomOUE5\/Ed4zh75FLsDoMRsY2zXORTmByTdmm88BCeCmHikJoJlHTM\/SCz6o\/XOF5YcgXK5dQHrk9NqBjYIZ4wWyB2l0YDkdOiDG5HmWjSvsqPEDUAHADaqEThf4v073sEleHrrui4nRFhTAA0CsAl4oVz4IfclHFKFGUw1HTOkD5CBhyCKYvdNzTLvRuHY2FwjXKRJ63BTvpFoV5nLqy1e9SFarcAPd3tZDuCKckjBm893hKsouaNQAfl\/THdb8\/kJta1VSLwB58IyiBYC2OXXr03ISpVD6NkneFRSnW2RGUa4XQohnSlcuAHSN3MbkJTcLNI8DmuOwUXKJ1jVZofoNBluXBfRXNx\/WWr2iBQ0Weu0ESI+3XnLvrMSjQ0ooakpFNGUznpyDHPJFz1qcXUzavV4xkrWQlgkBl9UBBWL4oTKnZsTJCk3RCWqpNRXhdJLDvZWVBGH6YdBym5EU85mJo88WMWUZX5q0IPckYqAQvvRqJ68p9dZdRq3AbCiwtoKjuKBX30IgWE2Z7yuFpFfPV2zwrhxHTQLN+Vd7xqUB+F3wwEiwV62NVcr7FhpvG3ckJh4Cql3buI8PqLfbyqcifUHCCGY2h81j2TTENrpLc5CKEh04pXco5hQ7PiwmpG54JX9R1uwG7O8r7xnGwOoA2uu+o+SpVILtdOq8J6tTtE59hw4DPKGqoyorOry2nKUi5YWuVHyJzkLAtm6UQ8ziiILqF9lYEid0DwJ7E24nXv21rys7XqwN6UPbMgr1p7du9LlYF5cOvslSyumDQNNwvWuAEcFqor25Gm5yPMtkk\/4WhOPNHVzwpdDarOyvWb5TA1SDDBkBkApUeZ\/\/ae\/MeX8iJ4DBfIsUainJgkmysENfYYuC5PRivYeJPjJM9ZkI8Mulla6xF3ktwSFXgFSZWhSh37uSHX73+\/MJ9V8Pf3dY9PxxlRDqi9xyPTgSwPFXY8f\/5IPbawSvQZMttmTG\/LAL3\/mxGXHe48pZnR6u\/RCtOU2qMzP4abiYGlWiPf6cNz8tP73k6fzXUs3X+wuZLQoeFMorsUbfUHrs5d\/PGsqGseR4IxsoUS1cyWylcmhX6e7ICfhlGAX154G9pEW1KL7p1Hlu6F9152jNNfesXtXJvV50LrbGDVKmjs17\/fvomu4RLlOW8A9vvhikFZv1C5F0VYH2NlijqH\/RalmF3Omek9fVDxQjZJYzI8AwIkG1JHM2mpZemyudgRzQ9T0aelKiRpKsc9Swh7RIqd\/qQ2jZhUlDGofqiJVHqXpLi2jQxQKQZrtKZ7vfUbj45soiQXGepS2t\/cqhpSx+DzSzgDp65CkGEprLgN5jhTGopt2VeqBoxfJGCFWUX1wkRTAXclTh4QbRErMrjN9PQmlnajismhpDIeQimT8NIVnmbx\/1xdJurIrPef2HccSKNwBKIGYRcxqRfQWzgENgCzalA5M++U6J3OQzVLc\/ixMdfuKr3OvumSVicdIxlzQRvEUzjmiw0WpelQTZDk32ukfVBJj4ecgTe8gNQ9nXUG2tZ917oQIa24RUCKe0\/eWhbnHHuRmJ4g25IMKAAx\/MU06GPysS\/1p63lRYgiwUUghdtDClvjzRy1moDcfNBNoLpq7b2vvpXvN7F\/AKLLsWDAj8QcQS+MhVmsLh9lLZ98o0\/dlwGzd6+JNadxRQEp8ayDE19bvqZaqCNgCPqo99kEVWi0L+vHskD+cICudRNlUxi\/U5nkMJR9D10VXZkuMqJCJRedxQ47MJWc9jA\/trN0fo7oSK0XH9yHcii\/BgHB7gqEtfLGNq5kQK0tnJwp803RHmYlKjmXAxaj+AWbU2j7XCYF8BMBnKlJWWK83arCsK0PNznKyLsgiG0dbrIAucpwqDW+LZ81tQoyuDbEKFJBi42Q+wi4xkLhMmFH2tvz+BKchWZG\/YLiqs6hKqh49u30tzzJpqHKA7tJ1sG0b\/eVEo52rd6r0m8UQlZ5YkdVjAaMSC47qEjVmM8rF235TXStc3pGmS\/+iKslrHWNZqpgIEM4+om5kXk++3o11TGd\/xai043CiB0Bx69CEdzVSbsPoYC6L3wtZ25uDzGu6hwq0LH7v\/w==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">La pand\u00e9mie a mis en perspective notre mani\u00e8re de consommer et d\u2019aborder la culture. Mise sous projecteur d\u2019une situation plus complexe qu\u2019il n\u2019y para\u00eet.&hellip;<\/div>\n","protected":false},"author":133,"featured_media":12259,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[160],"tags":[63,2161,1969,1934],"class_list":["post-12258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","tag-cinema","tag-cinemotion","tag-post-covid","tag-streaming"],"views":1302,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/12258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/133"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=12258"}],"version-history":[{"count":3,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/12258\/revisions"}],"predecessor-version":[{"id":12275,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/12258\/revisions\/12275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/12259"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=12258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=12258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=12258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}