{"id":13369,"date":"2021-12-06T10:15:15","date_gmt":"2021-12-06T09:15:15","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=13369"},"modified":"2021-12-06T10:18:04","modified_gmt":"2021-12-06T09:18:04","slug":"giant-step","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2021\/12\/giant-step\/","title":{"rendered":"Giant Step"},"content":{"rendered":"<h1><strong>Giant Step<\/strong><\/h1>\n<p><strong>Apr\u00e8s trois ans de concerts, les musicien.ne.s\u00a0 l\u2019orchestre des jeunes jazzistes de Fribourg s&rsquo;appr\u00eatent \u00e0 sortir leur premier album. Let\u2019s jam\u2026 <\/strong><\/p>\n<p>Cela fait plus de trois ans que l\u2019orchestre des jeunes jazzistes de Fribourg fait swinger les salles de spectacle helv\u00e9tiques. Cr\u00e9\u00e9 sous l\u2019impulsion du saxophoniste Gerry Lopez, le groupe se veut \u00eatre un Big Band dans la plus pure tradition, c\u00e9l\u00e9brant les diverses facettes du Jazz. La formation de l\u2019ensemble part \u00e0 l\u2019origine d\u2019une simple constatation : \u201cJe trouvais qu\u2019il y avait \u00e9norm\u00e9ment de talent chez les jeunes musiciens\u201d explique Gerry Lopez, devenu entre temps le directeur artistique de l\u2019orchestre ainsi que son compositeur et arrangeur: \u201cJ\u2019ai rencontr\u00e9 beaucoup de jeunes musicien.e.s lors de <em>jams sessions<\/em> et je me suis dit qu\u2019il serait bien d\u2019entreprendre quelque chose avec eux.\u201d Avec son conservatoire et sa Haute Ecole de Musique (HEMU), le canton de Fribourg est en effet un riche vivier \u00e0 musicien.ne.s. Cela est \u00e9galement vrai pour toute la suisse, comptant de nombreuses institutions d\u00e9di\u00e9es \u00e0 la musique.<\/p>\n<figure id=\"attachment_13378\" aria-describedby=\"caption-attachment-13378\" style=\"width: 647px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13378\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2725-900x600.jpg\" alt=\"\" width=\"647\" height=\"432\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2725-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2725-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2725.jpg 1800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2725-530x353.jpg 530w\" sizes=\"auto, (max-width: 647px) 100vw, 647px\" \/><figcaption id=\"caption-attachment-13378\" class=\"wp-caption-text\">\u201c\u00c7a swingue \u00e0 Fribourg\u201d<br \/>\u00a9Orchestre des jeunes jazzistes de Fribourg<\/figcaption><\/figure>\n<p>C\u2019est lors d\u2019un gig que Gerry Lopez fait la connaissance de Manon Mullener. Ensemble, ils se mettent \u00e0 rechercher activement des membres pour grossir les rangs de la jeune association : \u201c Pour former le comit\u00e9, nous avons contact\u00e9 des gens qui travaillent dans l\u2019administration et la politique culturelle. \u00c9tant souvent eux-m\u00eames musiciens, ils ont \u00e9t\u00e9 d\u2019accord de nous soutenir et c\u2019est l\u00e0 que tout a commenc\u00e9.\u201d raconte la jeune pianiste de 24 ans. Avec pour but de repr\u00e9senter le jazz dans toute sa vari\u00e9t\u00e9, du swing au r\u00e9pertoire latin, la jeune association a commenc\u00e9 en comit\u00e9 relativement restreint. La recherche d\u2019instrumentistes s\u2019est donc av\u00e9r\u00e9e cruciale. Pr\u00f4nant un principe d\u2019ouverture, l\u2019orchestre accepte volontiers les musicien.ne.s venant d\u2019autres univers musicaux, comme le classique, \u00e0 condition que ceux-ci manifestent bien s\u00fbr de la curiosit\u00e9 pour le jazz : \u201cOn a assez vite vu qu\u2019il y avait de l\u2019int\u00e9r\u00eat et de la motivation autour du projet. D\u00e8s la premi\u00e8re r\u00e9p\u00e9tition, on a senti le potentiel d\u2019un son de groupe.\u201d se souvient Manon. Apr\u00e8s avoir pass\u00e9 trois ann\u00e9es \u00e0 affiner la dynamique de l\u2019ensemble\u00a0 en tournant dans plusieurs salles de spectacle, l\u2019orchestre des jeunes jazzistes de Fribourg s\u2019appr\u00eate \u00e0 passer \u00e0 la prochaine grande \u00e9tape de son histoire: la sortie d\u2019un premier album.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>In a noisy way&#8230;<\/strong><\/h3>\n<p>\u201cL\u2019album, c\u2019\u00e9tait simplement l\u2019\u00e9volution logique \u00e0 suivre quand on initie ce genre de projet.\u201d remarque Gerry Lopez. L\u2019orchestre des jeunes Jazzistes de Fribourg ayant vu, comme de nombreux autres collectifs artistiques, ses projets frein\u00e9s par la pand\u00e9mie de Covid-19, l\u2019id\u00e9e d\u2019enregistrer un album est venue suite aux succ\u00e8s d\u2019une reprise confin\u00e9e de<em> When you\u2019re smiling<\/em> du Louis Armstrong Orchestra:\u201d \u00c0 partir de l\u00e0, on s\u2019est dit qu\u2019il fallait sortir un truc \u00e0 nous, quelque chose de vraiment adapt\u00e9 et arrang\u00e9 pour cet ensemble\u201d continue Gerry. S&rsquo;inscrivant dans la d\u00e9marche h\u00e9t\u00e9rog\u00e8ne de l\u2019ensemble, l\u2019album contiendra des couleurs venus de diff\u00e9rents genres musicaux; du Swing au Be Bop, en passant par le Funk, le R\u2019n\u2019B ou encore le Free Jazz: \u201cC\u2019\u00e9tait int\u00e9ressant de traduire les influences individuelles des membres et d\u2019en faire quelque chose de concret. Mais malgr\u00e9 toutes les diverses facettes de l\u2019album, il y a une unit\u00e9, une coh\u00e9rence, un son\u201d d\u00e9crit Gerry Lopez qui signe \u00e0 l\u2019occasion de ce projet, ses premi\u00e8res compositions originales pour l\u2019ensemble.<\/p>\n<figure id=\"attachment_13370\" aria-describedby=\"caption-attachment-13370\" style=\"width: 486px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13370\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2713-900x600.jpg\" alt=\"\" width=\"486\" height=\"324\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2713-900x600.jpg 900w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2713-768x512.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2713.jpg 1800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/MG_2713-530x353.jpg 530w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><figcaption id=\"caption-attachment-13370\" class=\"wp-caption-text\">Manon Mullener<br \/>\u00a9Orchestre des jeunes jazzistes de Fribourg<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><strong>\u201cPour les musicien.ne.s venant d\u2019autres genres musicaux, L\u2019orchestre repr\u00e9sente une opportunit\u00e9 extr\u00eamement int\u00e9ressante de plonger dans le Jazz\u201d -Manon Mullener <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Swinging Sarine <\/strong><\/h3>\n<p>Constitu\u00e9 de cinq morceaux \u00e9crits par le saxophoniste et de trois reprises enregistr\u00e9es en compagnie de chanteur.euse.s invit\u00e9.e.s, l\u2019album se veut \u00eatre des plus ambitieux. \u00c0 tel point que les subventions habituelles accompagnant les entreprises musicales ont d\u00fb s\u2019accompagner ici d\u2019un financement participatif: \u201cNous nous sommes tourn\u00e9s vers notre public. On a lanc\u00e9 un WeMakeIt pour couvrir tous les frais de postproduction.\u00a0\u00bb raconte Manon. Une \u00e9tape qui, l\u00e0 aussi, s\u2019est montr\u00e9e \u00e0 la hauteur de l\u2019ampleur du projet. Mix\u00e9 par l\u2019ing\u00e9nieur du son Erwan Boulay, arrangeur de l\u2019orchestre national de Jazz de France, l\u2019ensemble a enregistr\u00e9 au studio de la Fonderie en Juillet 2021, avec la plupart des instruments rassembl\u00e9s dans une salle: \u201c\u00c7a a \u00e9t\u00e9 un challenge pour Sacha Ruffieux, qui s\u2019occupe de la prise de son \u00e0 la Fonderie. C\u2019\u00e9tait la premi\u00e8re fois qu\u2019il enregistrait autant de monde dans ce studio.\u201d\u00a0 s\u2019amuse Manon en rappelant pourquoi une telle entreprise est et reste si importante quand on enregistre un disque de Jazz : \u00ab\u00a0Jouer ensemble, c\u2019est quelque chose de primordial. C\u2019est vraiment un \u00e9l\u00e9ment constitutif du genre. C\u2019est un style qui capte l\u2019instant pr\u00e9sent. Il y a beaucoup d\u2019improvisation et c\u2019est impossible \u00e0 retravailler par ordinateur. S\u2019il y a une note qui tombe \u00e0 c\u00f4t\u00e9, \u00e7a fait partie du moment; on doit la garder&#8230;\u201d<\/p>\n<figure id=\"attachment_13376\" aria-describedby=\"caption-attachment-13376\" style=\"width: 400px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-13376\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/T7A7244-400x600.jpg\" alt=\"\" width=\"400\" height=\"600\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/T7A7244-400x600.jpg 400w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/T7A7244-768x1152.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/T7A7244.jpg 800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/T7A7244-530x795.jpg 530w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption id=\"caption-attachment-13376\" class=\"wp-caption-text\">Gerry Lopez<br \/>\u00a9Orchestre des jeunes jazzistes de Fribourg<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>L\u2019album, en plus d\u2019\u00eatre une lettre d\u2019amour au genre qu\u2019il repr\u00e9sente, prendra \u00e9galement les atours d\u2019une c\u00e9l\u00e9bration de Fribourg : \u201cJe me suis inspir\u00e9 de la ville et de ma fa\u00e7on de la vivre au quotidien.\u201d r\u00e9pond Gerry lorsque la question des influences de l\u2019album lui est pos\u00e9e. La phase de composition a repr\u00e9sent\u00e9 un d\u00e9fi: \u201cL\u2019arrangement \u00e9tait vraiment le plus gros du travail. J\u2019ai pass\u00e9 beaucoup de temps \u00e0 me demander ce que je pourrais bien faire du piano ou de la section de cuivres avec les m\u00e9lodies que j\u2019avais compos\u00e9es. \u00c7a m\u2019a pris 2 mois de travail quotidien.\u201d sourit le compositeur.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Le vernissage de l\u2019album aura lieu le 11 d\u00e9cembre 2021 au coll\u00e8ge de Gambach. En attendant, Manon et Gerry\u00a0 commencent d\u00e9j\u00e0 \u00e0 organiser une tourn\u00e9e nationale pr\u00e9vue pour 2022. Ce dernier constate d\u2019ailleurs avec enthousiasme le d\u00e9veloppement de l\u2019orchestre: \u201cL\u2019id\u00e9e au d\u00e9but \u00e9tait de monter un projet avec les jeunes qui ont envie de devenir professionnel. Maintenant, la majorit\u00e9 des musiciens sont en haute \u00e9cole ou ont fini leurs \u00e9tudes de musique. On voit que le projet se transforme: c\u2019est d\u00e9j\u00e0 un orchestre professionnel\u00a0 et \u00e7a, \u00e7a n&rsquo;existait pas du tout \u00e0 Fribourg. Nous sommes tr\u00e8s ambitieux.\u201d Ce n\u2019est pas Spectrum qui le contredira&#8230;.<\/p>\n<p>&nbsp;<\/p>\n<table width=\"602\">\n<tbody>\n<tr>\n<td width=\"602\"><strong>Une jam session, c\u2019est quoi ? <\/strong><\/p>\n<p><strong>Une jam session, ou b\u0153uf en fran\u00e7ais, est une session d\u2019improvisation musicale. De par la nature du genre, les jam sessions sont tr\u00e8s r\u00e9pandues dans le milieu du jazz.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u00a0<\/strong><\/p>\n<figure id=\"attachment_13374\" aria-describedby=\"caption-attachment-13374\" style=\"width: 482px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-13374\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/JazzFR30319-2-800x600.jpg\" alt=\"\" width=\"482\" height=\"361\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/JazzFR30319-2-800x600.jpg 800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/JazzFR30319-2-768x576.jpg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/JazzFR30319-2-1600x1200.jpg 1600w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/JazzFR30319-2-1920x1440.jpg 1920w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/JazzFR30319-2-530x398.jpg 530w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" \/><figcaption id=\"caption-attachment-13374\" class=\"wp-caption-text\">\u00a9Orchestre des jeunes jazzistes de Fribourg<\/figcaption><\/figure>\n<table width=\"602\">\n<tbody>\n<tr>\n<td width=\"602\"><strong>Si vous \u00eates int\u00e9ress\u00e9e \u00e0 d\u00e9couvrir le travail de l\u2019Orchestre des jeunes Jazzistes de Fribourg plus en profondeur, Spectrum vous invite \u00e0 \u00e9couter leur reprise de <em>When you\u2019re smiling : <\/em><\/strong><a href=\"https:\/\/www.youtube.com\/watch?v=bZPODNH3dvA\"><strong><em>https:\/\/www.youtube.com\/watch?v=bZPODNH3dvA<\/em><\/strong><\/a><strong><em> (code QR)<\/em><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-13372 alignright\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/Unitag_QRCode_1637499331115.png\" alt=\"\" width=\"131\" height=\"131\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/Unitag_QRCode_1637499331115.png 300w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2021\/12\/Unitag_QRCode_1637499331115-100x100.png 100w\" sizes=\"auto, (max-width: 131px) 100vw, 131px\" \/><\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQ2NrMEAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c89MzCtRCC5JLQAA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcHBEYAgDATAiuQkT7txIAoPMhly6Z\/dQXo8QDC7Gkva\/HZpA+HauHNBbqmogn++xiuojgM=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"iyxLzFMIyEwtKsoEAA==\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtQ1NNI1MFMwNLAyNLIyNAUA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"tVrJjlvHFd3nKwodwLABNsdWa2rJkGR5ECwPUgwD2RjF94pkdd7kqvfY3VppF2SdVYAE0Co2na133onIj\/hLcs6tehy61S11TANxRLL5qm7d4dxzbvFoNrh\/5GtXFtP7n1hd1Op5baqjXvzoqIe\/\/+GoWn3nQeWWP3qFN9YrXXiVGpWURWJc7TsqM17ljbeJNUW3MF3\/+pXKfn35j9IlM4MVDL7u1bFpCv6jX7ywvjayxsfOjsvGTZV\/z\/nvm\/KurrDTT7WBRctXypeutg7rN05VzuTWOKWzcZN31eemxg5cLv\/15b\/VhumVWP7IZFpNtK1VlTWy19r47xtzXftkJX9ii6lxcl6vsyx8x1cmqXWSGTUz2Xy5qC3W9131yC0XywXOgO25m82rJvO2LFTa4PHTspqVBXdSnxjnztTnZWVe0Jlq6sqmwsJGzU0DR\/xEE5tCPbRT9VAXqUp5CpxPjlY1jofTqa2xeEcly0W2XIwdoyom2rlxHi8mOjG1HKxRT3BKOBEuKl2ua7EqOMUU3uRjWFFpJ0EInrJTW8BPeA0vKY\/DZJICvtZ1eP6O+vXlP5+In5u5tnQzT52pM6XndN9yUWCz5SJndBkQnfEVYvBCDI0BaDPJ\/\/ryX8qcVhn9ue2j1MxN0Sg8zaObvPJ0W2odIsFcgeVwrDyXng+1toW3kgIeRidlXpXeylOmxoNw2xRvwmHwoLbKmQIHrRFONTa6SRAcLnvO3C7yXmWlk5w4Mvl9ZCbSxHiG3B\/18Al3ODYqx9aNZWDqlY+8cXTRGAuJk+VoSPkihckwNqPByaxETui5SZRpTrv0zwO+CQdB3Nxc1yW8wI28Vp\/qBtn1OCkz8cNTWMpl3v\/08dNvPpBMS5AkIfSrTIeX4FhlJhMsgqRzFp5Tcztn8SEdtgodWc464zPLxRTxlNjOcRZVYTVVl7QA3+CBvemIv2sd4l+U+diZhqmJmNS2bphH8MtykdrlAh8z+7TsCLu7obQndsqEt+m9PV2j7mbc8rvBaHTz1h7iZ\/U+ijnBaUw6Pru3l+iKq+6vv7sfv+vrs8zc2zuxaT27ow4PblaneyrJtPf4sNqPDwJv7BRAV9TG7d0\/svkUQUatFdN7e5l+cbaHkyRleK\/9WZGs1lBYxOZ6alYbuuTe3qyuK3+nB7hqUizabQo7cd1k1hMYcU3e495IN\/yx11Tcy\/eG\/eGgNxj2nn7y3fDm8Mb+7X7\/9LDf7x5XU5w5q+\/tYTee494ezrEHILLTGT49GA1lW2\/q3e+s8Pqko3ay7M3DW6c3BkNZFq93tKwsN7i1OzNvjPqnoxsjWRevT+Bc+8Ig1ii0sqPez\/Xp\/mY+faAG\/f4cu8fs6t1n+raZxRS+PD0vZOJ+bU7rvfvApeVfdehFKGaUSFu6wIOjscMmrxdfvnNnO+qtLbovb1BdoYMShlDYAdME+NUUHegcGofWiDKF8wrAvteoFoEbXeCQTxv0ycK4rnocG0tH2YzACBys20YP4J4Z2gzsTmo0rNgjAK+GIOEDnKAxAk5DAyZQy0mwtRxQwV9lYjeakfqKD7HDSdMm+Nh6uegAedA39Zxgw5BjS2A7d5saoQeW\/RQ9K5MGFbote0GaW3ZsF\/YwcuyqzGxoNUmT1XAeHuqq5d8E5dD851wCcL2fL3\/KN9tb8ENJByxkf+6QJKVLAzjCRE\/4LKy0pqQNB9zF3Qitil7P4Sv0fGkHTksKr31SgdwJx8CSwwOyn27oGeLPcSNAzE6zXHjBOPqJiRJOHfAbrWQOZBUzO8JemHxKNwqPVeCA0nMyeAX0443h2LCTzSUGAhvzoRhtJwlrUZvkJauMEL+wP6BG8bWQwD46IwUHRSCXCxiCALgGG9L9X7nlzwUDgJytnC0SW4WFGA\/HKHXO04IkMRXOOi8zeBC9zl+ktaBjsqhEqqmZloARsqvwPd2cdsJBJdtYwEyMDjMccQkETYKXMCESq3JEZwIDeH7p\/X75i4tJnTTOkprATxKsNjCS2l\/Sp1gf9Te3NLu5QLci84FD6Z6faiZRWDkv4fQYGAAX1kZMK1ceG\/j+IxJ95jX59vJHuIZBJq0N9FKiyVyxtKgqabs1WYsQPtCJQGElJ72RMrA8o2ACMjDICVQgcrvCMXDGlp4XbefXkwkop6Mt6Vmh800615JUCA04jUcIgWHOkhRbULg3cvTOtYUJYx1FCa2itYEIiY\/KZKZJjKeAIzwGN+lKrKQfZliOpXFHGBC1TMugz6mZVrS8V4x9dTe8m41W6uszuryAe87UiT5774+3hqP+3U2xNpKnkRaf01ou2RG8oDnULcLWpcgy+RRJLlwL2D4Vt1JrNXYuXJMCg92psLQXWA5QFE+1KSJAY3LtznUC1O1lvn3yRt\/qMwZt3rRFs+aEpyrWF7hrhtDZid8g9YBOksZgDnQNUQP4RcUiUcEJoDKsLPionNt0f3A7BN6mxIlAsJ2ZEssRhKYIcRAeS2UhBB3xRkHjVZIwWVvpQ7C0XrTPhNtyF9J99e0MqXhWsgpxeJ\/bDCAZeD\/K6\/OSlP+By0PUVNuh9R26c\/lS5JYNtb98JWW2ArkNnTBBSktIgzKG5cDFhPFjw+ickwpYjFxcIq9TNHnCb6tyWlyBKFRtPdEWdhBbtKHtqudRmgODQavnqzpjXcLNWkB6Js3BldPlj8WFKg2+Dy6W1SlrtOQHxFQmtUq3S3akdjLBSjDZh8xbg+tdOvJ523seGvWwrDoEABYl7ZIEQII1xV9E3jzDtgX+e6hKqkX0VkHmj50xkpICpY\/WhRKw0oTF0qCqG+ltolEmWYNF5CVEtU0bE\/FlTVNMHbOLtOiCdItTE0ecfUqJnOtsSl0pfdZfJtfN2n8kDUR4xVRE85GOzNdJOROvJYbvCT+MJQKEmNVbfI30xkPTmJW4TxLt4wQgaau8LbHYBPxKKYtEC\/MAnbXEbDPab9Vp\/WvotP55nXZw6\/AKneaoe36LTOvvTKYNRlfJNBxjLdNGw4NdyrTtnXcm07Ds7yHTBqPdyjSYeQ2ZJum0kmkxud5ZpvUvl2nb6meXumyTJKwntACyrwJLfDtpPQernXN9e0MOCLSUVYVuE8BG4XCOQkZ6yiZeBoYA8swJaWgQAWSJQ\/vb7rg4rm2P8frVhT9dQoqkD7AVPAeYwMqLfOhRGaZKou1UYovvwXxdYtjVAy76tmNsjWNNvR4Xx24PYG\/5gtDToGEqPS0CywALLDhD7HKc1WWDmNNbnAluNr\/tiS5TQCa4Oh+TazWnXRKBGmS6KuHaMKem2mnGVJGCvDON78bGQ7UoRrSj3jg1FINDdPkpJWa6\/CVQ2fYRBAE50tJRMBnKdgmqEBEIJgiEiTTILyhFox7NKWGFb5NwifQpSh6masaZTbpKhEmmRelh4W\/NU\/0X81kdqQZ0gLMyFgzNbuLYBZk4pa\/ReNIm4TG7r1+9\/mUlZqNo+KZY8Wu0sI4IYd1AYnVWTCkPY1oT6fmM88\/GrRooWfC22HlqT0mDtItSCaSosPE7ZPCP3YkuQDOaTJ911tPhi1PlQuSUzviXJyKfWcpa2vHWVF1vZhJpDJHOllGZfQyVaBxyCgn2pOH8oVZEt06Y+oaRvwzm0zg1DaqY4xAvOzAsUn0ypqcAkhhyZKTjoAFhQb6yEqcmxOU5QE2rZw0UlyEeCEUIzKAJckbEjvUraRMc3JrbVRskaks7TsqNi4DVyfk1xCayrJyrBKNBP4I\/KDIg7iRlkcntNAlucVBjJhO2B9NBTK0ctWZJbBRAmGOHqQLvKxQ0EFBMgGqlcdYigE5JrY8S80nQ2a\/\/8\/rVk7JBqayZbDuGuUDssCvQJbU6C94QLdGSb6wutzLyJinbafeEeSZovH6G5I2MR4LABtDKeC\/+aqG5qz4LRHB9JRHumBwEj18NqFpzeXqUCjNQxm2r+ZaT7KfhSGEimHq+GiOIY1HewZYa0kyeTpY\/C+1c\/tDesOkgbRuEkie8S9+mZciFqXbIkShaOaJ8Czs8vAY7PLzADvv9K9hhZibXJIfkDfu5SS3Ae4snHu6CJ\/7p5oObw4OD\/YMreGK\/v+aJh\/3+jnjiG3am734rAWuXJU8cDG7sjCjGdWW5W7szkzzx5u0b78QTmVhrnhjS7J154uHlPHFDmf1+JHFjLES1LBfiBOx4sUyWUct+ArfsCDri0gq7N0hhR4WLSb155yd8hMRgPSlZXUS318urwU97VdzehALcKusCTwNkzK1geWgOxJjlD\/F+mn\/jlEpz3FnWNiXLlXnUclGhjUShyysLIU+aOO3j\/lsSflNUqwzwRpQERoI9yPy5mulWsK90r9IbbgiNFAJ7YuU44uNAEMQhsRuuWgCHpXQ87zAIlRGBuyreMscx6OYNc7jZ5p0rLck5YeS4RnjhcWjdwp9kchzmDeQ2Fq2SA4\/gMG+S1v+JjPh85BLkiIgQcM+En0Qc0xC5uQ9nJtMFIwVzyPkXIQBqCIy38fcUcoBzgfAwytbxtqW9Wn\/jgPNCkpIcu4I3SFOzHR\/dINkycBOuOxjIWEMGLkKOmA2cEy5\/DM99Aj6N6uONE1ISCABqUXdaBhGHIa9ftVcScsWzXBzDz\/hf6aa8MZGpoGmZ7prfGWnA8yYSJ2w\/5B04toXljE74RUQsJeYxKyJc2Rf1DLzXah\/uB7Dn3GQQV+1l1zalXCVVmFnijPiXFzYxsQJxqsP4MvDZdWAjaLBtk\/0byBFxjfxwgjN3V07CLxMKk8ksikgpbuL9gD4unW3vxFYXViR+8tsA4dWUUPxhARKNH0NBWBVOCwObNJRYe3VPWTAvbStpWnu9ZFHh5YruzoqsxGjgXGuCvWUxx\/41+UcgIUWcUJpTIGQgJKHEeEW2cUHaVV9sqphwB7HSXsxeRLKIRnCN57GZiCPD711gS2qdjnzmjYlda9Ks9j6+P9zjZ+MyPeO\/jv+Xbv21VbQUOMc6b38zssk1QXI\/vFw0X3gQMRn\/9+\/NhMGCxCrgJAshGuilab\/3BsbYisau+si043SkfhOQRTpC+LnXxnYxL4I7icPAqcb41QyAg3BULp5nD+tunKJOcYyeuKTXOqgn3rt6JnA5eTy4Bnk8uDhaHP6uPwE52AVnpDT5+NmoPxrc3h\/u37pqwjjcmDAeDnbEHC\/dfxfEbHtxmTbePNwVidxefACzTwfDaDvf7Xj920Osf3AQ18e73a4vM87bt95txjncmnEOr8VdDy7nrrugqv8vWD63aCgAc97L+vUgMg5\/SBDirClbM5XYYr989xtKYWxG+uuEU4rGddZNQfaXSZ\/sKVuGX1CAGbRjiPhjwDdeDoIHy\/3gGt60mjkzWZfoyclJF0\/Vzdh0QVd6J7pOZh\/O743\/\/NWXH33x6SidP1i7hPtc48FzW\/f01kLqfUCaUV8\/++D8964Y2L4N0K8BnVvIOdy83dkBiH5T2FpPv\/v62SOc8bvBIbL89u3RaADN2q2KC1A6GA3WUCpvdgKlb7FCjX47Jl2xxf6AAAj841b49yoEwZk3EETeCYIwF\/4H\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Giant Step Apr\u00e8s trois ans de concerts, les musicien.ne.s\u00a0 l\u2019orchestre des jeunes jazzistes de Fribourg s&rsquo;appr\u00eatent \u00e0 sortir leur premier album. Let\u2019s jam\u2026 Cela&hellip;<\/div>\n","protected":false},"author":150,"featured_media":13378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[160,5],"tags":[1202,799,78,2349,714],"class_list":["post-13369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","category-music","tag-fribourg","tag-jazz","tag-musique","tag-orchestre","tag-unifr"],"views":1386,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/13369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=13369"}],"version-history":[{"count":14,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/13369\/revisions"}],"predecessor-version":[{"id":13394,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/13369\/revisions\/13394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/13378"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=13369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=13369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=13369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}