{"id":14146,"date":"2022-10-04T13:47:09","date_gmt":"2022-10-04T11:47:09","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=14146"},"modified":"2022-10-04T14:10:23","modified_gmt":"2022-10-04T12:10:23","slug":"la-tour-vagabonde","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2022\/10\/la-tour-vagabonde\/","title":{"rendered":"La Tour Vagabonde"},"content":{"rendered":"<h1>La Tour Vagabonde<\/h1>\n<h2><strong>Qu\u2019elle est la forme d\u2019un th\u00e9\u00e2tre ou d\u2019un cabaret, peu importe, \u00e0 la Tour Vagabonde dont le concept s\u2019inspire du Th\u00e9\u00e2tre du globe londonien, ce qui compte c\u2019est ce qui s\u2019y passe.<\/strong><\/h2>\n<h3>Une tour transformable \u00e0 souhait<\/h3>\n<figure id=\"attachment_14149\" aria-describedby=\"caption-attachment-14149\" style=\"width: 409px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14149\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/10\/20220824_173153-1-800x600.jpg\" alt=\"Emilia Astorina\" width=\"409\" height=\"307\" \/><figcaption id=\"caption-attachment-14149\" class=\"wp-caption-text\">\u00a0Emilia Astorina<\/figcaption><\/figure>\n<p>La Tour Vagabonde, malgr\u00e9 ses cinquante tonnes de bois, de m\u00e9tal et de b\u00e2che, est bien mall\u00e9able. En effet, elle peut\u00a0 prendre la forme d\u2019un caf\u00e9-th\u00e9\u00e2tre aussi bien que celle d\u2019un cabaret ou du fameux jardin aux betteraves. Mais d\u2019apr\u00e8s ses d\u00e9tenteurs, la structure r\u00e9serve encore bien des surprises puisqu\u2019elle offre d\u2019autres possibilit\u00e9s qui ne demandent qu\u2019\u00e0 \u00eatre\u200b explor\u00e9es. Gr\u00e2ce \u00e0 son caract\u00e8re d\u00e9montable, la tour a d\u00e9j\u00e0\u200b bien voyag\u00e9. Depuis 2012, elle a \u00e9t\u00e9 dress\u00e9e rien qu\u2019\u00e0 Fribourg, \u00e0 la route des Arsenaux, sur le chemin de la tour Henri, sur le site de bluefactory et sur le parc de la poya, o\u00f9 elle y s\u00e9journe actuellement. Cette ann\u00e9e, la structure aura pris la forme que l\u2019on conna\u00eet \u00e0 Fribourg depuis 2012, celle du jardin aux betteraves, mais version cabaret. Il s\u2019agit d\u2019une grande tour de trois \u00e9tages, avec un bar au rez-de-chauss\u00e9e et des tables aux \u00e9tages. L\u2019acc\u00e8s \u00e0 l\u2019int\u00e9rieur se fait par la porte principale mais aussi par une porte au dernier \u00e9tage, accessible par des escaliers externes \u00e0 la tour.\u200b\u200b<\/p>\n<h3>Une salle de spectacle, un bar, un cabaret et de la restauration<\/h3>\n<p>Que ce soient des pi\u00e8ces de th\u00e9\u00e2tre, des concerts de rap, des repr\u00e9sentations de cirque ou encore de la danse, \u00e0 la Tour Vagabonde, on ne s&rsquo;ennuie pas et il y en a pour tous les go\u00fbts. De plus, gr\u00e2ce \u00e0 ses multiples formes possibles, les repr\u00e9sentations th\u00e9\u00e2trales prennent une dimension nouvelle inconnue des sc\u00e8nes traditionnelles. En effet, les acteur.trice.s peuvent circuler librement d\u2019un \u00e9tage \u00e0 l\u2019autre et leurs mouvements et leurs trajectoires semblent infinis. Dans ce lieu de culture atypique, il est donc possible d\u2019\u00eatre assis \u00e0 une table au premier \u00e9tage tout en regardant tant\u00f4t un com\u00e9dien donner sa r\u00e9plique au rez-de-chauss\u00e9e, puis lever la t\u00eate vers le com\u00e9dien qui lui r\u00e9pond, car il s\u2019av\u00e8re se trouver au deuxi\u00e8me \u00e9tage. Lors d\u2019un concert, nulle crainte de devoir se hisser sur la pointe des pieds pour admirer la personne qui chante puisque la sc\u00e8ne se trouve au milieu du rez-de-chauss\u00e9e et que les \u00e9tages permettent de tourner tout autour de ceux qui s\u2019y produisent. Et si l\u2019envie d\u2019un plat consistant prenait soudain un spectateur de court, la restauration de la Tour saura satisfaire son palet.<\/p>\n<h3><strong>Qu\u2019en<\/strong> <strong>pensent<\/strong> <strong>les<\/strong> <strong>visiteurs<\/strong> ?<\/h3>\n<p><strong>\u00a0<\/strong>A la question: \u201cQue pensez-vous de la tour vagabonde et que lui trouvez-vous d\u2019original ?\u201d, les r\u00e9ponses fusent avec enthousiasme. Pour H\u00e9l\u00e8ne, 55 ans, la Tour Vagabonde se pr\u00eate tr\u00e8s bien au th\u00e9\u00e2tre de par sa structure atypique et originale car elle permet de rendre la pi\u00e8ce plus vivante. Elle se souvient de la pi\u00e8ce de Cyrano de Bergerac et raconte: \u201cle d\u00e9cor tout en bois donnait une authenticit\u00e9 \u00e0 la pi\u00e8ce et la forme ronde de la tour nous rapprochait des com\u00e9dien.ne.s, ce qui change des sc\u00e8nes frontales traditionnelles. Tout ceci rend le lieu chaleureux et cosy. On s\u2019y sent bien\u201d. Mathilde (nom d\u2019emprunt),\u00a0 25 ans r\u00e9pond avec conviction: \u201cj\u2019appr\u00e9cie l\u2019endroit pour son concept simple et atypique qui ouvre \u00e0 la d\u00e9couverte. On sent qu\u2019on est dans la transmission de valeur et pas dans un show! C\u2019est fait avec sinc\u00e9rit\u00e9.\u201d Elle ajoute: \u201cL\u2019architecture en lien avec le th\u00e9\u00e2tre de Londres \u00e9voque Shakespeare et donne une identit\u00e9 au lieu.\u201d Cette structure permet, selon elle, de favoriser les contacts visuels entre les spectateur.trice.s ce qui amplifie l\u2019esprit de communaut\u00e9. Un dernier point qui, \u00e0 n\u2019en pas douter, y est pour beaucoup dans le succ\u00e8s de ce lieux ambulant\u2026<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQxNDEDAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"80lUCMkvLVIIS0xPTMrPS0kFAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcFREoAgCAXAE+kzPrsNKWUzhY5A52+3u0\/bAfNoop5D73Pl2mFTqq94QYUIW8HDyUes9PHFx9Am+AE=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c83NzMlMVHAsLskvysxLBAA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtI1NNA1MFEwNLYyNLAysAQA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"dVfLbhvJFd3nKypcBAlAkZRkZ2YcSQPHcR6AgySIJ9tBsbrILqW7ul0PjuiV9vMFA2QAYRaBlUVW2QTZmX+iL8k5t5pNSdYAEkh2Vd26j3POvX1WH1+80eptl4P6m17rZecrezbH05+c1ScXZzGFzq8v\/pLvrr+zTWOVjUk1Wq260FpV4Wn2KtW7290PKVjV5f0zo5c62DRVvc3KtX0Xkp2q3Q0PP7xNVZ2HTatM543tk4qw4HzsHQxWWb0drePHuumWVjU413ln\/VQZq95lh7Ntn2CCbsLD4SktbVWvY7Szs\/kQC6I7YXSnF195qxJ9SUH7yJD0En7AydjlWruErafYunLrjOtddT7RKWlTt9anr4+fHT\/7YqJ0cPqostEEt7TVcns+MbpPrvNHh71Hw96Yto09n3zjqlS\/UM8WX\/RXE2Ua+IeH\/dFwUOnGrX1w6zpNLs5cu0a8unJ+fT5p9PvtRFXWdOW3jltvRhMKNlyr13a8L5jzSZ1SH1\/MEX6u4Msse7cKM1PPY29NCrmd82rUAIvz3POuOD9ZnJzMjxfyufj85NnXx5+dHj8\/PTo++nyxuPrlYjG77NcIvknnk9eta5xWL2PqgvMabjC+8wnim6jaMo7zyenis4maXzCX+zCZzx\/P1SdpOUr2Cgn5ePPovrP5weaF\/ECxULX+U2BPVaubddjdqmijMs6\/yxpxAwTe4wGwuOxcnPJLu7tNulE2ydPdD6bGaUJrCdjRTLO7JVpm6rVXdrUi1IUgwHv6eKP6YH0F0DzmitGr3e3RgTE6x+iK0XcZABYbDzkkrMpqpVubr9SlDqg9zl2ppU3JBr2xcab+qF2Uc7oPuw9RAqwQAzJqc0BMcAQEyCYRykhBtGEDOnvT4bfcDxCrmEMfHA\/32cV3I+271SoUv3SG21ju4PcShUgwJWQDmSrbak+QKTkJIu3+hd13198qewVk4Vr6+ruAfA48Y5RBm7T7QPu72xZAZF7FYSGn5uPL3Q2tiJ+bbqvXu9uZ+o2lk+pkcXwyJF8rhIzyIvMx4jIVSmKLM78FRWFxvdeh0OVkJeyXIVqPlE6ZANGi2raOKRnd+L0FJcf16OSkWjbZruB+F7bEyrDa62CGsz2cnapu99\/i4FbBrUvYQ7ZwLPMhUT9Tr1hMpb2H24+qpXOAIZTlgCZipUFUzB\/Aq3f\/TupehLj8XmoGUOWnsUNSYOvGhui6EXQz9YdG9FOvXRoAadU6sL4lIfwMoAtTDs2BHVgzCriFAdyhgn0PYTwyNTHOYgiZopL6RvFiODpTb3iTMUQuayMdAIVE+XBTtAA\/vEBaS0rRS5gPb1yvEZn4X4jELXS07IETlQ1oFGG4CT4aY4ncUiXxB9oNxUX4AClyQiUo+GCYM8AOf2fz\/tAzopZ84gsVVBuitYQtn3vaFu0gzqAbrCEVamgpPVoq2Q4GOPKFfvRu98EUGRr1YSor0hlDkqWg+\/Iw2F5oDL7QsCwaF4gMCMZA7OJAhfb2I90X2PSkbvxZAN27X1nvs2NuIv13DRALBjHp7JNdBgZx97rb\/S9FMlD1TUbp1wdKY7nNTXI9Nwpa92rRECTNU67v49VcpXR6JoWFrBzoIcD0Xd4IkFF3QD4X5kZghhXD2crRmOeeeF+WBWyGMjhLwRk7ixTpDW9AvkxuAI\/GLYMQca+9BS97MIroMSENxVS1dIW74+EZHLgEGjpHdYy2RbSw5vzKecdMoQSsN4CWpVJIkXA7bXuHmk2Za\/YXDDZmzJd4Ixqq0A2dAJNZEQoR3shVe4A3C5RYr2DXoDp6G3aCR\/9JgssOTa0SpWeawCvNRtA3vP8pwk6lCSC+jRXiJXhiRSjKuLY3R\/Vv8E9jwNSUks5wRD42ouxRxCLTkJAyXwHs0LHiN\/jfhTi2vYL2qfKZ5TZBO1\/UtrIb5JfGaoeZLhS9JTiHHSSRrWJBq65aFKNsgM+MucyKtTT90uCEHwVEByfpI4cMK433KR2Tg3bUPl7QUlGFyiIcTLCUA9gZ5NKwf9+bS0NXwQdR\/9foHU6gZv3GjRNA3+jEfKD0LKRQg0qI+bRCVljVokFEt1yBq9L0segMMiDMj9JNIp5HiCpLg3XKaJqNIvdw7Pfj6Kz2Cz04Cb8\/XUBOPn24cWyXIMlh6ctRB\/ebPt6Mqy\/pLDIc6fsLdXf9D4ql3Pn+aEMNuteXN+N7xL4sSHAp434z+yTGacyKjfry7vr7QYQErZSrVWYwpX3hS41DTscWsPyzdP7dbUN8TNXz52jQZZZ69A4T2ZCEHknGLxlUgKLDoFeVhhMfNPaB\/HR976EV9gyjJEEloj8Ok6VJiOqqjdsQyUAPd0eWMm+GdnJvL3682qJxd\/z2axvW6PuGV+KDY79kuJHpCz1j1BCOwqIUBBxFB0CuYdwZznxDMxmusPdeCkN5qTtUyLMIaFvAu+Fb1dDSBvWYeQjy4T0O3Fw\/VPZV4EjYPKXxb+mqscZJgihKwlkYoSaTbZb0iduZ+pMfWCelZnkABI7NqXYNnP2571pBim37kH36xRRD\/InUe69rBSBI2caZEZmXMnKznRlnBwJXGItS0aDY+cN7LV6DG8nVWHeGjJoFO6RTSkCVZFXp8jhLw450B\/rDxPKNtYUIDuzeSMS0zc4tu6gNdffNT9Wr4aVYZiiJIaKFcrhCHTHffF\/woy85DktQMo0FU4O1BaiAQyOI5unGPoT1m47gpBZuOgb111r\/3UKWdGmZ0mwEQI6vBgIeMIOVksvL4HsgRUE9Jm3bMOimkSEI3m86vpkEIS+Bi55ODkQM0ZG8DUWSD4I4tvsBXBr5d6t9mSImyFQ0s20zpn9mQ33lx5FRugoPyuTkpbQlvUwUZr2tlETqvLQ6o3L9UCDEk8s0K7IvwV7h\/mVuwNi763+K1P4f\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">La Tour Vagabonde Qu\u2019elle est la forme d\u2019un th\u00e9\u00e2tre ou d\u2019un cabaret, peu importe, \u00e0 la Tour Vagabonde dont le concept s\u2019inspire du Th\u00e9\u00e2tre&hellip;<\/div>\n","protected":false},"author":163,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[160],"tags":[2498,2499,2497,756],"class_list":["post-14146","post","type-post","status-publish","format-standard","hentry","category-culture","tag-cabaret","tag-shakespeare","tag-spectacle","tag-theatre"],"views":1393,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/14146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/163"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=14146"}],"version-history":[{"count":0,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/14146\/revisions"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=14146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=14146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=14146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}