{"id":14189,"date":"2022-10-04T23:12:33","date_gmt":"2022-10-04T21:12:33","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=14189"},"modified":"2022-10-04T23:21:22","modified_gmt":"2022-10-04T21:21:22","slug":"liberte-egalite-et-soirees","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2022\/10\/liberte-egalite-et-soirees\/","title":{"rendered":"Libert\u00e9, \u00e9galit\u00e9 et soir\u00e9es\u00a0!"},"content":{"rendered":"<h1>Libert\u00e9, \u00e9galit\u00e9 et soir\u00e9es\u00a0!<\/h1>\n<h2>Petite vision d\u2019ensemble de trois importantes commissions universitaires pour la rentr\u00e9e, que vous soyez int\u00e9ress\u00e9\u00b7e\u00b7s par la politique, la lutte contre les discriminations, les bonnes soir\u00e9es ou les trois \u00e0 la fois, vous ne pouvez qu\u2019y trouver votre bonheur. Your University needs you\u00a0!<\/h2>\n<p>Il est certains principes, certaines id\u00e9es ch\u00e8res aux \u00e9tudiant\u00b7e\u00b7s de l\u2019Universit\u00e9 de Fribourg. Cependant leurs mises en \u0153uvre concr\u00e8tes demandent un travail de r\u00e9flexion et d\u2019organisation essentiel pour que celles-ci ne cessent de se d\u00e9velopper, de rayonner et d\u2019\u00eatre tangibles dans le quotidien estudiantin. Et pour passer des belles id\u00e9es \u2014 qu\u2019il faut d\u00e9j\u00e0 chercher \u2014 aux actes, l\u2019Universit\u00e9 dote les \u00e9tudiant\u00b7e\u00b7s de multiples outils, dont, entre autres, un l\u00e9gislatif purement estudiantin (le Conseil Estudiantin ou CE de l\u2019AGEF), des places dans les l\u00e9gislatifs g\u00e9n\u00e9raux de l\u2019Universit\u00e9 aupr\u00e8s des professeur\u00b7e\u00b7s et collaborateur\u00b7trice\u00b7s de l\u2019Universit\u00e9 (Conseils de Facult\u00e9, Conseils de D\u00e9partement, S\u00e9nat, etc.) ou encore un ex\u00e9cutif \u00e9lu par le CE (le Comit\u00e9 de l\u2019AGEF).<\/p>\n<p>Pour autant, cela n\u2019est qu\u2019un d\u00e9but, car pour avoir des t\u00eates et des bras d\u00e9volus dans la dur\u00e9e \u00e0 des missions claires, le CE a cr\u00e9\u00e9 des commissions, ouvertes \u00e0 tout\u00b7e\u00b7s les \u00e9tudiant\u00b7e\u00b7s qui souhaiteraient s\u2019engager. En voici trois, pr\u00e9sent\u00e9es bri\u00e8vement\u00a0:<\/p>\n<h2><strong>Libert\u00e9, avec \u2026<\/strong><\/h2>\n<figure id=\"attachment_14190\" aria-describedby=\"caption-attachment-14190\" style=\"width: 526px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-14190\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2022\/10\/image_unipolitique-861x600.jpg\" alt=\"Biblioth\u00e8que de l\u2019Universit\u00e9 de l\u2019Illinois\" width=\"526\" height=\"367\" \/><figcaption id=\"caption-attachment-14190\" class=\"wp-caption-text\">Repr\u00e9sentation all\u00e9gorique de l\u2019Alma Mater entour\u00e9e de Labor et Learning, Statue en bronze accueillant les \u00e9tudiant\u00b7e\u00b7s de l\u2019Universit\u00e9 de l\u2019Illinois<\/figcaption><\/figure>\n<p>UniPoKo, la commission de la politique universitaire qui permet \u00e0 chacun\u00b7e d\u2019avoir la garantie de voir ses droits et devoirs politiques au sein de l\u2019Universit\u00e9 d\u00e9finis et soutenus. Elle soutient activement la mise en \u0153uvre de divers dossiers de l\u2019ex\u00e9cutif et du l\u00e9gislatif de l\u2019AGEF, mais peut aussi se lancer dans des initiatives propres telles que des soir\u00e9es de sensibilisation ou des conf\u00e9rences autour d\u2019une th\u00e9matique, et doit tenter de d\u00e9finir la vision politique de l\u2019AGEF, en accord avec celle du CE. Une commission id\u00e9ale pour des r\u00e9flexions sur ce qu\u2019est l\u2019Universit\u00e9, ce que sont les \u00e9tudiant\u00b7e\u00b7s et quels doivent \u00eatre les rapports entre les deux.<\/p>\n<h2><strong>\u00c9galit\u00e9, gr\u00e2ce \u00e0 \u2026<\/strong><\/h2>\n<p>EquOpp (pour Equal Opportunities) qui est en charge du dossier aussi essentiel que monumental qu\u2019est l\u2019\u00e9quit\u00e9 et la justice en toute circonstance universitaire, peu importe son genre, son orientation sexuelle, ses origines, sa religion, sa situation sociale ou physique. C\u2019est une des commissions les plus imposantes, ayant m\u00eame en son sein un sous-ensemble, appel\u00e9 groupe de travail, enti\u00e8rement d\u00e9volu aux in\u00e9galit\u00e9s de genre, HERights. C\u2019est cette commission qui g\u00e8re l\u2019outil de reports des discriminations, organise des workshops ou conf\u00e9rences sur les probl\u00e9matiques de la justice sociale, a cr\u00e9\u00e9 un club de lecture f\u00e9ministe, sensibilise mais aussi lutte concr\u00e8tement pour l\u2019avanc\u00e9e de l\u2019\u00e9galit\u00e9 au sein de l\u2019Universit\u00e9, s\u2019est mobilis\u00e9 pour la mise \u00e0 disposition gratuite de protections hygi\u00e9niques dans l\u2019UniFR. C\u2019est la commission o\u00f9 l\u2019on \u0153uvre \u00e0 \u00e9chelle estudiantine pour faire bouger les mentalit\u00e9s\u00a0! Et comme toute commission, ses r\u00e9unions sont ouvertes et tu peux y assister avant de t\u2019y engager.<\/p>\n<h2><strong>Soir\u00e9es et \u00e9v\u00e9nements, jamais sans \u2026<\/strong><\/h2>\n<p>UniKult, la commission des \u00e9v\u00e9nements culturels au sens large, des ap\u00e9ros de l\u2019AGEF au mythique Centre Fries aux festivals, en passant par du speed-dating pour les \u00e9tudiant\u00b7e\u00b7s. Sa mission, faire de la vie en dehors des auditoires une opportunit\u00e9 d\u2019aussi se d\u00e9tendre, s\u2019amuser, se rencontrer et se retrouver. Son but est de promouvoir et soutenir les \u00e9v\u00e9nements estudiantins hors \u00e9tudes. Bien \u00e9videmment l\u00e0 aussi la porte de la commission est ouverte \u00e0 tou\u00b7te\u00b7s (en particulier si \u00ab\u00a0tu as des talents pour servir les cocktails\u00a0\u00bb nous dit-elle).<\/p>\n<p>Si t\u2019engager te titille, n\u2019h\u00e9site plus ! Il y a bien assez \u00e0 faire et ce sur tous les plans, pour notre ch\u00e8re <em>Alma Mater<\/em>\u00a0!<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"604\">Petit rappel\u00a0: l\u2019AGEF est l\u2019Association G\u00e9n\u00e9rale des \u00c9tudiant\u00b7e\u00b7s de l&rsquo;Universit\u00e9 de Fribourg et tout\u00b7e \u00e9tudiant\u00b7e en fait automatiquement partie \u00e0 son inscription \u00e0 l\u2019UniFr\u00a0! En sont une \u00e9manation, les Fachschaften aupr\u00e8s desquelles tu peux t\u2019engager sans h\u00e9sitation. Mais aussi le CE et le Comit\u00e9. L\u2019AGEF est ainsi \u00e0 la fois impliqu\u00e9e dans la politique universitaire, dans des \u00e9v\u00e9nements culturels, mais aussi aupr\u00e8s du quotidien estudiantin au travers de nombreux services : bourse aux jobs, aux logements, aux livres, location d&rsquo;un bus, etc.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQxtLAEAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"88lMSi0qObxSR+HwyvTEnEwgUyG1RKE4P7Po8MrU4kMLFAE=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"FcVBDoAgDATAF8EiR3+DWKUJImmX\/xvnMo2cvgPOdcpgXEMvi7XBp1TaepBTztgSuh5ilCB36frP4K+aiOMD\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c8zJLM7PU3AtTT+8Mi8zVcEpNS8ltQgA\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtI1NNA1MFEwMrYyNLAyNgYA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"jVhNbxzHEb3nV7T3YEjAcJdiHCaRlwRkhXIEK7AgIYecjN6e5mzLPdPD\/lhzdfLV5+SSm5BDoHV+gBHkxkH+iH9JXlX37A5NEshB4s5MT3fVq1evqma5fnL+yqy0j8OuEsOukdbgp9BRBGf8sNPh5sMnywWW\/Wq5Pjl\/raOJWmxMMK4T9c\/f\/113Qbcrq0WtRfTOBGHa3vkou6iDUK5tTaDFQaTObLQPJkrj8ah3yQsrhdddpIMqcZWws0sBR2\/1e2E6WIKVYdjd\/KRvfsIrkt\/oHYw0WF3RlU0RFimHXbSw2Lg2QXnTmk5GOrfimyvXdTrsnRIu8e1s8fCBNrrEzyob0GkybwMjrhJ83NI6XHo8pVOw2VonPxd\/IR\/+PPq1xXu6DmLrUgbtBKD15y+t0CEKBZClAQ69N50yvcZh5R4MMTWbpdbDRwJHpmtEI6baAMfiPQC2MGZ\/HMKEWy+8WcGKZi6e6153NdbDs+SDAPDYSXfiv39NG88QKT98pLDUupVdDeARFPgmN9JY2gzYXFp9TbEFAyi8zjeyM4GhhBsB7xhtc\/AoXkpb4HikDGGm8gLaKYAQw26jret77SveXG4pCH7ceviRsARRGrPiuEmAAyJdJRdNbTSdVxAw3VxcxHxqL3GIx4YIKh8+Yvfz93\/L4YIvlzJFMuAdQqvW2tM\/XkDAShUJ\/DtgupgJdA\/wbbLR9JaJE43F2zUIVwnNrMNhnnYEmBY5ZIIFXpeiT163hMfED\/EIHj4HLTWsvJjcByGfX4wxfvblxYvHFfvYW6kO4ITpAUE0w65DjpBT97BDph7xDnkb7y4pOskXpxAE5ayVK+dl5NvRG\/UQ0R4Vk\/nhC6kABwnG9O4fhh3yM7LHlXgLyyQBFNX8MTmnO+UAFSDS18NOJQJo2NmUk1qT8xmadmT2Hoj5ctFzJr2m+ANsSSeAeVJ0pEBILo479kbIV4keYlNmi9wg4xmBCL5p9pup42VghjqbRnSlqBOpA+kBrdkrl7IsWVWxUwrk0Y6NvKVwlWCRoFOwQwRTCtb3keoqGahRWkvoqZeGaBJYThvZaEjLRQexMcgrlqgKARx2lFxM9ZU3w8cNQ33z4WmGB2qzDFjcNRNFlxutwPt\/LhflUVGlS9OAnMics5mMUao1bfXNk8+e\/P54JqQ38gi+QUVXul5tz2ZK9iQAR4e1R2VtiFurz2bfmTqun4rfnJz21zPCKwTc7I\/KiwJlpekU3tN+dr40bSOsk7XpmrOZle+3M0CpXL6WYdup\/R4Cm5gWkOwP9Opsto6xD08XC8ofbDpHabn0c7VehF6r6FO7oLORoXi4SD2dFRYnxycniyfHC97uG7yyryNHvzt9cn16fDx\/1zdw38az2RfQJOMi5JhU7n7ppVsvrTUdAgRDCYKzGSCYibU2zRq7\/Pr0tzOxOCe4RyQI8ofhvIPcUdTXcXb+Ro\/xlwVP0gHnzcS6Z7aV4k9IZk+y5DKV8ewV5Tjx\/pWWvgPGyE5sgxchsSuw4j0UTKmERLa5eoT\/s\/ZMAVguDk6e8wUIxlmLl167rxwX60O28PuTWn67PeD0QOFoYTZLOCSngy1cOHJO4+VGehJP9pLvUcGrkS+x5DndDIczqK5ijenu9Qe1z6DU5d4ngTopIA1RYfiSMxSVw+S0o+OpwE7qK\/aseTvUBrjIP\/IxB8Ujq9KtIjERukq0Euf3GrVLJmxBVRQhUVTuSKFIb2BiNJLMYFHvqVuIuQ5mLkyaHK7DXTArY8cSDiXOqtVdUnPVKQaF2MLQJlRxkH7XytJgkcHAU0TOXfYx48QBKH3gIYi3vAE04JXzdZYhbhXI\/ecXczRNekoGKuHS6qzZZOChE4E\/uKd01ngS+19ErsoPKUwPsFdTgdBUphzewqLcetBSL3vqVkOp5NyH6HQ9v6Opww+lN65E44d\/KK4S9yhrf35xlb7ue\/GIfcGFtOJrPiRR6HR4zOQmRwAQmO0bRqWQpkT+0GqRZ63rErFO2tsoDDtsVfp1hONdChE1nPal6gOEjUekQyQO3U6wimhWWnVGTjS6o9v0E7qyV5qgrxMFruLkwpOG+lVcUecOVccavsC+qbzhlKFYgmr9ehuIF2hOi9VEsF+UTQa9pzJM5gQeHFC5tqRF7fBjy\/4ENgWZm+h3Ckfj3IGV6DCRUQiLS32ZQ7ij5fbMUEPNGVuqPbeAptvPOpwmxfk\/Xrwh4Q4He5XO08WeqRS7hvbkAHA3yM2tzjSq7xtAShOdPf\/O+W\/D2vU8g9zKQ+K5zWm9svscDEUpx+AWeKtDGwJIlE0rXofyR4Udm7YkZpHjNkqAzgKTGbafm\/JQwBDlmYwlFpQp9SMTbZwMH1bQKjcwAK11fBxWj0MeSyW1VSYgxIZ50qDxTDRNYiu4HGE602G9bQy6x+I7d2b5oBdvDnG5XUvc8O8cjr0Y4yxo7polZ9J+F4W55BqDuQmtFkOek4vpgNGNZg3aXY9ptD8pZwFgRzKxNJHk7Ls+ZGFMlFjXYitQyAl\/akFlnokij5Jjh3dHYd6Osk01b7cBBBwU8Oed5LgFwuJeyQE4X6Elv1tiw62dBPXtoIcthZCbXshPnjRkDya6MNVwWtZu45q1\/XmWSAycZUDFQIE6JGkaQobSXEaOUj8POUMnpuujGhzumkKDu8o8F2+l2EObo5LZvjGc9rVeO5+zSuLF6PjTAYmI20sq1W6i7FgxkeeoVjWLGd1vU6AJNFCSdvk7AbdDfKMM9jAEeGF0YF3OhGzxhJqKfT9gRh8miE64BeaSreyihmtf0AiLxQbTdm4ZQMqSe9T4+Dg6OwkZHV\/4VIYIDGZcxB4xxh4akCzVCWxz86+bDyCczACBwGwSgw2XN8Ve5dS30HwLZt\/8R3T0fQNIHlFqHEart4bpWciJci8ispR1n2YstASBUpVl+hPx0hLBxYo8pHH8Pdmaw0dzpWYpi3RS1nZJKsh2dfwBJX\/mEEvdnh+61uUCl\/zhhEyKEuJOf1eu3tJfT\/\/VY5t9evzZLH+N4hKuLeagA23H+vgssFqy3HxZZmWbZXj44W6H+6kPV8l9\/sAXFk7vPNTd4jHxFL5H7qOKaGc1pWhxGKl6gSCoCnkIoA9ORdM8602XlYSITcKfK0f+coVpex3QJlxGAvsw0l+l3PWNijMNHytFjhnvNAfCB+HnIZY6hv24PRevptDRZyoz+SpGhdnCLS4IZVR+oHGvDp3q\/cpTTWvQ3p10\/1cf0h8q5qWX7ly78uQrs5tK5lMScR8069E7t6LGAb+sa0bt5EuzyeO7U5kLdYl0opwP+SvFchFrUGzBRFuMtFuMPOzPP+1Wof+c2fk\/\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Libert\u00e9, \u00e9galit\u00e9 et soir\u00e9es\u00a0! Petite vision d\u2019ensemble de trois importantes commissions universitaires pour la rentr\u00e9e, que vous soyez int\u00e9ress\u00e9\u00b7e\u00b7s par la politique, la lutte&hellip;<\/div>\n","protected":false},"author":151,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[113,174],"tags":[186,2266,1746,2511,2512,2513,1134],"class_list":["post-14189","post","type-post","status-publish","format-standard","hentry","category-campus","category-politique-universitaire","tag-agef","tag-discriminations","tag-egalite","tag-liberte","tag-soirees","tag-unikult","tag-unipoko"],"views":1240,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/14189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/151"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=14189"}],"version-history":[{"count":0,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/14189\/revisions"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=14189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=14189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=14189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}