{"id":15154,"date":"2023-09-26T13:57:38","date_gmt":"2023-09-26T11:57:38","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=15154"},"modified":"2023-09-26T13:58:05","modified_gmt":"2023-09-26T11:58:05","slug":"antigone-ou-quand-la-rebellion-tourne-a-la-tragedie","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2023\/09\/antigone-ou-quand-la-rebellion-tourne-a-la-tragedie\/","title":{"rendered":"Antigone, ou quand la r\u00e9bellion tourne \u00e0 la trag\u00e9die"},"content":{"rendered":"<h2><strong>Quelle figure f\u00e9minine pour parler de r\u00e9volte ? Jeanne d\u2019Arc ou Rosa Parks par exemple, mais le choix de <em>Spectrum<\/em> s\u2019est port\u00e9 sur l\u2019antique Antigone de Sophocle. <\/strong><\/h2>\n<p><strong>Antigone dans le Grand Dictionnaire Larousse de la Mythologie Grecque et Romaine (2011)<\/strong><\/p>\n<p>Incarnation de la r\u00e9volte face \u00e0 un pouvoir injuste, cette femme au destin tragique aura suscit\u00e9 d\u00e8s sa cr\u00e9ation nombre de questions et de d\u00e9bats philosophiques, encore vivants aujourd\u2019hui. Appartenant \u00e0 la famille maudite du c\u00e9l\u00e8bre \u0152dipe, la \u00ab\u00a0rebelle\u00a0\u00bb est issue de l\u2019union entre ce dernier et la reine Jocaste, m\u00e8re de celui-ci. Lorsqu\u2018\u0152dipe comprend plus tard qu\u2019il s\u2019\u00e9tait mari\u00e9 \u00e0 sa m\u00e8re, il se cr\u00e8vera les yeux et sera chass\u00e9 de Th\u00e8bes. Antigone d\u00e9cide alors de rester \u00e0 ses c\u00f4t\u00e9s jusqu\u2019\u00e0 son d\u00e9c\u00e8s \u00e0 Colonne. De retour \u00e0 Th\u00e8bes, la jeune femme se voit \u00e0 nouveau frapp\u00e9e par une trag\u00e9die. Ses deux fr\u00e8res Et\u00e9ocle et Polynice s\u2019entre-tuent dans leur lutte pour acc\u00e9der au pouvoir. Le roi Cr\u00e9on d\u00e9cide d\u2019accorder des fun\u00e9railles uniquement \u00e0 Et\u00e9ocle car, \u00e0 ses yeux, Polynice \u00e9tait un tra\u00eetre \u00e0 la patrie. Ce dernier interdit m\u00eame \u00e0 quiconque d\u2019\u00e9lever un tombeau pour le rebelle sous peine de mort. Antigone, refusant cette id\u00e9e, tente de convaincre sa s\u0153ur Ism\u00e8ne de l\u2019aider pour dresser une s\u00e9pulture \u00e0 leur fr\u00e8re. Celle-ci, jugeant l\u2019entreprise trop p\u00e9rilleuse, refuse. Antigone, bien r\u00e9solue \u00e0 le faire malgr\u00e9 tout, se fait prendre et est conduite devant Cr\u00e9on, intraitable. L\u2019intr\u00e9pide jeune femme ainsi que sa s\u0153ur, bien qu\u2019innocente, sont condamn\u00e9es \u00e0 mourir de faim, emmur\u00e9es \u00e0 l\u2019int\u00e9rieur d\u2019un tombeau. H\u00e9mon, le fianc\u00e9 d\u2019Antigone et fils du roi, se dispute avec son p\u00e8re, qui accepte finalement de lib\u00e9rer Ism\u00e8ne. Le jeune homme s\u2019enfuit alors, tandis que le devin Tir\u00e9sias pr\u00e9vient Cr\u00e9on d\u2019un grand malheur \u00e0 venir s\u2019il s\u2019obstine \u00e0 retenir Antigone prisonni\u00e8re. Refusant d\u2019abord, il finit par accepter de rendre sa libert\u00e9 \u00e0 la jeune femme. Malheureusement, il est d\u00e9j\u00e0 trop tard. La jeune rebelle s\u2019est pendue et son fianc\u00e9 \u00e9treint son corps sans vie. Une nouvelle dispute \u00e9clate entre le roi et son fils. H\u00e9mon tente d&rsquo;assassiner son p\u00e8re mais finit par s\u2019infliger le coup de gr\u00e2ce. Eurydice, sa m\u00e8re, ne supportant pas la perte de son fils, se tue, souhaitant le malheur \u00e0 Cr\u00e9on, son \u00e9poux. Ce dernier est effondr\u00e9 et la pr\u00e9diction de Tir\u00e9sias r\u00e9alis\u00e9e.<\/p>\n<figure id=\"attachment_15155\" aria-describedby=\"caption-attachment-15155\" style=\"width: 810px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15155\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2023\/09\/Dossier_Emilia_Illustration.jpeg\" alt=\"\" width=\"810\" height=\"551\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2023\/09\/Dossier_Emilia_Illustration.jpeg 810w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2023\/09\/Dossier_Emilia_Illustration-768x522.jpeg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2023\/09\/Dossier_Emilia_Illustration-530x361.jpeg 530w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><figcaption id=\"caption-attachment-15155\" class=\"wp-caption-text\">Antigone devant le corps de Polynice, Nikiforos, Lytras, 1865, 100&#215;157 cm. \u00a9Wikimedia commons<\/figcaption><\/figure>\n<p><strong>Quelles le\u00e7ons tirer de la trag\u00e9die d\u2019Antigone, cons\u00e9quence de ses convictions in\u00e9branlables ?<\/strong><\/p>\n<p>En partant de la r\u00e9ponse donn\u00e9e par Antigone \u00e0 Cr\u00e9on lorsque celui-ci rend sa sentence \u00e0 la jeune femme, c\u2019est-\u00e0-dire, qu\u2019il n\u2019est personne pour aller \u00e0 l\u2019encontre des lois divines qui sont au-dessus de tout, m\u00eame d\u2019un roi, <em>Spectrum<\/em> se propose d\u2019explorer bri\u00e8vement les d\u00e9bats philosophiques et moraux inh\u00e9rents \u00e0 r\u00e9volte. Certes, en pronon\u00e7ant ces mots, la rebelle r\u00e9v\u00e8le son id\u00e9alisme et sa noblesse, mais peut-\u00eatre \u00e9galement son manque de patriotisme, \u00e9l\u00e9ment qui, sans doute, lui enl\u00e8vera toute magnanimit\u00e9 de la part du roi.<\/p>\n<p>Selon Hannah Arendt, cit\u00e9e dans l\u2019ouvrage de Lionel Ponton <em>Philosophie politique et philosophie du droit<\/em>, la r\u00e9volte ne peut se faire par la violence, outil propre au pouvoir. Le bin\u00f4me Antigone\/Cr\u00e9on peut \u00eatre apparent\u00e9 \u00e0 cette id\u00e9e, en ce que la premi\u00e8re, d\u00e9crite comme douce et id\u00e9aliste, s\u2019oppose de mani\u00e8re douce et noble \u00e0 Cr\u00e9on qui, lui, est violent dans sa r\u00e9action. Or, que penser d\u2019une r\u00e9volte faite avec douceur et passivit\u00e9 comme celle d\u2019Antigone, lorsque le pouvoir, lui, d\u00e9montre toute sa puissance et sa violence dans la r\u00e9pression ? Faut-il croire que r\u00e9volte va de pair avec violence pour qu\u2019elle aboutisse ? D\u2019apr\u00e8s Hannah Arendt, si la violence permet de d\u00e9truire le pouvoir, elle est incapable d\u2019en construire un nouveau. En ce sens, la r\u00e9volte pacifique men\u00e9e par Gandhi, et ayant abouti \u00e0 l\u2019ind\u00e9pendance de l\u2019Inde, est un exemple inspirant.<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQ1NDUBAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c8wryUzPz0vVUcgvVSgsTcxLUchJVCg6vDIpNScnMz9PoSS\/tCgvVeHwApB4SVFi+uGVKZmpAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"FclBEoAgCADAFxGNneo3lKTMGBbC\/6vrbnW\/x4Y4PDKrT6Fy2nRUHDcfbnFhmtOC84qkLqUrQw94gjRDIzDeuTXpCt7DvqRf3ahwFsYX\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c83NzMlMVHAsLskvysxLBAA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtY1sNQ1MlMwNLYysLQytgAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"tVhNjxvHEb3nVzQYwLABfixXWFmxd1cQJMWWsU4Uy0GOQrOnSbbc0zPqnqZ2ffJvSC7xTcjFogPk5FtuIvxH\/EvyXvUMybWcowBBCw57uqpevXpVxfP16eV56mITVpd\/ydZ7q5ZulSP+7La1Cy5Y1TY5qlZHb6OqrIq77abxnVX31RdWBxyofvnu+wfRqCarr5qk1VMdv0l8Q9lrW7fejlWtXVK43Kwbd81bzm19+ay1pou5Pp\/hg0q4xaYO5mK326oEox6PdOjcy2zVA\/xdNbRm1bOmXTfG26k6n\/XOn88Qye\/O2300h\/M6iOnPog6VeuRM55oQtEOMVzo2OSW502v15U23bnyzcjxsDa3aDiHBedzz4enJfP7RkcFW7D0JRsegeWl\/zR6gpTZW7V6rHIjhpnFRufAipw6AGNvxhK1rq3TGm6lzQXVRryRanaMGBMk4YlHt3iQFYA2uLpZCUy+i+I3TiY8SfcXnardd6A7wr51vEoDifWmsbDAN3ti4DRBNMPACaWXm1tlN1YMW6epswHf0GFEsde1Ih1rnysHVKiuz2\/rdG9r9+e+VaxEFzr3999vX0S5Inbev3\/5XMYUupVxAxf050GEbOrxn+DQGBybBW2JlCe0XjdGCSr17U6Iy1mc3MfDsqonpZf7lu38Wm8o0dRstMtn6nFSnY6X49ffOC4N22067Dl5HB+AQCmCTW8eKJywxfLOxQNfbpG5svqYniQ\/MWqdEtK36eo04bZoesW63NQ7faA9\/pAwQKMKgBVxkdj8hUUkhu+INH5MQeIu5w8eHYBaKZaoe8d2ONYWnvSFB8oXNYaAEHAVfJBcB1LGgyDLqtt1trRQWT5Isu23lcOczS58QyzIy1qQewxtWCIN72vib4AC9VBjzMOky\/g6VwULLZKMUujZIM5JEVvasRRLgc+PUQ\/Cvj4pYkD043sRKlCGpZQ67bdTkTYKLZF5tC6P2DqFaxgNqhH988K\/PXZY62P2HhClcbHUXGebDA31cAPoVM737sZZzL7MzTWDxVMIDb5FmuQy1Yks0kULQsxUJAoFaISCCqSE7h3yPcWqZE8uhVKpD0HiKEukKQZuwgSwY+AiGpZ\/\/gbufJDAt7ImvHXERqxVykmxJGyjWZt\/lPjrCX7LG+OAXWD8Gj1aWxv2Qsja6xJQ3rQIJIiHOaXDTHju+cDZQg1Ljc28CxUy5q7Vf4QsAkrsxKbYk3FJNUZjC2kVgVZaCt1SKPudjAo7MdnpB2b1iweEBQiERjpkLUJKjKu1x6V0qVRpCY4jhmPVRrOkarLFSJDXActJl4FoN0arrHIcvfTHK6AlaJdoyZHeqPkfDoqPSwnQwrGQ2pqGCEd\/S+UQhA5cl\/sqlNiNUvbFG6rUtSgEqsQ5sS4l2QftCY+bVLWDf7nMtpVHCXzdSuJKwJRAsUgHKoO2g+RERL6hC5792TJDT4B+7hbN7oIewVtKtkLG1LUqxsQHIpIPSNQu2DMkw9ES+3cdKtkBtXKHVVwOVpWAXqFcRQ0TG9Os4xFrae2EDkodYrbTiUoRHSZ6qL4tj5CChkfvIHlTJCxwXnlKbgc\/w5r7shj4PQ6XDEvkhZdAA9oTyENLSsvFBpjas\/7\/iGpFD3jMkD2LkNf6WDuOLUu1v9WlgxlC7H7CfNJ9C6\/EPAMZD5suYcsBF0A5L71ZWlMM0uSVGqKJ\/GfjzOMebCso1PuoyrPDccogh4i1STAEDkKILg1NCP6gwyyCvWVcsdnuc8KHw+ArqrMnXtwSQENrlEvXDki7dlGSqyoAjXWzPMs4N3kF57LTMLf2Q56qLke46bdbM4vP52fzsbKTQO\/UEem4iGFAtbi5GRre8dHI4O+nPpu7G24vRK1d160\/UvflJez1SSEhKeNhO+hdRC26F0g92dHnu6pXyja5cWF2MvP72ZgRnTVM+63QTzP6G5L61k2X2XuEuV+uV3duN5mK07ro2fTLDSJYr+DRFy1nGqVnPUj9ZzugCdAZfznJLo2l2enJ6Z3byh9mjBum38fljzDlOP3\/iMU9A4uju9EVrV8DBdxejkZLYLkaIbaTW1q3WeHp2Nhcfku3esxvE9NVYvS8bk4\/v3rs+Oz0ttvDhfdo6u3NyfefuvNjCh1fAEBlGonXumrH6sNbXk2MqfaTmJycbuNQTa3ZJ5g6kInv\/PzPfIeGks9fd6GgxKA1O6po6g4oZRpGx+pP7xi2b2KBSr27gP\/7O7909G9OhD35\/Oj\/7dH72sTL1VL3d\/g1na1s5zeEUSpPOZwcvL+UDiu3WdlJ2LU5fux84u3cuFvlFFe\/nulv9a8xeiQpGHwmmaAnnTowhpeATOjRGf7QNzx6d1P13VpXHgaomUrPfVFq8idvQLIbRco\/PXoOUlxn8MJVLk5D+TkkNxr7bIuBu0fnJ7vWkcqWrluYV9g0gskkNc6f3ZZwuIw\/pJasAMGogypVD37RJWrNMDjpTorAiMZYy0ZRRsG+g0uN\/Y8tkc2zaJpWD9hr0JfQL7AvYC6TPE73fXqOosxgUNSZtF9acBLhLsQP3Ox8lGlIv+xYNQfJ2P5QpMuHNrkz6QyvkW7s3vrQFTpgU6br0RI1OxzymYXtubQaYP8pUvF0NMwnfrHUZe20ZlJuOl2DIxra2lUMAbVzaaAWguLcBRRt8vwkRPbaeFdY\/V5eN05a5O3b9vDQdSPTMYo9Rn2Px12v1gEQA8rKmDqs2Z5O8AYnFpStw03pUVujwHhPydA8pU+9d2e8Rc3v0BaxWMNtJ1sa31moyBlj0A2wsrMWBjWs8yThWiAc8Y56j\/fUes0CZ\/FQffk+Y9RyXKwu8msuwDf3oc2v+R1aNLbMc262tXen6XIkip2YjUyBgNhLSkFQZeAlMW6hHuMt4djgr+T6qOsma53+slhJdv7QlgUNL4U\/Vn+NYXMJExSWjFIA9\/h3CDUOuGMuyfbccfzaS7eK0KWPVLc0ZKt\/bAcTepUpmKqJV2AOP2oy9Xwcz8HfIR0+LIjdchKjd99UfofkTpMkgzbFguvd4owubMdOK2\/urRCpESMRZDLNINX\/Bua8ecbjFBIR1+1fsxD5yRA\/qTr3\/rQTK4OLt+ORm+RkjQMMppkUqgihw\/0IOw2KOMVBIAS1Mt4naauOWQm5U4SCvn2GuXzOnkLAbKkOJ4bDgwCmOxrpXeT58EipbWACz\/W9q8C61DnLfldL8Hw==\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Quelle figure f\u00e9minine pour parler de r\u00e9volte ? Jeanne d\u2019Arc ou Rosa Parks par exemple, mais le choix de Spectrum s\u2019est port\u00e9 sur l\u2019antique&hellip;<\/div>\n","protected":false},"author":163,"featured_media":15155,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[1228],"tags":[],"class_list":["post-15154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dossier-2"],"views":2077,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/15154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/163"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=15154"}],"version-history":[{"count":1,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/15154\/revisions"}],"predecessor-version":[{"id":15157,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/15154\/revisions\/15157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/15155"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=15154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=15154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=15154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}