{"id":16253,"date":"2025-12-08T16:42:44","date_gmt":"2025-12-08T15:42:44","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=16253"},"modified":"2026-03-24T16:30:49","modified_gmt":"2026-03-24T15:30:49","slug":"pafe-p-comme-polemique","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2025\/12\/pafe-p-comme-polemique\/","title":{"rendered":"Pafe : P comme Pol\u00e9mique"},"content":{"rendered":"<h1><strong>85 mesures, 405 millions de francs \u00e9conomis\u00e9s, mais de nombreux m\u00e9tiers touch\u00e9s. Vous l\u2019avez vu dans les journaux, \u00e0 la t\u00e9l\u00e9, et m\u00eame dans la rue\u00a0: Spectrum vous fait un topo.<\/strong><\/h1>\n<h2><strong>Unifr s&rsquo;en m\u00eale<\/strong><\/h2>\n<p>Si vous vous baladiez sur le campus de Mis\u00e9ricorde dans la matin\u00e9e du 1er octobre, vous avez s\u00fbrement remarqu\u00e9 un attroupement devant le b\u00e2timent 01. Si vous vous \u00eates attard\u00e9s un peu, vous avez peut-\u00eatre entendu un ou deux discours enflamm\u00e9s, voire pris un morceau de pain, une brochure ou une assiette de frites.<\/p>\n<figure id=\"attachment_16254\" aria-describedby=\"caption-attachment-16254\" style=\"width: 396px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-16254\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/12\/manif-PAFE-photo-article-800x600.jpeg\" alt=\"\" width=\"396\" height=\"297\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/12\/manif-PAFE-photo-article-800x600.jpeg 800w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/12\/manif-PAFE-photo-article-768x576.jpeg 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/12\/manif-PAFE-photo-article-1536x1152.jpeg 1536w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/12\/manif-PAFE-photo-article-530x398.jpeg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2025\/12\/manif-PAFE-photo-article.jpeg 1600w\" sizes=\"auto, (max-width: 396px) 100vw, 396px\" \/><figcaption id=\"caption-attachment-16254\" class=\"wp-caption-text\">Manifestation du 1er octobre \u00e0 Mis\u00e9ricorde<\/figcaption><\/figure>\n<p>Ces manifestants, principalement des \u00e9l\u00e8ves ainsi que quelques professeurs, \u00e9taient l\u00e0 depuis huit heures du matin. Selon Lionel Roche, \u00e0 dix heures et demie ils \u00e9taient pr\u00e8s d\u2019une centaine. Leur plan, nous informe-t-il, \u00e9tait d\u2019attendre leurs coll\u00e8gues de l\u2019h\u00f4pital cantonal, puis de marcher jusqu\u2019\u00e0 la fondation le Tremplin, \u00e0 la route des Arsenaux.<\/p>\n<p>Soudain arrivent \u00e0 point nomm\u00e9 leurs coll\u00e8gues de l\u2019HFR, qui d\u00e9barquent en brandissant des drapeaux rouges au logo de la SSP, ainsi que des pancartes aux divers slogans. Ils se regroupent en demi-cercle devant le b\u00e2timent, scandant \u00ab On est l\u00e0, m\u00eame si l\u2019\u00c9tat ne veut pas nous on est l\u00e0 ! Pour d\u00e9fendre nos valeurs, et pour tous les travailleurs, m\u00eame si l\u2019\u00c9tat ne veut pas nous on est l\u00e0 ! \u00bb en ch\u0153ur.<\/p>\n<p>Leur but ? Convaincre le Conseil d\u2019\u00c9tat de ne pas mettre le PAFE en marche.<\/p>\n<h2><\/h2>\n<h2><strong>Le PAFE, c\u2019est quoi\u00a0?<\/strong><\/h2>\n<p>Le Programme d\u2019Assainissement des Finances d\u2019\u00c9tat (PAFE) est d\u2019abord une r\u00e9ponse aux mesures d\u2019\u00e9conomies du Conseil f\u00e9d\u00e9ral, elles-m\u00eames pour pallier des probl\u00e8mes de financement et d\u2019endettement que l\u2019on craignait d\u00e9j\u00e0 depuis 2023 selon les rapports budg\u00e9taires de l\u2019AFF. L\u2019\u00c9tat de Fribourg se retrouve donc contraint \u00e0 son tour d\u2019\u00e9laborer un programme d\u2019assainissement des finances de 2026 \u00e0 2028. Celui-ci vise une am\u00e9lioration de 405 millions de francs sur cette p\u00e9riode en augmentant les revenus et r\u00e9duisant les d\u00e9penses. En effet, dans les ann\u00e9es \u00e0 venir, Fribourg perdrait certaines mesures de compensation, notamment par une diminution du revenu provenant de la p\u00e9r\u00e9quation<span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"#_ftn1\" name=\"_ftnref1\"><sup>[1]<\/sup><\/a> <\/span>d\u00e8s 2026 et son arr\u00eat en 2034 au plus tard, ainsi que l\u2019arr\u00eat du financement additionnel de l\u2019AVS en 2030.<\/p>\n<h6><span style=\"color: #3366ff;\"><a style=\"color: #3366ff;\" href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> R<\/span>\u00e9partition des ressources entre cantons plus ou moins \u00e9conomiquement forts.<\/h6>\n<h2><strong>Cons\u00e9quences pour la population fribourgeoise<\/strong><\/h2>\n<p>Cette liste, accompagn\u00e9e d\u2019explications et tir\u00e9e du document officiel, pr\u00e9sente une s\u00e9lection de certaines de ses mesures. Ainsi, sous ce projet, nous verrions\u00a0:<\/p>\n<ul>\n<li>Une r\u00e9duction de la d\u00e9duction des frais de d\u00e9placement dans le cadre professionnel, le plafond passant de 12&rsquo;000 \u00e0 8&rsquo;000 CHF.<\/li>\n<li>Une suspension de l\u2019indexation des salaires pour ces deux ans, sauf si l\u2019inflation d\u00e9passe un certain seuil.<\/li>\n<li>Un d\u00e9calage de l\u2019augmentation du palier\u00a0de huit mois\u00a0: de 2026 \u00e0 2028, les travailleurs publics soumis \u00e0 la Loi fribourgeoise sur le Personnel de l\u2019\u00e9tat (LPers), c\u2019est-\u00e0-dire une majorit\u00e9 d\u2019entre eux, ne pourront pas demander d\u2019augmentation de salaire entre le 1<sup>er<\/sup> janvier et le 1<sup>er<\/sup><\/li>\n<li>Une augmentation du co\u00fbt des EMS, passant de 13 \u00e0 23 CHF par jour.<\/li>\n<li>Une augmentation de 20% de la charge financi\u00e8re des communes dans le domaine de l\u2019aide sociale en r\u00e9duisant de moiti\u00e9 les subventions de l\u2019\u00c9tat.<\/li>\n<li>Une augmentation du revenu consid\u00e9r\u00e9 dans le calcul des bourses d\u2019\u00e9tudes\u00a0: l\u2019on prendrait une plus grande partie des revenus en compte, ce qui r\u00e9duirait le montant de la bourse octroy\u00e9e.<\/li>\n<\/ul>\n<p>Mentionnons aussi la limitation du soutien financier dans les structures d\u2019accueil extrafamilial, comme les cr\u00e8ches, les cantines, les colonies et les accueils extrascolaires. Financ\u00e9e par le m\u00eame canal, la prise en charge du soutien \u00e0 la construction des b\u00e2timents scolaires pour l\u2019\u00e9cole primaire et enfantine sera aussi supprim\u00e9e. Les frais d\u2019\u00e9colage et taxes d\u2019examens finaux pour le secondaire 2, quant \u00e0 eux, se verront augment\u00e9s.<\/p>\n<p>Et voici finalement la section dont l\u2019on entend beaucoup parler\u00a0: les mesures en mati\u00e8re de personnel. L\u2019\u00c9tat pr\u00e9voit de renoncer aux mesures p\u00e9nibilit\u00e9 (c\u2019est-\u00e0-dire les compensations donn\u00e9es aux m\u00e9tiers consid\u00e9r\u00e9s comme physiquement p\u00e9nibles), aux primes de reconnaissance en faveur du personnel et aux salaires des \u00e9l\u00e8ves de l\u2019EMF et \u00e0 l\u2019Eikon. Il est pr\u00e9vu de geler les diverses indemnit\u00e9s vers\u00e9es aux employ\u00e9s. Les institutions sp\u00e9cialis\u00e9es, l\u2019ORS, l\u2019HFR et le RSFM sont \u00e9galement touch\u00e9s.<\/p>\n<p>Les cons\u00e9quences financi\u00e8res du c\u00f4t\u00e9 environnemental risquent aussi d\u2019\u00eatre importantes\u00a0: il s\u2019agit de r\u00e9duire l\u2019aide pour l\u2019agriculture et les subventions en faveur de la biodiversit\u00e9 et du d\u00e9veloppement durable, ainsi que de renoncer \u00e0 la compensation des baisses des aides f\u00e9d\u00e9rales pour l\u2019environnement.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Taxes \u00e9tudiantes<\/strong><\/h2>\n<p>En tant qu\u2019\u00e9tudiants, vous avez s\u00fbrement entendu parler d\u2019une augmentation des taxes d\u2019\u00e9tudes. C\u2019est en fait une mesure au niveau f\u00e9d\u00e9ral. Pour citer le plan d\u2019all\u00e9gement budg\u00e9taire 2027, \u00ab\u00a0L\u2019estimation de l\u2019all\u00e8gement induit par cette mesure repose sur les revenus suppl\u00e9mentaires que les hautes \u00e9coles pourraient percevoir en doublant les taxes pour les \u00e9tudiants indig\u00e8nes et en les quadruplant pour les \u00e9tudiants \u00e9trangers \u00bb (p.58). Il est important de noter que ce plan est une version provisoire, et que seule la version qui sera publi\u00e9e dans la Feuille f\u00e9d\u00e9rale fera foi.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Et maintenant\u00a0?<\/strong><\/h2>\n<p>\u00c0 la mi-octobre, le Parti Socialiste Fribourgeois (PSF) a fait la demande d\u2019un r\u00e9f\u00e9rendum pour le projet, qui sera donc suspendu jusqu\u2019au 26 avril prochain, date de la votation populaire.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Sources utiles\u00a0<\/strong><\/h3>\n<p><a href=\"https:\/\/www.rts.ch\/info\/regions\/fribourg\/2025\/article\/fribourg-le-plan-d-assainissement-des-finances-cantonales-adopte-29024678.html\">Article de la RTS sur le PAFE<\/a><\/p>\n<p><a href=\"https:\/\/www.fr.ch\/sites\/default\/files\/2025-09\/message--programme-d-assainissement-des-finances-de-l-etat.pdf?v=1757329043\">Document officiel du PAFE<\/a><\/p>\n<p><a href=\"https:\/\/fribourg.ssp-vpod.ch\/news\/2025\/pafe-reponse-a-la-consultation-du-ssp\/\">Article de la SSP sur le PAFE<\/a><\/p>\n<p><a href=\"https:\/\/www.laliberte.ch\/\/articles\/suisse\/selon-sebastien-guex-la-seule-justification-de-lausterite-est-politique-1258637\">Interview de S\u00e9bastien Guex<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: right;\"><strong>Texte et Photo<\/strong>\u00a0Elise Shapiro<\/h3>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQzMjUGAA==\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"C0hMS1WwUghQSM7PzU1VCMjPObwyN7OwNBUA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcVBDoAgDATAF8FqEy\/+xmAJJBYqbf+vc5nmrnYC5nHz8Byj15VLgykXXyGgjQ7sBL0qJ01livzPh6W\/wfgA\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"c83JLE5VCM5ILMgsygcA\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwMtU1NNI1sFAwNLMyNLIyMQEA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"vVnLjhvHFd3nKyo0YkgAm+TMaB6SZ8YQFE1sQIIF0fEmCIxidzVZSr9U1c0ZeeVt1lllJ2SlsbfeaTdEfiRfknNuVTc5etgwEGchcbq7Hvd57rlVp6u981Pfurpanp8cqtL4zhk\/VvdmeLBFYevKq8yo3Okq9WpzndZVXVq\/ucagUlv5iDcLZ7orVW6uW2ucV23dpSuMmahv6s6r4j\/f\/1OvzXdq3alMY8XCePWi7lylu6ux2rxWhVbt5rrYXI+VabHOD6WJI7Vynbl5\/UDNG5O2rivVmkvm2raqq7BTU09Op1GF0yn0+d3pan9Q6s+VzZ3ynzr\/sqs\/MxXXLszuhH1MaM7nNqwr\/y10oTMLeWENyKpSXTadqPqUqjub1i7bCljq1laba7zo1J5xqk7bGgYZh8VEcb9560xpqlbhR7uX3eaa0usWYnRN+JKZtcYP9lts\/tVaeTfbm6hbom1+aGE7zNMug4G5SGO63a3w2CYY5ozCCqaCUBhUw\/J0UWZ9CsN7fMsLXZbiyHVtMbpxVtYra5cazfGq0bYa4x1EcnW6QmxwIT5r761pWxOCw0IoeKGBKXO75DCbnY0oZbqiHt\/uHe0f3hsp7axOMuNTZxcmW7w6G6W6aRFkyXZsEsf69lVhzkaXNmtXD9TB\/aPmaqTSAhvjZZPEiUoXdlk5u1y1o\/NTWy5VUcN31fJsVOjvXo0gX1qHZ+1fVemwhMIattRLM+zn0rPRqm0b\/2CK8OgyyDLpGD6TdDX1Mfqm3LqmXdtp13AvP92f7R9O9\/anpcbo5NnDi8dJs6rbOtGutWlhkpPZ7OpoNpu8aMwSRijasxH2p2JnIyg2UitDBc5G+\/ePRRBv2v+HLAoPl2P122x0fHRydXh8FDbCw2+20d7hwdHV3t7hftiKj7\/ZXocHs6uD+ydhJzz8VhtFVeCoSwSE\/c4gYnXX1mN1p9RXyW5S3FV7s9kagsQUmZ4zB\/v0YB5+PMfeS6ekNVdIpKcUy\/hWyxq3YY1wvQuDp9PtdufygPwXTH0EpCr7laoWQAOIqVLb6KJHPJaUYvNmTUyzlbfqZWf4r8A\/j+E15noDvEKVuG615awCAmSm6YBWqw5VYGVYsyilADEA0xSQ+gnkMYV6DtwyUmMye9WPNdy7tICpwm8XbtzmDdZBsSLCpXgFmcxEPcEk1RQaUFgRZm2V1640SZvYIsrVyjQYGHgLExUUWaV1Ad2W1AQoySK42vzU2FYXqChVW1ca00UPfEZVgKBOvehQqTA0FMW8rrLgBJSFr1E7moKIHD6idAgAe\/XQecNaGjEY5azuMggPwHV2Td0wo6kt\/kCxBuh\/VMIvLp6P4QCrUF0WLFScjLK5AAFA7fA6ui1zukGRuKIQS3qvA\/Aua1lGq\/n82XjHoZzQgEAguGUoy9CaPMFjDoroRH0JP3iD4riUehj2pIuS1Djkw4eK41h5mDHj65sf1VeVQpgxOMaRP2BzarT5O8JYwaFrFEaI4YMT62G8+r16hpJIjfPgvqpGtdVFiDvESsPPrTAZyN86vdbgRuHzr97r5i11S1f\/\/kfnBn9JiC0w53P1qK6wfJVKGPHJG1tIeIXVSbiMrF2iAIdRBBCuGoIorkoWFOjNDh96EgaPVYoFKRRokb15\/fn7jIgjXb10IAlGtn8I79sKMbBN3gtbwa3G74h3h8vfFX0lJRbACGEMbnPdUBnxfySaYV4klSGHe4XzzTUc4pgiBrb2iRjaB18AQQoQzRBYrl4giMsQw3mQSCQ0QQT4lExFXjEa6Sh4JHUazEFSd3P9YospgOYDxGIhOecV4rypXQtS2GVLyXW3zZaHFxeAh13XXIDZQMJliGayuzWsV1epYgnAliEXfU3qyqATAxQ0E\/Qhm7tlc\/2+zfPB5oayHnE5\/J5M1CNTdEgY0EWL3YWlIdXB4V3EcfMxXk+emwqda4jrdUbuCEctuWvIO1jCAEk6AU\/4MoOt+i8wIHLWgwOqxwj1PDdIzoHo64rk2FNOLGDdeGukxjgACVyALBew9dvIAALXJZcV4Qm9Lc1CnNZOtMtsaauuL1FBPNoPvwGmCEVUaHP9spNVTj1gqGeWAL\/aPVCfHBwcHeX5Z6CP+mOf1MqZ\/Gz0ybd5W+2NVKVLDOIDXu9hou+a87\/s\/RVJhD9Op\/pc4U9sdZ6xooiXYDU6HYAMbk7r7s8O7hE2mwI2JZ3fRUzpmMJQqLYb1DrLLFVhbeuj8Jt5XHDWp\/7R+f9CVdFuR1uoKlpCv+dRQXielCXGF4PEe7iW8QlpnYmVzgc10TyUqELbRhK6ilY5UwzCQ\/BbcEU0oPeMRLzkPn1aN10RYjqPoWRqxPz7IPZIgrqwvgUH0CkjSi9Dr0ZkuEI5TWUhCevWutjGZXXaiWB1ntvUGhZqfPPsqCT2IFUBehfTahu+ePDbKJ6oh3QpKhXLQMoeq37B5JCygBLouDW62+C2rsB\/hUXTakKKDRtA6Wz3hWfmBuLA5Ct0jI6YdLB6Jh2d8KcQLWO+x0hSCpaPWMrV3n5sjmezGXP0ZOfx0RcXcAokGsTynWdO9mLBiBbweqUHuTx6Z4FIcVbAKQA+5IIVdJf3pdKy\/wyzGENeEKs3JGzY2eLW1hyWYu2l6Tfu4akHABQF1ISb1\/gsvBCRRtO+i5Pj94o4ONgCceDppdL6yK6e1PZ2dPWnAc\/AXG7lH6sCCt8Tfrg7VNZk8zrJ2FczXEr9okaXDOIVKpJ05zz7YCnHDojawBfAecBpTCgMtzU0vW1jZkGUPUEe4wLwqBe6WrMsmvb9j7fd+K7t0nrzNpSXx0\/n41vhcSCGO2AsCPLy3Gbyc6vR3H+IQZuuNKwXAcxu3rhABpGHZSfpEuM1q0vmz+BaS23r1IKEEdp26g2pcg28EQ7LyrUgv+3r2UDCJj+vbywWACFvM6kQO6lTpF0hYtL3fmAp7O8koCKBaBzZYjiHMgHflmTJJGeARBPxMBbNSsoZYSg1QrCDTjK\/oE6h0AazhY3Zcbn6FSCp12YqCNGcPw0qV9Rad54ppYFypd1qiFiGDFVvekZUX5ABkgCSgX8BFjsyLnR+Tuca9MCSddFHRsan6ItAK33IHAI6oS4+oXxUNrRUUuzDYj6s5vFZ0GASqSLhlUFEjYU4YzVuRlB3zDGhxhIzOzqEhKSzRPIeaoZOACr1G8UaEWllIadaZUgaVt08CA98cTpaDsnBMbQyOr0BWPsVCDgsDfoqmgtghz0DDwOwhf24YspejTvts4PSgehJknsjWM8cj4HIs9Ge+z9ueQAH2sYVY2cMdX1fXjgthlw40FMLdF4p+iSasiDkPRDb99RJGoG2zzaSrIBXu1SV1Qy7SsAhjkFQESG7zBy8qbILxAJB6867mBZcv6VnnmIGmqd3D4J3EszHiGpWr\/xQ98MuWA24KdaEJ0IVdbQn6DmBKJW4yPWaXRKRfkBg08q0oejcOlGIePD46QXHMYj4ZP9WV2w4pUURM8hR59LAkoHNSm9q2OcDjSsaQGq1H9RjG8689CFiUOLBgLpgBw+ViFtWho9lz6+ez8d9dx3B+fn84ikJIeS6XvZeH47Nt21hMOGWAu0gqbRL6eYnOsgA+B1NIihXKORSaN1DjEs0y5GwLdnNIDgDlCHtPSFgGSMhYNIOCA\/ppJfOAhcJG32u72Lvjn8CgqGJEDtK\/BihsYiDNfqqpj\/v7pyG628fFGyDsU\/6bZCFpGdIRE9TQr\/tFHez\/5ZBBnt+Wi1889m2PY508WtJbkF4K6Z5n0iirxF8Dmcz\/Uj\/4TP+\/tw9pOdwovROmfQ7oBKrC3q42JaLPWNpCSnJXqGCSfEzaDwJJxepbSV25ZAqYHpRIK6CNDuNKwnQ8Vjd\/Hjz+knYyJZD1S7ivDdxHsKfNIpwHXrDKIczTT2woW2FI45iU9FQclH6GPyudNeaQPl7F7l44GbQKPDyQU57arCwvqMMlonYuuMaSUq73LypQskxoUkH3Gaua2T6hybhT1TmJRHp5q2600wOT+4OGDCkRLjLoikpehrNySGdHOk4ob1sMK3njYmcDXEo2GohUd+PYX2XEiPMUnqKeFd0QWKLwdugVTkH5rX9pShFnSBJaqW7\/eCRzeZ7uY6yyXADRbpKMqLmdQCldntEQVKr7jybX9xVOgQbu4zAP2PMEhAgKYlOVw6lrm9iBi3lfCN0Boj6\/gQTgQrWrdcOINPw+kgukzIdLo1orTrmQujnYNEPm+BgMME8tpbA2oIAtmuCA5mIxjY0sP2x\/OXl5YS9Zbqa8tx26sySgDXtqX04io\/H7sPbpDAJvZ9kye0jGN5eJf0RTNIf4+JPndVgd8n+\/dn+vaPjk8mqLYvR+cOwblT4+dfzoYl4ePGYjXSv8AfljvcIvF2bZibXgN9pTs1F6GR2f4qU9LzDSoZjo1+QODNJkRgS5CbLP1+f7R0fHh9A6HsHo\/M\/vtv0ErR\/UdDeZBPvm2Td1BllrsxlvORodG4SQkblTaKTQvMuxEMTcX2SdQnmTd+11Hz+7FdZqkBsL9A7Gm7ee9Oj8aEVpnKal3iz0J58Mll25oqSSN4miNfW5vEcQAyEogkUgNkTcp6mBgkiY0n29g9Pjg6OR+dfIgsdWq1LijvnSbksrP6EhXdl3Q3jd4O6P4DhjUsit5gPlNxj8nimL0z4JuX2GS+Hhmi\/ef24IFmer3SDKheC\/78=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">85 mesures, 405 millions de francs \u00e9conomis\u00e9s, mais de nombreux m\u00e9tiers touch\u00e9s. Vous l\u2019avez vu dans les journaux, \u00e0 la t\u00e9l\u00e9, et m\u00eame dans&hellip;<\/div>\n","protected":false},"author":197,"featured_media":16254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[113,174],"tags":[],"class_list":["post-16253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campus","category-politique-universitaire"],"views":453,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/16253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=16253"}],"version-history":[{"count":5,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/16253\/revisions"}],"predecessor-version":[{"id":16483,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/16253\/revisions\/16483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/16254"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=16253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=16253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=16253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}