{"id":1778,"date":"2015-04-04T16:46:53","date_gmt":"2015-04-04T16:46:53","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=1778"},"modified":"2021-05-09T14:44:01","modified_gmt":"2021-05-09T12:44:01","slug":"contemplation-dune-vie-silencieuse","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2015\/04\/contemplation-dune-vie-silencieuse\/","title":{"rendered":"Contemplation d\u2019une vie silencieuse"},"content":{"rendered":"<h2><b>Dans ce premier roman, Arian Schr\u00e9der nous invite \u00e0 entrer dans la vie d\u2019une jeune femme silencieuse et discr\u00e8te, qui tente de se reconstruire \u00e0 la suite d\u2019un \u00e9chec amoureux. La l\u00e9g\u00e8ret\u00e9 des mots et la bri\u00e8vet\u00e9 des phrases, qui touchent le lecteur en plein c\u0153ur, sont autant d\u2019\u00e9l\u00e9ments qui vous feront appr\u00e9cier ce livre.<\/b><\/h2>\n<p>\u00ab\u00a0La silencieuse\u00a0\u00bb est un livre po\u00e9tique, retra\u00e7ant la p\u00e9riode de deuil qui suit une rupture amoureuse. Clara, femme discr\u00e8te et artiste, ne supporte plus de vivre \u00e0 Paris apr\u00e8s la fin de sa relation avec Barnab\u00e9. Elle d\u00e9cide de partir \u00e0 la campagne.<\/p>\n<p>C\u2019est l\u00e0-bas qu\u2019elle commence \u00e0 se reconstruire, d\u2019abord par le silence et la solitude, puis par les nouvelles connaissances du village. Tout au long de son exil volontaire, la cr\u00e9ation de sculptures a\u00e9riennes parle pour elle, exprimant le silence mais aussi le vide qui l\u2019entoure.<\/p>\n<p>\u00ab\u00a0La silencieuse\u00a0\u00bb retrace ce que chacun vit apr\u00e8s une d\u00e9sillusion amoureuse, la sensation de vide, l\u2019envie d\u2019une retraite solitaire. Len remettre.<\/p>\n<p>e temps n\u00e9cessaire pour s&rsquo;la fin d&rsquo;amoureuse, la sensation de vide, l&rsquo;le, exprimant le silence mais aussi le vide \u00e0 o\u00f9 l\u2019h\u00e9ro\u00efne ne parvient pas \u00e0 s\u2019exprimer, l&rsquo;auteur le fait avec finesse et sensibilit\u00e9, afin de nous faire comprendre la douleur de la fin d\u2019un amour, et le temps n\u00e9cessaire pour s\u2019en remettre.<\/p>\n<p>Ariane Schr\u00e9der conclut ici son premier livre, qui, s\u2019il n\u2019est pas tr\u00e8s original, enchante par son \u00e9criture d\u00e9licate. En abordant des th\u00e8mes tels que le silence et la solitude par le biais de l\u2019art, l\u2019auteur nous invite \u00e0 nous pencher sur nos propres \u00e9motions.<\/p>\n<h4>Iris Wolfisberg<\/h4>\n<p>disponible chez Albert le Grand<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzQ3twAA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c87PK0nNLchJLMnMz1NIedQwszQvVaEsM1WhODMnNS85M7W0OBUA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"BcHRDYAgDAXAiaBo9MdtTHnGJlAIbZ3fu9d92kVkHhXqOVSelfklm2Bf0Wkv20nlIB7q6LPdLkNTDUX6BMmkQVkQBvoB\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNU1MAEiBUMzKwMTK1NjAA==\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"lZXPihw3EMbveQqdcuqsIfiWYcCxjTHkEIghZ7W6ZlpBLWlLUmN8yjvklNveskMOOYfcVuRF8iT5qqZnsjgsxrBsb6tV\/371Ve1u\/nq\/G\/evbCzGkclMiyc2nBYbB\/OCvY3mBzdzP004jqkV4+PqK5l+ZyhWxukkxsGa1ZOZ\/vn51xbJ\/ETy+0DLQqb4QNF5aoUMVTP54rjfVxrMbfOmwgvscI0Mk0uxVG6eNQCclibBzm5NP7mZnLFLakzt\/Y35zprQT8d+z1T7CV6KWVItEga2I\/t+v16\/5JltobKFTQ2+Iu4RflylxqjH5EA+Gvf3L40HUxK+21YtHpJBPyHYAqOiLlahcSDWWzmDkRN2wBj8ynSzezbud88A+Itd3j\/8\/nCHbB+xeLh7+MtQqQaFqYHJqZ+qv20gg3rY9t8kMgrJ\/cQ+TYppouaDxhc0RjBzyxVALlwK3ZiXwbIdtgZciQsXy9UXgQ\/D0nJOjPMcUAqcr5oHyH9v2RdUBTPt7QFUpEcWmQVbfYrGrmjFt5ajHfvpxrwOIDkJg3OeWQLx1kVnl2yPUZhkxfESOKX20O++Gq3wlANx4RJSjk6z+EgSg3bBjokncS+tO\/OkreElBV\/bhIu5If3znSKyXcU3JJ5itL4UCxsU3FBwCPYIYO9Sk16bkOJRK0WF9B6k14SjajW8VII2n+uXS64FRQ9U0iKKkTRskGaKohB1gJ\/MfrFnsV0yXqwAbqV4OV2FmjQ1CIdYpZFXWE9oRzUCT04s8Zitg5QwnJe+iTbQEdihvdqyi0C0lEKxXEuRBIYt+uNB1iAygspWMGDqMChYFFTroyQJk7xkwIYECIQ9bwzKl1xuW\/rmoqLt9dO5XOw+gyA0k\/qfWsaMhqT+B0qIKkYUBfMMrYmwpE71SfxfJIy6rAE4O1ihKAJHyqhGBSY5+tEDQz8Nxm4joTvxoOVCuligccKfKGlKLYi7ia4DdN5iWvmgkn0amjbi\/5R1I9OjlQxFuwDpeudVs5cNrhtFV92gzqDkuM2cMKgqkMT+6KMNSCZCPrKIZWbEDxJir1sFCgre2YrGv0byMn26EKH0Ovf7RZ4UimrwyYm8zOvopWmCRCaZ61lyG\/iP\/r3oa5bMUE\/R73jnlGXesIiT6KVsaObn+7eysn5M4eDLSHzE6n2uzLD+cop+lOUy0wfzIuCzwn\/DNk5q\/y8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Dans ce premier roman, Arian Schr\u00e9der nous invite \u00e0 entrer dans la vie d\u2019une jeune femme silencieuse et discr\u00e8te, qui tente de se reconstruire \u00e0 la suite d\u2019un \u00e9chec amoureux. La l\u00e9g\u00e8ret\u00e9 des mots et la bri\u00e8vet\u00e9 des phrases, qui touchent le lecteur en plein c\u0153ur, sont autant d\u2019\u00e9l\u00e9ments qui vous feront appr\u00e9cier ce livre.<\/div>\n","protected":false},"author":13,"featured_media":1779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2272],"tags":[874,875,876],"class_list":["post-1778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","tag-ariane-schreder","tag-la-silencieuse","tag-roman"],"views":1121,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/1778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=1778"}],"version-history":[{"count":1,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/1778\/revisions"}],"predecessor-version":[{"id":1780,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/1778\/revisions\/1780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/1779"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=1778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=1778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=1778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}