{"id":2634,"date":"2016-01-11T11:50:18","date_gmt":"2016-01-11T10:50:18","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=2634"},"modified":"2017-04-30T18:13:36","modified_gmt":"2017-04-30T16:13:36","slug":"2015-team-spectrum","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2016\/01\/2015-team-spectrum\/","title":{"rendered":"2015 dans le r\u00e9tro, par la Team Spectrum"},"content":{"rendered":"<h2 style=\"text-align: justify;\"><strong>Il y a quelques jours \u00e0 Paris, Christophe Al\u00e9v\u00eaque, humoriste, souhaitait\u00a0\u00ab\u00a0<em>qu&rsquo;on propose au gouvernement que cette ann\u00e9e 2015 de merde soit d\u00e9clar\u00e9e ill\u00e9gale et hors la loi\u00a0\u00bb.\u00a0<\/em><\/strong><\/h2>\n<p style=\"text-align: justify;\">2015, ce n&rsquo;\u00e9tait pas qu&rsquo;une ann\u00e9e d&rsquo;attentats fran\u00e7ais. Une ann\u00e9e complexe, une ann\u00e9e de presse. Quelques membres de notre \u00e9quipe ont choisi de vous partager 3 articles qui ont fait &#8211; <em>selon eux<\/em> &#8211; l&rsquo;ann\u00e9e 2015.<br \/>\nUn regard singulier qui vous permettra peut-\u00eatre d&rsquo;un peu mieux conna\u00eetre la sensibilit\u00e9 de ceux qui font votre journal !<\/p>\n<p style=\"text-align: justify;\"><div class=\"row\">\n<p style=\"text-align: justify;\">[col size=\u00a0\u00bb3&Prime;]\n<figure id=\"attachment_2656\" aria-describedby=\"caption-attachment-2656\" style=\"width: 960px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/capture_d_e_cran_2015-12-16_a_22_10_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2656 size-large\" src=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/capture_d_e_cran_2015-12-16_a_22_10_-1024x981.jpg\" alt=\"aurel dewarrat\" width=\"960\" height=\"920\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/capture_d_e_cran_2015-12-16_a_22_10_-1024x981.jpg 1024w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/capture_d_e_cran_2015-12-16_a_22_10_-300x287.jpg 300w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/capture_d_e_cran_2015-12-16_a_22_10_-335x321.jpg 335w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/capture_d_e_cran_2015-12-16_a_22_10_-1050x1006.jpg 1050w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/capture_d_e_cran_2015-12-16_a_22_10_.jpg 1136w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><figcaption id=\"caption-attachment-2656\" class=\"wp-caption-text\">Aurel Dewarrat<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">[\/col]\n[col size=\u00a0\u00bb9&Prime;]<strong><div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Aurel Dewarrat - R\u00e9dacteur depuis septembre 2015<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><\/strong><div class=\"su-button-center\"><a href=\"http:\/\/www.letemps.ch\/opinions\/2015\/10\/21\/suisses-intolerants-face-immigration-vite\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0Des Suisses intol\u00e9rants face \u00e0 l&rsquo;immigration? Pas si vite\u00a0\u00bb,\u00a0par Fran\u00e7ois Grin, via Le Temps<\/span><\/a><\/div>\n<p><\/p>\n<p style=\"text-align: justify;\">L\u2019immigration a \u00e9t\u00e9 un des grands d\u00e9bats de cette ann\u00e9e 2015. Si les articles \u00e0 ce sujet foisonnent et se ressemblent souvent, rares sont ceux qui sortent des sentiers battus pour nous pr\u00e9senter une vision neuve. Le sentiment d\u2019un certain regain du populisme en Europe semble n\u2019\u00e9pargner personne et tout le monde y va de ses petites explications. En Suisse, une des causes \u00e9voqu\u00e9es serait que l\u2019on vote par peur. Cet article tente de donner une r\u00e9ponse plus nuanc\u00e9e et rejette, par cons\u00e9quent, les r\u00e9ponses simplistes face \u00e0 un sujet aussi complexe. Il fait, par ailleurs, \u00e9cho \u00e0 l\u2019article \u00ab coup de gueule \u00bb de Caroline Iberg du 20.10.15, dans l\u2019Hebdo :<\/p>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"http:\/\/www.hebdo.ch\/les-blogs\/les-al%C3%A9as-dune-jeune-pro-europ%C3%A9enne-en-suisse\/la-suisse-est-x%C3%A9nophobe-europhobe-et-raciste\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0La Suisse est x\u00e9nophobe, europhobe et raciste et cela ne choque personne\u00a0\u00bb,\u00a0par Caroline Iberg, via L&rsquo;Hebdo<\/span><\/a><\/div>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"http:\/\/www.jetdencre.ch\/faut-il-interdire-les-jeux-video-violents-9482\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0Faut-il interdire les Jeux Vid\u00e9o violents ?\u00a0\u00bb,\u00a0par Lukas \u00e0 Porta, via Jet D&rsquo;encre<\/span><\/a><\/div>\n<p><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">A chaque drame, les jeux vid\u00e9o dits \u00ab violents \u00bb sont point\u00e9s du doigt par des politiciens ou des intellectuels. Mais qu\u2019est-ce au juste un jeu vid\u00e9o violent ?<br \/>\nSont-ils r\u00e9ellement un danger pour notre soci\u00e9t\u00e9 ? Faudrait-il les interdire ?<\/p>\n<p style=\"text-align: justify;\"><\/div><\/div>\n<p style=\"text-align: justify;\">[\/col]\n<p style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">[hr style=\u00a0\u00bbstriped\u00a0\u00bb]\n<p style=\"text-align: justify;\"><div class=\"row\">\n<p style=\"text-align: justify;\">[col size=\u00a0\u00bb3&Prime;]\n<figure id=\"attachment_2669\" aria-describedby=\"caption-attachment-2669\" style=\"width: 919px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/p1020038.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2669\" src=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/p1020038.jpg\" alt=\"Guillaume Peugniez\" width=\"919\" height=\"919\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/p1020038.jpg 919w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/p1020038-150x150.jpg 150w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/p1020038-300x300.jpg 300w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/p1020038-335x335.jpg 335w\" sizes=\"auto, (max-width: 919px) 100vw, 919px\" \/><\/a><figcaption id=\"caption-attachment-2669\" class=\"wp-caption-text\">Guillaume Peugniez<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">[\/col]\n[col size=\u00a0\u00bb9&Prime;]<strong><div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Guillaume Peugniez - Responsable Web depuis mai 2015<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><\/strong><div class=\"su-button-center\"><a href=\"http:\/\/www.liberation.fr\/debats\/2015\/04\/29\/jupe-pas-laique-une-erreur-monumentale-du-proviseur_1276722\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0Jupe pas \u00abla\u00efque\u00bb : une erreur monumentale du proviseur\u00a0\u00bb par Mehdi Thomas Allal &amp; Asif Arif via Lib\u00e9ration<\/span><\/a><\/div>\n<p><\/p>\n<p style=\"text-align: justify;\">Au m\u00eame titre que se dessine parfois un ath\u00e9isme <em>int\u00e9griste<\/em> et irrespectueux de l&rsquo;individu aux Etats-Unis, nos voisins Fran\u00e7ais continuent d&rsquo;instaurer ce que les auteurs appellent justement une la\u00efcit\u00e9 par neutralisation des cultes. Entre la\u00efcit\u00e9 et islamophobie, cette version francophone d&rsquo;Ahmed, arr\u00eat\u00e9 pour avoir os\u00e9 d\u00e9monter une horloge, fait trembler.<br \/>\nQuel crime m\u00e9rite qu&rsquo;on placarde l&rsquo;image d&rsquo;un mineur dans nos journaux ?\u00a0Pourquoi\u00a0criminaliser les v\u00eatements d&rsquo;une adolescente ?<br \/>\nUne longue jupe noire est-elle vraiment un signe ostentatoire de religion ? Si on ne peut m\u00eame plus \u00eatre gothique tranquillement \u00e0 15 ans, que nous reste-t-il ?<\/p>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"http:\/\/www.liberation.fr\/societe\/2015\/07\/07\/le-dispositif-meilleurs-bacheliers-pour-les-nuls_1341874\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0Le dispositif \u00abmeilleurs bacheliers\u00bb est-il efficace ?\u00a0\u00bb, par Marie Piquemal via Lib\u00e9ration<\/span><\/a><\/div>\n<p><\/p>\n<p style=\"text-align: justify;\">Toujours en France, un projet souhaitait relancer la \u00ab\u00a0m\u00e9ritocratie\u00a0\u00bb en laissant les 10% des meilleurs bacheliers choisir d&#8217;embl\u00e9e leur orientation dans l&rsquo;enseignement sup\u00e9rieur. Ce qui signifie donc qu&rsquo;auparavant, faire partie des meilleurs n&rsquo;\u00e9tait m\u00eame pas suffisant pour s&rsquo;assurer de \u00ab\u00a0bonnes\u00a0\u00bb \u00e9tudes en France.<br \/>\nProbl\u00e8me syst\u00e9mique non pr\u00e9vu par la classe politique : choisir ces 10% apporte d\u00e9j\u00e0 un biais de classes sociales. La r\u00e9ussite scolaire \u00e9tant fortement corr\u00e9l\u00e9e au niveau socio-\u00e9conomique des parents, laisser les enfants des plus riches choisir leur fili\u00e8re semble idiot.<br \/>\nIls y ont d\u00e9j\u00e0 tout acc\u00e8s.<\/p>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"http:\/\/www.liberation.fr\/planete\/2015\/02\/10\/aux-etats-unis-les-etudiants-riches-ont-huit-fois-plus-de-chances-d-etre-diplomes-que-les-pauvres_1198999\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0Aux Etats-Unis, les \u00e9tudiants riches ont huit fois plus de chances d&rsquo;\u00eatre dipl\u00f4m\u00e9s que les pauvres\u00a0\u00bb, par Amel Chettouf via Lib\u00e9ration<\/span><\/a><\/div>\n<p><\/p>\n<p style=\"text-align: justify;\">Le mod\u00e8le universitaire am\u00e9ricain continue de montrer ses faiblesses. Avec une \u00e9galit\u00e9 des chances enterr\u00e9e depuis bien longtemps, les dipl\u00f4m\u00e9s des classes moyennes et pauvres doivent se lancer dans la vie active avec des dettes de plusieurs dizaines de milliers de dollars. Tant que les R\u00e9publicains ne se d\u00e9cideront pas \u00e0 rendre l&rsquo;acc\u00e8s \u00e0 l&rsquo;Education plus \u00e9quitable, l&rsquo;Universit\u00e9 reste vou\u00e9e \u00e0 \u00eatre le symbole de l&rsquo;immobilisme social interg\u00e9n\u00e9rationnel.<\/p>\n<p><\/p>\n<p style=\"text-align: justify;\">Ces 3 articles offrent un regard vers l&rsquo;ext\u00e9rieur, pas par d\u00e9sint\u00e9r\u00eat de la Suisse mais par inqui\u00e9tude pour elle. Parce que tout le monde commet des erreurs.<br \/>\nMais si nous pouvions ne pas reproduire celles des Fran\u00e7ais et des Am\u00e9ricains, nous nous en porterions tous mieux.<\/p>\n<p style=\"text-align: justify;\"><\/div><\/div>\n<p style=\"text-align: justify;\">[\/col]\n<p style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">[hr style=\u00a0\u00bbstriped\u00a0\u00bb]\n<p style=\"text-align: justify;\"><div class=\"row\">\n<p style=\"text-align: justify;\">[col size=\u00a0\u00bb3&Prime;]\n<figure id=\"attachment_2662\" aria-describedby=\"caption-attachment-2662\" style=\"width: 825px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/image.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2662 size-full\" src=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/image.jpeg\" alt=\"Florian Mottier\" width=\"825\" height=\"825\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/image.jpeg 825w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/image-150x150.jpeg 150w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/image-300x300.jpeg 300w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/01\/image-335x335.jpeg 335w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\" \/><\/a><figcaption id=\"caption-attachment-2662\" class=\"wp-caption-text\">Florian Mottier<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">[\/col]\n[col size=\u00a0\u00bb9&Prime;]<strong><div class=\"su-box su-box-style-default\" id=\"\" style=\"border-color:#000000;border-radius:3px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:#333333;color:#FFFFFF;border-top-left-radius:1px;border-top-right-radius:1px\">Florian Mottier - R\u00e9dacteur en chef - Membre depuis novembre 2012<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:1px;border-bottom-right-radius:1px\"><\/strong>Alors qu&rsquo;on arrive au terme de cette ann\u00e9e, je suis heureux de pouvoir revenir sur les quelques articles qui ont marqu\u00e9 cette ann\u00e9e. Cette ann\u00e9e semble particuli\u00e8rement noire, surtout lorsqu&rsquo;on se laisse submerger par le d\u00e9luge m\u00e9diatique qui a g\u00e9n\u00e9ralement accompagn\u00e9 les plus sinistres \u00e9v\u00e8nements. Pourtant, cette ann\u00e9e laisse tout de m\u00eame un peu d&rsquo;espoir, \u00e0 l&rsquo;image de la COP21, \u00e0 l&rsquo;image de la progression des droits de l&rsquo;Homme dans certains pays ou encore des manifestations de solidarit\u00e9 et d&rsquo;entraide que l&rsquo;on a vu \u00e0 la suite des attentats du 13 novembre.<\/p>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"http:\/\/www.letemps.ch\/culture\/2015\/11\/19\/syrie-un-siecle-influence\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0Syrie, un si\u00e8cle sous influence\u00a0\u00bb, par Nic Ulmi, via Le Temps<\/span><\/a><\/div>\n<p><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Avec les attentats de Paris, l&rsquo;EI et le terrorisme ont fait un retour en force dans l&rsquo;opinion publique, qui ne se pr\u00e9occupait gu\u00e8re de la situation au Moyen-Orient auparavant. Dans les jours qui ont suivi, on a vu fleurir toutes sortes d&rsquo;analyses, des plus s\u00e9rieuses aux plus farfelues et un panel d&rsquo;experts autoproclam\u00e9s ont pu d\u00e9verser une logorrh\u00e9e l\u00e9nifiante et convenue sur les plateaux de BFMTV. Pourtant, dans tout ce chaos (m\u00e9diatique), quelques bons articles, prenant la peine de remonter aux sources g\u00e9opolitiques et religieuses du conflit syrien ont permis \u00e0 leurs lecteurs d&rsquo;avoir acc\u00e8s \u00e0 de bonnes clefs de lecture pour comprendre un peu mieux la situation.<\/p>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"http:\/\/www.letemps.ch\/opinions\/2015\/06\/03\/confondent-etudes-superieures-club-mediterranee\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0A ceux qui confondent \u00e9tudes sup\u00e9rieures et Club M\u00e9diterran\u00e9e\u00a0\u00bb, par Fran\u00e7ois Gar\u00e7on\u00a0via Le Temps<\/span><\/a><\/div>\n<p><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Au niveau suisse, les \u00e9tudes ont fait un retour remarqu\u00e9 sur le paysage m\u00e9diatique avec l&rsquo;initiative sur les bourses d&rsquo;\u00e9tudes, refus\u00e9e en juin 2015. Face \u00e0 un syst\u00e8me d&rsquo;\u00e9tudes souvent d\u00e9cri\u00e9 par ses propres participants, en butte aux attaques d&rsquo;un certain parti, il \u00e9tait bon de lire un article qui prenait la peine de rappeler en quoi le syst\u00e8me dual et le syst\u00e8me acad\u00e9mique suisse constituaient des tr\u00e9sors de notre pays. Tr\u00e9sors fragiles, qu&rsquo;il conviendrait de surveiller avec attention&#8230;<\/p>\n<p style=\"text-align: justify;\"><div class=\"su-button-center\"><a href=\"http:\/\/www.letemps.ch\/economie\/2015\/12\/07\/travail-un-bienfait-humanite\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#811a1a;border-color:#681515;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:6px 18px;font-size:14px;line-height:21px;border-color:#a75f5f;border-radius:5px;text-shadow:none\"><i class=\"sui sui-hand-o-up\" style=\"font-size:14px;color:#FFFFFF\"><\/i> \u00ab\u00a0Le travail est-il un bienfait pour l\u2019humanit\u00e9?\u00a0\u00bb, par Amanda Castillo\u00a0via Le Temps<\/span><\/a><\/div>\n<p><\/p>\n<p class=\"p1\" style=\"text-align: justify;\">Le travail est-il l&rsquo;avenir de l&rsquo;Homme ? Lorsque l&rsquo;on voit les crises se r\u00e9p\u00e9ter, le ch\u00f4mage frapper de plus en plus de jeunes, et de plus en plus longuement, on serait tent\u00e9 de r\u00e9pondre par la n\u00e9gative. Comment appr\u00e9hender exactement le travail, d&rsquo;o\u00f9 vient-il ? Cet article apporte quelques \u00e9l\u00e9ments de r\u00e9ponse qui nous permettent de r\u00e9viser notre jugement sur cette activit\u00e9 cardinale de notre soci\u00e9t\u00e9.<\/p>\n<p style=\"text-align: justify;\"><\/div><\/div>\n<p style=\"text-align: justify;\">[\/col]\n<p style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">[hr style=\u00a0\u00bbstriped\u00a0\u00bb]\n<p>Nul doute que l&rsquo;ann\u00e9e 2015 n&rsquo;aura laiss\u00e9 personne indiff\u00e9rent.<br \/>\nEt pour vous, chers \u00e9tudiants, chers coll\u00e8gues, quelles informations repr\u00e9sentent cette ann\u00e9e 2015 ?<\/p>\n<h4 style=\"text-align: justify;\"><strong>Guillaume PEUGNIEZ<\/strong><\/h4>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzIzNgEA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"MzIwNFVIScwrVshJVSg6vLKkKF9HoSCxSCEnUSEkNTFXIbggNbmkqDQXAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1TcyMDTTNzAE0aa6JamJubpwKQA=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"cy\/NzMlJLM1NVQhILU3Py0ytAgA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNM1MNQ1NFQwNLQyMLQytAAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"7VzNbhxHkr77KXI5sLEDdLF\/KFKiSFHgypLHhuTRjqVZYBcDIrsquzvlqspSZlWL9GlfY2+6rWgDO5e5LOamfpN9kv2+yKrqJinb8piSZgAJkthdP5mREZERX\/wkDxcTFeqz3NzZqs1pnejczsvb6lkTajs7O9g6Ogy1d+X86MtcnSmtnjcmx7+gnrnGB7V6qR5rb8NA3VvgR+2qhVHH+ep8ufoejw3Uoikcb+BjcM1C2xp\/X798\/cPrl4emOHrefObD88YduFJV3lUuGKUbNXfN0vjSFKasOaVKTV3jTlmuzo2ajMa7KjOqMB7\/B2drla3O01x73rU5pp\/r3ChTq4UDkblWubOY9K\/bmHWIaQ+H7aoOh4vJ0SeH1U\/zgBMOQIMqW2pX51yGqnRQ\/Qqasicway9pEF3Wug5q5nW5+m9tw7Z6un4udUWVm1PwZvNlA06YEMy2+teO2YUpprjGe6WrvVGr8+eNrYxy4E+6cDZY3lu6JoAoX+u58WpH4ZNNc0MirTw6I9Wf\/ebWZDw+UOR\/MDk4b5pTYUt\/K+8WsGb49uHUq+HRJ09L5c1c+0wFW86b3GImDh\/nNr6ApLzGp6ZOVt+T1qxnEK+qwmI6LL0s9ep\/eB\/iCaYMdmpzW6\/OuZCUj3DUGaleypKpcKXO1T8dDqufF9lhZpcKKhHCnS3vXmz9\/Bv\/kboca\/rO3KGm7Hz22NvCHPzpk8OZnTeY32Z3tiBQnS6olSeTvd29LXDY6iQzIfV2arLp2Z2tVFe1dWWyfjSJj7aTv7BZvbit9vdG1elWR+GLKmnfU0JXbmY11qDVwpvZna1FXVe3h9DZJsN4201pZ347XQxDZdLaN8WQ74NTuDlsqtzpLAwhs73haDzkuCD\/JDsxJym08ITCTMaTZLx3ok8mk5Px6GT7WTXHdLaYK74Mud7ZyvV3Z1uQReridx3OynSTYFtAy2RtwrUE229usEyfvnuCk\/FocuN0\/9ZYKAfPahCIl3IQ\/EJ7r+stJYy+swVGb6mFsfMFntmfjITCYOpIZHhvVCp+eQGD+M5n3RmNTie3bsqk+Px+5tzZPd2ZxIXi83uZczzaHZ2OR6O9lr2772WpcbLxzt6LLdH7QM2r3UD9c6FPk83d\/VvQNFqCpnavD+Ft9BHNSbfXaVJ+1F5cMQ0J7dbW0bHo+eetnh8O1+MdyRfcfgtjN4S1+9MnF23efmfzOp+\/aURDk0zdqYo\/Ehkchm+mmxx7jQvpLdzUwS17MDl3\/vZvRvLnoL3oYV2acHunOj1Ys6t0pdl6w2RJbevcrMfV6bdz75oy68bekT8H7bcH8qebCVAkoRntphxjyo1bngZh495lvqpE\/WF1num0No2HVakaG+Cmqlo8sXjEwyEofhPZrXqRV00C\/6v9zJ7GbzUYfJlRU1fXrvgxYtu7V+ldY5hLFDR4oUxSUGD8VSfy4sWL7dxgGVXgtnCVLaE6sgd2h+PRcDIeBqw1mJDYsna5wT6oQzLTqYHJL+wczKEyLm1ttq5Mq9YEXFKRds2XZHVFpLfGYz3WBxd1aO\/WeHe8e0mHdrmnajod2PKTaa7Lb7cATfI7W6VzlSmBS0qHlRvvhQ+h0uWbqah0Rh93e686VeNbYD1RR8JtcXt8A19zW5okupDbkw3RtKPom7uz3dlV6g5k64WFztyLTsftmmMWvLLJQmPtLmmqnkOXJr9AKqVujxTR8+eAdd9EQSkR1OpcJKUoKeLyDsNtCO0uwDq0GGANwuOOH7x+CbioHgg6BYpUX3hbDnBbq4dGPaGSQM3AuGi6ROFhW47eCoI9\/L\/\/\/K+NyRE8ADYD3wEHAjEpXC6zQOQ+JULO3gDyt9U3VhG\/9kAW68LqQvMM2H4GgoEiudPwDYGDoOZimsveYwRR1gPlNYFzEKDcocrgvGxQkgHoWQPDBgUqakJYwEwoDj8hnAiyiwSeLwGysYrSYOBtskfelAglw0qxqtQAeduIj\/EjazBYBYQcCsQipbrfIMDhayRRlXhndQ7uz6mpAM6yFq6kdk2NVavClWDKmVpqModyrgwsIn6a0yq3qXAVAcX9slWEGEZwUalu+DzCMPe8ATe5TE\/sz1gqx8xYCFC1YbBAUO631T3M3LJZkTkSiGSkKS4fzKgwHV7JwZuy0WVKMeEtb55RcAMZDLYvMDgR3lNi3XvUO0Q7DAXXOtqUrSxBL9Syi4e2FaJNxipxTI2QDjQiyESUt3Ci3FhDR+3rH\/BiU5HeeWMaXvkrv9zT3nHrqi+nxs8pjsloe4y\/iOUyXQYZ5Hdmmjl1+xfHFG9naBccnWYWnEimuZsH+aTzT+\/tfHq8r0OSgbfJM8P\/Ef8mhjoSbxqwPjGwoyLbYa7bT4kJdXIanykRb7upia\/FT3QSKbn80Th\/OOP8ULdbUkFY6nR13gpqoHpJyc6JkuLH1CAMhq5Cv7lHO3uwYaQvqnNrpFsbL1r8Jkt93QqNvQpYnXpDpYby1InNiROMz6xHDAjlhjKfAh1kxuF\/R2Mckv0btyYf9fHD6eODKCnVS0pM81f0h3+08MBOdaJSdzdU7mHzrY45PjhMHVXuKyjr563aiSb8JEBoF1CNt35aE4+h+JqKn3ldmOg5qEiYUsjLLEiDoe\/JhIkXn145rAl+muY9c3Zei8egD6ywW+AgrIGld41c4vLhStK6MTkc5yNtmRqDF6BJTSXzSJIM\/RJm7yZvJ1V32xTYN2S6zcW3cTzBAEQ1umTerUUQzFkFl9oIeu4qyCCjD6Yc8paYKIu7b+d9Yrjxdju7je\/ebsyfH23h2weoHAg7bGUyfvzT30Mebm\/\/rfNwfPRSHm68\/37ycNV4NBmNdm798lybZNdmTZ6rjaybrOTXptou0BSzaF80AFu6AWJ9bJp5ac1360zaeH8jkzbev6ZM2iYRFMevTeJ04yVjpod2RzFh8+uTQ\/24zK\/h33Xl19bjMoe2s9vn0H4qv0StXeeXog7\/gvwStefH8ktXNeBjjum6ckxXecs8kwmMkDSjwn8z0y7ZVGj7j55mgi2Osf\/2zA8zwzg\/5plGN4aT\/eGzpkLUgyAo1xa+P2EQRADW+ASxb0Nd1dSAhqERwm\/cOBlPbu7dnHwEkx8QTH4FsUnp8\/UPuV79GZIDGLstSYIoPbUhPcmCdNKjARB89sgsMqueLFyBYY6xJXL1mS6qA3Uc7Ewde\/wn4Y2dMqtFDfrb01DHjSpW32PLYacDPhBkBsmSBAZToIZ5JMI3XS9W55KsYWVUYOVcStexNgrca7E8MekNoWlm1jm2EiRZLFXj+n1WfJOnJavipQtqyfIsQOiDrgbMJElty0ZSR\/0IoWYFyzO\/JVkapr0aZp\/xs6qIM\/G4wNMWb7JyuvpzKjVTMrU0Te2x\/BDTbZIHwgYwkiKKhdbuca4l5LqQUNSaQZt6WyLq5KusVqe8V66rt8fwHdkAQMuvvpcZiXI11uaVC6zars4L1yfLFs7nbo6BpeKMyZnz8l0NmXVtldIPQDTn3tZGXWgEyHWq\/SZ7CXo268gFRMe0PLM4ZHGsDYP3iF4e4zMes69fcgZbkiOgivxcgnThXtgYDLA\/A74PYsl6jM8qfQ6zB0nQTGEWInXGCZSEWgLJd7A\/QOEMmBBr\/fJcxmQkFJHMvMskpiQOpSjeKqNk0WJ9fO7qBe0f2KTL5\/QQUcKIu8a7CksciEJIThL6V5tEYoi77yhnddFqM4IxtWnN9k3+pW21cFkB4dUsKUybnUtgUheG\/QAhoXJIMqBs8nAy3rkxvnXzxkeb\/QETUtDJXma40ktNraUG20z9hmqZ2cymTNHGZEA02QixAFuoqAXM9bWZ5yeuia1EphQLmUoamz6DeeF1zxCFxbue\/SJcUrQcLiUBkifjCEASIeiylu0+Hn0qVvBNi227ZmBDpOfl5gEtFBPafFA5rJWbWeyopIr7jEcw3O5FBF4VaWjT57GygJt2ZiVznq6Nmm7AQr3UTIrDInrxO7U1l8i71F7UWgqWbBpIRNYlZjd0w4YgLiMzwpEpM4ZBWIERGo7dM7UzvY+9wzpfYdxwFmDHCxttSynljmUjsgaHRfFMm0ThI7d7jqUta+GVWEeh5X8Wc\/lTS+\/GSo68HST\/ARAAD\/RQM1vCLD\/eCFBT4QIXyrYkjiMsTR38y7kIQjeqtEuDHxzFJatzuE0X6ZX8jva05IMo89bCm3ImRTB5gCbWW0h8LW2R7szmdvXK96UYm1lXdwz6Mg\/qTJql2nVJOUan6epV2H4vJhfur1yb3AmLsnBtiRFYgdAyiGU1ELCV0mxcYkJDsGhsnRDPJFw8zGmSLih9fMQLnoYb0WeB78TbHKbSzRJO5WQ83r+1v7\/\/0UZ\/OBt9fAk7Sr3zvBNzp8nUTIpZyp9Rx7nhoph7WNN23kHaq78UTI92kLKV99quHxfAYvcWwH+uuUbU\/ZD1y2z1Kmcy1QqwrGXLa7HbKQukHQyWXk5HiOqlzAkLiW1JA7KtjpcmFUQpPZ1tf2Do1yubyse2SYmagWZLAW7S4RCZuMEGebc1ToU7Y40tEA23bGEKeSmmnWhZvE00\/xqcAe1pjdtAvaApk3bMuo5dmZSDFRue2e+wtni1gGEXZyOlVIQ5Hit6otueVpL2h9V51Uxz4UcgRAxiT1MLxZP0dsy\/w9Jlfo2HozXaLPLfz5pYD26BJdtDa2YUBv0jTzsxgIUCI9mySc5hmKguOZ1CMXW5uRDbFIVjayYDo2jPY+p6vjovOz0pTd7ZxrdTj3tY+0Z\/qpvNfIum2+ZSkrr2uqd162gHwhFJ8UOcEqMxHhF6+5pbQS\/EZyzhdHSF0XESu2+zY7kNsi6W2lNXFCZ2BcRANnROQSoFwbZ9Aa5ZsvIuiF4TkwOsZA2VO+UEUcvW0V475HGv+BIXsojO\/6Cu4ka9DFnzknTIbn8sCvyqosDk7YsCk8tFgVuT3fdTFJDAdvtZZf729tu9ieoLBNdQEtigKBYEHsBZwQGpR65mn0xfDQCP1tUA+XIt1YD1\/JTCr82tRyatCwHmWioBcdR1GcBcSx2gHbUvApifrQKImvZVgFZpf0kVYPLjVYBLYv9YAriuEsAlxl7sM4UzAMib4eKj2GfaoprSLfu+08nfS0HgOOfhms3EnfZe8FGjah4EudzTN1DP2LuH9Syw2DaFSm\/KJKI3AF74iYhWxSMr7dmXK4dYCu3Z1HZhaOlfWzcPtoGdBNlpE6M9iS8ljTfgJNH1O9K+XoDAPsEQoZkWwDgs5zMgFlSWN3NJWAKQx5iYFGnVAaE2bQdw5opKz3EtIm4CMkAVC7bFnrzVq5hAABhksrKWtMCF5seWCKGROFISAe35mQ7is2pkAYgutHpKnlSw0L3fP56Mf\/QuEMuc7ZJdojjzzsYmzO7p3xEMRfTb9jUSU51JL4UpEae3yQsNGwc0GZsRpVHR5TaD623zzD25wPcasDZC3w2dUctGqNRUjTqOuj44lTVqvNPr\/zsLwNcN0UyZQznbfujxcLw\/DGfAnoi8EcMZaGJiy1negAcfW+w+YLT8DYUyiPn31Sv2gQZi51426wj3a5uqp3lhf0Ff81u3LTESzC8qrOlORPax2ZfcB9JW6z0PQxZmfRhPIp7aRds\/cwxMLiQc2\/58JVGinKik0YmBIjN2Lk2bigPNG0lpxe2NKK9pm64beBrEucnvJaWp1pnIbfW5TNSf5ezsK8SyBLO6vTljzgyGmcZIUnq+3kg06FLnZ4imB+uUW4ixWpAC1mm8NoMvMnkTg20aMl3ysFYf31UwMVLvcrBM4L4E6xIAN7S8jAbbylLu5s77hVhJGF47Y3YktlC6Ei6E5b3WhVS5ro2ObuZfHjx68sdNeytcFgObSvrEBWCrtW3\/7WDtgaa0bJ0bGvB0ZikpZp5ytGVb7WmLX5wOiuiZnIBjcH0CNcRWaRaFIm9g2UDxDLeVGJgyrheO08bQXtIJ7FaLeYWO4eIt1xkATB7zvlBaM4smnBVK34a8dEZt+uDCAcxNLXkPZvXiOZMREO\/OkMtn4I39biRdnYQG62ecj89p3kyTwmSW2wbq8tHafsjc5PrwxFpqfZVhXQiJan4PolOPuJmi7LBZ1+Z447CJ9vhQvn55\/XZ5XTtoT0b0ydQ2hXrJ+GL\/tqgyGg+BOvoS3JO837rkj32tJR\/Y2ZspzehmEjbON8DosybIaYkSRNqyPdzyYOMUBIsxrMpcerc7xyJJQW\/bSr+cBfGOx8RbjGsrLbUQTMANYcQOMdgTy7NROe\/OqMhrA2Vz1RabpoIEVW6joegOV1DiYvDsJYMnPQlG3Bar7TF52C2i0Xnr8\/prOtVZV26KQpGzIjVtkO0O49Q8cuP8xkF3ymFbPemuz7yeW7HCPWzHEmj5LW0cqcxEIEspqvkos+idYX5Y69sZHbx7c2diraqDkRPWzWv6XZsTSDJLTQ1MFg0B9MfDGh+4Nt6Kpqt\/SykzSig6UZ4UakW1Or+7WTzBpIi1NJQmz907sGRXieuLADFevhKy3VUPJaq9EGUt+UsyaKNgRKQwGw90Ye8bT+MIBLT6i8SHM9nZvitqSH66LTLJMSUamfrK3dgqU8ipL4mjZSty18Vf6BBPgWWx8E1DUrKeQ+uJyJ1kE5pWBLQL7GOalVOmROR63rNg0Fsyt\/pfVmTK2Alz4fBaV5bu4ZvUk9uun41zbIKjN35pRbRBvL+UhqFof54h5m+L\/b6L0VkFkvCWXUpsMDJre9V3\/P9j5++Pvm4Az4n4L8Trm7+Apex7G7yOCQt6p+4cIzviZjOgAuZB2yrK\/XY38VeFDJjo8psFzu4K1pivXkGbYt9THs9KIDQq2hwD6y3tyUw51Hn5N8O0jVGLG2\/3i202enLvP\/3i6y\/v\/\/vmb4e5cfTJ\/wM=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Il y a quelques jours \u00e0 Paris, Christophe Al\u00e9v\u00eaque, humoriste, souhaitait\u00a0\u00ab\u00a0qu&rsquo;on propose au gouvernement que cette ann\u00e9e 2015 de merde soit d\u00e9clar\u00e9e ill\u00e9gale et&hellip;<\/div>\n","protected":false},"author":10,"featured_media":2679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[29],"tags":[1004,1006,1007,1005,129,1008],"class_list":["post-2634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-1004","tag-aurel-dewarrat","tag-florian-mottier","tag-guillaume-peugniez","tag-spectrum","tag-spectrum-team"],"views":3141,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/2634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=2634"}],"version-history":[{"count":47,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/2634\/revisions"}],"predecessor-version":[{"id":2685,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/2634\/revisions\/2685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/2679"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=2634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=2634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=2634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}