{"id":2943,"date":"2016-03-17T16:26:35","date_gmt":"2016-03-17T15:26:35","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=2943"},"modified":"2016-03-17T19:25:31","modified_gmt":"2016-03-17T18:25:31","slug":"fiff-2016-2","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2016\/03\/fiff-2016-2\/","title":{"rendered":"FIFF 2016 : Un th\u00e8me, multiples genres !"},"content":{"rendered":"<h2><strong>FIFF 2016 partie 2 : Morceaux choisis par nos journalistes<\/strong><\/h2>\n<div id=\"su_carousel_6a98609b3705b\" class=\"su-carousel su-carousel-centered su-carousel-pages-yes su-carousel-responsive-yes su-lightbox-gallery\" style=\"width:100%\" data-autoplay=\"3000\" data-speed=\"600\" data-mousewheel=\"false\" data-items=\"2\" data-scroll=\"1\"><div class=\"su-carousel-slides\"><div class=\"su-carousel-slide\"><a href=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/born-battle.jpg\" target=\"_blank\" title=\"born battle\"><img decoding=\"async\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/born-battle-422x400.jpg\" alt=\"born battle\" \/><\/a><\/div><div class=\"su-carousel-slide\"><a href=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/granny.jpg\" target=\"_blank\" title=\"granny\"><img decoding=\"async\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/granny-422x400.jpg\" alt=\"granny\" \/><\/a><\/div><div class=\"su-carousel-slide\"><a href=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/mary-kom.jpg\" target=\"_blank\" title=\"mary kom\"><img decoding=\"async\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/mary-kom-422x400.jpg\" alt=\"mary kom\" \/><\/a><\/div><div class=\"su-carousel-slide\"><a href=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/tag.jpg\" target=\"_blank\" title=\"tag\"><img decoding=\"async\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2016\/03\/tag-422x400.jpg\" alt=\"tag\" \/><\/a><\/div><\/div><div class=\"su-carousel-nav\"><div class=\"su-carousel-direction\"><span class=\"su-carousel-prev\"><\/span><span class=\"su-carousel-next\"><\/span><\/div><div class=\"su-carousel-pagination\"><\/div><\/div><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-arrow-circle-1 su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Born in Battle - de Yangzom Brauen<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Par le langage po\u00e9tique du r\u00eave, \u00ab\u00a0<strong>Born in battle<\/strong>\u00a0\u00bb d\u00e9nonce une v\u00e9rit\u00e9 qui d\u00e9range\u00a0: Celle de milliers d\u2019enfants soldats enlev\u00e9s chaque jour \u00e0 des fins militaires.<\/p>\n<p>La voix d\u2019un seul enfant, utilis\u00e9 comme arme de guerre, qui pourtant en unie plusieurs. L\u2019horreur de la guerre c\u00f4toie la beaut\u00e9 de la vie, le fantasme et la dure r\u00e9alit\u00e9 s\u2019entrechoquent. Et pourtant, lointain, l\u2019espoir pointe son nez.<\/p>\n<p>Un court-m\u00e9trage poignant et innovant tant par son sujet dur et poignant que par la fa\u00e7on dont la r\u00e9alisatrice le traite. Qui a d\u2019ailleurs re\u00e7u un prix de lors de projection en avant-premi\u00e8re durant le <strong>FIFF<\/strong>.<\/p>\n<pre>Born in Battle - de Yangzom Brauen\r\nSuisse - 2015\r\n20'<\/pre>\n<h4><strong>Jodie Nsengimana<\/strong><\/h4>\n<\/div><\/div>\n<div class=\"su-youtube su-u-responsive-media-no\"><iframe loading=\"lazy\" width=\"640\" height=\"440\" src=\"https:\/\/www.youtube.com\/embed\/iK4o7Ej6VsY?\" frameborder=\"0\" allowfullscreen allow=\"autoplay; encrypted-media; picture-in-picture\" title=\"\"><\/iframe><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-arrow-circle-1 su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Granny\u2019s got talent - de Shin Han-sol <\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Dans ce film \u00e0 mourir de rire, nous allons \u00e0 la rencontre d\u2019une Grand-m\u00e8re pas comme les autres\u00a0: sortant de prison, elle d\u00e9cide de retrouver ces deux fils qu\u2019elle n\u2019a pas vu depuis des ann\u00e9es. Pour ce faire elle engage un d\u00e9tective. Elle d\u00e9couvre alors qu\u2019ils sont tous les deux mari\u00e9s et tente de faire \u00e0 nouveau partie de leur vie. Mais cela c\u2019\u00e9tait sans compter sur l\u2019insistance des producteurs d\u2019un jeu pour les faire participer \u00e0 un concours de jurons, car oui, Granny \u00e0 un talent cach\u00e9\u00a0: un langage bien plus que simplement fleuri.<\/p>\n<p>Ce film arrive malgr\u00e9 un th\u00e8me plus que loufoque \u00e0 toujours garder la cadence et \u00e0 aborder des th\u00e8mes plus s\u00e9rieux (l\u2019abandon, l\u2019importance des apparences au Japon, \u00a0la prison\u2026) tout en ne sombrant jamais dans le m\u00e9lodramatique. Un film que nous conseillerons \u00e0 toutes personnes pensant encore que le FIFF n\u2019est consacr\u00e9 qu\u2019\u00e0 des films d\u2019auteurs d\u00e9primant.<\/p>\n<pre>Granny\u2019s got talent - de Shin Han-sol\r\nCor\u00e9e du Sud - 2015\r\n108'<\/pre>\n<h4><strong>Jodie Nsengimana<\/strong><\/h4>\n<\/div><\/div>\n<div class=\"su-youtube su-u-responsive-media-no\"><iframe loading=\"lazy\" width=\"640\" height=\"440\" src=\"https:\/\/www.youtube.com\/embed\/tOBzQErIc8A?\" frameborder=\"0\" allowfullscreen allow=\"autoplay; encrypted-media; picture-in-picture\" title=\"\"><\/iframe><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-arrow-circle-1 su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>TAG - de Sion Sono<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>De jeunes lyc\u00e9ennes font un voyage en bus scolaire &#8211; jusqu\u2019ici rien d\u2019anormal &#8211; une bataille de polochons s\u2019en suit. Une chose en entra\u00eenant une autre, le car ainsi que la totalit\u00e9 de ses occupantes se retrouvent coup\u00e9s en deux par une rafale de vent, tripes \u00e0 l\u2019air. Les cadavres diss\u00e9min\u00e9s aux alentours sont, bien s\u00fbr, au rendez-vous. La totalit\u00e9 vraiment\u00a0? Non, une jeune fille semble avoir \u00e9vit\u00e9 le pire et nous suivons ainsi sa course folle pour survivre.<\/p>\n<p>Hybride d\u00e9jant\u00e9 entre un \u00ab\u00a0<strong>Ph\u00e9nom\u00e8nes<\/strong>\u00a0\u00bb qui aurait pris du galon et un humour qui n\u2019aurait rien \u00e0 envi\u00e9 au c\u00e9l\u00e8bre \u00ab\u00a0<strong>Shaun of the dead<\/strong>\u00a0\u00bb. Tag nous fait perdre la t\u00eate (et c\u2019est le cas de le dire) pendant ses 85 minutes de d\u00e9lire purement nippon. Avalanche de culottes blanches (f\u00e9tichisme japonais oblige), floril\u00e8ge de combats dignes d\u2019un Tarantino sous valium et h\u00e9moglobine \u00e0 gogo.<\/p>\n<p>Un film qui nous en fait prendre plein les mirettes par le g\u00e9nial r\u00e9alisateur <strong>Sion Sono<\/strong>, lui-m\u00eame inspir\u00e9 par une nouvelle de <strong>Yusuke Yamada.<\/strong>\u00a0 Si l\u2019absurde et le gore vous d\u00e9plaisent passez votre chemin mais sinon attrapez vos pop-corn pour allez voir ce film que nous r\u00e9sumerons en trois lettres\u00a0: <strong>WTF<\/strong>.<\/p>\n<pre>TAG - de Sion Sono\r\nJapon - 2015\r\n85'<\/pre>\n<h4><strong>Jodie Nsengimana<\/strong><\/h4>\n<\/div><\/div>\n<div class=\"su-youtube su-u-responsive-media-no\"><iframe loading=\"lazy\" width=\"640\" height=\"440\" src=\"https:\/\/www.youtube.com\/embed\/RSmNYUj7oFo?\" frameborder=\"0\" allowfullscreen allow=\"autoplay; encrypted-media; picture-in-picture\" title=\"\"><\/iframe><\/div>\n<div class=\"su-spoiler su-spoiler-style-fancy su-spoiler-icon-arrow-circle-1 su-spoiler-closed\" data-scroll-offset=\"0\" data-anchor-in-url=\"no\"><div class=\"su-spoiler-title\" tabindex=\"0\" role=\"button\"><span class=\"su-spoiler-icon\"><\/span>Mary Kom - de Omung Kumar<\/div><div class=\"su-spoiler-content su-u-clearfix su-u-trim\">\n<p>Bas\u00e9 sur une histoire vraie, ce film retrace l\u2019ascension jusqu\u2019au sommet de Mary Kom, une jeune boxeuse indienne. En empruntant certains codes aux superproductions am\u00e9ricaines comme \u00ab\u00a0<strong>Rocky\u00a0<\/strong>\u00bb et ses fameuses s\u00e9ances d\u2019entrainement rythm\u00e9es, cette r\u00e9alisation parvient, tout de m\u00eame, \u00e0 apporter un vent de fra\u00eecheur sur le genre. Petit b\u00e9mol\u00a0: bien que la sauce bollywoodienne soit mod\u00e9r\u00e9e, certains clich\u00e9s subsistent et peuvent rapidement agacer.<\/p>\n<p>N\u00e9anmoins, on reste s\u00e9duit par la d\u00e9termination de cette boxeuse qui est pr\u00eate \u00e0 tout pour pratiquer son art. Le parcours de cette championne contraste \u00e9galement avec l\u2019image traditionnelle de la femme indienne qu\u2019on peut se faire. En effet, en pla\u00e7ant la boxe au centre de sa vie, Mary Kom brise les conventions en s\u2019opposant, tout d\u2019abord, \u00e0 son p\u00e8re et en restant insensible face \u00e0 toutes critiques sur ses ambitions en tant que femme. M\u00eame si on peut regretter un sc\u00e9nario lisse et souvent pr\u00e9visible, ce biopic a le m\u00e9rite de nous faire d\u00e9couvrir une star nationale avec un destin exceptionnel.<\/p>\n<pre><strong><em>Mary Kom\r\n<\/em><\/strong>Inde, 2014\r\n2h02<\/pre>\n<h4><strong>Aurel Dewarrat<\/strong><\/h4>\n<\/div><\/div>\n<div class=\"su-youtube su-u-responsive-media-no\"><iframe loading=\"lazy\" width=\"640\" height=\"440\" src=\"https:\/\/www.youtube.com\/embed\/hu9Ac_HPC7s?\" frameborder=\"0\" allowfullscreen allow=\"autoplay; encrypted-media; picture-in-picture\" title=\"\"><\/iframe><\/div>\n<h4><strong>Par nos journalistes Aurel Dewarrat &amp; Jodie Nsengimana<\/strong><\/h4>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"M7I0MQYA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c\/N0c1MwMjA0U7BSCM1TKMk4vCI3VUchtzSnJLMgJ7VYIT01rwhIKQIA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1TcyMDTTNzDWT8tMS9MFcXSN9AE=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"cy\/NzMlJLM1NVQhILU3Py0ytAgA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNM1MNY1NFcwNLMyMLYyNgUA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"7VpNcxy3Eb2zSv8BtakkdhWXXNLUhyVSLkmW\/ClZtuSkdFJhZ7CzoGaAMTBYcnXy38hNp9jrVOWUm2\/af+Jfkvcas8tlTMuusuWkHB8cc2cwQPfr7ve6ER9O928exi54V92898G9e2p\/tHdFtTp01qh9dV3d96EwOp2qYupttJHvlPNRHfsUnK5t7Ew83O23ONzFfluHpZ0pWx4NYnpa6OBTNPXTK\/rta1dGb4\/fujq6PB6ootYxcsVwtUJt\/D0sjOtMMOW5h62uTBzOTTz3NJjYehftzKxe1baadmN\/Oqx0XZswH6jYzWtzNDixZTe9vjca\/XGgSt3poU6db2s9Pxq8NRqN+oexNQbGX1k\/aHjQydSY+mgw0XU0\/XPbmQY+7K++K4KvsWRvcFMQ+L6Lw1jb0sQfeY\/XWk2DmRwNpl3Xxuu7gDeVQGQnOTsJO8V0FzYWXUjN7kk7LDywct1uamuvy7jLEO6O3tod++CGY911tdk5bquB6nSoTHc0eDqutXuG37YjKlyn8jocbZtKlabwpXXV0UDHuSuAXyh+OWOGB\/v7pwejUTZK1915E9Qu0kjjH2D06wBVBe3c\/JUY5SWvD568\/wXI9Af\/+qA0OsyHz3zzSli4SGHR6wNmZcYF0KwP\/\/XB6XT1Slzw\/vVBgs0vQINHngfilXA4PfthGiptgBnWOyyJrXYXrWmD4Q67fP\/Dq5w57c5WvdIisLt1uj910wP5363\/+Aycb8Ht6uzPoZD8cKJdMd98bIHjUIfgT4aFDQWW7G2+LmofTXmOwod+MomM6koAsOXUYyc3TAEE7\/z3oFvtJvFnWoytK82pbIEtybKp6y4CdNPMNVK3yYfWqdtCiWqINFJPtKue+0bdDjoZdyGWa59y5tBNAFwbHSb2NP\/qgkW1bh22Nx9CyLE38raCrqrWLxed\/SIZVSYVlt\/MzLZ6+Y+XL1bdwcqkzNJrxX\/54uW3qlwunHeFUckZNVsugu2WC\/VFsnwDAqvMyxfX1R0DNaYnja1ra0JU5Xdf\/s04RKyDbvsaWEdlXG2wRUTDoWkN+wy1fIHvoppYF\/m17TQyNO4c7rbiysdazTw85H7JqWhSrfK+2yp1WB9hTuGbxigdGrGhSiYEuEgjWxzRYTG+gQdofNo6RWtSiDvqY2yJ2Af84me17r9UxfJfnbfyZIwGiQ7n9zOLbeEoj9cRp5mOj8uEj8JygZaJa6O43qHOph5uggPU3W5tCTbwFp9bh7+4kpENeI2HBlA55czztfufI5\/44bBBCEMOpq2ceNQhZs7P+Le4yPaN38d0jHcwikvWywk4V8DeiV5+hXUlUok\/s+VRI38QZ7iHg9D\/7KhPAaAW5DXCStBUMMuvEpBUbWBQsNwz2Ng6+ONMLIRa0yrySGOXXwfmXaAN2HuzI11n2srdYH5CeVzaepRsjHwH2rx8aWt\/9Gd8j2+3DqcH65b3Q3CzUQ+icZVttNObjewBlr6CgOY+dWlsclVt9KCNKa0eCkWA03VD73VWgFo\/h5JLE4r28gDUMDVsVY8GB\/xxThlOTk52+iN2kLm7phmbctd+dOCv3j2+8pf45J2Bku3ROpUmCNGg2\/Unk1TXoDFDgPkbwtM3uTcAehHmbWfKbOUN1dqiQ16S2fo\/1xJGLsoO\/F8y8HvSdyGro6o8a6cmoUqmPZoi9d7XbgjKUj+fh9\/VIDXU1MTWDYkO00awQjb4F6jEQR4llFiG16xFxNGTO3rCM4rWIqhSRq2OPdfVoEwEH8lJ+o0+k5zUoQUHbKtMyMtFgdZIDjTI\/jRDUAvDgsXYB6siaIEcxMWOdS5HzBIWtCgyYWaAtVyAkdVD0jW9IUPnA0wWGPABjupY\/zPwxt3V2TgQK7VwhBzEEyNpp6Pn9coStHuWugC+IqhicD4FqDiardNqciXnkLHBxTvqvrYEGMAV2B0mgLhUFNR9g2pgCgehWcgL5llNJaNToKsyFZ1wWi8txyYJSYtZ+XQ5srCtEZlK5GJHOhbGO06gk7it0OUon+y2ynnVr+yzqtDFdLlgjPBspcdjiwqmEAkpR9u0tWm4ekLP7Jr87\/SZg\/oCrkCprsDVsvt0+XVjzvaofZpQa3g4oD0WGytN+mBWFRqtaCFyhQU684rgkDeKeadIeWc83iBieozE871KwUbJsR4+3QIabsksVB\/qlutevsBROf+++\/Lvb9IQ0V1HWWvGogDHumHISoYISQJVq30JJtLSn+wo6J24TF+kOoB4NFSf0BcJd6XBaDK8c\/KXi1nhC4+YCRxGyY2HE33tZBNdBGlcmCerlqNucvRRSTkTlgvYD7XoNhTpJ9LFpa07HidIj\/UolWt12htd+y3IU\/fJ7eef3g0fFNdu\/S5Pr1WeHt96r88uNlOPvPO\/gBAZ0hurpZ4XSFIpnAmJGGQy83OyEsI2JgkUvhby+9Mfru3v7d0Az8XM3YWFbGGVVIzzAXy0XkSlwvggfaLIkK89cEPJ5m4YBtmO5W142xjlNPbIevlP6U75veiZ9NekVE3GztWsUfRd31xj7wjbfVEkgEUmiGfiRsL1qRUpcVla2PJy86AnOpvGZdvocUHrWXWlvw2YB\/AbTKmhWaACtJjLRWMdN+MlqZS98CoFbDuTeFx+G7ZJgSDD0jwfzkBZ2GjT4BmaaZL7yxfvqAekSVojwSAB1XSnGeNfesYxYLmYyVd40IrKdpkGAd+MaGZUopapAJ5PPLcQ2YLSzSxsX8vH+\/NxEPVfLo4BFXaVqYQh35z+Hk454qHBcBu3vTL7cYDSicOA0DqZrYKYO1qFTaaJ\/Yyskt4hr5QUAazGzaDpxAYJVy+\/HuPkzWMfTTX28BNIEMOiy3Nn76jHusquT+R8E8qQU2H5DRqEN2BC0bO7JEzMjYHi\/cab1ISSacVUuXYZc6UT0chg1CLtYBzRXGdbEOiOujXTNWtdcqRIte\/4xTg\/i+qNCWfoYmo59h1T8Khjflzbyry5DeX2wcLLKn8OuePAW2L2MusG47GmBFrnkUHwC+fZ1BBLBKDxVe3BG6Lgla\/85gTYK6LNeADeDAlzjp7UBirEpqWBY2J1m+f\/CoG1KNL1gMe+aY3\/Gbv0T1B6yaLT\/AYeIs2Qf4jfqn6kC+uLe7XFkxTTM45nDapmZyN+oK5cVmMkZZnHZJhDeWaFiM6CZKKRqRWz3HM8Z2oCasRKSY8QgRSUpANJtLIAfnlenWFAlITn\/wPA5zase+x12wDTY2py0wDAYJhlw9GtOuaVC399fOEU+n0OvrQlXc5a1q9d\/i2o+mePmgdPPj++6u\/531X9tar6fd5of+SbnFafNMlV6qOEwefni\/ttzTswDjosVDBU58lwFB7I6ao0qJGa9zusy1igaWZqr8QdNB05WMoMubJ1U6vG\/tSkSGJAhqN9wJQHHWjakJyMnoUJvNNiwy4DQqKZYO1+0LIiXg0HjALLzGqO3VSEz3zxbI6fax75lsQRZRpreLhMKFqmjrK\/Y+NeQuNh3k0bzqn0GCR4Rnp0EyyGeVF0n0MJLypJc9syDrUcbUyQVsjkKXrCxgRklPoBEuRlHKRVPTTIBzUmYdfkEekC+iYl6lQQqLqen3ifYQKqWN94XpbCuu0NnGrL0ZDSPuZoavKVXmtyHwPSg3aLa7pC3MJaEB4Qg8Zbzp5wDVTBe8Ploky2W93wyTQemv7SXSRJQFlFkWJC6WyDqGk\/VmVabUMexvJlIiZgdkbceD355r2KqW5ayxlMyZWFph3LBTqE3uyZKfrZke0lFpS2k\/W9jPAm0jTNWU7l6YzhMomBz1N4zrTJxCB6Mjfr5Vc631zSHekwcmPD3rC\/pF2XG1qgmK9LYCSRtb0ksC\/1CH3UZ2khkgX+k7yg961cuxgZYwk0zwXwLJ6x3AMXZmMmLYIV5KIkDfNVN2O7PrFbXcOK1zvqvigt2rmVx8FUIuCSihFtk9PBelXLbSdLoe9xETW0iWKC1PfYerCt0v1EDSsEi1X3FM4uY2zmCDgSVM4NLa0nIsU7HHgI9TWnhWn7SG1o4qpMD02zZrNLkDT8XJfsB6DIbSrkwaWt\/elo\/wKJvAVRqNW75gQErrv\/dYGcprdvFU\/ff3jnavwvCOQGbA8v+G8z1Hks1Z9QkDfUj\/Qg\/wY=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">FIFF 2016 partie 2 : Morceaux choisis par nos journalistes Par nos journalistes Aurel Dewarrat &amp; Jodie Nsengimana &nbsp;&nbsp; Envoyer l&rsquo;article en PDF &nbsp;&nbsp;<\/div>\n","protected":false},"author":10,"featured_media":2944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[160],"tags":[1006,1209,1027],"class_list":["post-2943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","tag-aurel-dewarrat","tag-fiff","tag-jodie-nsengimana"],"views":2007,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/2943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=2943"}],"version-history":[{"count":7,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/2943\/revisions"}],"predecessor-version":[{"id":2955,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/2943\/revisions\/2955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/2944"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=2943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=2943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=2943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}