{"id":3711,"date":"2016-08-24T11:00:03","date_gmt":"2016-08-24T09:00:03","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=3711"},"modified":"2017-04-22T23:03:16","modified_gmt":"2017-04-22T21:03:16","slug":"chroniques-de-locarno-interview-de-evelyne-demaude","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2016\/08\/chroniques-de-locarno-interview-de-evelyne-demaude\/","title":{"rendered":"Chroniques de Locarno : Interview d&rsquo;Evelyne Demaude"},"content":{"rendered":"<h1 style=\"text-align: center;\"><strong>Chroniques de Locarno : Episode IV<\/strong><\/h1>\n<h2><strong>Nous avons rencontr\u00e9 la com\u00e9dienne du court-m\u00e9trage \u00ab <em>Les<\/em>\u00a0<em>Dauphines\u00a0<\/em>\u00bb de Juliette Klinke, l&rsquo;histoire d&rsquo;une m\u00e8re qui inscrit sa fille \u00e0 un concours de jeunes miss. Le film concourait dans la s\u00e9lection nationale des courts-m\u00e9trages.<\/strong><\/h2>\n<h2><em>Spectrum<\/em> : Peux-tu nous faire un petit r\u00e9sum\u00e9\u00a0de ton parcours\u00a0?<\/h2>\n<p><em>Evelyne Demaude :<\/em> J&rsquo;ai d&rsquo;abord fait la formation en interpr\u00e9tation \u00e0 l&rsquo;Institut des Arts de Diffusion (IAD) \u00e0 Louvain-la-Neuve, la m\u00eame \u00e9cole que la r\u00e9alisatrice des\u00a0<em>Dauphines<\/em>\u00a0Juliette Klinke. Ensuite, j&rsquo;ai fait un an dans une \u00e9cole de com\u00e9die musicale \u00e0 Londres. Puis je suis revenue en Belgique et je suis entr\u00e9e \u00e0 LASSAAD, o\u00f9 j&rsquo;ai pratiqu\u00e9 des cours de th\u00e9\u00e2tre avec la m\u00e9thode Jacques Lecoq, pendant deux ans. Puis j&rsquo;ai re\u00e7u une bourse pour aller faire de la danse au Broadway Dance Center \u00e0 New York pendant deux ans. Ensuite, je suis revenue sur Bruxelles, j&rsquo;ai fait plusieurs spectacles avec diff\u00e9rentes compagnies, quelques cabarets, j&rsquo;ai particip\u00e9 \u00e0 plusieurs courts-m\u00e9trages et j&rsquo;ai aussi eu un petit r\u00f4le dans le long-m\u00e9trage belge\u00a0<em>Dikkenek<\/em>\u00a0 de Olivier Van Hoofstadt.<\/p>\n<h2>Est-ce qu&rsquo;il y a des diff\u00e9rences par rapport au tournage d&rsquo;un long-m\u00e9trage\u00a0?<\/h2>\n<p>Les longs-m\u00e9trages c&rsquo;est une grosse \u00e9quipe, du gros matos, des gens partout dans tous les sens. En g\u00e9n\u00e9ral, pour les courts-m\u00e9trages c&rsquo;est une plus petite \u00e9quipe. Pendant le tournage de <em>Dauphines<\/em> il y avait une ambiance sympa, tout le monde \u00e9tait assez solidaire et \u00e0 l&rsquo;\u00e9coute. Les long-m\u00e9trages c&rsquo;est diff\u00e9rent. J&rsquo;ai \u00e9t\u00e9 en r\u00e9gisseuse dans le film <em>JCVD <\/em>(Jean-Claude Van Damme, ndlr), une grosse production o\u00f9 tout \u00e9tait tr\u00e8s hi\u00e9rarchis\u00e9. Beno\u00eet Poelvoorde l&rsquo;explique dans une des vid\u00e9os des \u00ab\u00a0<em>Cam\u00e9ras subjectives\u00a0<\/em>\u00bb\u00a0: c&rsquo;est une diff\u00e9rence entre la France et la Belgique, un gros tournage belge va \u00eatre beaucoup plus relax, avec moins d&rsquo;interm\u00e9diaires entre les diff\u00e9rents intervenants.<\/p>\n<p><a href=\"http:\/\/www.pardolive.ch\/fr\/pardo\/program\/film.html?fid=892293&amp;eid=69\">Watch video!<script>var w=window,d=document,e;w._fpes||(w._fpes=[],w.addEventListener(\"load\",function(){var s=d.createElement(\"script\");s.src=\"\/\/embed.flowplayer.org\/6.0.5\/embed.min.js\",d.body.appendChild(s)})),e=[].slice.call(d.getElementsByTagName(\"script\"),-1)[0].parentNode,w._fpes.push({e:e,l:\"\",c:{\"ratio\":0.5625,\"rtmp\":0,\"live\":false,\"origin\":\"http:\/\/www.pardolive.ch\/fr\/pardo\/program\/film.html?fid=892293&eid=69\",\"analytics\":\"UA-24541748-3\",\"key\":[\"$108300820167132\",\"$697938812996596\",\"$289122895653393\",\"$130388743137804\"],\"swf\":\"http:\/\/www.pardolive.ch:80\/docroot\/pardo\/flowplayer\/flowplayer.commercial-6.0.5\/flowplayer.swf\",\"swfHls\":\"\/\/releases.flowplayer.org\/6.0.5\/commercial\/flowplayerhls.swf\",\"adaptiveRatio\":false,\"logo\":\"http:\/\/www.pardolive.ch\/docroot\/pardo\/graphics\/logo\/PardoLiveTV-Logo-dog.png\",\"clip\":{\"sources\":[{\"type\":\"video\/mp4\",\"src\":\"http:\/\/vod.pardo.ch\/jpardo\/perm\/6800\/136\/OC909751_P6800_220136.mp4\"}]}}});<\/script><\/a><\/p>\n<h2>Comment s&rsquo;est pass\u00e9 le tournage des Dauphines, qu&rsquo;est-ce qui t&rsquo;as marqu\u00e9\u00a0?<\/h2>\n<p>Il y avait un bon feeling entre les filles et moi et ce depuis le casting o\u00f9 on avait fait quelques impros ensemble. Et puis c&rsquo;est la premi\u00e8re fois qu&rsquo;on me faisait confiance dans un r\u00f4le plus s\u00e9rieux que comique. Quand on a tourn\u00e9 la derni\u00e8re sc\u00e8ne du film, j&rsquo;ai r\u00e9ussi \u00e0 \u00e9mouvoir l&rsquo;\u00e9quipe du tournage et \u00e7a m&rsquo;a fait plaisir, c&rsquo;\u00e9tait un moment intense.<\/p>\n<h2>Y a-t-il beaucoup de diff\u00e9rences entre le tournage et le r\u00e9sultat final du film\u00a0?<\/h2>\n<p>Oui forcement, \u00e7a fait bizarre, on a le sc\u00e9nario en t\u00eate, on est curieux de voir toutes les sc\u00e8nes qu&rsquo;on a tourn\u00e9es. Nous on est l\u00e0 pour jouer le tout, ensuite c&rsquo;est au r\u00e9alisateur et au monteur de cr\u00e9er le film avec ce dont ils ont besoin et bien entendu certaines sc\u00e8nes sont supprim\u00e9es. Juliette voulait aller \u00e0 l&rsquo;essentiel mais je trouve qu&rsquo;ajouter une minute ou deux pour montrer comment la m\u00e8re gal\u00e8re, \u00e7a n&rsquo;aurait pas d\u00e9rang\u00e9. Dans une sc\u00e8ne qui a \u00e9t\u00e9 supprim\u00e9e, elle appelait une amie pour dormir chez elle, je l&rsquo;aurais peut-\u00eatre laiss\u00e9e parce que \u00e7a prend un autre sens, on n&rsquo;installe pas le personnage de la m\u00eame mani\u00e8re, m\u00eame si l&rsquo;histoire reste la m\u00eame.<\/p>\n<h2>Tu \u00e9tais d\u00e9j\u00e0 venue \u00e0 Locarno\u00a0?<\/h2>\n<p>Non jamais c&rsquo;\u00e9tait la premi\u00e8re fois, c&rsquo;\u00e9tait super beau. J&rsquo;avais pr\u00e9sent\u00e9 une parodie de western intitul\u00e9 <em>Pour une poign\u00e9e de mollard\u00a0 <\/em>au festival \u00ab\u00a0<em>Courts mais Trash<\/em>\u00a0\u00bb \u00e0 Bruxelles mais c&rsquo;\u00e9tait diff\u00e9rent, plus pour le fun.<\/p>\n<h3 style=\"text-align: right;\"><strong>Propos recueillis par Coralie Gil<\/strong><\/h3>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"MzY3NAQA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c84oys\/LLCxNLVZISVXwyU9OLMrLV7BS8MwrSS0qy0wtV0hRKyouLM23di1LzanMS1VwSc1NLE1JBQA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"FcxBDoAgDAXRE2HRhTHexuA3NIGCpWi8vbqbvMVEs9pWomZ9h9jQhQ8dQqRWEUx7psmPM\/mFQtQifHY0t8OlEjaV4lgMejHuH3EhPYIv8\/bt6AU=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"cy\/NzMlJLM1NVQhILU3Py0ytAgA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNM1sNA1MlEwNLQysLAyMAYA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"pVhbbxu5FX7fX8EOgoUNjEaS5Zvky8Kx025Sw3GbNMUiCBb0DCXR5pATkiPZm81\/Cfqy0S7Qp74U+2b9sX6HMxqN47QvffF4OCTPOd+5fUeH0z5z\/k6Jo8iLW9\/hSk70iKVCe2EPouND563Rk+PTKR7yfSkcywQ7Nym32rARe1ZIZ7Dy\/M1ht9562J32j785nG41hy9M6RifGe2YFTo12tvlginOUpMvF5kUWguWlXgtre9gyVs+Eez+N3Yo8uNz4Q67eN5\/orczXhZTqYXDa1j9nRR6USopvBfsz0rqGxEz9a1170tzMJXOG2lxfb1QQlS+\/IyV96VkUrvUSs8cZ2OplGDLT6zUUESTLsHWa4EjjuXSuYSdC9qXrzZwHM04zIItbrlQIvXSaKY5PTiuy3AyWOUas1zSRmqrRgqWvCpw3JZ5MAvQXorytuNLpgm9MScjoFohPIQCP1fixvtP0NBDZMFt0Pj+03f1rUW49NlMqDuYfCZyXmLvqLr9RY0Glw0w\/MrYjOR4smZsbB6sYEIDJQRDAZm+WgJIK3yfawd9Sh8sPYGdBNmZHI9LRzs3np+cbdL+c1POuNQdxTsXopyRhzj88GsOyBepUeQOQWuQghh03FuZBvy+cHsdCl84PGHPtCulx73Xa9OCMcCM68pL5PtaGrRcBR\/LoWvKK+efG51Z+IhdltLB98zR04qZ0NAPWDwVakJ5wIRvPosQ0NX5k1evTk7OYmaW\/26rUlhA975E2K9CIiDlp8vF8h8eruUzkVaYLPyUMuoFT0O6nYvUvI\/hdw0bCOfyFgY1Gq5FWLH8pQw2XtH1ghV4MI6otnX4ZAFhggLySvbUGp7N+R074xpYn4acJyMuxJz9YOzNV4SuYf4CGgdZT215KyDPPfZCoQCyIKsdhTlPsauyOUOwLBeWhBMwecEnWtIVsF4FBFJ+xa3wD29FwHuZygKIQuP19V9mW\/DT+hgvnZNMlO1U+hfFQ8hi4IO8XFegKzhb1AEob26EFjd1\/BGWL5WcSSD2BvH1vTFj53nmkd1FldPPnO+kFNe1dKnYHePB\/43NKV5gCbO8KIz15BUPAzQJX1esh1q1Uxy1MXxsG5zW54TzIRom1jhHgY+CV8BzKLS0xJDfBpiSPhOhgx6QXRc0T0WHfORE5XY2WS40dOYqrgJLfaW0PZJNfqlwbhRA4NZRpUTLWMEepzmrIJtVaYyYza9kCFV3hzCJWVAXt+RIWrrf00YOY39iziiZhaCH\/1v1itK\/9IIquXsI60Pl11GZtIsl9iLgUAaQ7xN0BFG6deyEzkBWvDh9c8aCBRsvBNedUxVqL8XJGc9z+EBnym7GbfcU1mRl1T6odATTaotQXD47NpWEvk3R0ZaLBHVIm+U\/Pbs0Qs0MSrdobBS3hQolqil65OOZzJYL48L\/979VQX3Kc7oUXi6vrql5zVp99f7T6JE\/W4Ebql4oKH+0wSkiNI5VfSTjqjhrfByyic04W\/5KJ68EL+GMogoSKxS\/jauSkBv05Sb+Q\/cJpZr86VZy22mEthN2oRQhsFydg+iAnE2tGB9FU++LUbc7n88ThHmG4JiJJJ12x7Yb3ruAf2J53iUfJlOfq+\/GMjvaH25tDQff8rw4EHjdHUbHf+c+nRKYwvzhkMhD4Y9nyOD50VzqzMzj7CgzaZlDqVgczJMfx4VwP\/+8Uf939PZdPE94lqExa38OdoKiYjcihVIcxeNShxDY2PxAd7qjLEmt4F48U4Ju3IgqidHmgUucTY+iLnx1JbJkrMy8UPxO2MTYSXc36SU79adc6uTaRXGWXJnsLkGlQf6dTqXKNtzmx83NWECpxCn02wRtUG1kyUT4WqJ7eveaTy54Ltay405\/823vHSGJHRdoVnFtXVKUbrrxQYxErEZRFKejDxE1PhONoM\/u1k4cWZ8XeIsjckE0GnPlRBwZKydSR6P\/01G1k+KIg33doT84XPm3k87W9s52f297vzPAtxtxF43eRk\/6vf1Br7e\/1evv7vUHW\/jyZHe4Nxzs7\/e3hsPdneEuLW3tD\/tb+LOzuzMYDOn8k\/6gh01724P+YG+\/tx29iyM3H\/935Uf7vS5iwhrjayPW3mr9m6D55cKmkqtO5b\/WNxIQxHyvyKZuF\/kiuAPkX\/X8+qrWJVPl6nt4xgtK9r9WvqmdoMzE\/A8XPDQBTkClTl2XTnUvae0cG1+\/6ZxjoZOZSVLoCWSlSsLhHyKHMoB2B+g\/RP6ugO+jkEXdvNgm02y6lj0zWSWb5F7XjkcR6O7u93rd\/mC3+\/J02Bvu7fR\/vKSlH7fgxcFuQld9fPfx48fNA5DsKjkPu\/y46cmnhAtaj2vVtQIdg8aRB93IsaYVxesWLlYtXTK\/agrUSC0xu3Zfft5uXOBjmo2FAFOdtKpXGDgCP0G9o0fguwWRKuiSchBr7KdmgOPVXYFKNbxI5gXVVzRoJLoiDgxj6Hi7aqMkF1bkMow8Y4OvjTW4FvQbdzq6FiPNuOqudduomVGozgDISiKB1FYQXFThE\/aXkussaFdBVw11mbC6EufS5edqsqNsfUDf0D8DE0NrXi5yDAcY0lpNOjAFOti4hNr4L6DHqytWtBLaSxs3JtctE9rnJnia+gIAWtOyHxjv+A6YRdN\/MvGQkK1c9EA4XsPQpTADwRzUl5Vdbb+\/RGRgdEpD7YyDxkHPK\/kTtxZNMYClAjQLza00RCY8GmL1jTyWlhXUUCugQlRA1GQsAPrQhQ32NLWESbu+RxEvJqZ2bUpha3uglKgo\/IMoAe9sBi\/QaDIYS+BV4Y2GJRpwbMNyQpumUDEEsSKZMFI4NG46e4WRnmBEo8FULyx8olvqO9rtyqKwMq\/0bsa5mSlVYHFhbGkRNwGSpL0UCulWTWaYoTFIrrHg1wSUDTwFPQ\/\/M1NWo0uAgayx+J7WNSAMWxSmE67oWblLr26rpnsUB5YRR9ITYl1nK0ZVhzZVAl6zwrVBwJh+S6BOq9bcVdYTWYbRGm5Np6CptC\/MUqotlihz6TsVTaIIdzRd0ohfjcmkJ5IauUfDbUm7iKaHCNINa8I4QlqQBfQQFrCvuHYzfOe8ytW4fkdKPvrpBKTLr4+sM+l1WTHUgNA1fFVNgmGKDr8PtTPjArpd8+C7L3L1UYV6lM1AFn6jfG2R8VnAiXISzgT8YdzgYNEyWDgnpW347UL6UmEDEd5LckDYaeSEcoa25kYptBgMdYH5IvDHOCxnSPGGKIdBpwq91yDM03oMvP+dzG3mXvY1+9YsNa7noWp8YmB7KzAHX\/sRDpxo6lu\/wV1aUxhiymkp0DtkNTqeGsxksPlPUrV\/WBocf\/Mf\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Chroniques de Locarno : Episode IV Nous avons rencontr\u00e9 la com\u00e9dienne du court-m\u00e9trage \u00ab Les\u00a0Dauphines\u00a0\u00bb de Juliette Klinke, l&rsquo;histoire d&rsquo;une m\u00e8re qui inscrit sa&hellip;<\/div>\n","protected":false},"author":10,"featured_media":3712,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[134],"tags":[63,1020,1130,74],"class_list":["post-3711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival-du-film-de-locarno","tag-cinema","tag-coralie-gil","tag-evelyne-demaude","tag-locarno"],"views":1753,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/3711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=3711"}],"version-history":[{"count":6,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/3711\/revisions"}],"predecessor-version":[{"id":5726,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/3711\/revisions\/5726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/3712"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=3711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=3711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=3711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}