{"id":499,"date":"2012-10-21T23:15:48","date_gmt":"2012-10-21T21:15:48","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=499"},"modified":"2021-05-09T14:07:23","modified_gmt":"2021-05-09T12:07:23","slug":"friscenes-ouverture-remarquee-dune-5eme-edition-mitigee","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2012\/10\/friscenes-ouverture-remarquee-dune-5eme-edition-mitigee\/","title":{"rendered":"Frisc\u00e8nes: ouverture remarqu\u00e9e d&#039;une 5\u00e8me \u00e9dition mitig\u00e9e"},"content":{"rendered":"<p><em>Malgr\u00e9 une s\u00e9lection peu diversifi\u00e9e, Frisc\u00e8nes convainc gr\u00e2ce \u00e0 une remarquable pi\u00e8ce d\u2019ouverture. Plong\u00e9e dans la cinqui\u00e8me \u00e9dition du Festival international de th\u00e9\u00e2tre de Fribourg.<\/em><\/p>\n<p>\u00ab\u00a0Il y a vingt ans, j\u2019ai \u00e9t\u00e9 invit\u00e9 \u00e0 faire une travers\u00e9e de l\u2019Atlantique Sud en catamaran. Nous ne sommes jamais arriv\u00e9s. Notre navire a \u00e9t\u00e9 attaqu\u00e9 par un cachalot qui a d\u00e9truit notre embarcation\u00a0\u00bb. C\u2019est avec un poignant r\u00e9cit de survie en haute mer, retranscrit en pi\u00e8ce de th\u00e9\u00e2tre, que l\u2019acteur suisse Jacques Michel inaugure la cinqui\u00e8me \u00e9dition de Frisc\u00e8nes, le fameux Festival international de th\u00e9\u00e2tre de Fribourg. Les amateurs verront se succ\u00e9der du 16 au 21 octobre pas moins de dix pi\u00e8ces dont six sont en comp\u00e9tition. A l\u2019issue du concours seront remis les prix de la meilleure actrice, du meilleur acteur, de la meilleure pi\u00e8ce et de la meilleure mise en sc\u00e8ne. Seule ombre au tableau\u00a0: le festival ne pr\u00e9sente cette ann\u00e9e qu\u2019une seule pi\u00e8ce non-francophone en comp\u00e9tition. De quoi s\u00e9rieusement \u00e9corner la r\u00e9putation internationale de l\u2019\u00e9v\u00e8nement. Quant au jury, compos\u00e9 de Jacques Michel, Sidney Ali Mehelleb et Marianne Radja, il ne rassemble lui aussi que des personnalit\u00e9s francophones.<\/p>\n<p><strong>Un One-Man Show t\u00e9m\u00e9raire<\/strong><\/p>\n<p>Qu\u2019\u00e0 cela ne tienne, l\u2019ouverture des festivit\u00e9s s\u2019est faite mardi soir dans la bonne humeur. \u00ab\u00a0L\u2019ann\u00e9e de la baleine\u00a0\u00bb, sorte de One-Man Show mettant en sc\u00e8ne Jacques Michel durant soixante minutes, qui r\u00e9ussit le pari de fasciner le public. Son atout principal consiste sans doute dans l\u2019aspect v\u00e9ridique des \u00e9v\u00e8nements relat\u00e9s. En effet, entreprenant en 1991 une travers\u00e9e de l\u2019Atlantique en catamaran, Jacques Michel et deux amis sont confront\u00e9s au naufrage de leur embarcation. Naufrage provoqu\u00e9 par un cachalot agressif cousin de Moby Dick, qui r\u00e9p\u00e8te \u00e0 trois reprises ses attaques destructrices sur les voyageurs. D\u00e9rivant \u00e0 la merci de l\u2019oc\u00e9an, les trois hommes sont finalement recueillis par le \u00abTaise Maru\u00bb, un cargo japonais transvasant les prises des tonniers japonais dans les mers de l\u2019h\u00e9misph\u00e8re Sud.<\/p>\n<p>\u00abL\u2019ann\u00e9e de la baleine\u00bb est le r\u00e9cit de l\u2019attaque et du naufrage, mais aussi celui du traumatisme qu\u2019en gardent les trois rescap\u00e9s, sauv\u00e9s in extremis de la mort en haute mer. L\u2019agression inexpliqu\u00e9e du cachalot les laisse dans l\u2019incompr\u00e9hension, la col\u00e8re, l\u2019angoisse, la tristesse; leur survie miraculeuse dans la joie et l\u2019incr\u00e9dulit\u00e9. Le tourbillon \u00e9motionnel les porte m\u00eame \u00e0 personnifier leur agresseur. Le cachalot anonyme devient \u00abRalf\u00bb, tant\u00f4t monstre marin diabolique et assassin, tant\u00f4t \u00abgentleman des mers\u00bb, protecteur d\u2019une famille de baleines effray\u00e9e par le catamaran. Bient\u00f4t, souvenirs et r\u00e9alit\u00e9 s\u2019entrem\u00ealent et laissent le narrateur dans une solitude d\u00e9boussol\u00e9e, poursuivi dans ses r\u00eaves par le L\u00e9viathan.<\/p>\n<p>La mise en sc\u00e8ne de \u00abL\u2019ann\u00e9e de la baleine\u00bb r\u00e9ussit habilement \u00e0 contourner les r\u00e9cifs de ce genre de t\u00e9moignage. La narration est soutenue par une bande-son alternant musique classique et compositions contemporaines, ainsi que par des jeux de lumi\u00e8re. Le d\u00e9cor minimaliste, quant \u00e0 lui, concentre l\u2019attention du public sur le compte-rendu.<\/p>\n<p><strong>\u00ab\u00a0La vie est faite de centim\u00e8tres\u00a0\u00bb<\/strong><\/p>\n<p>Un autre \u00e9l\u00e9ment int\u00e9ressant de la pi\u00e8ce tient du langage utilis\u00e9 par Jacques Michel pour illustrer son histoire. Toujours rythm\u00e9, celui-ci reprend les enregistrements authentiques pris par le naufrag\u00e9 lors du voyage. Oscillant entre prose soign\u00e9e et parler populaire, r\u00e9p\u00e9tant en cadence et avec ironie les tics verbaux (\u00ab\u00a0\u00e7a va tout seul\u00a0\u00bb\u00a0; \u00ab\u00a0tout va bien\u00a0\u00bb\u00a0; \u00ab\u00a0un superbe coucher de soleil\u00a0\u00bb) et semant les proverbes faits maison aux quatre vents (\u00ab\u00a0La vie est faite de centim\u00e8tres\u00a0\u00bb\u00a0; \u00ab\u00a0la terre, c\u2019est d\u2019abord de la flotte\u00a0\u00bb\u00a0; \u00ab\u00a0nous, on est des popcorns \u00e0 c\u00f4t\u00e9\u00a0\u00bb\u00a0; \u00ab\u00a0c\u2019est bonnard, l\u2019eau\u00a0!\u00a0\u00bb).<\/p>\n<p>Au-del\u00e0 de ces quelques p\u00e9pites philosophiques, qui t\u00e9moignent autant de la d\u00e9tresse psychique de l\u2019auteur apr\u00e8s le drame que de la virtuosit\u00e9 de la mise en sc\u00e8ne, la pi\u00e8ce se r\u00e9v\u00e8le toutefois plus noire qu\u2019humoristique. Les rires des spectateurs gardaient mardi soir un accent de pudeur.<\/p>\n<p><strong>=&gt; \u00ab\u00a0L\u2019ann\u00e9e de la baleine\u00a0\u00bb d<\/strong><strong>e Jacques Michel et V\u00e9ronique Ros de la Grange <\/strong><strong>p<\/strong><strong>ar O\u00f9 sommes-nous\u00a0?<\/strong><\/p>\n<p style=\"text-align: right;\"><strong>Blaise Fasel<\/strong><\/p>\n<p><strong> <\/strong><\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"M7G0BAA=\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"cyvKLE4+vCIvtdhKIb+0LLWopLQoVaEoNTexqLD08MpUhRQ1ZQNjS+vSvFQF08MrclMVDq9MySzJzM9TyAVS6UAlAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcXLEYAgDAXAimLQGS9248BDOBA0H+vXvWxzv+1gNo8C8SWkV11yY7uRXWPwltaN18RVu2UIjGa8UA8FKcapTwBUQkA7Bgile59C4+8C+AM=\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNI1NNA1MlQwMrYyNLAysQAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"lVjLbiTHEbz7K8o6CDLQnMX6YEBaisLK8ho2ll5rV9a9prump+jqqmY9xpybf8M3QhdztFddBN1m\/sRfooisbs6QlCwbWCzZj6rKzIiMyOb5eHFuhotL7fp42KnijUqHnTNttsGr0RTV2Y2Jya7sYWca9Sra1B7uvEmqDX6jrW8VVn7TGnW4leXRDDpeF710Ro32cIcn3X\/++a9QsE0u0SzUX13wPXZTnfZJOa1a668LXh2wya6zcnRX1CuTst1op6zPJnrN+7jqjMrrw+7wTY6GFwhpGUrsF+fPkMn5s\/HiV+fjxf79\/vZPTm2VVhvr+6xwVqOuEIm2OCUjWes3lj8R+EpbbMbwc9TMV8IzyuH9l9lpn+11Mepd6ZTxqtVZI0ntF+ovoSTFooVhQE2ucN8mpWO0m8Mu8Tmj9HrD\/fV0sM5ZXxf8MuqIQ7Ffu9YuZIUq4KUOb8Vis\/Ky2AxLHVvJfn+7\/2Ghfo+gUBqFQFsuH4PtPUJUQLDFMsSdStxYw1jXumSjBhMbIIPkfGoj3sGTGZyTcjaKWTJp3WZTIvaxKRn1Z93iQVKXtl0b4qFLDyh\/FjtzwpNGgQgrPZhy838jql7jUJSUsSQFXGJAmon5tS2OM5E8ef47pYv67XMV2hyW2GLUSQ3BglzYrLM3U6q4lOW4kfgLkQzDiGpL2Av1UlJHxigC9gXB28CDk5FzwWxg67DPGLFHJ\/kPxjpnWAyULNoWNcTS+a6qdWyevDwV3+QnT3CGAFfLt1DvTEEBw8DEkGZmY+myv\/1E6joXFBQcAX8yKKxqTcb\/2nuy+LogJ+lr2Wg62Ad\/tgIb2jCugzdPa\/EFVwZLNYjWlGQGbA2I2xA9yo6QcdxYsmD4EM\/7zjnsNsyBKxfqy0KKIoOrEreNnBawOd99SK9GvbOdN1v10ll1aXDHmSUrdamjRVJGvdXdlW6UlbSjBkMHqo1j95SUrLC4I07o5OAREvs8qZOE02IWivOUgW5\/8Tev3nhzdqm9ercO\/1BYMSB3CsP5s+mdec2XrClkozWoA0XDGsTVSNL3QicRVIDq8WnqW4gNW1LHDuUNNt7r4DIwu3VBr8SFooK9ZitWHCtPliiv9YZC0GBxzPLgQeAD0NeV3pVDj9u3K5HPcfSNJl0G66ERqRH5AaosYSa7IE+W2690QpsTddwrS2db0BKo6xxKZjP41o4gIRom2YQdExPqApWn5sY00ghXURvyqbMzQicUSWgwp7PI5h+8MquVyQ2ygCiM0fgppecff\/z8l4X6VKSbx\/lL00GNNNtZlACBr9jiRAkMhbyBKn3dmF18IsGQ9PnpGMMm\/KSO6z4aFHGFjUuyIoiXYblVX9j27\/dlHg93WVwT3LJMHoVMhmqTJoegYoEwsVRlSZR10Z9N2CIASBP6lPXcsDjYSYQktnauSIBIsgBcU09ZV5+SrFeWzSp9HU1bqEB4g7kA5\/37rzSVCE1XyDVJL\/YBFjeiyS03BLQbnXj2JIqpRqwyiGwBzvHlSgM8Gnh7Cg+aDwjG9eEuircujub9s8T\/QbGFEODR7IRdtWCC7RHARlU7FlFAs6LweIrACzzFpmFSR7ClRzeaKZEZj9RqCCL6IulCN4fKKXOTqw1Mso0OfOCysCxGU\/EXYTQ3o7NkSfWUmSI8yGlx1\/sWQR9BFZHY2niubsRgg2N9qrho3weukScgBZoNVy8qSyfTH2zULaS+pOOEdRWs1GY6BUd0RUSRFgu4SlwCfcQLRAJp7tEnAqpIzHD4dhCqToKKaVDUgAYnqYpgYadjB8BgtgPBQ0io6\/79W+1WJBK16fBdRul8ot+jR9khVi+DsxOEkHT8s\/749v59j23AVu2FYaQRd0MPZlNnlW7yOcwa9FIiNJEmUUyi3hKDid4nI9znDBBnUE+h3d6CoEaGqeobVbcpQyiDYzIspEAnhAHbYtQ1BJZbvBa55MLp47DDKJNwLePzyHmiwBDqq+yXePh2Y+7b7jUE0eq8RmBzM7zWj2YCZvZfO+Rew9casE7OfUuVI9JVyFNtoJUwGQMByluHL\/qeDJQ9hg+cXbMjl9l4iaLui5kkjyX2nTlLdAMnMwDOGiB6RLJ1RHHCtBq+TBfy7ZANrmGvMiLix2Tb3JcAX1GhmVgZLPkv9Opk\/qBh2QHggP1U01n8im1kZhOsZlXAxfQ5UZ1r0lAJJ5szGEtXnswCYr38cDDqaNhSJ+w2QLfBeVrwk8EAQwSUIHIWBuBSeEtbYY8wzIrUNINl6QxEBtvqaSglWyQ1+ckj0yJzMPG4wqaJFHC1RgEwPqA0X4VyJZNq3OY1ppamit0ZnKCaZyeIE+LecoPqtwh1bapjVvmeWTjpJyJxgXJdJsdZqDeYBJyrXsw80X8cx0kYMhE4YwuHAMcwFsfhqalet5tnklZDaOvoKx8wFgW0pgqvbWXKX2pg\/xFBOPwbKGglcwbnVxZ9f\/tCZiO5iYdLlPH0PpwqFQjVkiAXFC\/KF1FAd8j63\/DoRCWZfSvwTA5rwDmJZZDOiAHcYpIbqdZH\/ysr5kAo0fhkQQXaafKjREHnYjcRYQWpzOZ0jYdYNGpqNhlhw8iRO0kDQ6UOu9PX5405OcLBqknI58GvJdV7Zr8sZ51x2EPiTWw1V2EHOMgDv6ytCwnTsdChTimzFhiZ3PORwfKJSt1XY9q262mcqz1XRAo1fOyOlq+6qMVoZ53Cp3AuVII6\/LvH8tactEgSn8eI6MSlslnRmkfHj25Sv\/o3JuZAL2QY9Zsx4lkdRWTqnD4gafJamu5k+AZddNuamtoIzYaVPdaDTz\/s84tfHMhVd9SD6af5idnza8gBKM+CvA3zIPFHWBEU4MkG45M76NA3h++nPzickS\/7288eC5FKeevMpx9kzCtnUMref4Ka9Ov84oP7jT53MuC90sm4J0I2v6QePvkR\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Malgr\u00e9 une s\u00e9lection peu diversifi\u00e9e, Frisc\u00e8nes convainc gr\u00e2ce \u00e0 une remarquable pi\u00e8ce d\u2019ouverture. Plong\u00e9e dans la cinqui\u00e8me \u00e9dition du Festival international de th\u00e9\u00e2tre de Fribourg.<\/div>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2272,160,29],"tags":[401,443,477,730],"class_list":["post-499","post","type-post","status-publish","format-standard","hentry","category-archives","category-culture","category-news","tag-friscenes","tag-jacques-michel","tag-lannee-de-la-baleine","tag-veronique-ros"],"views":1463,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=499"}],"version-history":[{"count":1,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/499\/revisions"}],"predecessor-version":[{"id":12846,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/499\/revisions\/12846"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}