{"id":6801,"date":"2017-05-18T14:00:08","date_gmt":"2017-05-18T12:00:08","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=6801\/"},"modified":"2017-10-10T11:22:35","modified_gmt":"2017-10-10T09:22:35","slug":"le-petit-guide-du-yoga-universitaire","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2017\/05\/le-petit-guide-du-yoga-universitaire\/","title":{"rendered":"Le petit guide du yoga universitaire"},"content":{"rendered":"<h1><strong>Le yoga : tout le monde conna\u00eet ce sport qui fait fureur depuis quelques ann\u00e9es. Ce qu\u2019on ne sait pas forc\u00e9ment, c\u2019est que ce sport se d\u00e9cline en une multitude de sous-cat\u00e9gories parfois tr\u00e8s diff\u00e9rentes. Spectrum vous invite \u00e0 un tour de l\u2019offre propos\u00e9e par l\u2019Universit\u00e9.<\/strong><\/h1>\n<p class=\"dropcap dropcap-borders\">Le yoga trouve ses origines dans l\u2019hindouisme. Depuis plusieurs ann\u00e9es, ce sport rencontre un vif succ\u00e8s en Occident. Si, dans votre esprit, il se destine uniquement \u00e0 des jeunes femmes en leggings buvant des smoothies verts, sachez qu\u2019il existe de nombreuses variantes. Rien qu\u2019\u00e0 l\u2019Universit\u00e9, quatre cours diff\u00e9rents sont propos\u00e9s.<\/p>\n<h2><strong>Le yoga \u00ab traditionnel \u00bb <\/strong><\/h2>\n<p>Ce cours de yoga classique place la respiration au c\u0153ur de l\u2019exercice. Chaque posture doit \u00eatre maintenue de fa\u00e7on statique pendant un certain nombre de respirations. La m\u00e9ditation joue \u00e9galement un grand r\u00f4le : entre chaque pose, un temps y est consacr\u00e9. Durant ces interm\u00e8des, il s\u2019agit de ne penser \u00e0 rien, tout en restant concentr\u00e9 sur son souffle. Un exercice plus difficile qu\u2019il n\u2019y para\u00eet ! Toute la s\u00e9ance se d\u00e9roule les yeux ferm\u00e9s, incitant \u00e0 ne pas se comparer aux autres. On en ressort d\u00e9tendu : le cours offre une coupure avec l\u2019effervescence du quotidien. Et m\u00eame si l\u2019on ne s\u2019en rend pas forc\u00e9ment compte, les muscles travaillent aussi.<\/p>\n<p style=\"text-align: right;\"><strong>\u263a Id\u00e9al si : vous souhaitez prendre une pause de l\u2019agitation de la semaine.<\/strong><\/p>\n<h2><strong>L\u2019ashtanga yoga <\/strong><\/h2>\n<p>Ici, ce que l\u2019on remarque tout de suite, c\u2019est le silence. Sans musique, au seul son des respirations, les sportifs commencent par une m\u00e9ditation assez longue. Celle-ci demande un r\u00e9el effort de concentration et permet de se brancher en mode \u00ab yoga \u00bb. Puis, les postures sont encha\u00een\u00e9es de fa\u00e7on calme. L\u2019accent est mis sur la souplesse, avec la possibilit\u00e9 de s\u2019aider d\u2019une sangle pour s\u2019\u00e9tirer au maximum, par exemple en attrapant son pied avec. Le guidage par la parole prend moins d\u2019importance que dans les autres cours, mais le professeur corrige volontiers les postures des \u00e9l\u00e8ves.<\/p>\n<p style=\"text-align: right;\"><strong>\u263a Id\u00e9al si : vous d\u00e9sirez vous assouplir tout en travaillant vos muscles.<\/strong><\/p>\n<p><a href=\"https:\/\/student.unifr.ch\/spectrum\/2017\/05\/le-petit-guide-du-yoga-universitaire\/14_societe\/\" rel=\"attachment wp-att-6802\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6802\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2017\/05\/14_Soci\u00e9t\u00e9.jpg\" alt=\"\" width=\"3879\" height=\"1640\" \/><\/a><\/p>\n<h2><strong>Le yoga ow <\/strong><\/h2>\n<p>Dans ce cours, les diff\u00e9rentes postures s\u2019encha\u00eenent de fa\u00e7on fluide, le but \u00e9tant de faire circuler l\u2019\u00e9nergie dans tout le corps. Les mouvements sont assez libres, avec la possibilit\u00e9 de bouger un peu dans chaque posture pour se sentir \u00e0 l\u2019aise. Le tout est continuellement accompagn\u00e9 par les paroles de l\u2019instructrice, qui met l\u2019accent sur les ondes positives et l\u2019accord avec soi-m\u00eame. Entre deux postures, on peut s\u2019agiter pour d\u00e9tendre les muscles et lib\u00e9rer ses \u00e9nergies. L\u2019objectif est de chasser de notre esprit ce qui nous emp\u00eache de nous d\u00e9tendre physiquement. Le ma\u00eetre mot est la positive attitude.<\/p>\n<p style=\"text-align: right;\"><strong>\u263a Id\u00e9al si : vous avez besoin d\u2019un coup de boost au moral !<\/strong><\/p>\n<h2><strong>Le power yoga <\/strong><\/h2>\n<p>Le programme de l\u2019uni donne le ton : contrairement aux autres cours, le power yoga n\u2019est pas class\u00e9 dans la cat\u00e9gorie bien-\u00eatre, mais dans la cat\u00e9gorie fitness. Dans ce cours, les postures s\u2019encha\u00eenent de fa\u00e7on tr\u00e8s dynamique. Tous les muscles sont travaill\u00e9s \u00e0 tour de r\u00f4le, et l\u2019effort est tr\u00e8s prenant. Malgr\u00e9 l\u2019intensit\u00e9 des exercices, le but est de rester d\u00e9tendu, de conserver son calme int\u00e9rieur. La voix du professeur guide les mouvements, et incite \u00e0 se donner au maximum. Attention aux courbatures le lendemain !<\/p>\n<p style=\"text-align: right;\"><strong>\u263a Id\u00e9al si : vous voulez tester le yoga mais que le c\u00f4t\u00e9 trop calme vous laisse sceptique.<\/strong><\/p>\n<p>Vous l\u2019aurez compris, le yoga est un sport aux multiples facettes. Cependant, toutes ces formes ont un point commun : lorsqu\u2019on sort du cours, on se sent bien, quelle qu\u2019ait \u00e9t\u00e9 notre humeur en arrivant.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><strong><span class=\"credits\">Cr\u00e9dit photo: W.C Colares<\/span><\/strong><\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"M7MwMAQA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"80lVKEgtySxRSC\/NTElVSClVqMxPT1QozcssSy0qzixJzCxKBQA=\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcthCoAgDAbQE81ZEEG3EV05KJP5Lej29f6\/CvSxMQ94kYbgTXcLufLokmF+8RynlePCp1AXKOhwLULF6b2PRH94xIYiqQl\/\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNc1MNU1tFAwNLEyMLUysAAA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"pVjLjhvHFd3nK8pcZEUOJcXxYzwzQDDKwoACB3EcL41idXWzhOqudj2omVn5H7JJdtlFVICsvIp3Jvwj\/pKcc6ubw9EjcCBAAodkV9W955577ilebB9fXaQcw9BdPbPqNnRanascSlbeqj4MjVUmDIM+\/DsrY1UaQ8zq2+JUq11WbYm2RNXYsbiEj63H\/6T0MBz2Np2pa4sPf\/7u72FQAxZzyaiTakM0h31vh7xUBl\/bxD3t\/QHJquawN95hlR1UwUtffHa5IB78S6GkldH5sO9CdDhx1LENCCHHw8ukGte2h33E\/gziy9GaHEuvdlil3LBz2arDP7ArE2X0yjPGto1WjTGMISF6bimffzW4nY3J4bCzi\/WE1cUawP3qYlTG65QuFw2WGT2q6XW1CbHBosURVCwrOwSOWBFxh8QQph6SHLF1QxOAYG\/P1NOK5ehLcsD2CObyHh0khppkRIsUdq5VqRjDvAHVF8a4BokjbbesJ+wCH7VpjA54Oy\/oAnKCWwYH4FkJIoJP1XNbGFtr+97Kjt52CLdLalN2Gs\/xodSHkLcEHtBkxJa02dq7WmycYG9cylKpIfQbcIR573R0upbkTw4by8M49TWQl\/hCM2ITmP59LXEssj5WKKEaI2qwffIGg3\/8F\/DWjcsO1LVe\/fiDOq3cE1bu6vp4wrRKSkk4AL4G2F4D6TS6qLmP0kWZn\/56zxd7Y6NxBiW73mpZFVJGP6gmgOaHV0yh1w4JD0WgaPXhn9gnZewnz9uhIaAoogGKeHRCiw+fnAy8nmnVH\/ZIqIbyPGA5uK99LR126KIeGhUP36Ntz1E2AfAYl10K220\/JnWr2G4gEGoWwWn1tESGYSybI9vYH1425BuZgjx157JUUiJONpIpaLphWXUClUSwWbYIg+HRhz0oGVkudmrbeoD01aBmxITcUlhnnLdH1gx4uWXfidp8oP6M7aUMqLYeSH+RBXQSFnmEe2vLDZiKiPeMdzBOwkB8DBZCk1jjHjsiao1ndQEuwPOLYQo7sZ+wJ4rUFADnZ1JUNaDw4P3IsuqdNbXwLY7c2YRUEROWfVtCdg0QOVO\/zyjUqx6huioqVfi4iuehRA\/1T8LLKA\/T6UsyfAV3d9p5z+91AScnpo\/gzq23l4tsb\/JKe9cN56hEt82fLY498PPf\/qM+R0baM4bzKnqowhbiiw4dGcSU2YjN7Uxnlrmyq6mYW5LXnkre693GVWkLyNE80kFvNtnnxolwkYcTHhEbR74X9lDMiyMC8yDwBM8TW2gY9QuwsF+W7MBkixdeUYVOe6QiKPro2kRYeytkFB2XAXLSQGh0YOERamH\/WmC9Mg6b9poTD70CDkM4UGohiD1Su6632Ba0szV+qzboIAhgJKv6gM+gQFWJfjhTf4Se1\/AmhZiEDPFtwXRR9xN9MNpzDgi6RjIgKj1mAnuKlQEhsRubunJSc+PkNs5TPyUkLsYcgFjhryKzd+g8tYB9Sd3dZ1e7AiJ14\/rSLwUp9GiP3ZmIzkh3ZEMR8NHZRs5DaFZ1xTW6m4ak5kvg7sLwPjhUjQe7nvWQ1mXB67yjP5A2rJ22pEjyYwp7y7QQoQkRvLYgL2qUHSbDQ\/xY\/cPeH16iDd+7OfA+AYu7+g7UIL4uHtVtbkcisQvHNn29M8arC6220baXi23OYzpf4\/sisxhTto1nZrtOkxVZP3n0+OP1o9+uwbvRwtesCKhdNWVF2qzKPA41Als\/\/vCbFIyz2a4XIL2\/XKA0GLgiIC\/GFd6tPvrk0RPk6foOtMboG7rLhdd3twtgZUJ9r9PtYBazZRGIyC+wILk7u2qL99zO9ahs3VClaH5JOlhFR4Iv18AO56djhgj+SwQPvmHWPB+7hdI+Xy4W6oVr8vZy8ZtPPv50obaWlbpcPP7ow0cLtQak+uqd4z28eIvSPCW5jJ1JRbqc2sCT3hMxrq1nxc\/Mndd6FoFr4XUwRvZZz987jlMXDSZPdYWH\/WBj5yZSz4YZvB05rinm9Hv9vW2ZJMdhvqd3N+4mlM5Sr6Avpe5tHrqL2sFUHTSGzGJRb5esNGYlbR3wcHiF0iY8gZZwEnaQm9q11TUHX8WHm6BtUU1UFDN6KSafCufvhUgEiA52aCqicFg7usTjU7C9NbcU3EomIWaimJGGs3ouwlIFyTAfHQaSlsymWRztg4nIA9yGtYxioWf0U9XJsHkOIsIIM\/FGjE+iURH\/eW9+6yBy+Ax9Dpk7vIJm14eqDEwnj9vbNNtiAbWnIaGdCxXbWjhJniop15L3liHAdqc2FsANk2qL9aisAG4i1SFizQf\/YyaTIC+Q+jvm8TORWZhFjMe57GhneFYYZTI4ozDnQp5I0lfqHJ3TfXedHjNMk5vWRsSFXBath6k+XtLUBg5pJb540vy3PNO6jNsHyvqWdv4FHTxd\/24H3bOAZ7SQ6QGTpBdnRYfws4HmW6C45+XM5mn2M7G6LaebJiP+oH1Hj1t7BqRJU\/umo8VNRxWZKEmLbI\/0LsvJUyQ6yeqUZe7TgYPmvPmJ698Fd0OLeTIbZVLUnI4SI0GL\/5WbLV0dC3o63s\/U7zIFul5lbgTYja6Aip0eGnF8ZNf7EXlHf36H24Zk7CfRloqLDUTih+8JGPYYp7RloccjVDZjR7khvTlh\/yKPUTIKBzYVLVZzVQ8h2Oibek1mlvKrAd0SGGJszvVHienmVS8wZLUVT96LtMkOI7pQzHlf2A8+xDT\/kFGvDGVmJj+paiwEX8qvIPOlhj94yOSbdGhbepaQ5goGh9fpWTaufj1s0vjZ\/4H9RYI3m4e5iRbmNi2urqPYXGhYyOFcfX12ra6DxwUoAUwsuHqI6X8B\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Le yoga : tout le monde conna\u00eet ce sport qui fait fureur depuis quelques ann\u00e9es. Ce qu\u2019on ne sait pas forc\u00e9ment, c\u2019est que ce&hellip;<\/div>\n","protected":false},"author":13,"featured_media":6802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[113,1220,119],"tags":[1203,1271,857,1270,744],"class_list":["post-6801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-campus","category-societe","category-vie-universitaire","tag-campus","tag-societe","tag-sport","tag-sportuni","tag-yoga"],"views":2621,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/6801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=6801"}],"version-history":[{"count":9,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/6801\/revisions"}],"predecessor-version":[{"id":7294,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/6801\/revisions\/7294"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/6802"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=6801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=6801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=6801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}