{"id":8231,"date":"2018-03-05T15:10:42","date_gmt":"2018-03-05T14:10:42","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=8231"},"modified":"2018-03-05T15:10:42","modified_gmt":"2018-03-05T14:10:42","slug":"big-data-clics-valent-de-lor","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2018\/03\/big-data-clics-valent-de-lor\/","title":{"rendered":"Big data &#8211; tes clics valent de l\u2019or"},"content":{"rendered":"<h1>Qu\u2019est-ce-que les achats en ligne et les \u00ab\u00a0likes\u00a0\u00bb Facebook ont en commun\u00a0? Ils permettent de collecter des donn\u00e9es sur les utilisateurs. Mais qu\u2019en est-il au juste du pouvoir que le big data implique dans le domaine des technologies digitales\u00a0?<\/h1>\n<p>Le \u00ab\u00a0big data\u00a0\u00bb n\u2019est pas un concept d\u00e9fini scientifiquement, mais plut\u00f4t une formule \u00e0 la mode. Ramon Reichert, l\u2019\u00e9diteur du livre \u00ab\u00a0Big Data\u00a0\u00bb, estime qu\u2019il s\u2019agit d\u2019un concept fourre-tout du domaine des technologies digitales. D\u2019apr\u00e8s lui, ces derni\u00e8res ne transmettent plus des informations neutres. Elles sont d\u00e9sormais actrices et s\u2019imbriquent dans des th\u00e8mes politiques et soci\u00e9taux. Wolfie Christl, cofondateur de l\u2019institut de recherche \u00ab\u00a0Cracked Labs\u00a0\u00bb, explique que le big data repr\u00e9sente de telles quantit\u00e9s d\u2019informations, qu\u2019elles sont \u00e0 la fois trop complexes, trop nombreuses et trop \u00e9ph\u00e9m\u00e8res pour qu\u2019elles soient analysables avec des m\u00e9thodes conventionnelles.<\/p>\n<p>Le big data est un mot dont le sens d\u00e9pend du contexte. Malgr\u00e9 cela et ce qui est certain, c\u2019est que les donn\u00e9es sont devenues l\u2019or du vingt-et-uni\u00e8me si\u00e8cle. En effet, les grandes banques de donn\u00e9es conf\u00e8rent un \u00e9norme pouvoir \u00e0 des entreprises comme Google.<\/p>\n<h2>Cookies et compagnie<\/h2>\n<p>Google agit en fonction de son ancienne devise \u00ab\u00a0Don\u2019t be evil\u00a0\u00bb. Depuis 2015, Google est une filiale de la soci\u00e9t\u00e9 <i>Alphabet<\/i>. Leur devise est similaire\u00a0: \u00ab\u00a0Do the right thing\u00a0\u00bb. Google explique qu\u2019avec la collecte des donn\u00e9es, leurs services se sont am\u00e9lior\u00e9s, la publicit\u00e9 est devenue plus pertinente et les utilisatrices et utilisateurs sont d\u00e9sormais mieux prot\u00e9g\u00e9s des escroqueries. La mani\u00e8re dont Google est \u00e0 m\u00eame d\u2019utiliser les donn\u00e9es peut m\u00eame \u00eatre individuellement r\u00e9gl\u00e9e par les consommatrices et les consommateurs. L\u2019on peut aussi, entre autre, faire des r\u00e9glages relatifs aux cookies, ces petits fichiers contenant des informations quant aux visites de sites internet. Les cookies sont la raison pour laquelle, par exemple, les m\u00eames chaussures que vous aviez aper\u00e7ues auparavant sur un site de shopping online apparaissent \u00e0 pr\u00e9sent sur votre \u00e9cran. Gr\u00e2ce \u00e0 la visite du site pr\u00e9c\u00e9demment visit\u00e9, Google pourra d\u00e8s lors afficher des insertions publicitaires personnalis\u00e9es sur le site que vous consultez. Ces derni\u00e8res sont toutefois soumises \u00e0 des limitations. Par exemple, les annonceurs n\u2019ont pas le droit de cibler un public sur la base d\u2019informations sensibles &#8211; dont font notamment partie les donn\u00e9es relatives \u00e0 la sant\u00e9 et \u00e0 la religion. Google assure qu\u2019il n\u2019y a jamais de transmission de donn\u00e9es personnelles (comme les courriels) aux publishers sans que la personne concern\u00e9e ait express\u00e9ment donn\u00e9 son accord. Les publishers sont des personnes qui proposent des plateformes destin\u00e9es \u00e0 la publicit\u00e9 des annonceurs. En outre, les annonceurs ne conservent pas les donn\u00e9es personnelles.<\/p>\n<h2>Une psychologie\u00a0des donn\u00e9es<\/h2>\n<p>Les donn\u00e9es peuvent aussi \u00eatre utilis\u00e9es dans un contexte politique. La compagnie <i>Cambridge Analytica<\/i> se base sur les m\u00e9thodes de la psychom\u00e9trie, la psychologie des donn\u00e9es. La compagnie analyse les personnalit\u00e9s individuelles \u00e0 l\u2019aide du mod\u00e8le OCEAN. Il s\u2019agit d\u2019un acronyme compos\u00e9 des cinq \u00e9l\u00e9ments principaux de ce mod\u00e8le de personnalit\u00e9\u00a0: Openness, Conscientiousness, Extraversion, Agreeableness et Neuroticism. Via cette analyse, la compagnie pr\u00e9sente aux utilisateurs des publicit\u00e9s sur mesure. Alexander Nix, CEO de Cambridge Analytica, d\u00e9finit le big data comme la plus grande accumulation possible de points de donn\u00e9es. Gr\u00e2ce \u00e0 ce syst\u00e8me, il est possible de cibler des gens sp\u00e9cifiquement \u00e0 partir de leur profil psychographique. Cette m\u00e9thode se diff\u00e9rencie de la publicit\u00e9 de masse traditionnelle, qui se base sur des indications g\u00e9ographiques et d\u00e9mographiques. Les points de donn\u00e9es sont relev\u00e9s quand on regarde la t\u00e9l\u00e9vision, ou lorsque l\u2019on surfe sur internet. Sur internet, la fa\u00e7on dont ces points de donn\u00e9es sont collect\u00e9s est peu claire &#8211; Google \u00e9tant le moteur de recherche le plus utilis\u00e9, et ne vendant pas les donn\u00e9es qu\u2019il r\u00e9colte. Selon la <i>BBC<\/i>, Cambridge Analytica a collabor\u00e9 avec Donald Trump, et a \u00e9galement travaill\u00e9 sur la campagne en faveur du Brexit. Cependant, l\u2019influence des analyses d\u00e9velopp\u00e9es gr\u00e2ce au big data, ainsi que l\u2019utilisation de ces derni\u00e8res \u00e0 des fins politiques, est controvers\u00e9e.<\/p>\n<p>Nous sommes \u00e0 une \u00e9poque o\u00f9 le monde digital est devenu \u00e0 ce point important, qu\u2019il est tr\u00e8s difficile de s\u2019en d\u00e9tacher, et o\u00f9 l\u2019on dit parfois de l\u2019acc\u00e8s \u00e0 internet qu\u2019il devrait \u00eatre un droit humain. Proposons une r\u00e8gle g\u00e9n\u00e9rale de ce qu\u2019on poste sur le net\u00a0: il s\u2019agit de g\u00e9rer les contenus comme des cartes postales. Personne ne les lit, mais tout le monde est susceptible de le faire. En soi, c\u2019est la mise en r\u00e9seau des donn\u00e9es qui vaut de l\u2019or, et non les donn\u00e9es en elles-m\u00eames. La fa\u00e7on dont ces r\u00e9seaux seront utilis\u00e9s dans le futur reste ouverte. Ce qui est s\u00fbr, c\u2019est qu\u2019avec la r\u00e9volution digitale, les discussions relatives \u00e0 la protection des donn\u00e9es et \u00e0 la sph\u00e8re priv\u00e9e seront de plus en plus pr\u00e9sentes. Si ce n\u2019\u00e9tait pas le cas, la ru\u00e9e vers l\u2019or des donn\u00e9es aurait de bonnes chances de nous faire retourner au temps du Far West.<\/p>\n<p class=\"western\" lang=\"fr-FR\" align=\"right\"><b>Auteur\u00a0: Vivien Stringer<br \/>\nTraducteur\u00a0: Arthur Rossier<\/b><\/p>\n<h6 lang=\"fr-FR\" align=\"right\">Cr\u00e9dits photo:\u00a0\u00a9 Pixabay<\/h6>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"szAyNgQA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c8pMV0hJLElUUFO2MDI0tFYoSS1WSM7JTC5WKEvMSc0rUUhJVch51DAzvwgA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcpBDoAgDATAF5VFvRh\/gwWhCSKhxffrnKeYdT0AtRlTMzebXMNxgfbENuaN1S87\/IZTMsVggbgKK72h\/p9iovoMfA==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C8ovLs5MLVJwLCrJKC0CAA==\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNA1MNY1MFUwNLUyMLYyMQIA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"hVhNbxzHEb3rVzQUIEiAJRUJiBE4FA2KkoIAjKRIjn3unendbWtmetTdsyZ9yt\/IjcjFWueaS+Ab55\/kl+S9qp7dWUpwDiSXO9Pd9fHq1as+2zw+\/+vw37\/\/w6V8UrmTD4MzjUvGVhubk3Gdafy6c8Zl+fruX3e3jX\/v0t3t3c\/mpa3cMoT3JnSZr1ahbYfu7vYr8+cmmd7F1uXs8Kx2eNY0rsou4p9k6tB14w4f0hBl4yH7xieb3RDTqfmL9cl8ELM6Q8t8Y+xgvhtSdqYeTB+GbfDRqLVm6demttka3\/aN55e17RKf1KG1HubzzOyqTReasPY0wK99tg0d+ersEYLw4Kw\/v3Li4LSd+NhpbExvYSRd7CrXw6Nxt\/KdN6nycNCveGqLTwvT0va+GfL474wVzqxCbAfYMt6axpo21O7UvLVt6Mxb56uNi1jU4JRxV3v6Twcbv41qzDMY87wYs2AsfOs0NIhJwh8LR0yNDzPrVmGI0Z3kMGTu9v+jcGqec6s+jh8Rt8EvTMXHLnZ+\/BjxEatzRFCnjMLBJPv5jv7Z7EPHt4YcuduLhklNxAUilfiGJ6hy9NwYaKLpvl1GBo5vMWFi32b82OJvHxqf+VDfDpUfd9kO16fm29CsvDOXm+hTbmBpWIWutho6J6H0HeKUBwFedIwxfiScl9FW711truwylZBeF8zcB1N0CMcuwTpGDoETnz4MFvnOeCBBn7u\/KJA9+K4pXwX4nmPoWSB9464dXpX\/u4AIuCGpk\/LVuOs3467VqAPn8XhTos3YzjY3yS6lULeuksC1iM8m8BNQsCUoUWOy7PTsUT\/he+8dMQ3EtCGzGFndBq4mpqt3XU3YYJ\/srrNjPTZrxAKggDuwtGK0vOxRAb8AF9JQCmVikEOJCwocTGIymZ4gGN\/6bp1PXD4ZCDKgOuFP1eC4Fyj61cqxLrBiDdzRraXtBA61O+wNE1cMVSfOjLsOyXB7ekD4uRBPmUufZEGLF\/4UwhoHaVw2T84vQWJek8AU2XXnHVjhiURNXzZSZ6AjgK1ibGkHXEMySAFSXVscISh7Hkgb2SxBnFvfEGioMNcPAMKT3z3+\/aJYULIAjgD72UZwhggXtCPgZ\/78ouk3duny2SN\/fmquFOVyEhcn3\/rG+ujubr8sR6OEgHq\/3gBRG8RYT58OPKCdBU\/w4MCJnI+4mdEHGwMWcStVm5zm0gJqjQ8sjgVX98Oy8RVrQkwqqVaKQBPIoB7WUGkhE9PvmWBO\/Z9QRuvdcG36GLD7WoqOi1IVA5yInlxzBVK1ylMK5VlsgYB2\/AkZF4KUg1w8hmcPziovjT8BKGC02m99PbB2SOkGjq4bvIseoGuBugQczXw4+lZ72BWB3un2dkgJnCpAxD\/4vTArZk3ckf3tmp9QX2gmqGo4XSkolYp7B9JJwEm18S4mrc3OSmXdI2FhKNkBKEFHkYrRDx6LYucycZSmAzTmyGNEwGkxSaexHyQAC3EalEXi0nqUWGH1hl4NUTjRmW0YSEbe\/WAskj7+yFK1A1bbLe1ho0eJ0g6xZxP6HuCEdGjYmmzPN30i3TJrE\/XKum1g3MZdBSYAkuP4z2pqp+oi6UT+clmFRupayZw8HXf7cqNr0QJf7HIBYbSrlbTgEsVEtDKGE6SZIwExAgPS9WkmWvTEve9M\/9Bk98OpuTzunRJf9mInnSCFoRUuKvTUoISz5u7UvLkfbdt1bOqsjU4QpVKEXBGDV2nl0Qkkumq22mdBmMl90qSE5b20jl\/\/6g9PHj\/+oxbNir+6kK1GDtnI\/h6RKzq3ajlpCnllzU99Ds+hJ0K3Jxsr+NirFdp\/Y6z5zkpp15OkQNYLn86KUiKuXe83StpaY0igd036rQBc\/E0bFkSynQKRhFRWqx6K3NJYsvd1j3wgh+KiHqYcXlUh1loV8z1Dqa9pwyRtD2zUh+SmZwiKY3wl6dAd6oGGZEaN9VEypckFZYL7aRa7ybpun+z0+dAcOtjfsKpPN9VGpd3d7ZzJ963s6h7xyQlCToX7lCLlsSgy1ZSiAg6KTCh33yfZoy4tlVy9duaC0iT7yrJdsWMICCeVf9Ao2ujUYn6LpC4O34gPR83o3pmqgBQTh+oUVTanb00DG52vhSSgvsePQObryxcXr04xpnwioS1aS3fTOjkspJK4yncfQECNQgdnRo+23xODLEC33xj\/HdnDtvy6pz5IYPJL5FUHBjCGfvXiGkWwxRKUwMJcrKNzFHZ8yMp6BUgExNOn9tR84xEDCvDJ\/4U27ykqB71Kw476au3SDIxKYUAsyvPUXECSUmJF88pfw8gXr+nGZ3K6mMaefCSUS3la7fgq11hSA8YeIR1AJwnnSHiCZwRn1T6ndPxONylTDy4MOENGr9nqwnV0Z025mnoQ\/mH8ktZB6tJRgGIJ1Qp1VYAF4\/qNYvhSAjkhklCt\/Wo17iAmKz8psaP6hcxAfyJpYVCb1PVCKGEOdG0lNeKlhAvZcjhXkoootrOvCu98EhflH7Cq2zJl7Os1+iW+Wduo9mXBJNsc0RMG6WrCgqo+YM9KrTq0\/nez\/wRAKzv+SP7ladUvWFJUIm2RtDiMCKI9952k8D4nNR0pMF6UsewwhjVFGk5cs2BIQF8go9p+jvGm\/sHeHhrOI+9cA4NhOrjn2bNLcs3ic4A1Km3tkmJVRyVIc9vU5us4tL2cbGHu2hapx1q0vmnYF7SJVlaqy4n0xw46nz+L7tpngqhXqxdl7lw1GGcrV9heilRmqi0s7ntxZ61gt8O+ghboTmjKZkrcVLmlK94bxYtsQB3Op+SFTmPIUwykExy1n\/teUZ9Qm+pqDhyY8qigTRj\/o3lizZbrgJmKLyUpiODtSohZnJ1SwjezXBqweFApWqVJb25qAoFpl0DLUQpL1A\/LVORQGdnBF9wG503Y3B8CUyLbd2lRXVE+m4G3GpBM0o6DdCvgbPxICKLoAJ5YZqqqiBClojw1JKAuk6CPblJkbXR7pQ+ZPUxzo7QC0IsUSSo3J28mtdFpP0JGyi2Q3L\/soyvj2pB4QTOxGX7LGCBqAMP9YYrmTZHMeJ0RUgda6uOa8GZr9YZDR2otI5bF\/D3en7ERnqhqlzZ6v97LAdec9PjdVJhpf422GjICBvAhdJitoZKFQPeXAGn8Oc5vAGajJTbfhmZQLJfrJpU8tU\/VINLvU2nJgc9NY\/bcnUlrpn4jAx8a8ZbyrpheF26B2zp+Th0Rnr\/zxEEnN23Z+r2OrqyOsXHgRqyd\/SXF\/Gg7CAhxwlKlIAagTksTYcdZOtBFh6wDvpEFniHkE\/niJWT9t4jNVJIkzpSePvyeIY3dQ5zfrZ8+XMWTl28fGss716cPZYZ\/eH62PL8YSKOE6jfQNnDuHQRTt3bxbBnNo\/MHX6MlDdX0zkXMG6TrLdsmXnm0PC8y8YtfOuYyygUkYrYJOXx5d3u3M2\/8tV3aG+jHL84f\/A8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Qu\u2019est-ce-que les achats en ligne et les \u00ab\u00a0likes\u00a0\u00bb Facebook ont en commun\u00a0? Ils permettent de collecter des donn\u00e9es sur les utilisateurs. Mais qu\u2019en est-il&hellip;<\/div>\n","protected":false},"author":22,"featured_media":8239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[1220],"tags":[1436,1457],"class_list":["post-8231","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe","tag-big-data","tag-n1-2018"],"views":1564,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/8231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=8231"}],"version-history":[{"count":8,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/8231\/revisions"}],"predecessor-version":[{"id":8245,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/8231\/revisions\/8245"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/8239"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=8231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=8231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=8231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}