{"id":850,"date":"2011-03-07T07:00:11","date_gmt":"2011-03-07T05:00:11","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=329"},"modified":"2021-05-09T12:59:36","modified_gmt":"2021-05-09T10:59:36","slug":"linfo-par-et-pour-les-etudiants","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2011\/03\/linfo-par-et-pour-les-etudiants\/","title":{"rendered":"L\u2019info par et pour les \u00e9tudiants"},"content":{"rendered":"<p><strong>Unicam, Unimix et Spectrum: les points communs entre ces trois m\u00e9dias? Ils sont fribourgeois, bilingues et \u00e0 100% g\u00e9r\u00e9s par des \u00e9tudiants.<\/strong><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2011\/03\/1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-335\" title=\"1\" src=\"http:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2011\/03\/1-300x144.jpg\" alt=\"1\" width=\"300\" height=\"144\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2011\/03\/1-300x144.jpg 300w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2011\/03\/1-335x160.jpg 335w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2011\/03\/1.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Si bon nombre d\u2019universit\u00e9s suisses publient leur propre journal estudiantin, rares sont celles qui en plus, proposent une \u00e9mission radio et t\u00e9l\u00e9 hebdomadaire. En cela, l\u2019Universit\u00e9 de Fribourg se d\u00e9marque clairement dans le paysage suisse. Vous connaissez sans doute d\u00e9j\u00e0 un peu le Spectrum \u2013 le magazine que vous tenez \u00e0 l\u2019instant entre vos mains \u2013 mais que savez-vous d\u2019Unicam et Unimix, les cha\u00eenes de t\u00e9l\u00e9 et radio des \u00e9tudiants fribourgeois?<\/p>\n<p><strong>Des m\u00e9dias ind\u00e9pendants<\/strong><\/p>\n<p>Tout d\u2019abord, il faut savoir que ces trois m\u00e9dias sont autonomes. Cela signifie qu\u2019ils jouissent d\u2019une grande libert\u00e9 r\u00e9dactionnelle et ne sont pas \u00e0 la solde de l\u2019Universit\u00e9 de Fribourg, ni de l\u2019AGEF, qui pourtant leur verse une subvention plus ou moins substantielle. C\u2019est peut-\u00eatre cette libert\u00e9 qui pousse les \u00e9tudiants engag\u00e9s dans ces m\u00e9dias \u00e0\u00a0 tendre vers un maximum de professionnalisme, tant par le choix des sujets que dans leur traitement.<\/p>\n<p>Mais s\u2019ils adoptent un comportement pro, il ne faut pas croire pour autant que les journalistes, producteurs et autres animateurs se pr\u00e9tendent infaillibles. Car il ne faut pas oublier que ces m\u00e9dias fonctionnent gr\u00e2ce \u00e0 des \u00e9tudiants, b\u00e9n\u00e9voles pour la plupart, et souvent autodidactes dans leurs domaines respectifs. Tant Unimix et Unicam que le Spectrum sont en cela le lieu id\u00e9al pour une premi\u00e8re exp\u00e9rience dans les m\u00e9dias. Les d\u00e9butants peuvent s\u2019y lancer: ils seront form\u00e9s et encadr\u00e9s jusqu\u2019\u00e0 ce qu\u2019ils se sentent suffisamment \u00e0 l\u2019aise pour \u00e9voluer sans filet.<\/p>\n<p><strong>Unicam sur le net&#8230;<\/strong><\/p>\n<p>Laissons ici votre magazine favori pour nous attarder sur ses cousins radio et t\u00e9l\u00e9visuels. Pour Daniel Monney, vice-pr\u00e9sident du comit\u00e9 d\u2019Unicam, bilinguisme signifie unit\u00e9. C\u2019est la raison pour laquelle la t\u00e9l\u00e9 \u00e9tudiante est organis\u00e9e autour d\u2019une seule r\u00e9daction et d\u2019un seul comit\u00e9. Ainsi, l\u2019\u00e9mission principale de la cha\u00eene, UniFlash, alterne diffusions en fran\u00e7ais et en allemand pour son \u00e9dition hebdomadaire. Dans ce programme d\u2019information pour les \u00e9tudiants, se succ\u00e8dent en principe un reportage sur un sujet d\u2019actualit\u00e9, un sondage d\u2019opinions autour d\u2019un th\u00e8me pr\u00e9d\u00e9fini et un agenda. Diffus\u00e9e uniquement sur internet, la cha\u00eene sait garder ses t\u00e9l\u00e9spectateurs fid\u00e8les, en leur proposant \u00e9galement d\u2019autres \u00e9missions.<\/p>\n<p>Dans les rangs d\u2019Unicam, Daniel Monney remarque la pr\u00e9sence d\u2019une majorit\u00e9 d\u2019\u00e9tudiants en m\u00e9dias et communication. Une tendance qu\u2019il s\u2019explique par la proximit\u00e9 des locaux d\u2019Unicam de la Facult\u00e9 des Sciences \u00e9conomiques et sociales, dans le b\u00e2timent de P\u00e9rolles II. Mais le jeune homme tient \u00e0 souligner l\u2019autonomie de la cha\u00eene qui \u00abne fait pas partie de la Facult\u00e9\u00bb. En outre, il vaut la peine de mentionner que pour les \u00e9tudiants de ladite Facult\u00e9, Unicam offre la possibilit\u00e9 de transformer, sous certaines conditions, leur collaboration \u00e0 la cha\u00eene en cr\u00e9dits ECTS.<br \/>\n<strong><br \/>\n&#8230; Et Unimix sur les ondes<\/strong><\/p>\n<p>Rien de comparable du c\u00f4t\u00e9 d\u2019Unimix, qui pourtant n\u2019est pas en reste avec ses deux heures de diffusion hebdomadaire \u2013 soit une heure en fran\u00e7ais le lundi soir et une heure en allemand le jeudi soir, sur les ondes de, respectivement, Radio Fribourg et Radio Freiburg. Ce privil\u00e8ge d\u2019\u00eatre diffus\u00e9 par le biais d\u2019un m\u00e9dia r\u00e9gional tout public profite \u00e0 Unimix, qui peut ainsi \u00e9tendre ses horizons et\u00a0 essayer de \u00abcibler non seulement les \u00e9tudiants, mais \u00e9galement les autres auditeurs,\u00bb explique Charlotte Bonamis, r\u00e9dactrice en chef francophone de la station.<\/p>\n<p>Mais un tel privil\u00e8ge s\u2019accompagne \u00e9galement d\u2019une pression suppl\u00e9mentaire, puisque la r\u00e9daction a d\u00e8s lors une responsabilit\u00e9 envers la station, qui lui pr\u00eate ses ondes une heure par semaine. Et la pression est encore d\u00e9cupl\u00e9e lors des trois \u00e0 quatre \u00e9missions en direct du semestre, pour lesquelles il faut faire preuve d\u2019une grande rigueur et \u00eatre \u00abhyper organis\u00e9,\u00bb souligne la responsable. Ainsi, Unimix demande \u00e0 ses collaborateurs de se donner \u00e0 fond. \u00abNous voulons des membres qui soient actifs, curieux, motiv\u00e9s et pleins d\u2019id\u00e9es,\u00bb lance la jeune femme. La motivation, une qualit\u00e9 d\u00e9cid\u00e9ment requise pour s\u2019engager dans un des m\u00e9dias fribourgeois faits par et pour les \u00e9tudiants de l\u2019Alma Mater.<\/p>\n<p><em>Unicam, Unimix et Spectrum: en bref<br \/>\n>Unicam:<br \/>\nUne \u00e9mission d\u2019info hebdomadaire, en fran\u00e7ais ou en allemand, diffus\u00e9e sur internet et mise en ligne tous les mercredis matin pendant le semestre. Plus d\u2019autres \u00e9missions tout au long du semestre.<br \/>\nhttp:\/\/student.unifr.ch\/unicam<\/em><\/p>\n<p><em>>Unimix:<br \/>\nDeux \u00e9missions hebdomadaires, une en fran\u00e7ais sur Radio Fribourg le lundi de 23h \u00e0 minuit et l\u2019autre en allemand, diffus\u00e9e sur les ondes de Radio Freiburg le jeudi de 20h \u00e0 21h.<br \/>\nwww.unimix.ch<\/em><\/p>\n<p><em>>Spectrum:<br \/>\nTrois \u00e9ditions mensuelles par semestre, en fran\u00e7ais et allemand, distribu\u00e9es sur tous les sites majeurs de l\u2019Uni de Fribourg gratuitement. Plus des articles in\u00e9dits sur le site internet.<br \/>\nwww.unifr.ch\/spectrum<\/em><\/p>\n<p style=\"text-align: right;\">Par Julie Rudaz (article paru dans notre \u00e9dition papier de mars 2011)<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"szA1AAA=\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"83nUMDMzLy1foSCxSCG1RKEgv7RIISe1WOHwypLSlMzEvJJiAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcZJDoAgDADAF5WC3vwNgRJIsDRd\/q9zmuku9iCaRyf2FLyGpjbRhJprvHjlUjDfuBePA1IVyEFOKGyy\/9FXZTf8AA==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNQ1MNY1MFcwMLcyMLYyNAQA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"rVjLbhzHFd37KwoTJLCB5pAUpSCgKBqOHoECOxAsKfua7pqZIrq7WlVdw8fK\/5BVdoI3IWMgq+y80\/yJvyTn3KrumaYsb5QVOV2v+zj33FN11p2fhd67dnX+trWlbgqFv429UqZXrztT9j42p6o2QXXOtn1QpWua2AZl2t4bVWIAy21Qzfausjp8rV7WQQXX9mrp7cJFvzIYLtTC1rZdRczHztv36vjo6Pdqtb3z2zvsrb2qMLS96yN2wTnzs8Ns19lhd\/7FWadCf12bJ7PeXPUHurar9hSnt73xj2fnZ1qtvVk+ma37vjs9xNJYYWweW7v083J9GLIrh5fdQQnjMHgYu9rpKhw+ODo+Pjw6OTyeX3Qr7GWbleIIzH0yq\/XN9Qy2lS791uG6LWeqrHUI+EU7khUq2Btz0JjKxkbhFNvolTk4OXk0U73tafnxTAVffqaNBydHR1fHDx+KrUrXvex7aat+\/WSGsZlaG7ta8\/PDh3JgMH06M\/xfDlX4\/7JQn7vhyaOr4z8epQ1PHn32hrIRIHV0OZNEMDexd4X6stFXBxKeU1reXX3FaRscKL9m6hAA0wPIzl9btXCtal2zALqrX374J+zYGB9sT5yGaENgLcRFbWEICiN61XnXYfYFwN7qWpmQQWzbQnntTa6H0tSso3fRonhUV0dUBZe6wJ1iawD\/BvtbGOABP8dKwbH19g5JXVSu0ZW23szV85ab6ULVMPDtzkDgVL3IVacC7MeG2r+LhnjFyoYHVRrVWxvU3HUARLNPc\/V3F1ndbav5+0YFzqtc7GWfC5RshNUmcu3ADOqXH\/7B38C6vrHwgGdtuBHShD2wiCbaNvSIR+aMjQNbaHyT1fgvyLKgN+bmQBZXyS3QEUOQCKkQEirXevufFv\/A0xwazEjRmhLIhH6+HvI7kN0zMzKWsi3860xbcdl92jl\/gwiIQXrhfFUoW6sloEVznfVi+UckmPJNAAJIJszVU2QLuFwB05ZBYkxAk0AMY932GWlGrbxu4VptF8YzoWDHSpc9INESPXQWs2T7DucwvtjY1VjDZZ+GQ6FaO0z55i\/PXxSCww5DkhnBMdcZAWKIiw3MIhKJU+WiahwzhgFJpaU18Au7Ae6ERX+w\/XfqCH2\/50A+BV5K\/vbyY9qVXrGoBJDlXkK27z+8J4AqggU2EXgoY9sAcHABNbM0UiaoNhsaUyjxgU0EISrXDu2LYAjxwvQJXBn0cLL32vZSCfMhxd8RgiHnRFeu61NBstd1zqfZPFayj\/AIABj\/ElmHkQwj000reBo9zWxgQ29SnVex7GGA9D\/MJS1oIFunj4F+ITrwmofZdqltjSjWAh94du9kJwy0w98Qu6VrM1ywy8pvfywNUTKtDXTj7V27vdu41NhhPWCETCOEfUEDg4sEgGC4soSgCbsgkhdYwfgGN8gFdgkz39D\/nXzIFZwCsqMMAa9JDMYBuBGVRQmCOsUUAhB82tjtLWJrrjqIBJBtOWZx9HauvqVZ27uFxD4Qh2I2k3kNn7DInyqmNRgvmsT5hpgzNKHUlaiPixikJBGncq86kRLWpuwXl0sbdCNAyKQG0OTMSyAjJQDtW9ra7LA1VVfYSDDamv4Pv\/vTg5Ojxx\/xzbekX4d9bGlBlSypkV2X4ByfqhYtCnWp+177iifjCxtTia+s03v9Y2NDNDXi9YpLnwF3plbfESXXhdrY0hwQfMEK9qpI4CcCGYl4FHAsuB2VoTti3o4IkFLUVyBvJFQh++QtfM90PaLQsFEq51ewJmzvjGANawYqDCZi4Y4A6U0ak6HBxrn6Bg7b1At3DbTzti1tp+tEjHroHKJvX0C9rQuqJ+NxUmWXy8hVJCX0Dd1u\/0VKEJBgVm0asHLyiK4RfGLRtCs\/SzzGWgeNAytiLioZmNOJSyUm90qRMItlub2V4JvRdAYX5UUCSm2alZE4LfWjso\/gF4SgkAGHBrZKZ7rOtuLOJKSqX29vm8QzqJkl5tBFDGAdFsMDCQRzgbwic03CPsinlUiBG3aRBNotKCbjjy1QEix0kEltibK+rcl\/cGuUSi6QJ7Z3KySnGZpfZsQxgWGsoGdD0SMvqzCB5ATIiFUWO+QywjlxRoZToy9QOwOoJ31oJE9EI11vsD0TNgdYjHQiMsnADMIuoKWaIUpdhwc6NKjcdWGvK3W82hcyCYUvdBnrYdLrUmiNXpdUCtwvJPYtrZa4DWJtsf2xtylYRr0CITrRki9fzpV0L0y5MHRz7Qi83maiAo\/zioIM1SnIcs69mpAm\/eEnIRib2gsbwThtMPrDzyI9HVMlrXDDbkTnDdkJk5skGtrcmH4F72lL1I8Zty2GTuGWS5+y54AB8k0WMejZbWAZGV\/QJZYZqkIaECKXqjEUCWIlQkOtlkouKaTBUbYdL+Ub1POnb17PzxYeN4AvBpbOPzM3q+djOwvZERxmPtaI3yPctJN6QXu9IOmARLf\/3eNQkbATzdUO4kkLCAF\/BAUiuJRqqgzws4ZDSeyOHDUhHVHQwdl0fZDZUwoj9UYEiJN8qva9eSO1JfjkacXUW5xejG1+IxVbqO+lv4x3DWw8fDF2gS+UvCSyja23t5mVkj6sMscMcm1haWdmqFSIJP0VXIUg6Km+5bZViu4jbpDSSTyhPRWvE1Yl\/eSNBHCNcr8RTu8hJyEY9bXhKwOQXlJXsYWmVpJY6D4vy8Vkj6U4Pui2SACD4YoPP6uRCZ6uta8d1e+fYXvDR4\/cvTw6rGBvbZaSnNJ1a9cO9QVFLWwz0aPka3DbXgyDkL5gbCWXxQmBZtWUul+IXQcu5iBhAv2Jvp2pca+jaminW5KVaGwjWUbE9FB6phX5vTMxRbxm1D3SmQKdULIDFhMbjOjDOUtI2DEbRryD85yXS2UZaaVJBlTjLQoJfhc1wbJrBwxfBVdK0SfYHjuJY5liks4I4\/VsKeWBcyEI79+uvF1FMgUfogSTH35aX3cAxChGmNeBOiVmQ2B46cl6IzNDJRUkqEwCbGCfpJON3MMTJWIK5Hk1x3l\/I4nhrlvTNXreGL44pNcBFKFob5HVhSoj5G8E2huHAszqtasNdZ4oDETSCBRF8NLe1AuWBr0AGlmnlTmDUQhfZ3JFErheYOQNTh9ErTQ5XtFYNOxCsU2GDheNveu19I30ikfTPsH6vHnWjUbDgpjYCWTT\/ObTI\/KOwCwzM+epp\/nn28mjySC3JhRZTAkRN9k94itGOjITnUMTGoaCukVA0DNhcvUwvvSm4mUfAeWLiDwckMoGVEJm1\/kV4yNZkxhNR2C+Xe1DeWhFn3odFFHSnB0iXPuhO08xGwLyjF1j77T9SISU+0k46PQ9Lh9bBnL24GRN1Da2jVaCUg8+\/VYU91vHvb6w6zTc\/Uh2f3C8Hpy\/vLykx3AILn\/s64iKPP1Noossx5mbNmQeyCSUWeK+rN+3HDNgGktIjB8THSzvvJCNQyHn15XJIxsYpY\/De0JOOxsE1FMpdNRmtZEvftx0RNk9r6fPnfve\/9rbt+cr7+PZ+Ss4+lcwFSIdK32jvsxnMwIxVW7rEpfmW0unO5s6IfRyUHxD\/UoO+h8=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Unicam, Unimix et Spectrum: les points communs entre ces trois m\u00e9dias? Ils sont fribourgeois, bilingues et \u00e0 100% g\u00e9r\u00e9s par des \u00e9tudiants. Si bon nombre d\u2019universit\u00e9s suisses publient leur propre journal estudiantin, rares sont celles qui en plus, proposent une \u00e9mission radio et t\u00e9l\u00e9 hebdomadaire. En cela, l\u2019Universit\u00e9 de Fribourg se d\u00e9marque clairement dans le paysage suisse.<\/div>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2272,29],"tags":[129,713,716],"class_list":["post-850","post","type-post","status-publish","format-standard","hentry","category-archives","category-news","tag-spectrum","tag-unicam","tag-unimix"],"views":2036,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=850"}],"version-history":[{"count":1,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/850\/revisions"}],"predecessor-version":[{"id":12802,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/850\/revisions\/12802"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}