{"id":8995,"date":"2018-07-11T16:15:15","date_gmt":"2018-07-11T14:15:15","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=8995"},"modified":"2018-07-16T10:41:46","modified_gmt":"2018-07-16T08:41:46","slug":"les-georges-2018-interview-ghetto-kumbe","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2018\/07\/les-georges-2018-interview-ghetto-kumbe\/","title":{"rendered":"Les Georges 2018 \u2014Interview: Ghetto Kumb\u00e9"},"content":{"rendered":"<h1>Hier, pour le deuxi\u00e8me soir du festival Les Georges, le trio carib\u00e9en Ghetto Kumb\u00e9 a jet\u00e9 un sort au public fribourgeois par ses rythmes hypnotiques et enflamm\u00e9s. La place Python s\u2019est transform\u00e9e en portail spatio-temporel pour nous plonger dans l\u2019histoire colombienne, une histoire de m\u00e9tissage musical qui nous est racont\u00e9e par les artistes du trio et leur interpr\u00e8te, que j\u2019ai eu la chance de rencontrer dans les loges, quelques minutes avant le d\u00e9but du concert&#8230;<\/h1>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-9004 aligncenter\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/07\/GK-429x600.jpg\" alt=\"\" width=\"429\" height=\"600\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/07\/GK-429x600.jpg 429w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/07\/GK-530x742.jpg 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2018\/07\/GK.jpg 686w\" sizes=\"auto, (max-width: 429px) 100vw, 429px\" \/><\/p>\n<p class=\"dropcap dropcap-borders\"><b>C\u2019est la premi\u00e8re fois que vous venez en Suisse pour cette tourn\u00e9e, quelle impression vous a laiss\u00e9 le public ici\u00a0?<\/b><\/p>\n<p>\u2014Nous avons commenc\u00e9 la tourn\u00e9e par Festi\u2019Neuch, \u00e7a a \u00e9t\u00e9 une tr\u00e8s belle exp\u00e9rience parce que c\u2019\u00e9tait la premi\u00e8re fois qu\u2019on venait en Suisse et qu\u2019on pr\u00e9sentait notre musique \u00e0 un public suisse. Les gens ont aim\u00e9 et dans\u00e9, on a eu une belle connexion avec eux et avec l\u2019\u00e9quipe de production, et on a eu une tr\u00e8s bonne qualit\u00e9 de son et de lumi\u00e8re aussi. Ce soir, nous jouons aux Georges et nous serons en concert au Pal\u00e9o le dimanche 22 juillet.<\/p>\n<p><b>Le public suisse est-il diff\u00e9rent du public latino-am\u00e9ricain\u00a0?<\/b><\/p>\n<p>\u2014Le public latino en g\u00e9n\u00e9ral va \u00eatre un peu plus expressif et un peu plus fou, il va vivre le concert d\u2019une mani\u00e8re diff\u00e9rente mais c\u2019est normal, il a aussi un style de vie diff\u00e9rent. Ici en Europe, le public est tr\u00e8s attentif \u00e0 la musique, les gens vont plus \u00e9couter et un peu danser aussi. Ce qu\u2019on appr\u00e9cie du public europ\u00e9en, c\u2019est qu\u2019il est pr\u00eat \u00e0 \u00e9couter de nouvelles propositions musicales, qu\u2019il est ouvert \u00e0 de nouvelles sonorit\u00e9s, et c\u2019est vraiment impressionnant de voir que le public se connecte assez facilement avec notre musique m\u00eame s\u2019il a moins de familiarit\u00e9 avec elle.<\/p>\n<p><b>Y a-t-il une diff\u00e9rence de r\u00e9ception de votre musique et de son histoire par le public colombien et europ\u00e9en ?<\/b><\/p>\n<p>\u2014C\u2019est un nouveau son qu\u2019on a cr\u00e9\u00e9, qui passe par l\u2019exploration de sonorit\u00e9s de diff\u00e9rentes origines. On a vraiment recherch\u00e9 \u00e0 retrouver les sons africains, qui ont \u00e9t\u00e9 import\u00e9s par les Espagnol\u2219e\u2219s en Colombie avec la traite des esclaves Noir\u2219e\u2219s, parce que c\u2019est ces rythmes-l\u00e0 qui ont donn\u00e9 la cumbia ancestrale dont la musique colombienne est issue. Que ce soit ici, en Europe, ou en Am\u00e9rique latine, ce concept musical est nouveau pour tous les publics, mais notre musique est toujours tr\u00e8s bien re\u00e7ue.<\/p>\n<p><b>Le message passe donc plut\u00f4t par la musique en elle-m\u00eame que par des textes\u00a0?<\/b><\/p>\n<p>\u2014Notre message, l\u2019union des trois cultures, africaine, afro-colombienne et colombienne, passe par leur r\u00e9union et leur simplification gr\u00e2ce \u00e0 l\u2019\u00e9lectro. Ca a \u00e9t\u00e9 assez incroyable de voir que les percussions permettent toujours autant de communiquer, aujourd\u2019hui comme il y a 500 ans. Les percussions ont jou\u00e9 un r\u00f4le tr\u00e8s important dans cette rencontre entre les Indig\u00e8nes et les Africain\u2219e\u2219s \u00e0 l\u2019\u00e9poque. Comme les deux peuples \u00e9taient pers\u00e9cut\u00e9s, ils les utilisaient pour communiquer entre eux afin de planifier des \u00e9vasions de camps par exemple. Au fur et \u00e0 mesure, des paroles se sont rajout\u00e9es sur la musique, ces peuples ont commenc\u00e9 \u00e0 chanter leurs joies, leurs tristesses. Quand on joue, on peut ressentir dans la perception du public que ces rythmes sont communicatifs.<\/p>\n<p><b>Votre musique a donc pour but de rassembler plut\u00f4t que d\u2019\u00e9voquer des sujets douloureux\u00a0?<\/b><\/p>\n<p>\u2014Notre musique est vraiment un retour vers la rencontre des Indien.ne.s d\u2019un c\u00f4t\u00e9 et des Afro-colombien\u2219ne\u2219s arriv\u00e9\u2219e\u2219s avec l\u2019esclavage, vers les premiers sons qu\u2019ils\u2219elles ont cr\u00e9\u00e9. Notre musique est leur histoire. Mais bien s\u00fbr, le pass\u00e9 est le futur&#8230; Et nous, aujourd\u2019hui, on cherche plut\u00f4t \u00e0 faire passer ces messages par la danse et la musique. Et la musique fonctionne\u00a0!<\/p>\n<div class=\"content-block block-border-all\" style=\"text-align: center;\">Les Georges durent encore jusqu\u2019\u00e0 la fin de la semaine\u00a0!<br \/>\nCe soir et vendredi: entr\u00e9e gratuite.<br \/>\nPlus d\u2019informations\u00a0: <a href=\"http:\/\/www.lesgeorges.ch\/fr\">http:\/\/www.lesgeorges.ch\/fr<\/a><\/div>\n<p style=\"text-align: right;\"><strong>Cr\u00e9dits photo:<\/strong> Maud Chablais \/ Diane Descheneaux<\/p>\n<div class=\"embed embed-responsive embed-responsive-16by9\"><iframe loading=\"lazy\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/aro7A2UPdms?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/div>\n<p>&nbsp;<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"s7C0NAUA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"80ktVnBPzS9KB9JGBoYWCo8apnjmlaQWlWWmllspuGeklpTkK3iX5iYdXgkA\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"FchLDoAgDAXAE5WiG43HUZ9AlE9oq9dXV5NMVG2yMIvajqLOSjq62yJLw6bdMo9+mNlPfEEooPbw+R+louh3wkMhQrXSaXkFvw==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNA1MNc1NFQwNLMyMLcyNAUA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"rVhLjxvHEb77V3QYwEgAvnat54pLQ1jLimFFkREkQI7Nnh6yNzPdo35wSZ189A\/wxTchF4s6+5ab55\/ol+Sr6pkhd6Xk4hyWO4\/u6np89VXVLDZnyz8Z7ceiccmLSotCp51p39VaBGe8KJIodYhmKyvxQgfxXDu\/1mFMS6M3Tijpzao9aCueb3SMTnybatwLKa51xP9kIchHIZNo0qoySpTYgMPW2pkgGulFgFy\/j5sa\/zf7xrpoXidc6yi0LStZ1+0hTMULKZpKKi1eYa2D2A\/f\/wTVoIa0oXQeqzQ2wBIfpalEaGQ0bhJ1jSe6yhZal3Bo5exawzhsFBXEbEyIsFYL5SpXr4y2Vo+huhbDm0ILHBBNCHKNyxSMgkteJ5NFkiJeKmcjaUFWVbBAemyIuIAb2VswqdJQw9iofePbdxHnwFhxDS2kETqJSgq1kVbxkV5bkukHZSGrchwA7KrYTbWxic6QW2kjh7A9rFKkM7FXaR8\/\/\/2j8y\/mTxYzRPuzRbNcmHoNMbIwdn05quSb\/QiHKZfvZdhbNRKqkiFcjoJ5oye1LkyqxU0zMTXMnzyez+8JWZk1xJMlIxG8uhxtYmzCxWwWYirwfJqsKf1UbWah0Sr6VM8ggezBy1lqSIMwO5+fPZrNH86efzu5d\/5492A+n1436xHEx8vRSNyYIm4uR3g1Ehtt1hs8xRo+Mej4fz1U4PpmLH6rxPtfzHcP752zRFz\/doks6cGjBzewGuFAVGSKbiz+UMvdhB10Qao3uz+Ks\/l8iwP5biRmy8WsoZD30Sy8a5RsRPd\/snK+0D6MlovV8qrLJwCw8boGCQD2JSUpAXRLKN9qq99Qjv01IRF0TimFtAcZ4NIC+xmYQKGpISUEg0zlvRKCsQmUgJcdFRhlfn375WK26vVcfvj+x5e8eusAd+XqGhlAe+RwAmfX10RKUPilTmozFu3PEgcgP5lxiJrad0GsWBG9a9qDR04r3opfskdhM9ZL82mD8ZYU15YWHA1G\/vbvkL2HgHjRAlCWz6RAotu3xHqdiYE3Tpk81xo2IcpCGnAJCaOkbg9jPIT6SH7SPWsNNFi9I+\/JrVZ4t6P1fF2x6qCehjmi8a5IClRnx7TkVFTnBhIFvZGw5J+CqN3y6VpUqbNbJsRqKq4y748zq127RGGQOLwjftrGr4L29Aqu6UiGGP6VrNqDYw4CUVi10eL8XFwnA4vitI8xsPZC3\/YP8ecEnF2YskSw4Fair25JBR63biJrCqOSxn6MmaO8vJj0WrcHwMWDpbeAxnuKEIUFrmkqYuxdxmdJJp2+KF0aC8O7tmaLXTkabGMB15NjYVx221FhegjoqC6LLAqSrFiQzM7lUhj3XGMh+XTvVHyjDOn8LCEx9fgkRXKFozDKSPQAfYEvQLZD25hrAiNrS9BiE9qDcqgJ\/sQ0QhoeHMPc41g2hGRF+gwe16QGFfXxYA8vhzF0jQ3vI6kxnAOLgIotITcQIBsXDCEy9JUyV6yjCFrsWcatrQCm84TSwFjuD996ZAyB4kgqloodOZK6FMq6o8tClz0KMQHrgbFKqUylWQJn0O18rdv31O5k5eBYZ6A3RJeyNpWRrE+XhVDyFMb\/EHLCuCVMDOHsSjecoxtyQlbz9MSce5SFQ3+RW4behKEP4Saoj4a4C\/ueshFj9iFSkIQOoRUKWhC\/UJ\/SSKZsOoe27VBmvOz1Ozqe7k5QDcLyZm2sRgf2FxI5xMJr5LdXGzgHYfQ6eg6q6OIIwJY5XUM+n9CZGdpQR8Zn9Y3SMzRra+uqDz\/8pPHHvHLV+aAjPUmNnonkW2q3UNC2uHgJ5\/WbxnfonTyjjr3lpIKavSIFAJLLikK\/apCiCFvACZSetOCYYadNIWMXhJXA6N\/RK6bLSIVsfJq\/LtHdU2YsBiexEp6rjkqaOLSQmSxy8LieRqJXziPGAsxiYrmNWaYFl0DQPvQ0T3Dxuv056TtUC+O5a80IgHmKaCK2v8QcgKOpBDhgfJJTgp7QAvJ41DuA4VPVmtXKJ4wZWuhuGFSkGFVTlaqYPDFAjwjNl25yy7Pxdvd9AlfqmAHkLLdvoQNQVJkS8hjDa9\/+S3HtzeWxosbKgemOjUHmAmOVd3u56nj4SB9wOOCcmF34utbMuEc\/o+vqWIcaE6iDjSiVkl9TadgAXdyzEO3vcfD9+RzICrn8n4oniGFXHpB8+0vVF+ucG3wMNfy5uRrGAAQo+qzsN7Yw6\/adzTWZnjztvDsk0eCMxr0mxF6xarSUpjwqCw3dcBtEhkJBdCMqZf41VYZhimDB0K3ghu9ofKcPSZOlYSbBjIbu1ugMm\/awldli8pqsm5zzeoepDFwqnmK+TFynoCxQBJyMeSNWOWYS5iYaruAuGq7wKPlbBVCxb7MttPTYNUImzVJRZxBRQ2Py8JrThoezQNT2XZK2oN4Jp2juxyCROC5Qj2f68UtyEHtaH+ols8TJFBt6NeAmwmcZTjPy77cyWXYJSZ7lsQ3hJqTWQKgf8pRWFhzLrWPHF+wIzNjwrEsVdiMI\/zU9T1hj4G8CnqamGm2uZ9uOMCs6gGk7tXoaur5HKKjSNa4ZbycpDMTZDDvpvdm2hwGGQ9OaWZt5Ih\/JzQI6b7rhktG1CIH2VkM8uYhNxce2MBH0JXQq\/kw8yTQY2n\/73EVJHjnyYkANRNRNw+JZ7mTv5C\/HPhc2PXgfOCplrtKBuiiKdUd5oadQbrA4FQdoTumME3YtEWhCjtW\/vv1dDlJhtv1s1s1\/k1Xl1D8F\/3bz2URW1Sj3jpcjIuIJz94XIk\/fT0bLk08zgCX3zxRLaHydAjs1N41djuIKACMiJkVWHoPiZ13nTxZg7Ck8Rv4LTm8audboFBKK77Rb\/Iq6TPKYsfTlhSkYxeFCLKTYeF3msRwT783NzRRxXGfdaOQt\/Wj5P14uZhL4hVt4bP2EzZ6+AcDkBaq1s+vlFRQsDNKg2bjoLhaz7jnQkApxtQHTEyxm4isjUWa+Agg3GGMx03wUAeScLgT\/TpD5DWwyW\/3Rg8nZg9X+MTTAEC+JUG9\/Sem+WJydPZyffLK4\/+jORxIyfg9KSys9BVXM+JQZWO\/h0\/O\/vSrq8GWpJdXNS8evRoJPy4i4HM3pC0nlbvK3AJDu\/gmF3O+bCGXpg43sVpSpqoLyWls4Nqt89PDyc7sKzRN2xX8A\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Hier, pour le deuxi\u00e8me soir du festival Les Georges, le trio carib\u00e9en Ghetto Kumb\u00e9 a jet\u00e9 un sort au public fribourgeois par ses rythmes&hellip;<\/div>\n","protected":false},"author":13,"featured_media":8996,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[160,111,169,5,6],"tags":[1586],"class_list":["post-8995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","category-fribourg","category-interview","category-music","category-news-culture","tag-les-georges"],"views":1736,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/8995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=8995"}],"version-history":[{"count":8,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/8995\/revisions"}],"predecessor-version":[{"id":9001,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/8995\/revisions\/9001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/8996"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=8995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=8995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=8995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}