{"id":910,"date":"2012-09-16T23:23:15","date_gmt":"2012-09-16T21:23:15","guid":{"rendered":"http:\/\/student.unifr.ch\/spectrum\/?p=435"},"modified":"2021-05-09T14:06:56","modified_gmt":"2021-05-09T12:06:56","slug":"la-bibliotheque-de-a-a-z","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2012\/09\/la-bibliotheque-de-a-a-z\/","title":{"rendered":"La Biblioth\u00e8que de A \u00e0 Z"},"content":{"rendered":"<p><strong>Le cours \u00abla BCU pour les nuls\u00bb est propos\u00e9 par la Biblioth\u00e8que Cantonale Universitaire (BCU). Il s\u2019adresse \u00e0 tous les utilisateurs de la BCU qui souhaitent mieux conna\u00eetre son fonctionnement et ses diff\u00e9rents services.<\/strong><\/p>\n<p>Selon Paola Delacr\u00e9taz, responsable de la formation des usagers, \u00ables biblioth\u00e9caires sont un lien entre le livre et le lecteur\u00bb. Cependant, ils n\u2019ont pas seulement pour mission de pr\u00eater des documents \u00e0 ces derniers. Ils doivent \u00e9galement leur expliquer le fonctionnement du syst\u00e8me complexe de la biblioth\u00e8que. C\u2019est une des raisons pour lesquelles le cours <em>la BCU pour les nuls<\/em> a \u00e9t\u00e9 mis en place. Ils assurent un conseil au lecteur plus pouss\u00e9 que les deux, trois recommandations gliss\u00e9es au guichet entre deux emprunts.<\/p>\n<p><strong>La BCU en une heure et demie<\/strong><\/p>\n<p>Plus qu\u2019une \u00abformation\u00bb,<em> la BCU pour les nuls<\/em> est plut\u00f4t une introduction \u00e0 la BCU centrale. Selon Paola Delacr\u00e9taz, le cours est plut\u00f4t \u00abune visite, une introduction et une explication de comment utiliser les ressources des biblioth\u00e8ques\u00bb. Le cours dure environ une heure et demie. Il comporte une explication des diff\u00e9rents services de la BCU. Ensuite, les usagers profitent d\u2019une visite de la Biblioth\u00e8que et de ses diff\u00e9rentes salles. Ils se rendent dans les magasins \u00abo\u00f9 se trouvent pr\u00e8s des 90% de notre collection\u00bb, pr\u00e9cise Paola Delacr\u00e9taz. Selon la responsable, nombreux sont les usagers qui d\u00e9couvrent la salle d\u2019exposition ou la salle des actualit\u00e9s \u2013 o\u00f9 de nombreux quotidiens et magazines sont mis \u00e0 disposition \u2013 pour la premi\u00e8re fois.<\/p>\n<p><strong>Un cours pour tous<\/strong><\/p>\n<p>Tous les usagers de la Biblioth\u00e8que Cantonale et Universitaire sont les bienvenus \u00e0 <em>la BCU pour les nuls<\/em>. \u00abEn g\u00e9n\u00e9ral, nous avons plut\u00f4t un public cantonal car les \u00e9tudiants ont souvent une formation en biblioth\u00e8que comprise dans leur cursus.\u00bb explique Mme Delacr\u00e9taz. Le cours s\u2019adapte en fonction des personnes pr\u00e9sentes \u00e0 la s\u00e9ance. \u00abSi nous avons une majorit\u00e9 d\u2019universitaires, nous allons aussi leur parler des p\u00e9riodiques en ligne comme Jstor, etc. Si nous avons plus de personnes de 50 &#8211; 60 ans souhaitant seulement emprunter des romans, nous n\u2019allons pas aborder ce domaine-l\u00e0.\u00bb<\/p>\n<p><strong>Une formation condens\u00e9e<\/strong><\/p>\n<p>Le cours offre un tour d\u2019horizon de la Biblioth\u00e8que en peu de temps. M\u00eame s\u2019il \u00aby aurait mati\u00e8re \u00e0 faire beaucoup plus\u00bb, nous dit Paola Delacr\u00e9taz. \u00abOn montre beaucoup de choses en une heure et demie. Surtout que la visite dure presque trois quart d\u2019heure.\u00bb D\u2019o\u00f9 l\u2019intitul\u00e9 du cours, repris de la collection d\u2019ouvrages explicatifs. Ainsi, cette formation est l\u2019occasion d\u2019en savoir plus sur un lieu que fr\u00e9quentent tr\u00e8s souvent les universitaires fribourgeois. Les participants auront aussi l\u2019occasion de poser toutes leurs questions sur la BCU, afin de tout conna\u00eetre de A \u00e0 Z.<\/p>\n<p><strong> <\/strong><\/p>\n<p><em>Le cours est gratuit pour tous. Inscription, dates et heures des cours sur:<br \/>\n<a href=\"http:\/\/www2.fr.ch\/bcuf\/Dynamic.aspx?c=953\"> http:\/\/www2.fr.ch\/bcuf\/Dynamic.aspx?c=953<\/a><\/em><\/p>\n<p style=\"text-align: right;\">Audrey Molliet<\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"szQ0AAA=\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"80lUcMpMysnML8k4vKKwNFUhJVXBUeHwAoUoAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"DcJLDoAgDAXAE8FDdnobPjUlQUTabjy9ZoZVpxyAqFUa6m20c\/nCkElFl12IYYsIO3pyueXebmV6jFwll34vPg==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwNNI1sNQ1NFMwMrYysLQyNAUA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"jVc9jxs3EO3zKwYXJEgAWbIdOIhtWYFju3BgIwYubtJRu1yJAZfc48f5zpX\/Q6p0Lk8+IFWa4DrtP\/EvyRuSWkmWHKQ67S45fPPmzRvetJtNfXDWLGYvJFU2Ok\/ray3opyevqcMjaenJRO3XNyR9oM7Zzvp+RZ3AN6xTc61sWPZXZ1HSE2GCNUJLem3UuXReBaGcpG8Q7tsxPdfkP777U9ROei+pf0\/BRp+OiEFp5UWQjKCWVCCcRUXexqVQQZpArZLxAjCNEf1fAYG9NdRYUwWFd7LlNTKQR8BaNU2\/cnjj8ezOVSX9eDopyU4n3eyLaTc7lRoRXgmL855KLSrXr4J4OyIg7KzxYo5cMpzGulbwOXgGXi8WyG\/EbOFxvqFhVXHCnoEFioa0koYAAlgRSatz\/ABC\/i0rznZ9M6YnspOmBncjUhp0gyPe3gmGHnXOK1WjVd5nCKhE\/yFIl9DUtoptShWcVvxCOqOAjznnzygGQvSrhSjRNI4medFphbpxlT+lsY7kL33or1rWRdtpebFhYr5bc6AHXJZGNDKBcUIhez\/IB4s0c6Q3ApvKdnZMYtMJPpAAzACBIVUQRx2KInMawvvIBWVeoQEvlSYRN0RiZUyHepYnq1EnIuLFiFB0RHMSibQCTHOenhZQHNZiFaIsoqqWqEyuFW8j2XYugtTxRi1Dq2TwQMc5L3F4Kmotoc8Dib1iWGcRJPHi9fWgo\/XNiJmgz1ORGk7H0P+d2VXAZuuYysSVLjsrxozCjumzch643w25vuag5wpdKkeHB8h8aBJJtVE+ayHpIzeszJC5nxE+K8\/vC8SzwgdzqRNX5lyBoyPsJY9guVkX5JHjj\/f11jDG9Mz4mPLR2y5l12qyg9SlDjnrzcY9E0tYPvEQ7mjBKs5KhHnhbZ0CCpMdrBUL4ZVh\/7T9P7wEXMbUd2jVq8zM\/dtfcXBjWWSV1azdLAVetKrA6GH5NnXF2x1bGiFKO3cs1GQ2u\/mybdYIh\/NTw2Bngp\/SB6MWyTOhNu584j6oQhRaof08fXz3B3EiCW456CzaoGpYmmeWOOO3ymzcjhsWoqyVH+JzjKxrgfxQ4P7KsdOow556bYpC0nqeCwed9OswLEqax6q3HUFAuD+FBprmyACFiQnvf7rRGNV8ZmjRrwyEIDSTjm3iPBnc0JrURWCoqCqH40cOhPrFWgkWKx\/uiyBYgdt5Ah\/Z65jUAI6lUMQFVBWoiX7MU7iYNr2EM++pZGiyPGRFF7jVBmNPFe5AB3u8T3rzWdrZSmCFwrDXrq9P1W6ejLYVv1vHwigdtMOr35CiNa8WMGCVQeOOoMuE6kCfsjUDT7au1cIUM6GffbBuhHpVULr6hOFU5S1qPNy7TV9\/+cPdO3ce0ve3iRkqNwTBDA\/zsrh3Od9ZGP8GKQ\/YgpZnrJhbh4EJH8WkbAUUfUv378H1oUZ3y4YRBAfgAXKg1KEStmkc+xgL2iXqlqDxbbbSQ+eBkGTkTwHo4TUv+w\/gh8uJUbe+vgS5mK7ceSG3EirXJG3PpYg4skuUsZ2kRGusPWIn6+tfDLU2TbphI3v70vpcnmPOfBodsgh5tIrBQXkRepvHfJmzZ1G47LQpBIv2KV9pYCaaUzFBhahZSjHTxNctFnwhZeuLKQibGPrdb0dBA2oew2rVCDULYa+XMN\/4EFtVwm8iICEPQalyR8AtolzNYkqmAS\/4a9KACMmrN42a3GZP7Fit5gC9kOxi6DnWkAuqUl1qc1SIO710wR4S8GR5YjKLMvc1kwXI6Tris0\/CiEYkGpU2JMJ37rt49ZiL\/tuBf9KBCNnYXuzO\/YUTAbNx67AYZsZXTnUMYAS3YVgoeCpbHljFUKJ7MJ07miCwoKWTzaOTZQjdg8nkzZs3d8eNG1fLybyKzeTppRGtqsbCdxc\/Vo\/u3\/vuZEb\/e+10ImbJeEsS5MOllo9OgrwItwSbxgNyarEMD09mjyP+j7ikl1CLkiFt+Bc=\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Le cours \u00ab la BCU pour les nuls \u00bb est propos\u00e9 par la Biblioth\u00e8que Cantonale Universitaire. Il s\u2019adresse \u00e0 tous les utilisateurs de la BCU qui souhaitent mieux conna\u00eetre son fonctionnement et ses diff\u00e9rents services.<\/div>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[2272,111,29],"tags":[218,219,289],"class_list":["post-910","post","type-post","status-publish","format-standard","hentry","category-archives","category-fribourg","category-news","tag-bcu-fribourg","tag-bcu-pour-les-nuls","tag-cours-bcu"],"views":1188,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=910"}],"version-history":[{"count":1,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/910\/revisions"}],"predecessor-version":[{"id":12836,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/910\/revisions\/12836"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}