{"id":9895,"date":"2019-03-26T13:54:19","date_gmt":"2019-03-26T12:54:19","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=9895"},"modified":"2022-05-08T16:57:06","modified_gmt":"2022-05-08T14:57:06","slug":"international-competition-short-films-2","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2019\/03\/international-competition-short-films-2\/","title":{"rendered":"Comp\u00e9tition internationale: courts-m\u00e9trages 2"},"content":{"rendered":"<h1>Le FIFF nous offre quelques p\u00e9pites dans la cat\u00e9gorie des courts-m\u00e9trages internationaux.<\/h1>\n<p><strong>\u00ab\u00a0Ombliguo de agua (Water Navel)\u00a0\u00bb de Laura Baumeister, Nicaragua et Mexique, 23min<\/strong><\/p>\n<p>La vie d\u2019une jeune femme, coinc\u00e9e entre un avenir brillant tout trac\u00e9, corollaire d\u2019une vie jalonn\u00e9e de r\u00e9ussites diverses, et une addiction grandissante au crack. Le court-m\u00e9trage est une plong\u00e9e dans le foss\u00e9 qui s\u2019agrandit jour apr\u00e8s jour entre sa vie officielle avec sa famille on ne peut plus classique dans une jolie maison et sa vie d\u2019addiction plus ou moins voulue et de moins en moins contr\u00f4l\u00e9e, dans laquelle elle se perd un peu plus \u00e0 chaque instant.<\/p>\n<p><strong>\u00ab\u00a0G\u00fcm\u00fc\u015f (The Gentle Sadness of Things)\u00a0\u00bb de Deniz Telek, Turquie, 16min<\/strong><\/p>\n<p>Apr\u00e8s la mort de son p\u00e8re, Ali ne veut pas laisser sa m\u00e8re seule. Il revient donc la chercher pour l\u2019emmener vivre avec lui en ville. Mais pour cela, il faut d\u2019abord se d\u00e9barrasser des affaires de son p\u00e8re, de la maison et surtout de G\u00fcm\u00fc\u015f, leur vieux chien. Comme toujours dans ce genre de situation, les choses ne sont pas aussi simples qu\u2019elles en ont l\u2019air. Le court-m\u00e9trage exprime avec subtilit\u00e9 l\u2019amertume douce\u00e2tre qui s\u2019\u00e9chappe de ce genre de moment, lorsque se d\u00e9barrasser des objets r\u00e9veille les \u00e9motions et souvenirs de vie qui s\u2019y rattachent.<\/p>\n<p><strong>\u00ab\u00a0Franco\u00a0\u00bb de Mariana Mart\u00ednez G\u00f3mez, Mexique, 13min<\/strong><\/p>\n<p>Le jeune Franco est photographe de presse au Mexique. En compagnie de coll\u00e8gues d\u2019autres journaux, il couvre le meeting \u00e9lectoral d\u2019un homme politique connu pour \u00eatre violent. T\u00e9moin d\u2019un incident au d\u00e9but de la rencontre, il d\u00e9cide de prendre le risque de le photographier. Jusqu\u2019\u00e0 ce que son regard croise celui des gorilles du service de s\u00e9curit\u00e9, qui n\u2019appr\u00e9cient pas du tout ce t\u00e9moin g\u00eanant. Pris en chasse, il doit fuir.<\/p>\n<p>Ce court-m\u00e9trage se fait le reflet de la situation tendue de la presse, dans un pays o\u00f9 la population, autant que les journalistes, en a marre de subir la violence politique en d\u00e9tournant le regard. Treize minutes de plong\u00e9e dans la r\u00e9alit\u00e9 d\u2019un ailleurs pas si lointain, pendant lesquelles vous n\u2019oserez pas respirer.<\/p>\n<p><strong>\u00ab\u00a0La Mazda Jaune et Sa Saintet\u00e9 (The Yellow Mazda and His Holiness)\u00a0\u00bb de Sandra Heremans, Rwandan, 11min<\/strong><\/p>\n<p>Retour aux sources pour le premier court-m\u00e9trage de la jeune cin\u00e9aste m\u00e9tisse. Elle nous emm\u00e8ne dans le voyage de sa vie, de ses racines originelles \u00e0 son enfance, au travers d\u2019archives personnelles. Tour \u00e0 tour rythm\u00e9es par la voix de sa m\u00e8re et sa propre voix, les images diverses et photos de famille se succ\u00e8dent. L\u2019une raconte sa rencontre avec son futur mari, alors missionnaire catholique au Rwanda, l\u2019autre lit les lettres de son p\u00e8re aux autorit\u00e9s eccl\u00e9siastiques, demandes pressantes de pardonner son amour pour sa m\u00e8re et son abandon du c\u00e9libat. La r\u00e9alisatrice nous livre une autobiographie visuelle aux accents d\u2019authenticit\u00e9 touchants.<\/p>\n<p><strong>\u00ab\u00a0Una Cabrita Sin Cuernos (A Little Hornless Goat)\u00a0\u00bb de\u00a0Sebasti\u00e1n Dietsch, Argentine, 14min<\/strong><\/p>\n<p>Ce court-m\u00e9trage plante son d\u00e9cor dans l\u2019Argentine des ann\u00e9es 1970. Nous sommes en pleine dictature et on ne rigole pas avec la propagande communiste. Un livre pour enfants, <em>Una Cabrita Sin Cuernos<\/em> (<em>Une petite ch\u00e8vre sans cornes<\/em> en fran\u00e7ais), s\u00e8me la zizanie dans une \u00e9cole. En cause\u00a0: le nom sovi\u00e9tique de l\u2019auteur. Cela fait \u00e9videmment l\u2019objet d\u2019une d\u00e9nonciation de la part d\u2019une enseignante bien intentionn\u00e9e et la police lance une enqu\u00eate, persuad\u00e9e d\u2019avoir affaire \u00e0 un complot communiste.<\/p>\n<p>Le film est une petite perle d\u2019humour et de l\u00e9g\u00e8ret\u00e9, tournant en ridicule la peur des conspirations et d\u00e9non\u00e7ant de mani\u00e8re plus g\u00e9n\u00e9rale le climat de d\u00e9lation et les copinages divers qui gangr\u00e8nent la soci\u00e9t\u00e9 de l\u2019\u00e9poque.<\/p>\n<p><strong>Cr\u00e9dits photo: \u00a9 FIFF<\/strong><\/p>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"s7SwNAUA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"c87PLTi8siSzJDM\/TyEzryS1KC8RxE7MSbVSSM4vLSop1s0FKihKTE8tVjACAA==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"FcdBDoAgDATAF0ERT\/obgjU0gULa5f\/GuU0Dlt9Ejv2wIm6V12Jt5IsrbA\/K6bgonSQKNi2QqaWHOsdiyL\/gbRrCK314yPQB\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"86lMyUzMS1XwSUzOSCwBAA==\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNQ1MNY1MlMwNLYyMLYytAQA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"dVfLbhxFFN3zFbVMpGGCAYFAVqRgyEtOQMQIsazpqemppLqqU4+J4xW\/wQrDBg+IFWwQWbnFj\/AlnHOre8YYIyX2eLoe95577rmnD9cHd4+Nuv\/o\/n3lQ0kqrFbRqJfFOPxPqh+2vc34sNQ+KadVo\/OwbUO0Ri3xdRNKzOntbtjmqFt8YX020etsg9fldH54Bxe8ddjfPUw5Bt\/evfzl8vzzbuFsWwJOULotWt36WmOXeqo3xt2+PL\/8k0+OdYlafaJLZ2zC45l6ahsdZYPJ6ok5tQhxpt59r7P+8M54\/uGdXu471mrDGP\/+9rvijXpu+HNlug47mmB9M2yNMj4j2eIVLvY2qkW0zmmfVQ4FP6LGKi6PAV\/buD+ORz\/XLnjPYxBsHLYlpYqU3ZiYTJoxSi7Wy6VtCIhqo\/ZLmxKuwNdFNbjhxVyhAILjDkZlUt3a44pWrhD4kUFIadiiPlYlxKLriVk9x36l+zhcpPq5ppYqCiiqbaxxOACZNvx6pTvLvxEV7zHIt3eof+M08gCw9UrBLjic0WmbsBg5pT20+9RkcyiqA7ZJbUJxOAKLgU39yvjxQxMQ2vC7Q1qziVbkG4KRH4nhxCXLgrDqwcO5atZcBX6lDPjmU52v8urB8KYb3vz1vbp1sjbqASDAcc\/00ptEYquTtfVt2hHsU9T8TJ0YZ17M1EmJABURHXxwE53uVWjRAF2IkhXB6IeLiC33nCWIGwFRcxVqDD4DqI4rkFJxZq4eORUNoAPBlsE30k5rE\/lf9SyaA6SkqMcXG7uJY7kcqg34NizYXD3B6XV5Y5yeKetQTNws9VgEIAcEl8N2oWPUEgcbVa9WZHC6Fjr+Yk772oKG5D6+n9CcgXeF8ZhyingR\/lwdBUTJLiHXRnFojGqNj9IO6IQiGsDNeLQOaAhihGsqRprtgnVdzwUvCzN3\/IhEuYZQIOAbm+O0j7abqFwW2ToLUapbOhMzFAMAl8YMP2YRs9oswxYc6nsJ8GqwXQDiGZGGmEixm+ALi+cmJ7b5xkjfMNRh2wUmmQS5UEREBGH2x3TtaxV1zhpV\/h\/a3kcPN2Fi5RMdrfaav\/PwqzdnKMRvnTmb7RXv4GbFm1Sunica0q9DDtCIfi2Z9iBAEuUZz5qrzzzg7XrdeluBgdQNFy21XwhVMknDMlPPhW0oB6kJEDpjMloKQDjT5BC1GxVSrYUgPZQji5ig6X2prB1+ZlE2NjgCok6IovXTRiizXbJDECSrULkIjkbjRTmMxIBHXDcm5Zc1nmilgEv5Y5+7NeDR45KEZZQSGXDSBtG0Gh3TxGATWcFWY7054YSOywI+xI1tKq9xbYlk20zq6wlRD21ANGZkNnZIC2FHHnNrh589RUt9gQjJcBARhaiZBMj3qoDqUyGP\/sN4hIbuzZKiWTkzYbJrM5WBwZi5Hss8mxQcUb0Gg4c\/5FnoixtbE8XlsCMWbldkx2HL4YWpCGGIY0OXBeaj02Pdmqu1xUqUI8tuPwZJVFHbaOwZaGJ9yVV6rg00zY7StX1HAmjiTlEhlpAIBwCztgi3R471glTnhcyZJEWAvkS0Cvcg+R5KF2\/stWM21tlSq8earQIkn2n8o2thDDI4vsHZ4dW4DuNVPUTRHiJdzpHd9HiGJ\/AnD3Fvh1xm6stXmvGhPQ9uas8vTZYZDRGFVMTGjCLuhMEdOHq96rWYtacbC6ehURnFxxwvaF3qkJg2zIzhwu9dwia8Hg+os1p0ngoMv8EsFNjd4oNgiIYQ8fcryIYhK+h86GGqAmA+wdEkDmWsq5tQWmnlcyVJxdd5jbi4SFeWBHs6Xl8nYLUNfQw9ex9P62CwnZjGyTJxmbStcGWyKIn0a5rhYimCcTx6MOQS6KPSFW0YZwLSWZWMwMBfi4yo7GAhJg4SECMHG7tGRUlf5FtLN6sThIqnnHQbwcz5+tSUGmJZECFA0E0DM5MsysMDE9EGJSgj0ol0e5X8aAoiGOUs3RE64cC\/YOKjBbbjN6QEDtTZhWbeU7MknSP1SErvxCaIzURECzspHsqeqqmSaJsG2O0knaMIhpCMR\/0gRnh2Y7t8hUF0pGGLM7oEQnZUYO5RnVv31LHNtFcPQ\/SO\/upB0HlqjsvzZ2ZBOIYfvPrUYnI2a9ik2PJezwn2\/k0t8l\/h651YZWJCxQ9xpDjS2J1W7Y048aQOPvrwnbl6SmQSR5CoLSyGrINV1WCFwFx9L9ogsAFpSMRpVY7qluXjYOyKpx7O1Vd+hLqv7npFzGbq0HR3\/wekwzt4pm7VFfS0Ga8HUP7hYiPOXKxwRDfWhYhzhcE9\/AQvdnuGSXPRSf+f2TMts3my48TBjZMbLgpgf6xECDqkvLGUh2kI1mpDTeHY4BXrEIGFweSky6wuS6zN7s0GMHt4U1vHyjhPdNwvMD4Z23qpywJDT974PFfLuxCOkinjyFBHRVF118uCwW9mIiNFL2UGMD6IQZzcKQWlVEPiQr6K\/xWTs7Ku278gVVRxqKvnrYu01Tgi8arKvpJ5vRtQiDlakKG4mh3dbX2X9ZwcemfpKhaoiK\/vMaiDdKm8kmCKIWFYHjEbjYOUySpsqvNVoJBje+uvyJwYBxCsjdRsL3il0LBwnIK1bHjtDvRn15vyCBKA971UZfJjdbmVd\/d\/t9I\/\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Le FIFF nous offre quelques p\u00e9pites dans la cat\u00e9gorie des courts-m\u00e9trages internationaux. \u00ab\u00a0Ombliguo de agua (Water Navel)\u00a0\u00bb de Laura Baumeister, Nicaragua et Mexique, 23min&hellip;<\/div>\n","protected":false},"author":168,"featured_media":9897,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[160,371,1642],"tags":[63,291,1643,1202],"class_list":["post-9895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","category-fiff","category-fiff-2019-2","tag-cinema","tag-courts-metrages","tag-fiff2019","tag-fribourg"],"views":1430,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/9895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/168"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=9895"}],"version-history":[{"count":4,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/9895\/revisions"}],"predecessor-version":[{"id":9901,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/9895\/revisions\/9901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/9897"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=9895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=9895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=9895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}