{"id":9924,"date":"2019-04-22T17:18:32","date_gmt":"2019-04-22T15:18:32","guid":{"rendered":"https:\/\/student.unifr.ch\/spectrum\/?p=9924"},"modified":"2019-04-25T11:08:40","modified_gmt":"2019-04-25T09:08:40","slug":"attention-talent","status":"publish","type":"post","link":"https:\/\/student.unifr.ch\/spectrum\/2019\/04\/attention-talent\/","title":{"rendered":"Attention, talent !"},"content":{"rendered":"<h1><strong>Curieux et inventif, l\u2019artiste aux multiples facettes Ken Mauron fait partie des musicien<\/strong><strong>\u2022<\/strong><strong>nes qui s\u2019explorent et se d\u00e9couvrent \u00e0 travers leur art. C\u2019est avec son nouvel album en poche que ce pianiste vient nous parler de lui, de son parcours, de ses projets et de sa musique. Rencontre. <\/strong><\/h1>\n<p><strong>Comment r\u00e9sumerais-tu ton parcours dans le monde musical\u00a0?<\/strong><\/p>\n<p class=\"dropcap dropcap-borders\">J\u2019ai commenc\u00e9 le piano vers l\u2019\u00e2ge de neuf ans en jouant des morceaux d\u2019auteurs classiques comme J.S Bach, Beethoven\u2026 Mais le c\u00f4t\u00e9 tr\u00e8s structur\u00e9 et scolaire du style m\u2019a vite lass\u00e9. J\u2019avais besoin d\u2019exprimer ma cr\u00e9ativit\u00e9. Cependant, m\u00eame si j\u2019ai explor\u00e9 d\u2019autres genres de musique (je fais aussi de la techno et de la trance), le classique reste clairement une partie de mon monde musical, notamment dans le piano. Il y a quelques ann\u00e9es, je jouais aussi pour un groupe de rock alternatif avec lequel j\u2019ai fait deux concerts. Malheureusement, dans notre musique, le piano n\u2019avait qu\u2019un r\u00f4le accompagnant. J\u2019ai eu envie de quelque chose de plus personnel sans \u00eatre soumis \u00e0 une dynamique de groupe et pouvoir faire ce qui me plaisait. Maintenant, je compose pour de la musique de film.<\/p>\n<p><strong>Que peux-tu nous dire sur ce projet techno, trance\u00a0?<\/strong><\/p>\n<p>L\u2019objectif est d\u2019amener l\u2019aspect acoustique dans l\u2019\u00e9lectronique et de se produire en live avec de vrais instruments, pas simplement avec un ordinateur. J\u2019ai toujours consid\u00e9r\u00e9 que le mix pur n\u2019\u00e9tait pas vraiment de la musique, dans le sens o\u00f9 il n\u2019y a personne qui joue vraiment le son qui sort de la machine. C\u2019est synth\u00e9tique.<\/p>\n<p><strong>Tu as sorti un album r\u00e9cemment, raconte nous un peu son histoire\u00a0!<\/strong><\/p>\n<figure id=\"attachment_9940\" aria-describedby=\"caption-attachment-9940\" style=\"width: 286px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9940\" src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/04\/Art-Music-1-600x600.png\" alt=\"\" width=\"286\" height=\"286\" srcset=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/04\/Art-Music-1-600x600.png 600w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/04\/Art-Music-1-768x768.png 768w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/04\/Art-Music-1-530x530.png 530w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/04\/Art-Music-1-100x100.png 100w, https:\/\/student.unifr.ch\/spectrum\/wp-content\/uploads\/2019\/04\/Art-Music-1.png 800w\" sizes=\"auto, (max-width: 286px) 100vw, 286px\" \/><figcaption id=\"caption-attachment-9940\" class=\"wp-caption-text\">Logo de l&rsquo;album de Ken Mauron<\/figcaption><\/figure>\n<p>Oui, il s\u2019agit d\u2019un album compos\u00e9 de dix titres jou\u00e9s au piano. Je l&rsquo;ai intitul\u00e9 <em>Evocation<\/em>, car \u00e0 travers ce travail j\u2019essaie de transmettre les \u00e9motions que la vie peut nous \u00e9voquer de la naissance \u00e0 la mort. Ces deux ph\u00e9nom\u00e8nes m\u2019intriguent d\u2019ailleurs beaucoup, tout comme les r\u00eaves. J\u2019adore mettre tout \u00e7a en musique. Pour chacun de mes morceaux,je puise mon inspiration de ce qui m\u2019entoure et de mes questionnements.<\/p>\n<p><strong>Et au-del\u00e0 de la vie, quelles sont tes influences\u00a0?<\/strong><\/p>\n<p>En classique j\u2019aime beaucoup Ludovico Einaudi, Yiruma, un artiste cor\u00e9en qui fait de la tr\u00e8s bonne musique. J\u2019appr\u00e9cie \u00e9galement Sofiane Pamart, un pianiste fran\u00e7ais qui travaille avec des beat-makers (concepteurs rythmiques) et des rappeurs\u00a0; lui aussi est un excellent musicien.<\/p>\n<p><strong>Est-ce que les gens sont r\u00e9ceptifs \u00e0 ta musique\u00a0? Le piano seul sans paroles n\u2019est pas forc\u00e9ment ce qui s\u2019\u00e9coute le plus aujourd\u2019hui\u2026<\/strong><\/p>\n<p>Je ne me pose pas vraiment la question. J\u2019essaie de m\u2019extraire un peu du monde musical actuel pour rester dans le mien. Je pense que les gens ouverts d\u2019esprit du point de vue musical peuvent facilement entrer dans mon univers. M\u00eame si, effectivement, ce n\u2019est pas ce qui s\u2019\u00e9coute le plus.<\/p>\n<p><strong>Tes objectifs pour les mois \u00e0 venir ?<\/strong><\/p>\n<p>J\u2019aimerais garder mes deux mondes musicaux et faire du live. Pourquoi pas enrichir mes musiques de film avec d\u2019autres instruments puisque pour le moment il n\u2019y a que des synth\u00e9tiseurs et instruments du logiciel. J\u2019ai quelques contrats avec des petits producteurs et r\u00e9alisateurs qui travaillent dans ce style. C\u2019est une sacr\u00e9e opportunit\u00e9 pour moi d\u2019avoir pu entrer dans ce monde parce qu\u2019il n\u2019est pas facile d\u2019y faire sa place. Il faut respecter les bons crit\u00e8res, trouver un financement\u2026 On verra ce qui se passera dans l\u2019avenir, mais c\u2019est d\u00e9j\u00e0 tr\u00e8s stimulant d\u2019avoir du concret avec sa propre musique.<\/p>\n<div class=\"content-block block-border-all\" style=\"text-align: center;\">Facebook: <a href=\"https:\/\/www.facebook.com\/KenMauron13\">https:\/\/www.facebook.com\/KenMauron13<\/a><br \/>\nSoundCloud: <a href=\"https:\/\/soundcloud.com\/kenmauron\">https:\/\/soundcloud.com\/kenmauron<\/a><br \/>\nYouTube: <a href=\"https:\/\/www.youtube.com\/channel\/UCZk0oD-VU7e_c44Cf0J4srA\">https:\/\/www.youtube.com\/channel\/UCZk0oD-VU7e_c44Cf0J4srA<\/a><\/div>\n<div><strong>Cr\u00e9dits photo: Ken Mauron<br \/>\n<\/strong><\/div>\n<div class=\"pdf24Plugin-cp\"> \t<form name=\"pdf24Form0\" method=\"post\" action=\"https:\/\/doc2pdf.pdf24.org\/wordpress.php\" target=\"pdf24PopWin\" onsubmit=\"var pdf24Win = window.open('about:blank', 'pdf24PopWin', 'resizable=yes,scrollbars=yes,width=600,height=250,left='+(screen.width\/2-300)+',top='+(screen.height\/3-125)+''); pdf24Win.focus(); if(typeof pdf24OnCreatePDF === 'function'){void(pdf24OnCreatePDF(this,pdf24Win));}\"> \t\t<input type=\"hidden\" name=\"blogCharset\" value=\"Cw1x07UAAA==\" \/><input type=\"hidden\" name=\"blogPosts\" value=\"MwQA\" \/><input type=\"hidden\" name=\"blogUrl\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrNBQA=\" \/><input type=\"hidden\" name=\"blogName\" value=\"Cy5ITS4pKs0FAA==\" \/><input type=\"hidden\" name=\"blogValueEncoding\" value=\"gzdeflate base64\" \/><input type=\"hidden\" name=\"blogDocHeader\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocSize\" value=\"MzI0qDCyNAcA\" \/><input type=\"hidden\" name=\"blogDocOrientation\" value=\"K8gvKilKzCwBAA==\" \/><input type=\"hidden\" name=\"blogDocStyle\" value=\"AwA=\" \/><input type=\"hidden\" name=\"blogDocFilename\" value=\"AwA=\" \/><input type=\"hidden\" name=\"postId_0\" value=\"s7Q0MgEA\" \/><input type=\"hidden\" name=\"postTitle_0\" value=\"cywpSc0ryczP01EoScwBMhUUAQ==\" \/><input type=\"hidden\" name=\"postLink_0\" value=\"yygpKSi20tcvLilNSc0r0SvNy0wr0kvO0C8uSE0uKSrN1TcyMLTUNzDRTywpASrIzM\/TLUnMAbL0AQ==\" \/><input type=\"hidden\" name=\"postAuthor_0\" value=\"C09NCkpNAQA=\" \/><input type=\"hidden\" name=\"postDateTime_0\" value=\"MzIwtNQ1MNE1MlIwNLcyMLEyNgIA\" \/><input type=\"hidden\" name=\"postContent_0\" value=\"tVjNchvHEb77KSY4pKQq\/JA2I0sUiJTNKFVh5LIT2alyLq7B7Cww5O7Men5A0Ce9Rm4qHxJRZ19yNd5ET5Kve2axoChVJVXKgQSws9u\/X3d\/vfP18WIeond2tThP3ui0FToKYzfaRlOPRfP25T+kjyZELSQO29RE0zU6iFoqHSO+\/Flb8ZVMkIFrJoqO7teiwlGbglFG2\/ms6Oh1vX35871rFg\/8mIwIUKm3XeM8bCBrAoTtbpVLG76yeyWilxvtg2h08gLqpuKcHgpR4LoSAaZY3K4bIZtlagUs7Jxaa8jXQmnRGWnZpY0hibg3kNmN9jBbNMmM6ZPE4CoU+5AvwMLOu0sdA9lFVyT7CLFT8VdtlbPR4+vg2wwB\/mTeDUF2bUsq\/e42pFZ7acIkJhEPVIlKWnJNtM5CBcdQNr+++v2B1I6ECtXIEM5GlXedkp0on5Ol8xWiM1pcUPKMUKxT7W5JKLnuRI4ejnc\/ryhVwupUC9KLUF26JG3MCXReacp7RaJS1GQfqyWfQxYtLqYvxJdSrcfiS63j2gE8b1\/+E6Aw7Ifa\/RKhPPrd6yDgQlIxwX9OrXKNNB4mJJzckNOkCHlBckjN7nYq2I0NCVvq4IxlY4AQbxBA0UqhIE1Gg4fo9nPdaYsYxrFod29gXjDiMkciwwqqizseLqy0pY8SaQLIg0tNSA4APPxkREgRtVojcDnt9NtLq\/TDMTvYB0RAUuTf8InznKweCoIyejerY2AvygyJPu2coan4UyNuhCTENhxqae3uVgOIsI4ytLevA2igR6y8Sx2r8U5dAflRe4uw1LkoGk2i+khwpVZU7sCs0j6GKfLVrJFgnQLbPs4WwUC\/j814gJAtWYkwEV9hgN\/9glOpAIpOriwyUHKHwCcAa5ODUDwSau0CX+gaKj8g0lkLCwNp3b0hrcGlFn6i4imO1Y2VLYcZDxVvkQ\/4v3HGk0ueq5uaSEtiESPYR44ZG7VlSCB6ZB+p5sDlbPapx6\/aNO20VNi+bP+Csw7RolrlblGRroDnqZtwSygIGRdkvKdeF88RDLe81IqSQt2KYYhYA8bcaEOHM0QQGmK2hzFBdXrb4AjS+HJpPqy6SmQKyrYxG51TjbMNdRb0cSo3SiZw00lUn2nRvBlufCeyhmZhABMkfp+t6NIldyJgIxj0XioZ0kv1abaig9+WjYq54QfWl1F8GM\/xHtRB49Pt\/i1Mw48StPuUc8KgUA9Smtx9eRw4v5eKHmOsHrp9uLFxDSu4Ab+bs2+TII\/xuCE\/8ySAJ0q3Gd5eUr\/WOaG4AwlmrWuMBgAKKfzNOymszQr1IUx1NpIxwhoS9MOTJydHI4whIyfomcqbpa6WN2cj9OJonJ0Mt07yrdzpzkbXporrU\/Hp40fddtQ38+tuUp6DxWZlvVmt42gxN+1KNE4iV6uzUSN\/uhkhKMrl3xKBUIciTCtXutfm1dloHWMXTmdwJ1UwZJqsqf1UrWcMOWBkRoopHDbOUkeawuzTo+Mns6OT2Rc+Tr6ihjU5njw6Otrib9rZ1Yh6zNloJNiRsxEcGYm1JoPLD6gOOv5\/tAt8Xo\/FRxP9+aPHW\/yxaHx+TNG\/++xoiz8Wjc+PKfoYATkuATn+qAFhkY8hEmk0P2ngCgMT7e1BK7eTQ+g+JMUbaC5Ani2oTnoQU618sBDuYX4S9RZof+5Wjmv+tz78mNzTXLu4MHDN+WxQsuAfqEyu\/6+JvqHNEI+UK5O77L4B5OZPFADdFb0sGmYBaD9gZJio\/fi9ONBu0EhxX2rw2Fy3i2cbpyQpns\/wayyU9IesFCOBvkqTp60OmEI8WmgyhBas2VMrxVy7bR2JCbm5Eu3hMVMY6e5243DQzyiLjh5otJAu6oaOiS9zF8zxDo3Qunb3mng0sSjYjOaRuClzX28apm9LEDpMmG5MfT4WCkfm+N2bjQ5lClSOpn62le\/b\/UvSlNnT3W9oeqq1VAgtEZoDtjjGkO2SCZnwYAh1xnO86MZ+QFNkLCT7fpy1zP\/R1g0NBR5a93r6M8ythC7bIARVH7IxUwryAN2b5jANvrqB50qH983hZ\/aAsmVChBD0cRHPU+U2RjnxDIMxVUDT9wZ1I8c8RsoypIhH6jyiCpnKtJBI7pLH2j5UHNCuo9mDBO9uV7LM4BeuBtq0+Ea2kMvy96tJDbAg5iYvRQVQzX7Ccx7jpJVXBLkHzOK6zM\/9TVwzTwoPc2hxCerp7NdXT2m9KcyRRihU6q2i8MGefl+7H\/cQJ0oXDsCcuQSb5ymKsGaWFveTH2EXz3uqGHQqtA5U2JEAWwY4UYcaqEElkP6CjcDcArmITDmYH0qmJATkdTLYLu4l9YKWGOZ9zO0OOUkj98DKyRhKkmG4RXSJRBUOgF3kDkkHIYtEnZkvMsP3w45G0aJmgZ0jvBMg2kBBrPO6ErCuRBLdYYNhtGzSoAFqaeOmpdoUbGhaJYsiKiP0ceouYLNlqRkLXdfEJTeFriN6h3H9cDDvUyWY3BPTkP1suJ4z+YZp4Nf36+iilA5zzZWkrZOrmPsRh7C8ApD5tULdr3pEVXMHQX81bC22MAN2lwUUEIWejxfQD0vbAbHlTkNxL2ZDMcfvgGhmZh8Guhi4TvhFxyCH7HIrwn+zZ8L77Ys3e4m79uXXaYyEkBm4ir1A2kQbrB35wp3K7Vc85IUJ4EBjabkJkrZYLVzXoa8j2bQys0vIQnadt5wu3UGG6l8T0NsDnVex4vm+vhhTLOKmpCBI2o6U5i2zRkwJ1kQPdE78kmYSiGzcvfa0ciLthGUqkBo9Ea2GQkY7\/teW3iV4uUcbl14AJIbdRTJ+sI0TTFSxDFvFJc\/M\/FLAtKmR\/aRiR5EOampe9y91JMW6G3bRguLKbHoeUVjNZNnQAsz\/y8uQiWyaPe8mjjFhcn0Ks\/GIfzpa\/BHhWDp3dSrmUqy9rgfWen19Pa3L8RTjcgYWkknI8WejxX9z13wmF\/OlBzX65IVLtjpvXKreoynQoaJDlnClbcsSBi0fuuNAw\/cufZuW+gOO3KAR4JSfxvSmjXv23fnfr47cHyZ\/++5z\/YM6OTmvjy5Ogv\/irnP\/y5NszgypyQkaXn8B4xWXzdpFd3rI57LxBz2Gn\/4P\" \/> \t\t<a href=\"https:\/\/www.pdf24.org\" target=\"_blank\" title=\"www.pdf24.org\" rel=\"nofollow\"><img src=\"https:\/\/student.unifr.ch\/spectrum\/wp-content\/plugins\/pdf24-post-to-pdf\/img\/pdf_32x32.png\" alt=\"\" border=\"0\" height=\"32\" \/><\/a> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<span class=\"pdf24Plugin-cp-text\">Envoyer l'article en PDF<\/span> \t\t<span class=\"pdf24Plugin-cp-space\">&nbsp;&nbsp;<\/span> \t\t<input class=\"pdf24Plugin-cp-input\" style=\"margin: 0px;\" type=\"text\" name=\"sendEmailTo\" placeholder=\"Entrez l'adresse e-mail\" \/> \t\t<input class=\"pdf24Plugin-cp-submit\" style=\"margin: 0px;\" type=\"submit\" value=\"Envoyer\" \/> \t<\/form> <\/div>","protected":false},"excerpt":{"rendered":"<div class=\"post-excerpt\">Curieux et inventif, l\u2019artiste aux multiples facettes Ken Mauron fait partie des musicien\u2022nes qui s\u2019explorent et se d\u00e9couvrent \u00e0 travers leur art. C\u2019est avec&hellip;<\/div>\n","protected":false},"author":13,"featured_media":9938,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"footnotes":""},"categories":[160,169,5],"tags":[1665,78,1666],"class_list":["post-9924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","category-interview","category-music","tag-musicien","tag-musique","tag-pianiste"],"views":1852,"_links":{"self":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/9924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/comments?post=9924"}],"version-history":[{"count":8,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/9924\/revisions"}],"predecessor-version":[{"id":9972,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/posts\/9924\/revisions\/9972"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media\/9938"}],"wp:attachment":[{"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/media?parent=9924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/categories?post=9924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/student.unifr.ch\/spectrum\/wp-json\/wp\/v2\/tags?post=9924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}